{"id":103862,"date":"2024-06-05T12:14:56","date_gmt":"2024-06-05T11:14:56","guid":{"rendered":"https:\/\/jazairhope.org\/?p=103862"},"modified":"2024-06-05T12:14:59","modified_gmt":"2024-06-05T11:14:59","slug":"a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/","title":{"rendered":"\u00c0 la d\u00e9couverte de l\u2019Alg\u00e9rie : National Geographic explore les secrets du Sahara"},"content":{"rendered":"<p>Par <a title=\"article r\u00e9dig\u00e9 par rima.a\" href=\"https:\/\/www.algerie360.com\/author\/rima-a\/\">Rima.a<\/a><\/p>\n<p>Apr\u00e8s le quotidien britannique The Times, qui s\u2019est int\u00e9ress\u00e9 \u00e0 la destination Alg\u00e9rie, au tour de National Geographic Travel UK d\u2019explorer les secrets du grand sud alg\u00e9rien. Cette r\u00e9gion du pays repr\u00e9sente l\u2019un des atouts du tourisme alg\u00e9rien et re\u00e7oit, toujours, les \u00e9loges de ses visiteurs.<\/p>\n<p>Dans le dernier num\u00e9ro, sorti en ce mois de juin 2024, le c\u00e9l\u00e8bre magazine National Geographic Travel UK, fait d\u00e9couvrir \u00e0 ses lecteurs la ville de Timimoune, le quotidien des Touaregs et la culture nomade qui trouve ses racines dans le grand sud alg\u00e9rien.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p dir=\"ltr\" lang=\"en\">NATIONAL GEOGRAPHIC TRAVELLER MAGAZINE \u2013 JUNE 2024 PREVIEW<a href=\"https:\/\/twitter.com\/NatGeoTravelUK?ref_src=twsrc%5Etfw\">@NatGeoTravelUK<\/a>\u00a0(May 2, 2024): The latest issue explores 17 unique ways to get out and about in Paris as it celebrates its Olympic year\u2026.<br \/>\nAlso inside this issue:<br \/>\nPhuket:\u00a0Divine gastronomy and spirited religious\u2026\u00a0<a href=\"https:\/\/t.co\/mFexJstqAZ\">pic.twitter.com\/mFexJstqAZ<\/a><\/p>\n<div id=\"div-gpt-ad-1664555632129-0\"><\/div>\n<p>\u2014 BoomersDaily (@BoomersDaily55)\u00a0<a href=\"https:\/\/twitter.com\/BoomersDaily55\/status\/1786089818507923904?ref_src=twsrc%5Etfw\">May 2, 2024<\/a><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<h2>Timimoune, Vall\u00e9e du M\u2019zab \u2026 Le Sahara alg\u00e9rien s\u2019ouvre \u00e0 National Geographic<\/h2>\n<p>En effet, la version britannique de National Geographic consacre une partie de son num\u00e9ro du mois de juin 2024 pour d\u00e9crire des citadelles ocre, des plateaux volcaniques, des \u00e9tendues de sables et l\u2019histoire des peuples et des communaut\u00e9s nomades.<\/p>\n<div id=\"div-gpt-ad-1679152293940-0\"><\/div>\n<p>\u201c<em>Les pics volcaniques, les canyons et les vastes \u00e9tendues de sable forment une toile de fond saisissante pour les villes, oasis et les cultures nord-africaines uniques<\/em>\u201c, \u00e9crit National Geographic pour commencer<a href=\"https:\/\/www.algerie360.com\/category\/tourisme-en-algerie\/\">\u00a0son reportage<\/a>\u00a0sur le Sahara qui couvre 80% du sol alg\u00e9rien.<\/p>\n<p>Le magazine de voyage National Geographic s\u2019est int\u00e9ress\u00e9, en particulier, \u00e0 Timimoune, surnomm\u00e9e l\u2019Oasis rouge, en raison de la couleur des parois de la ville. Une couleur selon les habitants qui fait r\u00e9f\u00e9rence \u201c<em>au sang et au sentiment d\u2019appartenance au d\u00e9sert<\/em>\u201c, pr\u00e9cise-le magazine.<\/p>\n<div id=\"attachment_869113\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-869113 size-full lazy loaded\" src=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/vallee-du-Mzab.jpg\" alt=\"Vall\u00e9e du M'zab\" width=\"630\" height=\"419\" aria-describedby=\"caption-attachment-869113\" data-src=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/vallee-du-Mzab.jpg\" data-srcset=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/vallee-du-Mzab.jpg 630w, https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/1_vallee-du-Mzab-320x213.jpg 320w\" data-sizes=\"(max-width: 630px) 100vw, 630px\" data-was-processed=\"true\" \/><\/p>\n<p id=\"caption-attachment-869113\" class=\"wp-caption-text\">Les villages fortifi\u00e9s de la vall\u00e9e du M\u2019Zab.<\/p>\n<\/div>\n<p>Plus au nord, dans la vall\u00e9e du M\u2019Zab, se trouve une cha\u00eene de cinq ksour aux habitations caract\u00e9ristiques de couleur pastel. Ces citadelles ont \u00e9t\u00e9 reconnues par l\u2019UNESCO pour leur \u201c<em>architecture extr\u00eamement originale<\/em>\u201d et pour avoir conserv\u00e9 \u201c<em>pratiquement le m\u00eame mode de vie et les m\u00eames techniques de construction depuis le XIe si\u00e8cle<\/em>\u201c.<\/p>\n<h2>\u201cLes paysages sont encore plus spectaculaires au Tassili N\u2019ajjer\u201d, National Geographic<\/h2>\n<p>\u201c<em>En Alg\u00e9rie, ces paysages sont, encore, plus spectaculaires dans le parc national du Tassili N\u2019ajjer et aux alentours, dans l\u2019extr\u00eame sud, qui s\u2019\u00e9tend sur plus de 28 000 km\u00b2<\/em>\u201c, dans ce passage, l\u2019\u00e9dition britannique de ce magazine d\u00e9crit la majest\u00e9 de ce massif montagneux, ses for\u00eats de rochers, ses arches naturelles et ses imposantes dunes multicolores, \u201c<em>les couleurs vont du blanc et de l\u2019or \u00e0 l\u2019orange terracotta et au rouge sang, et qui peuvent atteindre jusqu\u2019\u00e0 2 000 pieds de hauteur par endroits<\/em>\u201c.<\/p>\n<div id=\"attachment_869114\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-869114 size-image-galerie lazy loaded\" src=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/touareg-730x430.jpg\" alt=\"Toureg\" width=\"730\" height=\"430\" aria-describedby=\"caption-attachment-869114\" data-src=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/touareg-730x430.jpg\" data-was-processed=\"true\" \/><\/p>\n<p id=\"caption-attachment-869114\" class=\"wp-caption-text\">Les Touaregs sont les seuls guides qui connaissent les secrets du Tassili N\u2019ajjer.<\/p>\n<\/div>\n<p>Le Tassili N\u2019ajjer regroupe plus de 15 000 pictogrammes et gravures qui retracent l\u2019histoire de la pr\u00e9sence humaine dans cette r\u00e9gion de l\u2019Alg\u00e9rie. Les plus anciens de ses dessins dataient de plus de 10 000 ans et illustrent une \u00e9poque o\u00f9 le Sahara \u00e9tait une savane fertile que les chasseurs et cueilleurs partageaient avec des \u00e9l\u00e9phants, des lions et des girafes.<\/p>\n<p>La chaine internationale sp\u00e9cialiste des documentaires s\u2019est int\u00e9ress\u00e9e aussi aux Touaregs, dont le Sahara est leur terre ancestrale, facilement reconnaissables gr\u00e2ce \u00e0 leur Tagelmust, ce ch\u00e8che bleu de huit m\u00e8tres environs, qui est \u00e0 la fois symbole d\u2019identit\u00e9 et une protection contre les\u00a0<a href=\"https:\/\/www.algerie360.com\/transavia-combien-doit-on-payer-pour-voyager-avec-une-valise-cabine-video\/\">\u00e9l\u00e9ments ind\u00e9sirables de la nature.<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.algerie360.com\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/\">\u00c0 la d\u00e9couverte de l&#8217;Alg\u00e9rie : National Geographic explore les secrets du Sahara &#8211; Algerie360<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Rima.a Apr\u00e8s le quotidien britannique The Times, qui s\u2019est int\u00e9ress\u00e9 \u00e0 la destination Alg\u00e9rie, au tour de National Geographic Travel UK&hellip;<\/p>\n","protected":false},"author":61,"featured_media":103863,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[34,39,42],"tags":[],"class_list":["post-103862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art-fr","category-articles-en-vedette","category-histoire-et-patrimoine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c0 la d\u00e9couverte de l\u2019Alg\u00e9rie : National Geographic explore les secrets du Sahara - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 la d\u00e9couverte de l\u2019Alg\u00e9rie : National Geographic explore les secrets du Sahara - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Par Rima.a Apr\u00e8s le quotidien britannique The Times, qui s\u2019est int\u00e9ress\u00e9 \u00e0 la destination Alg\u00e9rie, au tour de National Geographic Travel UK&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-05T11:14:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-05T11:14:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Sahara.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"835\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Toufan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Toufan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\\\/\"},\"author\":{\"name\":\"Toufan\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\"},\"headline\":\"\u00c0 la d\u00e9couverte de l\u2019Alg\u00e9rie : National Geographic explore les secrets du Sahara\",\"datePublished\":\"2024-06-05T11:14:56+00:00\",\"dateModified\":\"2024-06-05T11:14:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\\\/\"},\"wordCount\":638,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Sahara.webp\",\"articleSection\":[\"Art &amp; Culture\",\"Articles en vedette\",\"Histoire et Patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\\\/\",\"name\":\"\u00c0 la d\u00e9couverte de l\u2019Alg\u00e9rie : National Geographic explore les secrets du Sahara - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Sahara.webp\",\"datePublished\":\"2024-06-05T11:14:56+00:00\",\"dateModified\":\"2024-06-05T11:14:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Sahara.webp\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Sahara.webp\",\"width\":835,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 la d\u00e9couverte de l\u2019Alg\u00e9rie : National Geographic explore les secrets du Sahara\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\",\"name\":\"Toufan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"caption\":\"Toufan\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/toufan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c0 la d\u00e9couverte de l\u2019Alg\u00e9rie : National Geographic explore les secrets du Sahara - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c0 la d\u00e9couverte de l\u2019Alg\u00e9rie : National Geographic explore les secrets du Sahara - AAH.JZR","og_description":"Par Rima.a Apr\u00e8s le quotidien britannique The Times, qui s\u2019est int\u00e9ress\u00e9 \u00e0 la destination Alg\u00e9rie, au tour de National Geographic Travel UK&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2024-06-05T11:14:56+00:00","article_modified_time":"2024-06-05T11:14:59+00:00","og_image":[{"width":835,"height":430,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Sahara.webp","type":"image\/webp"}],"author":"Toufan","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Toufan","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/"},"author":{"name":"Toufan","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f"},"headline":"\u00c0 la d\u00e9couverte de l\u2019Alg\u00e9rie : National Geographic explore les secrets du Sahara","datePublished":"2024-06-05T11:14:56+00:00","dateModified":"2024-06-05T11:14:59+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/"},"wordCount":638,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Sahara.webp","articleSection":["Art &amp; Culture","Articles en vedette","Histoire et Patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/","url":"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/","name":"\u00c0 la d\u00e9couverte de l\u2019Alg\u00e9rie : National Geographic explore les secrets du Sahara - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Sahara.webp","datePublished":"2024-06-05T11:14:56+00:00","dateModified":"2024-06-05T11:14:59+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Sahara.webp","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Sahara.webp","width":835,"height":430},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/a-la-decouverte-de-lalgerie-national-geographic-explore-les-secrets-du-sahara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c0 la d\u00e9couverte de l\u2019Alg\u00e9rie : National Geographic explore les secrets du Sahara"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f","name":"Toufan","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","caption":"Toufan"},"url":"https:\/\/jazairhope.org\/fr\/author\/toufan\/"}]}},"views":501,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/103862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=103862"}],"version-history":[{"count":2,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/103862\/revisions"}],"predecessor-version":[{"id":103879,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/103862\/revisions\/103879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/103863"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=103862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=103862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=103862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}