{"id":104256,"date":"2024-06-12T12:24:44","date_gmt":"2024-06-12T11:24:44","guid":{"rendered":"https:\/\/jazairhope.org\/?p=104256"},"modified":"2024-06-12T12:24:44","modified_gmt":"2024-06-12T11:24:44","slug":"tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/","title":{"rendered":"Tour du Cameroun 2024 : L&#8217;Alg\u00e9rie remporte le classement par \u00e9quipes"},"content":{"rendered":"<p>Par <a href=\"https:\/\/www.lexpressiondz.com\/profile\/moumen-ait-kaci-ali-1\">Moumen A\u00eft Kaci Ali<\/a> \/ <a href=\"https:\/\/www.lexpressiondz.com\/sports\/l-algerie-remporte-le-classement-par-equipes-382553\">L&#8217;Expression: Sports &#8211; L&#8217;Alg\u00e9rie remporte le classement par \u00e9quipes (lexpressiondz.com)<\/a><\/p>\n<p>Le cycliste alg\u00e9rien Abdallah Benyoucef a d\u00e9croch\u00e9 la 2e place lors de la 9e et derni\u00e8re \u00e9tape de l&#8217;\u00e9dition 2024 du Tour du Cameroun, disput\u00e9e dimanche matin, sur une distance de 108 kilom\u00e8tres, entre Ngoulmakong et Yaound\u00e9. Cette derni\u00e8re \u00e9tape a \u00e9t\u00e9 remport\u00e9e par l&#8217;Ivoirien Ciss\u00e9 Isaka, ayant boucl\u00e9 la distance en 2h26&#8217;30&#8221;, devant Abdallah Benyoucef et le Burkinab\u00e8 Vincent Mouni, ayant r\u00e9ussi eux aussi le m\u00eame chrono.<\/p>\n<p><strong>Sahiri vainqueur de deux maillots<\/strong><br \/>\nC&#8217;est donc le Camerounais Clovis Kamzong Abossolo qui a pris la premi\u00e8re place avec un temps total de 23 h 59&#8242; 9&#8221;. Abdallah Benyoucef s&#8217;est class\u00e9 deuxi\u00e8me avec un chrono de 24 h 1&#8242; 54&#8221;, suivi de son compatriote Ayoub Sahiri, qui a termin\u00e9 troisi\u00e8me en 24 h 2&#8242; 20&#8221;.<br \/>\nAu classement g\u00e9n\u00e9ral par \u00e9quipes, c&#8217;est la s\u00e9lection alg\u00e9rienne qui l&#8217;a emport\u00e9 haut la main, tant la domination des cyclistes alg\u00e9riens \u00e9tait \u00e9vidente dans ce Tour du Cameroun 2024.<br \/>\nSignalons \u00e9galement la performance d&#8217;Ayoub Sahiri particuli\u00e8rement remarquable lors de cette 9e et derni\u00e8re \u00e9tape du tour, puisqu&#8217;il a conserv\u00e9 \u00e0 la fois le maillot \u00e0 pois rouges, r\u00e9serv\u00e9 au meilleur grimpeur, et le maillot blanc, destin\u00e9 au meilleur espoir des moins de 23 ans.<br \/>\nCe jeune cycliste reste un \u00e9l\u00e9ment de valeur qui m\u00e9rite les encouragements.<br \/>\nTr\u00e8s bon durant toute la comp\u00e9tition, le cycliste alg\u00e9rien Abdallah Benyoucef, vainqueur de deux \u00e9tapes dans ce tour, a fait honneur au cyclisme alg\u00e9rien.<\/p>\n<p><strong>Benyoucef s&#8217;empare du maillot vert<\/strong><br \/>\nBenyoucef s&#8217;est empar\u00e9 du maillot vert, destin\u00e9 au meilleur sprinter, avec \u00e0 la cl\u00e9 plusieurs podiums r\u00e9alis\u00e9s tout au long de ce Tour du Cameroun qui s&#8217;est d\u00e9roul\u00e9 du 31 mai au 9 juin. Il a domin\u00e9 ses adversaires durant presque tout ce tour, en les repoussant derri\u00e8re lui au classement g\u00e9n\u00e9ral des meilleurs sprinters. L&#8217;Alg\u00e9rie pour rappel, \u00e9tait engag\u00e9e avec six coureurs dans cette comp\u00e9tition internationale, organis\u00e9e en neuf \u00e9tapes, du 31 mai au 9 juin au Cameroun.<br \/>\nLes trois autres repr\u00e9sentants nationaux sont: Zaki Boudar, Oussama Mimouni et Slimane Badlis.<br \/>\nOutre la s\u00e9lection nationale alg\u00e9rienne, dirig\u00e9e par le coach Samir Allam, onze autres \u00e9quipes \u00e9taient engag\u00e9es. Apr\u00e8s 2015, 2017 et 2021, le Cameroun a gard\u00e9 le maillot jaune.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Moumen A\u00eft Kaci Ali \/ L&#8217;Expression: Sports &#8211; L&#8217;Alg\u00e9rie remporte le classement par \u00e9quipes (lexpressiondz.com) Le cycliste alg\u00e9rien Abdallah Benyoucef a&hellip;<\/p>\n","protected":false},"author":61,"featured_media":104257,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[39,52],"tags":[],"class_list":["post-104256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-en-vedette","category-sport-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tour du Cameroun 2024 : L&#039;Alg\u00e9rie remporte le classement par \u00e9quipes - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour du Cameroun 2024 : L&#039;Alg\u00e9rie remporte le classement par \u00e9quipes - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Par Moumen A\u00eft Kaci Ali \/ L&#8217;Expression: Sports &#8211; L&#8217;Alg\u00e9rie remporte le classement par \u00e9quipes (lexpressiondz.com) Le cycliste alg\u00e9rien Abdallah Benyoucef a&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-12T11:24:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Sport.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Toufan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Toufan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\\\/\"},\"author\":{\"name\":\"Toufan\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\"},\"headline\":\"Tour du Cameroun 2024 : L&#8217;Alg\u00e9rie remporte le classement par \u00e9quipes\",\"datePublished\":\"2024-06-12T11:24:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\\\/\"},\"wordCount\":420,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Sport.jpg\",\"articleSection\":[\"Articles en vedette\",\"Sport &amp; Soci\u00e9t\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\\\/\",\"name\":\"Tour du Cameroun 2024 : L'Alg\u00e9rie remporte le classement par \u00e9quipes - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Sport.jpg\",\"datePublished\":\"2024-06-12T11:24:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Sport.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Sport.jpg\",\"width\":850,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour du Cameroun 2024 : L&#8217;Alg\u00e9rie remporte le classement par \u00e9quipes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\",\"name\":\"Toufan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"caption\":\"Toufan\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/toufan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tour du Cameroun 2024 : L'Alg\u00e9rie remporte le classement par \u00e9quipes - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour du Cameroun 2024 : L'Alg\u00e9rie remporte le classement par \u00e9quipes - AAH.JZR","og_description":"Par Moumen A\u00eft Kaci Ali \/ L&#8217;Expression: Sports &#8211; L&#8217;Alg\u00e9rie remporte le classement par \u00e9quipes (lexpressiondz.com) Le cycliste alg\u00e9rien Abdallah Benyoucef a&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2024-06-12T11:24:44+00:00","og_image":[{"width":850,"height":480,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Sport.jpg","type":"image\/jpeg"}],"author":"Toufan","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Toufan","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/"},"author":{"name":"Toufan","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f"},"headline":"Tour du Cameroun 2024 : L&#8217;Alg\u00e9rie remporte le classement par \u00e9quipes","datePublished":"2024-06-12T11:24:44+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/"},"wordCount":420,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Sport.jpg","articleSection":["Articles en vedette","Sport &amp; Soci\u00e9t\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/","url":"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/","name":"Tour du Cameroun 2024 : L'Alg\u00e9rie remporte le classement par \u00e9quipes - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Sport.jpg","datePublished":"2024-06-12T11:24:44+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Sport.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Sport.jpg","width":850,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/tour-du-cameroun-2024-lalgerie-remporte-le-classement-par-equipes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Tour du Cameroun 2024 : L&#8217;Alg\u00e9rie remporte le classement par \u00e9quipes"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f","name":"Toufan","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","caption":"Toufan"},"url":"https:\/\/jazairhope.org\/fr\/author\/toufan\/"}]}},"views":765,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/104256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=104256"}],"version-history":[{"count":1,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/104256\/revisions"}],"predecessor-version":[{"id":104260,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/104256\/revisions\/104260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/104257"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=104256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=104256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=104256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}