{"id":104620,"date":"2024-06-19T13:56:14","date_gmt":"2024-06-19T12:56:14","guid":{"rendered":"https:\/\/jazairhope.org\/?p=104620"},"modified":"2024-06-19T13:56:14","modified_gmt":"2024-06-19T12:56:14","slug":"le-drame-migratoire-de-nador-melilla-netait-pas-un-accident","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/","title":{"rendered":"Le drame migratoire de Nador-Melilla &#8220;n&#8217;\u00e9tait pas un accident&#8221;"},"content":{"rendered":"<p><strong>Le drame migratoire de Nador-Mellila, survenu le 24 juin 2022 et qui a co\u00fbt\u00e9 la vie \u00e0 au moins 37 migrants subsahariens, &#8220;n&#8217;\u00e9tait pas un accident&#8221;, selon les r\u00e9sultats d&#8217;une enqu\u00eate men\u00e9e par plusieurs ONG qui exigent que le Maroc et l&#8217;Espagne soient tenus responsables pour le massacre.\u00a0<\/strong><\/p>\n<p>Il y a deux ans, pr\u00e8s de 2.000 migrants subsahariens avaient tent\u00e9 de p\u00e9n\u00e9trer dans l&#8217;enclave espagnole de Melilla depuis Nador (nord du Maroc).<\/p>\n<p>Comme Amnesty, des experts ind\u00e9pendants nomm\u00e9s par le Conseil des droits de l&#8217;homme de l&#8217;ONU ont \u00e9voqu\u00e9 un bilan d&#8217;au moins 37 morts et d\u00e9nonc\u00e9 le manque de responsabilit\u00e9s concr\u00e8tes \u00e9tablies, aussi bien au Maroc qu&#8217;en Espagne.<\/p>\n<p>Une nouvelle enqu\u00eate men\u00e9e par les organisations Border Forensics, Iridia et l&#8217;Association marocaine des droits de l&#8217;homme (AMDH), avec le soutien du Centre europ\u00e9en des droits constitutionnels et de l&#8217;homme, r\u00e9v\u00e8le que &#8220;les \u00e9v\u00e9nements n&#8217;\u00e9taient pas un accident, mais r\u00e9pondaient plut\u00f4t \u00e0 une v\u00e9ritable strat\u00e9gie des autorit\u00e9s des deux pays&#8221;.<\/p>\n<p>Dans cette nouvelle enqu\u00eate, bas\u00e9e principalement sur des t\u00e9moignages de survivants recueillis au Maroc et en Espagne, ainsi que sur des documents officiels, des vid\u00e9os et des images jusqu&#8217;ici inaccessibles, les ONG documentent &#8220;la violence et l&#8217;extr\u00eame d\u00e9shumanisation des migrants&#8221; lors de la journ\u00e9e du 24 juin 2022, ainsi que &#8220;le manque de justice&#8221;.<\/p>\n<p>Selon les r\u00e9sultats de l&#8217;enqu\u00eate, les forces de s\u00e9curit\u00e9 marocaines ont &#8220;d\u00e9lib\u00e9r\u00e9ment permis aux migrants de s&#8217;approcher de la fronti\u00e8re et, une fois sur place, les ont dirig\u00e9s vers le poste fronti\u00e8re, o\u00f9 ils ont ensuite \u00e9t\u00e9 attaqu\u00e9s par des agents des deux pays&#8221;.<\/p>\n<p>L&#8217;usage intensif des gaz lacrymog\u00e8nes et le climat de panique qui en a r\u00e9sult\u00e9, affirment les ONG, &#8220;ont produit les premiers morts&#8221;.<\/p>\n<p>&#8220;Avec cette enqu\u00eate, nous voulons remettre sur la table, les demandes de justice des bless\u00e9s et des familles des disparus qui attendent toujours des r\u00e9ponses&#8221;, d\u00e9clare Maite Daniela Lo Coco, coordinatrice des migrations de l&#8217;organisation Iridia.<\/p>\n<p>Malgr\u00e9 l&#8217;ampleur de la trag\u00e9die, les organisations de d\u00e9fense des droits de l&#8217;homme d\u00e9noncent dans le rapport le fait que le Maroc a eu recours aux institutions judiciaires pour &#8220;continuer \u00e0 r\u00e9primer les survivants&#8221; et ne pas identifier les responsables de ce qui s&#8217;est pass\u00e9, tandis que le parquet espagnol dit &#8220;n&#8217;avoir trouv\u00e9 aucune preuve d&#8217;un crime&#8221; commis par les forces de s\u00e9curit\u00e9 du pays et a cl\u00f4tur\u00e9 son enqu\u00eate sur les \u00e9v\u00e9nements.<\/p>\n<p>Les agents des deux pays &#8220;sont responsables de ces morts&#8221;, accuse la responsable d&#8217;Iridia, et &#8220;ils ont utilis\u00e9 du mat\u00e9riel anti-\u00e9meute non autoris\u00e9 et de mani\u00e8re non r\u00e9glementaire, puisqu&#8217;ils l&#8217;ont jet\u00e9 dans un endroit sans issue&#8221;.<\/p>\n<p>De nombreuses personnes interrog\u00e9es par les ONG &#8220;ont racont\u00e9 qu&#8217;il \u00e9tait impossible de respirer en raison de la quantit\u00e9 de fum\u00e9e et des embruns ainsi que de l&#8217;utilisation de balles en caoutchouc&#8221;.<\/p>\n<p>Les organisations assurent que les \u00e9v\u00e9nements reconstitu\u00e9s avec diff\u00e9rentes preuves &#8220;ne sont pas seulement incriminants pour les autorit\u00e9s marocaines et espagnoles, mais aussi pour l&#8217;Union europ\u00e9enne (UE), qui les soutient politiquement et \u00e9conomiquement&#8221;.<\/p>\n<p>Les ONG exigent que les deux pays soient tenus responsables et &#8220;r\u00e9pondent enfin aux demandes de v\u00e9rit\u00e9 et de justice des victimes et de leurs familles&#8221;.<\/p>\n<p>Elles soulignent \u00e9galement que les survivants et les familles des d\u00e9funts pourraient engager des poursuites judiciaires contre l&#8217;Espagne et le Maroc, non seulement en raison de la violence de l&#8217;op\u00e9ration, mais aussi en raison &#8220;des formes de d\u00e9tention pratiqu\u00e9es au cours de celle-ci et de l&#8217;absence d&#8217;une enqu\u00eate&#8221; cr\u00e9dible.<\/p>\n<p><a href=\"https:\/\/www.lesoirdalgerie.com\/actualites\/le-drame-migratoire-de-nador-melilla-n-etait-pas-un-accident-118470\">Le drame migratoire de Nador-Melilla &#8220;n&#8217;\u00e9tait pas un accident&#8221; &#8211; Actualit\u00e9s : Le Soir d&#8217;Alg\u00e9rie (lesoirdalgerie.com)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le drame migratoire de Nador-Mellila, survenu le 24 juin 2022 et qui a co\u00fbt\u00e9 la vie \u00e0 au moins 37 migrants subsahariens,&hellip;<\/p>\n","protected":false},"author":61,"featured_media":104621,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[39,49],"tags":[],"class_list":["post-104620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-en-vedette","category-politique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le drame migratoire de Nador-Melilla &quot;n&#039;\u00e9tait pas un accident&quot; - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le drame migratoire de Nador-Melilla &quot;n&#039;\u00e9tait pas un accident&quot; - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Le drame migratoire de Nador-Mellila, survenu le 24 juin 2022 et qui a co\u00fbt\u00e9 la vie \u00e0 au moins 37 migrants subsahariens,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-19T12:56:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Makhnez.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Toufan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Toufan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\\\/\"},\"author\":{\"name\":\"Toufan\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\"},\"headline\":\"Le drame migratoire de Nador-Melilla &#8220;n&#8217;\u00e9tait pas un accident&#8221;\",\"datePublished\":\"2024-06-19T12:56:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\\\/\"},\"wordCount\":690,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Makhnez.jpg\",\"articleSection\":[\"Articles en vedette\",\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\\\/\",\"name\":\"Le drame migratoire de Nador-Melilla \\\"n'\u00e9tait pas un accident\\\" - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Makhnez.jpg\",\"datePublished\":\"2024-06-19T12:56:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Makhnez.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Makhnez.jpg\",\"width\":850,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le drame migratoire de Nador-Melilla &#8220;n&#8217;\u00e9tait pas un accident&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\",\"name\":\"Toufan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"caption\":\"Toufan\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/toufan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le drame migratoire de Nador-Melilla \"n'\u00e9tait pas un accident\" - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/","og_locale":"fr_FR","og_type":"article","og_title":"Le drame migratoire de Nador-Melilla \"n'\u00e9tait pas un accident\" - AAH.JZR","og_description":"Le drame migratoire de Nador-Mellila, survenu le 24 juin 2022 et qui a co\u00fbt\u00e9 la vie \u00e0 au moins 37 migrants subsahariens,&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2024-06-19T12:56:14+00:00","og_image":[{"width":850,"height":480,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Makhnez.jpg","type":"image\/jpeg"}],"author":"Toufan","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Toufan","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/"},"author":{"name":"Toufan","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f"},"headline":"Le drame migratoire de Nador-Melilla &#8220;n&#8217;\u00e9tait pas un accident&#8221;","datePublished":"2024-06-19T12:56:14+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/"},"wordCount":690,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Makhnez.jpg","articleSection":["Articles en vedette","Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/","url":"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/","name":"Le drame migratoire de Nador-Melilla \"n'\u00e9tait pas un accident\" - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Makhnez.jpg","datePublished":"2024-06-19T12:56:14+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Makhnez.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Makhnez.jpg","width":850,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/le-drame-migratoire-de-nador-melilla-netait-pas-un-accident\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Le drame migratoire de Nador-Melilla &#8220;n&#8217;\u00e9tait pas un accident&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f","name":"Toufan","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","caption":"Toufan"},"url":"https:\/\/jazairhope.org\/fr\/author\/toufan\/"}]}},"views":631,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/104620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=104620"}],"version-history":[{"count":1,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/104620\/revisions"}],"predecessor-version":[{"id":104624,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/104620\/revisions\/104624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/104621"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=104620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=104620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=104620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}