{"id":105027,"date":"2024-06-28T09:00:41","date_gmt":"2024-06-28T08:00:41","guid":{"rendered":"https:\/\/jazairhope.org\/?p=105027"},"modified":"2024-06-27T11:20:08","modified_gmt":"2024-06-27T10:20:08","slug":"festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/","title":{"rendered":"Festival du film du tourisme 2024 : le documentaire alg\u00e9rien \u201cT\u2019bal\u201d prim\u00e9 \u00e0 Johannesburg"},"content":{"rendered":"<p>Par\u00a0<a title=\"article r\u00e9dig\u00e9 par rima.a\" href=\"https:\/\/www.algerie360.com\/author\/rima-a\/\">rima.a<\/a><\/p>\n<p>La nouvelle \u00e9dition du festival international du film du tourisme en Afrique, a eu lieu du 11 au 15 juin dernier, \u00e0 Johannesburg en Afrique du Sud. L\u2019\u00e9v\u00e9nement \u00e9tait l\u2019occasion de mettre \u00e0 l\u2019honneur toutes les \u0153uvres au contenu exceptionnel visant \u00e0 promouvoir le tourisme, dans le continent.<\/p>\n<p>En effet, le jury, compos\u00e9 d\u2019experts dans l\u2019industrie cin\u00e9matographique li\u00e9e au tourisme, ont profit\u00e9 de ce festival pour r\u00e9compenser les plus brillantes r\u00e9alisations.<\/p>\n<h2>Festival international du film du tourisme : le documentaire \u201cT\u2019bal\u201d d\u00e9croche l\u2019argent \u00e0 Johannesburg<\/h2>\n<p>Dans la liste du palmar\u00e8s, de cette nouvelle \u00e9dition, figure le nom d\u2019un documentaire alg\u00e9rien distingu\u00e9 lors de cet \u00e9v\u00e9nement. Il en est question de \u201cT\u2019bal\u201d, r\u00e9alis\u00e9 par Salem Dahmani, qui met en lumi\u00e8re le patrimoine mat\u00e9riel et immat\u00e9riel d\u2019Alg\u00e9rie.<\/p>\n<div id=\"div-gpt-ad-1664555632129-0\"><\/div>\n<p>\u201cT\u2019bal\u201d, ou Tambour en fran\u00e7ais, met en valeur l\u2019utilisation de cet instrument de musique, tr\u00e8s r\u00e9pandue au sud de l\u2019Alg\u00e9rie, plus particuli\u00e8rement dans la r\u00e9gion d\u2019Adrar. Le documentaire retrace la dimension socioculturelle du T\u2019bal, pr\u00e9sents lors des manifestations populaires et culturelles de la r\u00e9gion.<\/p>\n<div id=\"attachment_869817\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-869817 size-full lazy loaded\" src=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/1_aaprix.jpg\" alt=\"Festival international du film du tourisme\" width=\"409\" height=\"612\" aria-describedby=\"caption-attachment-869817\" data-src=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/1_aaprix.jpg\" data-srcset=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/1_aaprix.jpg 409w, https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/1_aaprix-320x479.jpg 320w\" data-sizes=\"(max-width: 409px) 100vw, 409px\" data-was-processed=\"true\" \/><\/p>\n<p id=\"caption-attachment-869817\" class=\"wp-caption-text\">Le documentaire de Salem Dahmani remporte le prix d\u2019argent au festival international du film du tourisme 2024.<\/p>\n<\/div>\n<p>En plus de la pr\u00e9sentation d\u2019un instrument de musique essentiel pour chanter des \u0153uvres po\u00e9tiques, le film de Salem Dahmani, capture les images de plusieurs sites touristiques embl\u00e9matiques de l\u2019Alg\u00e9rie. En plus des oasis et des dunes, le film met en valeur les tenues traditionnelles et les coutumes qui contribuent \u00e0 la promotion de la destination Alg\u00e9rie. Tous ces \u00e9l\u00e9ments lui ont valu le prix d\u2019argent, d\u00e9cern\u00e9 par le jury du festival international du tourisme, \u00e0\u00a0<a href=\"https:\/\/www.algerie360.com\/les-etrangers-dehors-en-france-une-soiree-a-caractere-raciste-suscite-un-tolle\/\">Johannesburg.<\/a><\/p>\n<p>D\u00e9crocher un prestigieux prix gr\u00e2ce \u00e0 l\u2019\u0153uvre \u201cTambour\u201d, n\u2019est pas une premi\u00e8re pour ce r\u00e9alisateur. En effet, Salem Dahmani a d\u00e9j\u00e0\u00a0<a href=\"https:\/\/www.algerie360.com\/deux-photos-algeriennes-parmi-les-dix-premieres-mondiales\/\">remport\u00e9 le prix<\/a>\u00a0du meilleur film documentaire au festival national de cin\u00e9ma-Toua d\u2019Adrar, et un autre troph\u00e9e aux journ\u00e9es cin\u00e9matographiques nationales du film du patrimoine, en 2021.<\/p>\n<p><a href=\"https:\/\/www.algerie360.com\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/\">Festival du film du tourisme 2024 : le documentaire alg\u00e9rien &#8220;T&#8217;bal&#8221; prim\u00e9 \u00e0 Johannesburg &#8211; Algerie360<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par\u00a0rima.a La nouvelle \u00e9dition du festival international du film du tourisme en Afrique, a eu lieu du 11 au 15 juin dernier,&hellip;<\/p>\n","protected":false},"author":61,"featured_media":105028,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[34,39],"tags":[],"class_list":["post-105027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art-fr","category-articles-en-vedette"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festival du film du tourisme 2024 : le documentaire alg\u00e9rien \u201cT\u2019bal\u201d prim\u00e9 \u00e0 Johannesburg - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festival du film du tourisme 2024 : le documentaire alg\u00e9rien \u201cT\u2019bal\u201d prim\u00e9 \u00e0 Johannesburg - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Par\u00a0rima.a La nouvelle \u00e9dition du festival international du film du tourisme en Afrique, a eu lieu du 11 au 15 juin dernier,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-28T08:00:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Tbal-prime.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"835\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Toufan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Toufan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\\\/\"},\"author\":{\"name\":\"Toufan\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\"},\"headline\":\"Festival du film du tourisme 2024 : le documentaire alg\u00e9rien \u201cT\u2019bal\u201d prim\u00e9 \u00e0 Johannesburg\",\"datePublished\":\"2024-06-28T08:00:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\\\/\"},\"wordCount\":390,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Tbal-prime.jpg\",\"articleSection\":[\"Art &amp; Culture\",\"Articles en vedette\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\\\/\",\"name\":\"Festival du film du tourisme 2024 : le documentaire alg\u00e9rien \u201cT\u2019bal\u201d prim\u00e9 \u00e0 Johannesburg - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Tbal-prime.jpg\",\"datePublished\":\"2024-06-28T08:00:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Tbal-prime.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Tbal-prime.jpg\",\"width\":835,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festival du film du tourisme 2024 : le documentaire alg\u00e9rien \u201cT\u2019bal\u201d prim\u00e9 \u00e0 Johannesburg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\",\"name\":\"Toufan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"caption\":\"Toufan\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/toufan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festival du film du tourisme 2024 : le documentaire alg\u00e9rien \u201cT\u2019bal\u201d prim\u00e9 \u00e0 Johannesburg - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/","og_locale":"fr_FR","og_type":"article","og_title":"Festival du film du tourisme 2024 : le documentaire alg\u00e9rien \u201cT\u2019bal\u201d prim\u00e9 \u00e0 Johannesburg - AAH.JZR","og_description":"Par\u00a0rima.a La nouvelle \u00e9dition du festival international du film du tourisme en Afrique, a eu lieu du 11 au 15 juin dernier,&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2024-06-28T08:00:41+00:00","og_image":[{"width":835,"height":430,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Tbal-prime.jpg","type":"image\/jpeg"}],"author":"Toufan","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Toufan","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/"},"author":{"name":"Toufan","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f"},"headline":"Festival du film du tourisme 2024 : le documentaire alg\u00e9rien \u201cT\u2019bal\u201d prim\u00e9 \u00e0 Johannesburg","datePublished":"2024-06-28T08:00:41+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/"},"wordCount":390,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Tbal-prime.jpg","articleSection":["Art &amp; Culture","Articles en vedette"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/","url":"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/","name":"Festival du film du tourisme 2024 : le documentaire alg\u00e9rien \u201cT\u2019bal\u201d prim\u00e9 \u00e0 Johannesburg - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Tbal-prime.jpg","datePublished":"2024-06-28T08:00:41+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Tbal-prime.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/06\/Tbal-prime.jpg","width":835,"height":430},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/festival-du-film-du-tourisme-2024-le-documentaire-algerien-tbal-prime-a-johannesburg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Festival du film du tourisme 2024 : le documentaire alg\u00e9rien \u201cT\u2019bal\u201d prim\u00e9 \u00e0 Johannesburg"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f","name":"Toufan","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","caption":"Toufan"},"url":"https:\/\/jazairhope.org\/fr\/author\/toufan\/"}]}},"views":858,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/105027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=105027"}],"version-history":[{"count":2,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/105027\/revisions"}],"predecessor-version":[{"id":105044,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/105027\/revisions\/105044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/105028"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=105027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=105027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=105027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}