{"id":106811,"date":"2024-07-28T14:46:31","date_gmt":"2024-07-28T13:46:31","guid":{"rendered":"https:\/\/jazairhope.org\/?p=106811"},"modified":"2024-07-28T14:46:32","modified_gmt":"2024-07-28T13:46:32","slug":"golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/","title":{"rendered":"Golden Whisk 2024 : l\u2019Alg\u00e9rienne Mounia Lounes prim\u00e9e au Royaume-Uni"},"content":{"rendered":"<p>Par\u00a0<a title=\"article r\u00e9dig\u00e9 par rima.a\" href=\"https:\/\/www.algerie360.com\/author\/rima-a\/\">rima.a<\/a><\/p>\n<p>Nouvelle perc\u00e9e pour la cuisine traditionnelle alg\u00e9rienne sur la sc\u00e8ne internationale. Une fois de plus, l\u2019art culinaire alg\u00e9rien se distingue dans un\u00a0<a href=\"https:\/\/www.algerie360.com\/meilleurs-pains-en-afrique-la-mahdjouba-et-la-kesra-tronent-au-classement-de-tasteatlas\/\">prestigieux concours<\/a>\u00a0au Royaume-Uni. Une distinction remport\u00e9e par la talentueuse Mounia Lounes, qui a mis \u00e0 l\u2019honneur les recettes traditionnelles alg\u00e9riennes.<\/p>\n<p>En effet, r\u00e9sidente au Royaume-Uni, Mounia Lounes a d\u00e9croch\u00e9 le prix du meilleur plat, de la 8\u1d49 \u00e9dition du concours \u201c<em>Golden Whisk<\/em>\u201c. Et ce, gr\u00e2ce \u00e0 un menu vari\u00e9 issu de la cuisine traditionnelle alg\u00e9rienne.<\/p>\n<h2>L\u2019Alg\u00e9rienne Mounia Lounes remporte le Golden Whisk 2024 au Royaume-Uni<\/h2>\n<p>Le Golden Whisck est\u00a0<a href=\"https:\/\/www.algerie360.com\/nouveau-classement-de-tasteatlas-ce-plat-algerien-fait-saliver-les-internautes\/\">un concours annuel<\/a>\u00a0du groupe Mellors, organis\u00e9 pour c\u00e9l\u00e9brer et r\u00e9compenser les comp\u00e9tences culinaires dans le nord de l\u2019Angleterre, sous le th\u00e8me \u201c<em>du pass\u00e9 \u00e0 l\u2019assiette<\/em>\u201c. Les participants s\u2019affrontent dans une s\u00e9rie d\u2019\u00e9preuves culinaires pour tenter de remporter le grand prix, en pr\u00e9sentant des plats, \u00e0 la fois, innovants, rentables et faciles \u00e0 vendre.<\/p>\n<div id=\"div-gpt-ad-1664555632129-0\" data-google-query-id=\"CJGerf3pyYcDFaqx_QcdT94syw\">\n<div id=\"google_ads_iframe_\/10070506\/in-line-article-2_0__container__\"><\/div>\n<\/div>\n<p>Cette ann\u00e9e, le th\u00e8me choisi, \u201c<em>du pass\u00e9 \u00e0 l\u2019assiette<\/em>\u201c, met \u00e0 l\u2019honneur les recettes traditionnelles, transmises de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration, pour c\u00e9l\u00e9brer le riche patrimoine culinaire que plusieurs familles ch\u00e9rissent et s\u2019inspirer d\u2019une cuisine familiale et conviviale.<\/p>\n<p>Pour concourir \u00e0 ce prix, l\u2019Alg\u00e9rienne Mounia Lounes a fait face \u00e0 plus de 300 participants, pour enfin remporter ce concours, gr\u00e2ce \u00e0 trois embl\u00e9matiques de la cuisine alg\u00e9rienne : Le Bourek, le Couscous et le Mouscoutchou.<\/p>\n<p>&nbsp;<\/p>\n<div data-sliderid=\"53451\" id=\"penci-post-gallery__53451\" class=\"penci-post-gallery-container justified column-3\" data-height=\"150\" data-margin=\"3\"><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/07\/Post.jpg\"><img decoding=\"async\" src=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/07\/Post-585x518.jpg\" alt=\"\" title=\"Post\"><\/a><\/div>\n<div class=\"twitter-tweet twitter-tweet-rendered\"><\/div>\n<p><a href=\"https:\/\/x.com\/mellorscatering\/status\/1811361519331934520?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1811361519331934520%7Ctwgr%5Ec6aad5b6beb0ff447cd78aaeb9e56eb39d919e23%7Ctwcon%5Es1_&amp;ref_url=https%3A%2F%2Fwww.algerie360.com%2Fgolden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni%2F\">https:\/\/x.com\/mellorscatering\/status\/1811361519331934520?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1811361519331934520%7Ctwgr%5Ec6aad5b6beb0ff447cd78aaeb9e56eb39d919e23%7Ctwcon%5Es1_&amp;ref_url=https%3A%2F%2Fwww.algerie360.com%2Fgolden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni%2F<\/a><\/p>\n<h2>Le couscous, un h\u00e9ritage mill\u00e9naire richement d\u00e9clin\u00e9 en Alg\u00e9rie<\/h2>\n<p>Les d\u00e9licieuses recettes de Mounia lui ont permis, non seulement de reporter ce prestigieux prix, mais aussi d\u2019inscrire ces plats traditionnels alg\u00e9riens dans le menu de 370 \u00e9coles et 77 h\u00f4pitaux britanniques, \u00e0 partir de la prochaine rentr\u00e9e, rapporte l\u2019arabophone Echorouk.<\/p>\n<div id=\"attachment_870776\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-870776 size-image-galerie lazy loaded\" src=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/07\/4_couscous-730x430.jpg\" alt=\"couscous\" width=\"730\" height=\"430\" aria-describedby=\"caption-attachment-870776\" data-src=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/07\/4_couscous-730x430.jpg\" data-was-processed=\"true\" \/><\/p>\n<p id=\"caption-attachment-870776\" class=\"wp-caption-text\">Le couscous, un h\u00e9ritage mill\u00e9naire richement d\u00e9clin\u00e9 en Alg\u00e9rie.<\/p>\n<\/div>\n<p>Inscrit au patrimoine immat\u00e9riel de l\u2019humanit\u00e9 en 2020, le couscous est un h\u00e9ritage mill\u00e9naire richement d\u00e9clin\u00e9 en Alg\u00e9rie. Le couscous comprend plusieurs mets aussi subtils qu\u2019originaux. \u00c0 base de semoule de bl\u00e9 dur, il est g\u00e9n\u00e9ralement servi avec un ragout de viande et de l\u00e9gumes.<\/p>\n<p>Par ailleurs, cette recette de partage et de convivialit\u00e9 fait, aussi, partie des plats servis lors des r\u00e9unions de famille, des mariages et des \u00e9v\u00e9nements les plus marquants. En Alg\u00e9rie, il existe plusieurs vari\u00e9t\u00e9s de couscous, parmi les plus r\u00e9pandues : le couscous \u00e0 l\u2019agneau, au poulet ou au b\u0153uf. Mais aussi, sa version v\u00e9g\u00e9tarienne, connue sous le nom \u201cSeksou tassilt\u201d chez les Kabyles.<\/p>\n<p><div class=\"ose-wrapper ose-uid-ae974a2455ac675f88ebbd48fccd6ae2 ose-embedpress-responsive\" style=\"width:600px; height:550px; max-height:550px; max-width:100%; display:inline-block;\" data-embed-type=\"SelfHosted\"><iframe allowFullScreen=\"true\" width=\"600\" height=\"550\" src=\"https:\/\/www.algerie360.com\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/\" > <\/iframe><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par\u00a0rima.a Nouvelle perc\u00e9e pour la cuisine traditionnelle alg\u00e9rienne sur la sc\u00e8ne internationale. Une fois de plus, l\u2019art culinaire alg\u00e9rien se distingue dans&hellip;<\/p>\n","protected":false},"author":61,"featured_media":106812,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"link","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[34,39,42],"tags":[],"class_list":["post-106811","post","type-post","status-publish","format-link","has-post-thumbnail","hentry","category-art-fr","category-articles-en-vedette","category-histoire-et-patrimoine","post_format-post-format-link"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Golden Whisk 2024 : l\u2019Alg\u00e9rienne Mounia Lounes prim\u00e9e au Royaume-Uni - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Golden Whisk 2024 : l\u2019Alg\u00e9rienne Mounia Lounes prim\u00e9e au Royaume-Uni - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Par\u00a0rima.a Nouvelle perc\u00e9e pour la cuisine traditionnelle alg\u00e9rienne sur la sc\u00e8ne internationale. Une fois de plus, l\u2019art culinaire alg\u00e9rien se distingue dans&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-28T13:46:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-28T13:46:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/07\/mounia-835x430-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"835\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Toufan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Toufan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\\\/\"},\"author\":{\"name\":\"Toufan\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\"},\"headline\":\"Golden Whisk 2024 : l\u2019Alg\u00e9rienne Mounia Lounes prim\u00e9e au Royaume-Uni\",\"datePublished\":\"2024-07-28T13:46:31+00:00\",\"dateModified\":\"2024-07-28T13:46:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\\\/\"},\"wordCount\":508,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/mounia-835x430-1.jpg\",\"articleSection\":[\"Art &amp; Culture\",\"Articles en vedette\",\"Histoire et Patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\\\/\",\"name\":\"Golden Whisk 2024 : l\u2019Alg\u00e9rienne Mounia Lounes prim\u00e9e au Royaume-Uni - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/mounia-835x430-1.jpg\",\"datePublished\":\"2024-07-28T13:46:31+00:00\",\"dateModified\":\"2024-07-28T13:46:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/mounia-835x430-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/mounia-835x430-1.jpg\",\"width\":835,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Golden Whisk 2024 : l\u2019Alg\u00e9rienne Mounia Lounes prim\u00e9e au Royaume-Uni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\",\"name\":\"Toufan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"caption\":\"Toufan\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/toufan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Golden Whisk 2024 : l\u2019Alg\u00e9rienne Mounia Lounes prim\u00e9e au Royaume-Uni - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/","og_locale":"fr_FR","og_type":"article","og_title":"Golden Whisk 2024 : l\u2019Alg\u00e9rienne Mounia Lounes prim\u00e9e au Royaume-Uni - AAH.JZR","og_description":"Par\u00a0rima.a Nouvelle perc\u00e9e pour la cuisine traditionnelle alg\u00e9rienne sur la sc\u00e8ne internationale. Une fois de plus, l\u2019art culinaire alg\u00e9rien se distingue dans&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2024-07-28T13:46:31+00:00","article_modified_time":"2024-07-28T13:46:32+00:00","og_image":[{"width":835,"height":430,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/07\/mounia-835x430-1.jpg","type":"image\/jpeg"}],"author":"Toufan","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Toufan","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/"},"author":{"name":"Toufan","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f"},"headline":"Golden Whisk 2024 : l\u2019Alg\u00e9rienne Mounia Lounes prim\u00e9e au Royaume-Uni","datePublished":"2024-07-28T13:46:31+00:00","dateModified":"2024-07-28T13:46:32+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/"},"wordCount":508,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/07\/mounia-835x430-1.jpg","articleSection":["Art &amp; Culture","Articles en vedette","Histoire et Patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/","url":"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/","name":"Golden Whisk 2024 : l\u2019Alg\u00e9rienne Mounia Lounes prim\u00e9e au Royaume-Uni - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/07\/mounia-835x430-1.jpg","datePublished":"2024-07-28T13:46:31+00:00","dateModified":"2024-07-28T13:46:32+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/07\/mounia-835x430-1.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/07\/mounia-835x430-1.jpg","width":835,"height":430},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/golden-whisk-2024-lalgerienne-mounia-lounes-primee-au-royaume-uni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Golden Whisk 2024 : l\u2019Alg\u00e9rienne Mounia Lounes prim\u00e9e au Royaume-Uni"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f","name":"Toufan","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","caption":"Toufan"},"url":"https:\/\/jazairhope.org\/fr\/author\/toufan\/"}]}},"views":775,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/106811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=106811"}],"version-history":[{"count":6,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/106811\/revisions"}],"predecessor-version":[{"id":106838,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/106811\/revisions\/106838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/106812"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=106811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=106811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=106811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}