{"id":112254,"date":"2024-12-20T12:44:03","date_gmt":"2024-12-20T11:44:03","guid":{"rendered":"https:\/\/jazairhope.org\/?p=112254"},"modified":"2024-12-20T12:45:10","modified_gmt":"2024-12-20T11:45:10","slug":"la-france-doit-partir-dafrique-est-le-slogan-du-moment","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/","title":{"rendered":"La France doit partir d\u2019Afrique est le slogan du moment"},"content":{"rendered":"<blockquote>\n<h3>Alors que le Tchad et le S\u00e9n\u00e9gal rejoignent le Burkina Faso, le Mali et le Niger pour exiger le retrait des militaires fran\u00e7ais, un \u00e9lan de souverainet\u00e9 continue de d\u00e9ferler sur le Sahel.<\/h3>\n<\/blockquote>\n<p><img decoding=\"async\" class=\"alignleft\" src=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Vijay-e1626206174772.png\" width=\"160\" height=\"160\" \/><\/p>\n<p>Chers amis,\u00a0Salutations du bureau de l\u2019<a href=\"https:\/\/thetricontinental.org\/fr\">Institut Tricontinental de recherche sociale<\/a>.<\/p>\n<p>Une cascade de sentiments anti-fran\u00e7ais continue de d\u00e9ferler sur la ceinture sah\u00e9lienne en Afrique\u00a0: en novembre, rejoignant le Burkina Faso, le Mali et le Niger, le\u00a0<a href=\"https:\/\/www.lemonde.fr\/afrique\/article\/2024\/11\/29\/le-tchad-rompt-ses-accords-de-defense-avec-la-france-un-camouflet-pour-paris_6419906_3212.html\">Tchad<\/a>\u00a0et le\u00a0<a href=\"https:\/\/www.liberation.fr\/international\/afrique\/senegal-le-president-diomaye-faye-demande-a-la-france-de-fermer-ses-bases-militaires-20241129_MQ4DV62QHJHJLB2JPGDFNRXYFI\/\">S\u00e9n\u00e9gal<\/a>\u00a0ont exig\u00e9 que le gouvernement fran\u00e7ais retire ses militaires de leur territoire. De la fronti\u00e8re occidentale du Soudan \u00e0 l\u2019oc\u00e9an Atlantique, les forces arm\u00e9es fran\u00e7aises, pr\u00e9sentes dans la r\u00e9gion depuis 1659, n\u2019auront plus de base. La\u00a0<a href=\"https:\/\/www.lemonde.fr\/afrique\/article\/2024\/11\/29\/le-tchad-rompt-ses-accords-de-defense-avec-la-france-un-camouflet-pour-paris_6419906_3212.html\">d\u00e9claration<\/a>\u00a0du ministre des affaires \u00e9trang\u00e8res du Tchad, Abderaman Koulamallah, est exemplaire\u00a0: \u00ab\u00a0La France doit consid\u00e9rer d\u00e9sormais que le Tchad a grandi et m\u00fbri, que le Tchad est un Etat souverain et tr\u00e8s jaloux de sa souverainet\u00e9\u00a0\u00bb. Ici, le mot cl\u00e9 est \u00ab\u00a0souverainet\u00e9\u00a0\u00bb. Ce que Koulamallah signale, c\u2019est que les pays du Sahel ne se satisfont plus d\u2019une ind\u00e9pendance symbolique \u2013\u00a0ou ind\u00e9pendance des drapeaux\u00a0\u2013 critiqu\u00e9e par Frantz Fanon (dans\u00a0<i>Les damn\u00e9s de la terre<\/i>, 1961), ce qu\u2019ils veulent, c\u2019est une v\u00e9ritable souverainet\u00e9.<\/p>\n<p>Le livre de Fanon a \u00e9t\u00e9 publi\u00e9 l\u2019ann\u00e9e suivant l\u2019ind\u00e9pendance formelle des pays du Sahel vis-\u00e0-vis de la France en 1960. Mais cette \u00ab\u00a0ind\u00e9pendance\u00a0\u00bb \u00e9tait superficielle. Elle signifiait que ces pays, du S\u00e9n\u00e9gal au Tchad, restaient membres de la Communaut\u00e9 franco-africaine (CFA) et qu\u2019ils autorisaient l\u2019utilisation comme monnaie du franc CFA, \u00e9tabli en France, qu\u2019ils permettaient aux entreprises fran\u00e7aises de garder le contr\u00f4le de leur \u00e9conomie et qu\u2019ils autorisaient les troupes fran\u00e7aises \u00e0 stationner sur leur territoire. En septembre 1958, un r\u00e9f\u00e9rendum constitutionnel avait \u00e9t\u00e9 organis\u00e9 dans les colonies fran\u00e7aises du Sahel. Seule la Guin\u00e9e avait vot\u00e9 contre la proposition d\u2019\u00ab\u00a0ind\u00e9pendance\u00a0\u00bb de la domination coloniale directe de la France dans le cadre du CFA n\u00e9ocolonial fran\u00e7ais. Ceux qui ont fait campagne contre l\u2019adh\u00e9sion au CFA et qui ont obtenu une ind\u00e9pendance r\u00e9elle ont \u00e9t\u00e9 confront\u00e9es \u00e0 la r\u00e9pression de l\u2019establishment politique et militaire de Charles de Gaulle.<\/p>\n<div class=\"single-post--content--media-block single-post--content--image\">\n<div id=\"attachment_115869\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-115869 size-large img-responsive\" src=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-1-1024x682.jpg\" sizes=\"(max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-1-1024x682.jpg 1024w, https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-1-300x200.jpg 300w, https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-1-768x512.jpg 768w, https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-1.jpg 1280w\" alt=\"\" width=\"1024\" height=\"682\" aria-describedby=\"caption-attachment-115869\" \/><\/p>\n<p id=\"caption-attachment-115869\" class=\"wp-caption-text\">Conf\u00e9rence de solidarit\u00e9 avec les peuples du Sahel, Niamey, Niger. Photographie de Pedro Stropasolas pour\u00a0<i>Peoples Dispatch<\/i>.<\/p>\n<\/div>\n<\/div>\n<p>Djibo Bakary (1922-1998), chef du parti de l\u2019Union des forces populaires pour la d\u00e9mocratie et le progr\u00e8s \u2013 Sawaba (Lib\u00e9ration) et pr\u00e9sident du Conseil de gouvernement du Niger, a formul\u00e9 le sentiment du peuple \u00e0 la fin des ann\u00e9es 1950 avec son slogan \u00ab\u00a0l\u2019ind\u00e9pendance nationale d\u2019abord, le reste ensuite\u00a0\u00bb. Bakary s\u2019est attach\u00e9 \u00e0 la\u00a0<a href=\"https:\/\/thetricontinental.org\/newsletterissue\/niger-military-intervention\/\">notion<\/a>\u00a0de sawki (\u00ab\u00a0d\u00e9livrance\u00a0\u00bb), qui signifiait non seulement la lib\u00e9ration du colonialisme fran\u00e7ais, mais aussi l\u2019abolition de la pauvret\u00e9 et de la d\u00e9tresse. En mai 1958, l\u2019Union g\u00e9n\u00e9rale des travailleurs d\u2019Afrique noire (UGTAN) s\u2019est r\u00e9unie \u00e0 Cotonou (B\u00e9nin), appelant \u00e0 la suppression compl\u00e8te du syst\u00e8me colonial fran\u00e7ais. En juillet, lors d\u2019une conf\u00e9rence inter-territoriale\u00a0<a href=\"https:\/\/books.openedition.org\/pur\/43580\">tenue<\/a>\u00a0\u00e0 Cotonou, Bakary a propuls\u00e9 cette revendication dans le d\u00e9bat public au Niger et dans tout le Sahel. Lors du congr\u00e8s du parti Sawaba le mois suivant, en ao\u00fbt, Adamou S\u00e9kou a traduit le sentiment contre le d\u00e9sir fran\u00e7ais de domination coloniale autrement\u00a0: \u00ab\u00a0ce sens de notre dignit\u00e9 d\u2019homme que trop de nos amis m\u00e9tropolitains ont du mal \u00e0 admettre\u00a0; dignit\u00e9 \u00e0 laquelle nous ne saurons jamais renoncer car l\u2019homme n\u00e9gro-africain veut \u00eatre lui-m\u00eame d\u2019abord\u00a0\u00bb.<\/p>\n<p>A la m\u00eame \u00e9poque, Fanon \u00e9crivait que si les gens n\u2019\u00e9taient pas autoris\u00e9s \u00e0 \u00eatre \u00ab eux-m\u00eames \u00bb ou libres, ils se rebelleraient. \u00ab Les masses commencent \u00e0 bouder \u00bb, indiquait-il dans\u00a0<i>Les damn\u00e9s de la terre<\/i>. Elles se d\u00e9tournent de cette nation dans laquelle on ne leur a pas donn\u00e9 de place et commencent \u00e0 s\u2019en d\u00e9sint\u00e9resser. Fanon \u00e9crivait encore que les faux nationalistes, ou nationalistes du drapeau, mobilisent le peuple avec des mots d\u2019ordre d\u2019ind\u00e9pendance, et pour le reste s\u2019en remettent aux \u00e9v\u00e9nements futurs. Six d\u00e9cennies plus tard, nous sommes au c\u0153ur de ces \u00ab \u00e9v\u00e9nements futurs \u00bb.<\/p>\n<div class=\"single-post--content--media-block single-post--content--image\">\n<div id=\"attachment_115849\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-115849 size-large img-responsive\" src=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-3-1024x682.jpg\" sizes=\"(max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-3-1024x682.jpg 1024w, https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-3-300x200.jpg 300w, https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-3-768x512.jpg 768w, https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-3.jpg 1280w\" alt=\"\" width=\"1024\" height=\"682\" aria-describedby=\"caption-attachment-115849\" \/><\/p>\n<p id=\"caption-attachment-115849\" class=\"wp-caption-text\">Conf\u00e9rence de solidarit\u00e9 avec les peuples du Sahel, Niamey, Niger. Photographie de Pedro Stropasolas pour\u00a0<i>Peoples Dispatch<\/i>.<\/p>\n<\/div>\n<\/div>\n<p>Du 19 au 21 novembre, des centaines de personnes venues de tout le continent et du monde entier se sont r\u00e9unies \u00e0 Niamey, au Niger, pour la Conf\u00e9rence de solidarit\u00e9 avec les peuples du Sahel. Il s\u2019agissait de la premi\u00e8re conf\u00e9rence de ce type depuis les\u00a0<a href=\"https:\/\/peoplesdispatch.org\/2023\/08\/15\/whats-happening-in-niger-is-far-from-a-typical-coup\/\">coups d\u2019\u00c9tat<\/a>\u00a0militaires qui, au Burkina Faso, au Mali et au Niger, ont renvers\u00e9 les gouvernements li\u00e9s \u00e0 la France, et depuis la\u00a0<a href=\"https:\/\/peoplesdispatch.org\/2023\/09\/21\/is-this-the-end-of-french-neo-colonialism-in-africa\/\">cr\u00e9ation<\/a>, en septembre 2023, de l\u2019Alliance des \u00c9tats du Sahel (AES). La conf\u00e9rence, qui s\u2019est tenue au Centre international de conf\u00e9rence Mahatma Gandhi de Niamey, \u00e9tait coordonn\u00e9e par l\u2019Organisation des peuples d\u2019Afrique de l\u2019Ouest (OPAO), Pan-Africanism Today et l\u2019Assembl\u00e9e internationale des peuples (AIP). Parmi les intervenants figuraient des repr\u00e9sentants du Conseil national pour la sauvegarde de la patrie (CNSP), des organisations populaires de l\u2019AES et d\u2019autres pays du Sahel, de l\u2019Afrique de l\u2019Ouest et du continent, ainsi que des dirigeants politiques d\u2019Am\u00e9rique latine et d\u2019Asie. Ces trois jours ont culmin\u00e9 avec l\u2019adoption de la\u00a0<a href=\"https:\/\/ipa-aip.org\/declarations\/niamey-declaration-solidarity-with-the-peoples-of-the-sahel\/\"><i>D\u00e9claration de Niamey<\/i><\/a>, dont la derni\u00e8re partie m\u00e9rite d\u2019\u00eatre cit\u00e9e\u00a0:<\/p>\n<blockquote>\n<ol>\n<li aria-level=\"1\">Nous saluons les gouvernements issus des r\u00e9cents coups d\u2019\u00c9tat qui ont adopt\u00e9 des mesures patriotiques pour recouvrer leur souverainet\u00e9 politique et \u00e9conomique sur leurs territoires et leurs ressources naturelles. Ces mesures comprennent la r\u00e9siliation des accords n\u00e9ocoloniaux, l\u2019exigence du retrait des forces fran\u00e7aises, am\u00e9ricaines et autres forces \u00e9trang\u00e8res, et la mise en \u0153uvre de plans ambitieux de d\u00e9veloppement souverain.<\/li>\n<li aria-level=\"1\">Nous sommes particuli\u00e8rement encourag\u00e9s par la cr\u00e9ation par ces pays de l\u2019Alliance des \u00c9tats du Sahel. Cette initiative revitalise l\u2019h\u00e9ritage des dirigeants panafricains et repr\u00e9sente une \u00e9tape concr\u00e8te vers une v\u00e9ritable ind\u00e9pendance et une unit\u00e9 panafricaine.<\/li>\n<li aria-level=\"1\">Ces gouvernements b\u00e9n\u00e9ficient actuellement d\u2019un large soutien de la part de leurs citoyens, qui s\u2019impliquent et se mobilisent autour de ces actions r\u00e9volutionnaires. Cette unit\u00e9 est essentielle pour r\u00e9aliser les id\u00e9aux d\u00e9mocratiques et patriotiques et constitue un mod\u00e8le de d\u00e9veloppement ambitieux pour les autres nations africaines.<\/li>\n<\/ol>\n<p>En conclusion, m\u00eame s\u2019il reste encore beaucoup \u00e0 faire pour la lib\u00e9ration totale des \u00c9tats du Sahel, nous sommes optimistes quant au fait que ces gouvernements, en continuant \u00e0 \u00e9couter leur peuple, atteindront leurs objectifs de lib\u00e9ration nationale totale et contribueront \u00e0 l\u2019objectif plus large d\u2019une Afrique unifi\u00e9e et libre \u00bb.<\/p><\/blockquote>\n<div class=\"single-post--content--media-block single-post--content--image\">\n<div id=\"attachment_115859\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-115859 size-large img-responsive\" src=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-2-1024x682.jpg\" sizes=\"(max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-2-1024x682.jpg 1024w, https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-2-300x200.jpg 300w, https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-2-768x512.jpg 768w, https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-2.jpg 1280w\" alt=\"\" width=\"1024\" height=\"682\" aria-describedby=\"caption-attachment-115859\" \/><\/p>\n<p id=\"caption-attachment-115859\" class=\"wp-caption-text\">Conf\u00e9rence de solidarit\u00e9 avec les peuples du Sahel, Niamey, Niger. Photographie de Pedro Stropasolas pour\u00a0<i>Peoples Dispatch<\/i>.<\/p>\n<\/div>\n<\/div>\n<p>En ao\u00fbt 2022, quinze organisations sociales et politiques du Niger se sont regroup\u00e9es pour former le Mouvement M62 (Union sacr\u00e9e pour la sauvegarde de la souverainet\u00e9 et de la dignit\u00e9 du peuple, M62). Elles ont publi\u00e9 une\u00a0<a href=\"https:\/\/lanouvelletribune.info\/2022\/08\/manifestation-prevue-contre-larmee-francaise-au-niger\/\">d\u00e9claration<\/a>\u00a0contre la pr\u00e9sence de la force militaire fran\u00e7aise au Niger, qui a \u00e9t\u00e9 \u00ab chass\u00e9e du Mali et [est] ill\u00e9galement pr\u00e9sente sur notre territoire \u00bb, et ont exig\u00e9 son \u00ab d\u00e9part imm\u00e9diat \u00bb. Le mouvement a demand\u00e9 \u00e0 \u00ab toutes les citoyennes et tous les citoyens de se constituer en comit\u00e9s citoyens pour la dignit\u00e9 \u00bb dans tout le pays. L\u2019un des dirigeants du mouvement, Abdoulaye Seydou, dirige le R\u00e9seau panafricain pour la paix, la d\u00e9mocratie et le d\u00e9veloppement, dont le bureau porte le nom du leader burkinab\u00e9 Thomas Sankara (1949-1987). Ce bureau arbore une photo de Fanon avec la citation \u00ab Chaque g\u00e9n\u00e9ration doit, dans une relative opacit\u00e9, affronter sa mission, la remplir ou la trahir \u00bb. \u00c0 l\u2019\u00e9poque, la vision politique g\u00e9n\u00e9rale de Seydou \u00e9tait que la mis\u00e8re du peuple nig\u00e9rien ne pouvait \u00eatre surmont\u00e9e dans le contexte du contr\u00f4le n\u00e9ocolonial fran\u00e7ais. C\u2019est pourquoi le M62 a commenc\u00e9 \u00e0 organiser des manifestations contre la pr\u00e9sence militaire fran\u00e7aise et a organis\u00e9 un festival culturel nocturne \u00e0 Niamey pour renforcer le message de lib\u00e9ration. Ces manifestations ont galvanis\u00e9 l\u2019arm\u00e9e qui s\u2019est oppos\u00e9e \u00e0 l\u2019administration n\u00e9ocoloniale de Mohamed Bazoum et a mis en place un gouvernement dirig\u00e9 par le g\u00e9n\u00e9ral Abdourahamane Tchiani. Ce coup d\u2019\u00c9tat, comme ceux du Burkina Faso et du Mali, a \u00e9t\u00e9 largement c\u00e9l\u00e9br\u00e9 dans le pays pour avoir ouvert la porte \u00e0 ce que Fanon avait appel\u00e9 les \u00ab \u00e9v\u00e9nements futurs \u00bb.<\/p>\n<p>Lors de la conf\u00e9rence de solidarit\u00e9 en novembre, Souleymane Falmata Taya, une dirigeante du mouvement M62, a\u00a0<a href=\"https:\/\/peoplesdispatch.org\/2024\/11\/24\/people-of-sahel-inspire-global-movement-against-imperialism\/\">d\u00e9clar\u00e9<\/a>\u00a0que la lutte au Niger n\u2019\u00e9tait pas men\u00e9e par les militaires, mais par les jeunes et les femmes. Elle a ajout\u00e9 \u00ab\u00a0Tout ce que nous voulons, c\u2019est \u00eatre trait\u00e9s comme des \u00eatres humains\u00a0\u00bb. Quelques mois plus t\u00f4t, elle avait\u00a0<a href=\"https:\/\/www.facebook.com\/watch\/?v=842549048020555\">d\u00e9clar\u00e9<\/a>\u00a0que le peuple nig\u00e9rien appr\u00e9ciait les progr\u00e8s r\u00e9alis\u00e9s par le gouvernement du Premier ministre Ali Lamine Zeine, ancien ministre des finances, mais que le peuple devait \u00eatre vigilant et le gouvernement transparent.<\/p>\n<div class=\"single-post--content--media-block single-post--content--image\">\n<div id=\"attachment_115839\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-115839 size-large img-responsive\" src=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-4-1024x682.jpg\" sizes=\"(max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-4-1024x682.jpg 1024w, https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-4-300x200.jpg 300w, https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-4-768x512.jpg 768w, https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/Conference-in-Solidarity-with-the-Peoples-of-the-Sahel-Niamey-Niger.-Photograph-by-Pedro-Stropasolas-for-Peoples-Dispatch.-4.jpg 1280w\" alt=\"\" width=\"1024\" height=\"682\" aria-describedby=\"caption-attachment-115839\" \/><\/p>\n<p id=\"caption-attachment-115839\" class=\"wp-caption-text\">Conf\u00e9rence de solidarit\u00e9 avec les peuples du Sahel, Niamey, Niger. Photographie de Pedro Stropasolas pour\u00a0<i>Peoples Dispatch<\/i>.<\/p>\n<\/div>\n<\/div>\n<p>En 1991, d\u2019anciens leaders \u00e9tudiants de gauche ont form\u00e9 l\u2019Organisation r\u00e9volutionnaire pour la d\u00e9mocratie nouvelle-Tarmouwa (\u00ab\u00a0\u00e9toile\u00a0\u00bb en haoussa) ou ORDN-Tarmouwa. Cette organisation politique a jou\u00e9 un r\u00f4le fondamental dans les mouvements de masse contre la structure n\u00e9ocoloniale fran\u00e7aise et les gouvernements parasites qui l\u2019ont soutenue. Mamane Sani Adamou, l\u2019un des fondateurs de l\u2019ORDN-Tarmouwa, a\u00a0<a href=\"https:\/\/peoplesdispatch.org\/2024\/11\/19\/the-anti-imperialist-upsurge-in-the-sahel-is-irreversible-say-leaders-at-historic-conference-in-niamey\/\">qualifi\u00e9<\/a>\u00a0la p\u00e9riode r\u00e9cente de second r\u00e9veil pour le peuple nig\u00e9rien\u00a0: \u00ab\u00a0Nous vivons une r\u00e9volution patriotique, une lutte pour une seconde ind\u00e9pendance. Le peuple nig\u00e9rien a besoin de souverainet\u00e9 sur son syst\u00e8me mon\u00e9taire, sur sa production alimentaire et sur son programme \u00e9conomique global. Nous devons adopter une nouvelle strat\u00e9gie. La diff\u00e9rence aujourd\u2019hui, c\u2019est que nous d\u00e9cidons par nous-m\u00eames. Nous ne recevons plus d\u2019instructions de Paris. Nous recevons des instructions de chez nous\u00a0\u00bb.<\/p>\n<p>Le mot fondamental au Sahel est la souverainet\u00e9. Si un pays d\u00e9pendant comme le S\u00e9n\u00e9gal ou le Niger lutte pour sa souverainet\u00e9, et s\u2019il essaie de la renforcer, il devra certainement se d\u00e9faire des tentacules de la structure n\u00e9ocoloniale. Il ne peut y avoir de souverainet\u00e9 avec la structure n\u00e9ocoloniale en place. \u00c0 ce stade, l\u2019intervention imp\u00e9rialiste est in\u00e9vitable. Il reste \u00e0 voir comment les d\u00e9fenseurs de la souverainet\u00e9 feront face \u00e0 une attaque imp\u00e9rialiste brutale. Lorsque les Fran\u00e7ais ont tent\u00e9\u00a0<a href=\"https:\/\/peoplesdispatch.org\/2024\/07\/08\/the-sahel-stands-up-and-the-world-must-pay-attention\/\">d\u2019intervenir<\/a>\u00a0contre ces coups d\u2019\u00c9tat militaires populaires par l\u2019interm\u00e9diaire des forces militaires de la Communaut\u00e9 \u00e9conomique des \u00c9tats de l\u2019Afrique de l\u2019Ouest (CEDEAO) en 2023, cette menace n\u2019a fait qu\u2019acc\u00e9l\u00e9rer l\u2019int\u00e9gration du Burkina Faso, du Mali et du Niger dans l\u2019AES. Le premier test a \u00e9t\u00e9 pass\u00e9 avec succ\u00e8s par les gouvernements populaires putschistes, qui ont refus\u00e9 de se soumettre \u00e0 une intervention imp\u00e9rialiste. L\u2019escalade de la revendication de souverainet\u00e9 \u00e0 travers une lutte contre le syst\u00e8me imp\u00e9rialiste, comme le demandent l\u2019ORDN-Tarmouwa et le M62, obligera n\u00e9cessairement ces gouvernements \u00e0 approfondir leur engagement dans la r\u00e9solution des probl\u00e8mes sociaux.<\/p>\n<p>Les \u00ab\u00a0\u00e9v\u00e9nements futurs\u00a0\u00bb de Fanon sont aujourd\u2019hui notre pr\u00e9sent. Il en va de m\u00eame de l\u2019attente d\u2019Adamou S\u00e9kou du Sawaba, qui\u00a0<a href=\"https:\/\/books.openedition.org\/pur\/43580\">d\u00e9clarait<\/a>\u00a0en 1958\u00a0: \u00ab\u00a0De T\u00e9ra \u00e0 N\u2019guigmi, le refrain de l\u2019ind\u00e9pendance doit avoir ses \u00e9chos dans chaque village\u2026\u00a0\u00bb. L\u2019ind\u00e9pendance, disait-il, \u00ab\u00a0c\u2019est la fin du colonialisme retardataire, avec son \u00e9conomie de traite, ses spoliations, ses injustices sociales, c\u2019est la fin du calcul des valeurs bas\u00e9 sur la pigmentation des hommes, c\u2019est la fin des pr\u00e9jug\u00e9s, c\u2019est la r\u00e9surrection de notre race\u00a0\u00bb.<\/p>\n<p>Chaleureusement,<\/p>\n<p><a href=\"https:\/\/thetricontinental.org\/?s=prashad\">Vijay<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que le Tchad et le S\u00e9n\u00e9gal rejoignent le Burkina Faso, le Mali et le Niger pour exiger le retrait des militaires&hellip;<\/p>\n","protected":false},"author":50,"featured_media":112255,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[39,49],"tags":[],"class_list":["post-112254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-en-vedette","category-politique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La France doit partir d\u2019Afrique est le slogan du moment - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La France doit partir d\u2019Afrique est le slogan du moment - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Alors que le Tchad et le S\u00e9n\u00e9gal rejoignent le Burkina Faso, le Mali et le Niger pour exiger le retrait des militaires&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-20T11:44:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-20T11:45:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/jh-51.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hope Jzr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hope Jzr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\\\/\"},\"author\":{\"name\":\"Hope Jzr\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\"},\"headline\":\"La France doit partir d\u2019Afrique est le slogan du moment\",\"datePublished\":\"2024-12-20T11:44:03+00:00\",\"dateModified\":\"2024-12-20T11:45:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\\\/\"},\"wordCount\":2086,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/jh-51.jpg\",\"articleSection\":[\"Articles en vedette\",\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\\\/\",\"name\":\"La France doit partir d\u2019Afrique est le slogan du moment - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/jh-51.jpg\",\"datePublished\":\"2024-12-20T11:44:03+00:00\",\"dateModified\":\"2024-12-20T11:45:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/jh-51.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/jh-51.jpg\",\"width\":500,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La France doit partir d\u2019Afrique est le slogan du moment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\",\"name\":\"Hope Jzr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"caption\":\"Hope Jzr\"},\"description\":\"\u00c0 propos de Hope&amp;ChaDia Hope&amp;ChaDia n\u2019est pas un pseudonyme, mais une m\u00e9thode de travail. Hope : l\u2019id\u00e9e, l\u2019esprit, la structure, la vision. C\u2019est l\u2019impulsion humaine qui choisit l\u2019angle, trace la ligne \u00e9ditoriale et donne le sens. ChaDia : l\u2019assistante, qui met en forme, d\u00e9veloppe, affine le style et v\u00e9rifie les faits. Une aide technologique qui amplifie mais ne cr\u00e9e pas. Ensemble, Hope&amp;ChaDia produisent des textes hybrides : profond\u00e9ment humains dans leur inspiration, rigoureux et pr\u00e9cis dans leur r\u00e9alisation. . . SUPPORTEZ JAZAIRHOPE ET FAITES CONNA\u00ceTRE LE PATRIMOINE ET L\u2019HISTOIRE DE L\u2019ALG\u00c9RIE, EN ACHETANT LE LIVRE DE JAZAIRHOPE POUR VOUS OU POUR L\u2019OFFRIR A VOS PROCHES, ICI : https:\\\/\\\/jazairhope.org\\\/fr\\\/ebook\\\/ CEUX EN ALG\u00c9RIE ET CEUX QUI PEUVENT PAS L\u2019ACHETER ON OFFRE UNE COPIE DIGITALE GRATUITE, POUR CELA ENVOYEZ UN EMAIL \u00c0 : INFO@JAZAIRHOPE.ORG\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/hope-jazair\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La France doit partir d\u2019Afrique est le slogan du moment - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/","og_locale":"fr_FR","og_type":"article","og_title":"La France doit partir d\u2019Afrique est le slogan du moment - AAH.JZR","og_description":"Alors que le Tchad et le S\u00e9n\u00e9gal rejoignent le Burkina Faso, le Mali et le Niger pour exiger le retrait des militaires&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2024-12-20T11:44:03+00:00","article_modified_time":"2024-12-20T11:45:10+00:00","og_image":[{"width":500,"height":350,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/jh-51.jpg","type":"image\/jpeg"}],"author":"Hope Jzr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Hope Jzr","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/"},"author":{"name":"Hope Jzr","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d"},"headline":"La France doit partir d\u2019Afrique est le slogan du moment","datePublished":"2024-12-20T11:44:03+00:00","dateModified":"2024-12-20T11:45:10+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/"},"wordCount":2086,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/jh-51.jpg","articleSection":["Articles en vedette","Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/","url":"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/","name":"La France doit partir d\u2019Afrique est le slogan du moment - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/jh-51.jpg","datePublished":"2024-12-20T11:44:03+00:00","dateModified":"2024-12-20T11:45:10+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/jh-51.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2024\/12\/jh-51.jpg","width":500,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/la-france-doit-partir-dafrique-est-le-slogan-du-moment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"La France doit partir d\u2019Afrique est le slogan du moment"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d","name":"Hope Jzr","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","caption":"Hope Jzr"},"description":"\u00c0 propos de Hope&amp;ChaDia Hope&amp;ChaDia n\u2019est pas un pseudonyme, mais une m\u00e9thode de travail. Hope : l\u2019id\u00e9e, l\u2019esprit, la structure, la vision. C\u2019est l\u2019impulsion humaine qui choisit l\u2019angle, trace la ligne \u00e9ditoriale et donne le sens. ChaDia : l\u2019assistante, qui met en forme, d\u00e9veloppe, affine le style et v\u00e9rifie les faits. Une aide technologique qui amplifie mais ne cr\u00e9e pas. Ensemble, Hope&amp;ChaDia produisent des textes hybrides : profond\u00e9ment humains dans leur inspiration, rigoureux et pr\u00e9cis dans leur r\u00e9alisation. . . SUPPORTEZ JAZAIRHOPE ET FAITES CONNA\u00ceTRE LE PATRIMOINE ET L\u2019HISTOIRE DE L\u2019ALG\u00c9RIE, EN ACHETANT LE LIVRE DE JAZAIRHOPE POUR VOUS OU POUR L\u2019OFFRIR A VOS PROCHES, ICI : https:\/\/jazairhope.org\/fr\/ebook\/ CEUX EN ALG\u00c9RIE ET CEUX QUI PEUVENT PAS L\u2019ACHETER ON OFFRE UNE COPIE DIGITALE GRATUITE, POUR CELA ENVOYEZ UN EMAIL \u00c0 : INFO@JAZAIRHOPE.ORG","url":"https:\/\/jazairhope.org\/fr\/author\/hope-jazair\/"}]}},"views":280,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/112254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=112254"}],"version-history":[{"count":2,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/112254\/revisions"}],"predecessor-version":[{"id":112310,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/112254\/revisions\/112310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/112255"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=112254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=112254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=112254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}