{"id":113186,"date":"2025-01-15T17:59:15","date_gmt":"2025-01-15T16:59:15","guid":{"rendered":"https:\/\/jazairhope.org\/?p=113186"},"modified":"2025-01-15T18:01:27","modified_gmt":"2025-01-15T17:01:27","slug":"nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/","title":{"rendered":"Nouvelles du 15 janvier 2025 : S\u00e9lection comment\u00e9e du G\u00e9n\u00e9ral Delawarde"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"113186\" class=\"elementor elementor-113186\">\n\t\t\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-44eb8563 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44eb8563\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36b5d5b8\" data-id=\"36b5d5b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-544c0815 elementor-widget elementor-widget-text-editor\" data-id=\"544c0815\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>\u00c9conomie : Entre tensions et records<\/h3><p>L\u2019\u00e9conomie internationale continue de susciter des d\u00e9bats passionn\u00e9s. Parmi les interventions remarqu\u00e9es, celle de Marc Touati, qui s\u2019interroge sur la possibilit\u00e9 que la France engendre une nouvelle crise financi\u00e8re. Son analyse, \u00e0 travers une vid\u00e9o hebdomadaire, met en \u00e9vidence les fragilit\u00e9s structurelles de l\u2019\u00e9conomie fran\u00e7aise (<a href=\"https:\/\/www.youtube.com\/watch?v=1oJphTVFuCQ\">Lien<\/a>).<\/p><p>Parall\u00e8lement, Philippe B\u00e9chade critique le gouvernement Bayrou dans une vid\u00e9o g\u00e9opolitique, \u00e9voquant un manque de vision pour stabiliser l\u2019\u00e9conomie fran\u00e7aise (<a href=\"https:\/\/youtu.be\/v0FbFqYT0EQ?t=25\">Lien<\/a>).<\/p><p>Sur la sc\u00e8ne internationale, la Russie et la Chine battent des records commerciaux, atteignant 245 milliards de dollars d\u2019\u00e9changes en 2024 (<a href=\"https:\/\/tass.com\/economy\/1898227\">Lien<\/a>). Quant au FMI, ses pr\u00e9visions pour 2025-2030, pr\u00e9vues le 17 janvier, sont scrut\u00e9es avec scepticisme pour leur complaisance suppos\u00e9e envers les \u00e9conomies occidentales (<a href=\"https:\/\/www.imf.org\/en\/Publications\/WEO\/Issues\/2025\/01\/17\/world-economic-outlook-update-january-2025\">Lien<\/a>).<\/p><h3>\u00a0<\/h3><h3>G\u00e9opolitique : Une Europe en \u00e9bullition<\/h3><p>Les \u00e9lections allemandes du 23 f\u00e9vrier pourraient transformer l\u2019Union europ\u00e9enne. Le duo eurosceptique Weidel-Wagenknecht gagne en popularit\u00e9, promettant de relancer le gazoduc Nord Stream en cas de victoire (<a href=\"https:\/\/francais.rt.com\/international\/116022-allemagne-nous-remettrons-nord-stream\">Lien<\/a>). En Autriche, le parti FP\u00d6 est mandat\u00e9 pour former un gouvernement, un revers pour les partisans des sanctions contre Moscou (<a href=\"https:\/\/edition.francesoir.fr\/politique-monde\/autriche-kickl-s-invite-au-nez-et-la-barbe-de-l-ue-le-fpo-parti-oppose-l-aide-kiev\">Lien<\/a>).<\/p><p>En France, Emmanuel Macron atteint des sommets d\u2019impopularit\u00e9, son soutien \u00e0 l\u2019Ukraine et son impact sur l\u2019\u00e9conomie agricole \u00e9tant tr\u00e8s critiqu\u00e9s (<a href=\"https:\/\/francais.rt.com\/france\/116031-france-emmanuel-macron-deux-doigts\">Lien<\/a>).<\/p><h3>\u00a0<\/h3><h3>Moyen-Orient : Une crise humanitaire sans pr\u00e9c\u00e9dent<\/h3><p>En Palestine, les pertes humaines depuis le d\u00e9but du conflit en octobre 2023 sont d\u00e9vastatrices : 47 490 morts, dont pr\u00e8s de 17 666 enfants. Les estimations indirectes, incluant famines et \u00e9pid\u00e9mies, portent ce bilan \u00e0 plus de 237 500 victimes (<a>Lien<\/a>).<\/p><p>L\u2019ONU rapporte que pr\u00e8s de 70 % des victimes \u00e0 Gaza sont des femmes et des enfants (<a href=\"https:\/\/peacekeeping.un.org\/fr\/pres-de-70-des-victimes-de-la-guerre-gaza-sont-des-femmes-et-des-enfants-onu\">Lien<\/a>). Ces chiffres soulignent l\u2019ampleur de la trag\u00e9die, souvent occult\u00e9e par les m\u00e9dias occidentaux.<\/p><h3>\u00a0<\/h3><h3>Gouvernance : Des fractures soci\u00e9tales<\/h3><p>La crise sanitaire continue de diviser. Virginie Joron, d\u00e9put\u00e9e europ\u00e9enne, d\u00e9nonce les manipulations autour des vaccins et la d\u00e9fiance croissante envers les institutions de sant\u00e9 (<a href=\"https:\/\/www.youtube.com\/watch?v=zKe83ZPkN6M\">Lien<\/a>).<\/p><p>Sur un autre front, le wokisme est critiqu\u00e9 comme un mal ancr\u00e9 au sein des \u00e9lites, d\u00e9connect\u00e9es des r\u00e9alit\u00e9s populaires. Cl\u00e9mence Houdiakova explore les tensions entre m\u00e9dias alternatifs et mainstream, pr\u00e9voyant un r\u00f4le crucial des premi\u00e8res lors des \u00e9lections de 2027 (<a href=\"https:\/\/www.youtube.com\/watch?v=k_jtVg7Qrs4\">Lien<\/a>).<\/p><h3>\u00a0<\/h3><h3>Perspectives<\/h3><p>Cette synth\u00e8se des actualit\u00e9s illustre des d\u00e9fis multiples, de la stabilit\u00e9 \u00e9conomique aux fractures g\u00e9opolitiques et soci\u00e9tales. Entre \u00e9mergence des souverainistes en Europe, records commerciaux sino-russes, et la crise humanitaire en Palestine, le monde semble \u00e0 la croise\u00e9e des chemins.<\/p><p><strong>Pour une analyse plus approfondie, n\u2019h\u00e9sitez pas \u00e0 consulter les sources mentionn\u00e9es.<\/strong><\/p><p>\u00a0<\/p><p><em><strong>Hope&amp;ChaDia<\/strong><\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c9conomie : Entre tensions et records L\u2019\u00e9conomie internationale continue de susciter des d\u00e9bats passionn\u00e9s. Parmi les interventions remarqu\u00e9es, celle de Marc Touati,&hellip;<\/p>\n","protected":false},"author":50,"featured_media":113102,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[39,49],"tags":[],"class_list":["post-113186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-en-vedette","category-politique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouvelles du 15 janvier 2025 : S\u00e9lection comment\u00e9e du G\u00e9n\u00e9ral Delawarde - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelles du 15 janvier 2025 : S\u00e9lection comment\u00e9e du G\u00e9n\u00e9ral Delawarde - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"\u00c9conomie : Entre tensions et records L\u2019\u00e9conomie internationale continue de susciter des d\u00e9bats passionn\u00e9s. Parmi les interventions remarqu\u00e9es, celle de Marc Touati,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-15T16:59:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-15T17:01:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/01\/jh-27.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hope Jzr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hope Jzr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\\\/\"},\"author\":{\"name\":\"Hope Jzr\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\"},\"headline\":\"Nouvelles du 15 janvier 2025 : S\u00e9lection comment\u00e9e du G\u00e9n\u00e9ral Delawarde\",\"datePublished\":\"2025-01-15T16:59:15+00:00\",\"dateModified\":\"2025-01-15T17:01:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\\\/\"},\"wordCount\":460,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/jh-27.jpg\",\"articleSection\":[\"Articles en vedette\",\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\\\/\",\"name\":\"Nouvelles du 15 janvier 2025 : S\u00e9lection comment\u00e9e du G\u00e9n\u00e9ral Delawarde - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/jh-27.jpg\",\"datePublished\":\"2025-01-15T16:59:15+00:00\",\"dateModified\":\"2025-01-15T17:01:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/jh-27.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/jh-27.jpg\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles du 15 janvier 2025 : S\u00e9lection comment\u00e9e du G\u00e9n\u00e9ral Delawarde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\",\"name\":\"Hope Jzr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"caption\":\"Hope Jzr\"},\"description\":\"\u00c0 propos de Hope&amp;ChaDia Hope&amp;ChaDia n\u2019est pas un pseudonyme, mais une m\u00e9thode de travail. Hope : l\u2019id\u00e9e, l\u2019esprit, la structure, la vision. C\u2019est l\u2019impulsion humaine qui choisit l\u2019angle, trace la ligne \u00e9ditoriale et donne le sens. ChaDia : l\u2019assistante, qui met en forme, d\u00e9veloppe, affine le style et v\u00e9rifie les faits. Une aide technologique qui amplifie mais ne cr\u00e9e pas. Ensemble, Hope&amp;ChaDia produisent des textes hybrides : profond\u00e9ment humains dans leur inspiration, rigoureux et pr\u00e9cis dans leur r\u00e9alisation. . . SUPPORTEZ JAZAIRHOPE ET FAITES CONNA\u00ceTRE LE PATRIMOINE ET L\u2019HISTOIRE DE L\u2019ALG\u00c9RIE, EN ACHETANT LE LIVRE DE JAZAIRHOPE POUR VOUS OU POUR L\u2019OFFRIR A VOS PROCHES, ICI : https:\\\/\\\/jazairhope.org\\\/fr\\\/ebook\\\/ CEUX EN ALG\u00c9RIE ET CEUX QUI PEUVENT PAS L\u2019ACHETER ON OFFRE UNE COPIE DIGITALE GRATUITE, POUR CELA ENVOYEZ UN EMAIL \u00c0 : INFO@JAZAIRHOPE.ORG\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/hope-jazair\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvelles du 15 janvier 2025 : S\u00e9lection comment\u00e9e du G\u00e9n\u00e9ral Delawarde - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvelles du 15 janvier 2025 : S\u00e9lection comment\u00e9e du G\u00e9n\u00e9ral Delawarde - AAH.JZR","og_description":"\u00c9conomie : Entre tensions et records L\u2019\u00e9conomie internationale continue de susciter des d\u00e9bats passionn\u00e9s. Parmi les interventions remarqu\u00e9es, celle de Marc Touati,&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2025-01-15T16:59:15+00:00","article_modified_time":"2025-01-15T17:01:27+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/01\/jh-27.jpg","type":"image\/jpeg"}],"author":"Hope Jzr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Hope Jzr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/"},"author":{"name":"Hope Jzr","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d"},"headline":"Nouvelles du 15 janvier 2025 : S\u00e9lection comment\u00e9e du G\u00e9n\u00e9ral Delawarde","datePublished":"2025-01-15T16:59:15+00:00","dateModified":"2025-01-15T17:01:27+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/"},"wordCount":460,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/01\/jh-27.jpg","articleSection":["Articles en vedette","Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/","url":"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/","name":"Nouvelles du 15 janvier 2025 : S\u00e9lection comment\u00e9e du G\u00e9n\u00e9ral Delawarde - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/01\/jh-27.jpg","datePublished":"2025-01-15T16:59:15+00:00","dateModified":"2025-01-15T17:01:27+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/01\/jh-27.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/01\/jh-27.jpg","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-15-janvier-2025-selection-commentee-du-general-delawarde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles du 15 janvier 2025 : S\u00e9lection comment\u00e9e du G\u00e9n\u00e9ral Delawarde"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d","name":"Hope Jzr","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","caption":"Hope Jzr"},"description":"\u00c0 propos de Hope&amp;ChaDia Hope&amp;ChaDia n\u2019est pas un pseudonyme, mais une m\u00e9thode de travail. Hope : l\u2019id\u00e9e, l\u2019esprit, la structure, la vision. C\u2019est l\u2019impulsion humaine qui choisit l\u2019angle, trace la ligne \u00e9ditoriale et donne le sens. ChaDia : l\u2019assistante, qui met en forme, d\u00e9veloppe, affine le style et v\u00e9rifie les faits. Une aide technologique qui amplifie mais ne cr\u00e9e pas. Ensemble, Hope&amp;ChaDia produisent des textes hybrides : profond\u00e9ment humains dans leur inspiration, rigoureux et pr\u00e9cis dans leur r\u00e9alisation. . . SUPPORTEZ JAZAIRHOPE ET FAITES CONNA\u00ceTRE LE PATRIMOINE ET L\u2019HISTOIRE DE L\u2019ALG\u00c9RIE, EN ACHETANT LE LIVRE DE JAZAIRHOPE POUR VOUS OU POUR L\u2019OFFRIR A VOS PROCHES, ICI : https:\/\/jazairhope.org\/fr\/ebook\/ CEUX EN ALG\u00c9RIE ET CEUX QUI PEUVENT PAS L\u2019ACHETER ON OFFRE UNE COPIE DIGITALE GRATUITE, POUR CELA ENVOYEZ UN EMAIL \u00c0 : INFO@JAZAIRHOPE.ORG","url":"https:\/\/jazairhope.org\/fr\/author\/hope-jazair\/"}]}},"views":195,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/113186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=113186"}],"version-history":[{"count":5,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/113186\/revisions"}],"predecessor-version":[{"id":113191,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/113186\/revisions\/113191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/113102"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=113186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=113186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=113186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}