{"id":113381,"date":"2025-01-22T00:33:04","date_gmt":"2025-01-21T23:33:04","guid":{"rendered":"https:\/\/jazairhope.org\/?p=113381"},"modified":"2025-01-22T00:35:02","modified_gmt":"2025-01-21T23:35:02","slug":"nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/","title":{"rendered":"Nouvelles du Jour : S\u00e9lection comment\u00e9e de l&#8217;actualit\u00e9 par le G\u00e9n\u00e9ral Delaward"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"113381\" class=\"elementor elementor-113381\">\n\t\t\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-698e2bad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"698e2bad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61f74f89\" data-id=\"61f74f89\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32144245 elementor-widget elementor-widget-text-editor\" data-id=\"32144245\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex max-w-full flex-col flex-grow\"><div class=\"min-h-8 text-message flex w-full flex-col items-end gap-2 whitespace-normal break-words text-start [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"3b28d5f7-944c-4db4-8126-7a830b26065b\" data-message-model-slug=\"gpt-4o\"><div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\"><div class=\"markdown prose w-full break-words dark:prose-invert light\"><p>Voici une s\u00e9lection des actualit\u00e9s les plus marquantes du 22 janvier 2025, accompagn\u00e9es d&#8217;une r\u00e9flexion critique :<\/p><h4>\u00a0<\/h4><h4>\u00c9conomie : Perspectives mondiales et analyses expertes<\/h4><ol><li><strong>Marc Touati explore l&#8217;avenir \u00e9conomique<\/strong><br \/>Dans sa vid\u00e9o hebdomadaire, Marc Touati s&#8217;interroge sur l&#8217;\u00e9volution des \u00e9conomies fran\u00e7aise, am\u00e9ricaine et argentine en 2025. Une analyse pertinente pour comprendre les grands mouvements \u00e9conomiques mondiaux. <a href=\"https:\/\/www.youtube.com\/watch?v=CToStHHMH_0\" target=\"_new\" rel=\"noopener\">Regardez ici<\/a>.<\/li><li><strong>Investiture de Trump et impact g\u00e9opolitique<\/strong><br \/>Philippe B\u00e9chade, r\u00e9dacteur de \u00abLa Chronique Agora\u00bb, examine les cons\u00e9quences pour les investisseurs europ\u00e9ens de l&#8217;investiture de Donald Trump. Les choix \u00e9conomiques am\u00e9ricains pourraient red\u00e9finir les dynamiques globales. <a href=\"https:\/\/www.youtube.com\/watch?v=ZCuQItx8A_E\" target=\"_new\" rel=\"noopener\">Lien vers la vid\u00e9o<\/a>.<\/li><li><strong>L&#8217;\u00e9conomie russe sous la loupe<\/strong><br \/>Jacques Sapir d\u00e9voile la r\u00e9silience de l&#8217;\u00e9conomie russe face aux sanctions. Une perspective essentielle alors que l&#8217;\u00e9conomie reste un levier d\u00e9cisif dans le conflit Ukraine-Russie. <a href=\"https:\/\/www.youtube.com\/watch?v=VyZ_cYOqX6c\" target=\"_new\" rel=\"noopener\">\u00c9coutez l&#8217;interview<\/a>.<\/li><\/ol><h4>\u00a0<\/h4><h4>G\u00e9opolitique g\u00e9n\u00e9rale : Tensions et apaisements<\/h4><ol><li><strong>Donald Trump frappe fort d\u00e8s son investiture<\/strong><br \/>Trump a sign\u00e9 200 ordres ex\u00e9cutifs d\u00e8s son arriv\u00e9e au pouvoir, un record historique. Parmi eux, l&#8217;annulation de 78 d\u00e9cisions prises par son pr\u00e9d\u00e9cesseur. Cette avalanche de mesures montre sa volont\u00e9 de remodeler rapidement les \u00c9tats-Unis, avec des impacts mondiaux. <a href=\"https:\/\/odysee.com\/@jido.antaiji:7\/Discours-dinvestiture-de-Turmp-double%CC%81-en-franc%CC%A7ais:9\" target=\"_new\" rel=\"noopener\">Regardez le discours doubl\u00e9 en fran\u00e7ais<\/a>.<\/li><li><strong>Appel \u00e0 la paix en Slovaquie<\/strong><br \/>Le Premier ministre Robert Fico a exhort\u00e9 les puissances \u00e0 mettre fin au conflit ukrainien. Une initiative qui souligne le besoin urgent d&#8217;une diplomatie proactive. <a href=\"https:\/\/www.youtube.com\/watch?v=Ch4Y1_3gar4\" target=\"_new\" rel=\"noopener\">Lien vers l&#8217;appel<\/a>.<\/li><\/ol><h4>\u00a0<\/h4><h4>Proche et Moyen-Orient : Le bilan d&#8217;une guerre d\u00e9vastatrice<\/h4><ol><li><strong>Cessez-le-feu entre Isra\u00ebl et le Hamas<\/strong><br \/>Apr\u00e8s 15 mois de violence, un cessez-le-feu a \u00e9t\u00e9 \u00e9tabli. Cependant, les divisions au sein du gouvernement isra\u00e9lien montrent la fragilit\u00e9 de cet accord. <a href=\"https:\/\/www.tsa-algerie.com\/gaza-le-cessez-le-feu-entre-en-vigueur-apres-un-bilan-effroyable\/\" target=\"_new\" rel=\"noopener\">D\u00e9tails ici<\/a>.<\/li><li><strong>Bilan humain catastrophique en Palestine<\/strong><br \/>Depuis octobre 2023, les pertes palestiniennes s&#8217;\u00e9l\u00e8vent \u00e0 pr\u00e8s de 238 900 morts, y compris les effets indirects. Les femmes et enfants constituent 70 % des victimes, une r\u00e9alit\u00e9 effrayante document\u00e9e par plusieurs organisations. <a href=\"https:\/\/www.thelancet.com\/journals\/lancet\/article\/PIIS0140-6736(24)02678-3\/fulltext\" target=\"_new\" rel=\"noopener\">Sources et analyses<\/a>.<\/li><\/ol><h4>\u00a0<\/h4><h4>R\u00e9flexion sur le \u00ab d\u00e9clin \u00bb occidental<\/h4><p>Un exode progressif des talents et citoyens vers des destinations per\u00e7ues comme plus accueillantes refl\u00e8te une perte d&#8217;attrait pour l&#8217;Occident traditionnel. <a href=\"https:\/\/www.youtube.com\/watch?v=vd2XKvfBLVw\" target=\"_new\" rel=\"noopener\">T\u00e9moignage ici<\/a>.<\/p><p>\u00a0<\/p><p>Cette s\u00e9lection met en lumi\u00e8re des enjeux \u00e9conomiques, politiques et humains d&#8217;une grande complexit\u00e9. Elle invite \u00e0 une lecture critique et \u00e0 un engagement inform\u00e9 dans le monde qui nous entoure.<\/p><p>\u00a0<\/p><p><strong>Hope&amp;ChaDia<\/strong><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Voici une s\u00e9lection des actualit\u00e9s les plus marquantes du 22 janvier 2025, accompagn\u00e9es d&#8217;une r\u00e9flexion critique : \u00a0 \u00c9conomie : Perspectives mondiales&hellip;<\/p>\n","protected":false},"author":50,"featured_media":113102,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[39,35,49],"tags":[],"class_list":["post-113381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-en-vedette","category-economie","category-politique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouvelles du Jour : S\u00e9lection comment\u00e9e de l&#039;actualit\u00e9 par le G\u00e9n\u00e9ral Delaward - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelles du Jour : S\u00e9lection comment\u00e9e de l&#039;actualit\u00e9 par le G\u00e9n\u00e9ral Delaward - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Voici une s\u00e9lection des actualit\u00e9s les plus marquantes du 22 janvier 2025, accompagn\u00e9es d&#8217;une r\u00e9flexion critique : \u00a0 \u00c9conomie : Perspectives mondiales&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-21T23:33:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-21T23:35:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/01\/jh-27.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hope Jzr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hope Jzr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\\\/\"},\"author\":{\"name\":\"Hope Jzr\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\"},\"headline\":\"Nouvelles du Jour : S\u00e9lection comment\u00e9e de l&#8217;actualit\u00e9 par le G\u00e9n\u00e9ral Delaward\",\"datePublished\":\"2025-01-21T23:33:04+00:00\",\"dateModified\":\"2025-01-21T23:35:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\\\/\"},\"wordCount\":424,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/jh-27.jpg\",\"articleSection\":[\"Articles en vedette\",\"\u00c9conomie\",\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\\\/\",\"name\":\"Nouvelles du Jour : S\u00e9lection comment\u00e9e de l'actualit\u00e9 par le G\u00e9n\u00e9ral Delaward - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/jh-27.jpg\",\"datePublished\":\"2025-01-21T23:33:04+00:00\",\"dateModified\":\"2025-01-21T23:35:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/jh-27.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/jh-27.jpg\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles du Jour : S\u00e9lection comment\u00e9e de l&#8217;actualit\u00e9 par le G\u00e9n\u00e9ral Delaward\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\",\"name\":\"Hope Jzr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"caption\":\"Hope Jzr\"},\"description\":\"\u00c0 propos de Hope&amp;ChaDia Hope&amp;ChaDia n\u2019est pas un pseudonyme, mais une m\u00e9thode de travail. Hope : l\u2019id\u00e9e, l\u2019esprit, la structure, la vision. C\u2019est l\u2019impulsion humaine qui choisit l\u2019angle, trace la ligne \u00e9ditoriale et donne le sens. ChaDia : l\u2019assistante, qui met en forme, d\u00e9veloppe, affine le style et v\u00e9rifie les faits. Une aide technologique qui amplifie mais ne cr\u00e9e pas. Ensemble, Hope&amp;ChaDia produisent des textes hybrides : profond\u00e9ment humains dans leur inspiration, rigoureux et pr\u00e9cis dans leur r\u00e9alisation. . . SUPPORTEZ JAZAIRHOPE ET FAITES CONNA\u00ceTRE LE PATRIMOINE ET L\u2019HISTOIRE DE L\u2019ALG\u00c9RIE, EN ACHETANT LE LIVRE DE JAZAIRHOPE POUR VOUS OU POUR L\u2019OFFRIR A VOS PROCHES, ICI : https:\\\/\\\/jazairhope.org\\\/fr\\\/ebook\\\/ CEUX EN ALG\u00c9RIE ET CEUX QUI PEUVENT PAS L\u2019ACHETER ON OFFRE UNE COPIE DIGITALE GRATUITE, POUR CELA ENVOYEZ UN EMAIL \u00c0 : INFO@JAZAIRHOPE.ORG\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/hope-jazair\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvelles du Jour : S\u00e9lection comment\u00e9e de l'actualit\u00e9 par le G\u00e9n\u00e9ral Delaward - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvelles du Jour : S\u00e9lection comment\u00e9e de l'actualit\u00e9 par le G\u00e9n\u00e9ral Delaward - AAH.JZR","og_description":"Voici une s\u00e9lection des actualit\u00e9s les plus marquantes du 22 janvier 2025, accompagn\u00e9es d&#8217;une r\u00e9flexion critique : \u00a0 \u00c9conomie : Perspectives mondiales&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2025-01-21T23:33:04+00:00","article_modified_time":"2025-01-21T23:35:02+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/01\/jh-27.jpg","type":"image\/jpeg"}],"author":"Hope Jzr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Hope Jzr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/"},"author":{"name":"Hope Jzr","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d"},"headline":"Nouvelles du Jour : S\u00e9lection comment\u00e9e de l&#8217;actualit\u00e9 par le G\u00e9n\u00e9ral Delaward","datePublished":"2025-01-21T23:33:04+00:00","dateModified":"2025-01-21T23:35:02+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/"},"wordCount":424,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/01\/jh-27.jpg","articleSection":["Articles en vedette","\u00c9conomie","Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/","url":"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/","name":"Nouvelles du Jour : S\u00e9lection comment\u00e9e de l'actualit\u00e9 par le G\u00e9n\u00e9ral Delaward - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/01\/jh-27.jpg","datePublished":"2025-01-21T23:33:04+00:00","dateModified":"2025-01-21T23:35:02+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/01\/jh-27.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/01\/jh-27.jpg","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/nouvelles-du-jour-selection-commentee-de-lactualite-par-le-general-delaward\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles du Jour : S\u00e9lection comment\u00e9e de l&#8217;actualit\u00e9 par le G\u00e9n\u00e9ral Delaward"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d","name":"Hope Jzr","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","caption":"Hope Jzr"},"description":"\u00c0 propos de Hope&amp;ChaDia Hope&amp;ChaDia n\u2019est pas un pseudonyme, mais une m\u00e9thode de travail. Hope : l\u2019id\u00e9e, l\u2019esprit, la structure, la vision. C\u2019est l\u2019impulsion humaine qui choisit l\u2019angle, trace la ligne \u00e9ditoriale et donne le sens. ChaDia : l\u2019assistante, qui met en forme, d\u00e9veloppe, affine le style et v\u00e9rifie les faits. Une aide technologique qui amplifie mais ne cr\u00e9e pas. Ensemble, Hope&amp;ChaDia produisent des textes hybrides : profond\u00e9ment humains dans leur inspiration, rigoureux et pr\u00e9cis dans leur r\u00e9alisation. . . SUPPORTEZ JAZAIRHOPE ET FAITES CONNA\u00ceTRE LE PATRIMOINE ET L\u2019HISTOIRE DE L\u2019ALG\u00c9RIE, EN ACHETANT LE LIVRE DE JAZAIRHOPE POUR VOUS OU POUR L\u2019OFFRIR A VOS PROCHES, ICI : https:\/\/jazairhope.org\/fr\/ebook\/ CEUX EN ALG\u00c9RIE ET CEUX QUI PEUVENT PAS L\u2019ACHETER ON OFFRE UNE COPIE DIGITALE GRATUITE, POUR CELA ENVOYEZ UN EMAIL \u00c0 : INFO@JAZAIRHOPE.ORG","url":"https:\/\/jazairhope.org\/fr\/author\/hope-jazair\/"}]}},"views":286,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/113381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=113381"}],"version-history":[{"count":5,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/113381\/revisions"}],"predecessor-version":[{"id":113386,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/113381\/revisions\/113386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/113102"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=113381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=113381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=113381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}