{"id":113949,"date":"2025-03-13T01:15:54","date_gmt":"2025-03-13T00:15:54","guid":{"rendered":"https:\/\/jazairhope.org\/?p=113949"},"modified":"2025-03-13T01:15:54","modified_gmt":"2025-03-13T00:15:54","slug":"la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/","title":{"rendered":"La France et ses relents coloniaux : Gallimard, la l\u00e9gion \u00e9trang\u00e8re des lettres et les combats d&#8217;arri\u00e8re-garde"},"content":{"rendered":"<p>Gallimard et la l\u00e9gion \u00e9trang\u00e8re du nouveau r\u00e9giment des harkis, le bras arm\u00e9 de l&#8217;extr\u00eame droite fran\u00e7aise.<br \/>\nGallimard a \u00e9t\u00e9 actionn\u00e9 par la gouvernance coloniale de la France pour sauver le soldat Sansal.<br \/>\nC&#8217;est ainsi que cette maison d&#8217;\u00e9dition subversive, recrutant dans le courant des r\u00e9giments de harkis, de la l\u00e9gion \u00e9trang\u00e8re de la plume, nouvellement naturalis\u00e9s pour services rendus, a d\u00e9cid\u00e9 d&#8217;organiser de grandes manifestations publiques pour faire accr\u00e9diter la th\u00e8se d&#8217;une arrestation arbitraire de Sansal par les autorit\u00e9s alg\u00e9riennes, violant les droits de l&#8217;homme et les libert\u00e9s individuelles.<\/p>\n<p>On se souvient de ce d\u00eener \u00e0 l&#8217;ambassade de France \u00e0 Alger, lors de la derni\u00e8re visite de Macron en Alg\u00e9rie.<br \/>\n\u00c0 cette table cossue, il y avait notamment Sansal et Daoud, qui &#8220;ont suppli\u00e9 Macron de les d\u00e9fendre parce qu&#8217;ils \u00e9taient les d\u00e9fenseurs des int\u00e9r\u00eats de la France en Alg\u00e9rie&#8221;. Propos divulgu\u00e9s par Driencourt lors de ses d\u00e9clarations \u00e0 la presse fran\u00e7aise.<br \/>\nVous avez maintenant compris pourquoi Macron ne parle jamais des 1648 Fran\u00e7ais emprisonn\u00e9s dans d&#8217;autres pays et que personne ne se mobilise pour eux.<\/p>\n<p>\u00c0 travers Sansal et Daoud, Macron d\u00e9fend la bo\u00eete noire des tra\u00eetres de la France en Alg\u00e9rie, qui a permis de transf\u00e9rer illicitement vers la France des milliards de dollars.<br \/>\nTous ces combats d&#8217;arri\u00e8re-garde de la France, fond\u00e9s exclusivement sur un acharnement raciste et haineux, sont vou\u00e9s \u00e0 l&#8217;\u00e9chec, comme celui de Retailleau qui ne fait pas la diff\u00e9rence entre un migrant en situation l\u00e9gale et un migrant en situation ill\u00e9gale, lui ayant valu plusieurs camouflets judiciaires qui l&#8217;ont d\u00e9bout\u00e9 pour non-fondement d&#8217;une d\u00e9cision administrative.<\/p>\n<p>Sansal a d\u00e9cid\u00e9 de cong\u00e9dier tous ses avocats alg\u00e9riens ou fran\u00e7ais pour assurer sa propre d\u00e9fense.<br \/>\nL&#8217;avocat de Sansal, Me Fran\u00e7ois Zimeray, a d\u00e9cid\u00e9 de passer outre la volont\u00e9 de Sansal et de continuer \u00e0 \u00eatre l&#8217;avocat de celui-ci, en d\u00e9cidant de saisir l&#8217;ONU, accusant l&#8217;\u00c9tat alg\u00e9rien de d\u00e9tenir Sansal de mani\u00e8re arbitraire.<br \/>\nCe que nous pouvons dire \u00e0 cet avocat sioniste, c&#8217;est que celui-ci d\u00e9nie \u00e0 la justice alg\u00e9rienne la capacit\u00e9 de juger un ressortissant alg\u00e9rien coupable de crime contre l&#8217;int\u00e9grit\u00e9 territoriale.<br \/>\nSi les autorit\u00e9s alg\u00e9riennes ont refus\u00e9 \u00e0 cet avocat d&#8217;entrer sur le territoire national, cela est de bon droit, tout \u00e0 fait l\u00e9gal, relevant de la souverainet\u00e9 exclusive de l&#8217;\u00c9tat.<\/p>\n<p>La France vient d&#8217;interdire \u00e0 des Alg\u00e9riens, d\u00e9tenteurs d&#8217;un passeport diplomatique, d&#8217;entrer sur le territoire fran\u00e7ais, dans le m\u00e9pris des accords bilat\u00e9raux et conventions internationales.<br \/>\nMe Fran\u00e7ois Zimeray doit bien m\u00e9diter cela pour comprendre que l&#8217;Alg\u00e9rie peut aussi interdire \u00e0 tout Fran\u00e7ais ind\u00e9sirable d&#8217;entrer sur le territoire national.<br \/>\nSansal a \u00e9t\u00e9 arr\u00eat\u00e9 sur le territoire national pour de graves infractions, et cela constitue une affaire int\u00e9rieure qui ne concerne pas la France, m\u00eame si celui-ci est binational, conform\u00e9ment au principe de la comp\u00e9tence territoriale.<br \/>\nFran\u00e7ois Zimeray ne peut invoquer la d\u00e9fense d&#8217;un client pour entrer par la force sur le territoire d&#8217;un autre \u00c9tat, qui est le seul \u00e0 d\u00e9cider qui doit entrer sur son territoire.<\/p>\n<p>Gallimard, le prix Goncourt et ses laur\u00e9ats, des soldats de la subversion, a mis en rang de bataille les vendus, comme Sansal, Daoud, Ferhat Mhenni et bien d&#8217;autres, pour faire la guerre \u00e0 l&#8217;Alg\u00e9rie.<br \/>\nDe grands dossiers doivent \u00eatre rendus publics par l&#8217;Alg\u00e9rie, notamment celui des armes chimiques utilis\u00e9es par la France contre les populations civiles alg\u00e9riennes.<\/p>\n<p>Le temps des fanfaronnades de la France coloniale est termin\u00e9, et l&#8217;Alg\u00e9rie ne doit plus h\u00e9siter un seul instant pour d\u00e9terrer l&#8217;artillerie lourde et aller, d&#8217;un pas ferme, devant l&#8217;ONU et ester, concomitamment, l&#8217;\u00c9tat fran\u00e7ais devant le Tribunal p\u00e9nal international pour g\u00e9nocide et crimes de guerre.<br \/>\nLe temps de la repentance, de la reconnaissance et des excuses est pass\u00e9, et le temps de la justice internationale est arriv\u00e9 pour sanctionner cette France coloniale criminelle.<\/p>\n<p>Source : <a href=\"https:\/\/www.facebook.com\/share\/p\/1Bb2x46tqE\/\">Mr Hacen Kacimi<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gallimard et la l\u00e9gion \u00e9trang\u00e8re du nouveau r\u00e9giment des harkis, le bras arm\u00e9 de l&#8217;extr\u00eame droite fran\u00e7aise. Gallimard a \u00e9t\u00e9 actionn\u00e9 par&hellip;<\/p>\n","protected":false},"author":50,"featured_media":113950,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[39,49],"tags":[],"class_list":["post-113949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-en-vedette","category-politique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La France et ses relents coloniaux : Gallimard, la l\u00e9gion \u00e9trang\u00e8re des lettres et les combats d&#039;arri\u00e8re-garde - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La France et ses relents coloniaux : Gallimard, la l\u00e9gion \u00e9trang\u00e8re des lettres et les combats d&#039;arri\u00e8re-garde - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Gallimard et la l\u00e9gion \u00e9trang\u00e8re du nouveau r\u00e9giment des harkis, le bras arm\u00e9 de l&#8217;extr\u00eame droite fran\u00e7aise. Gallimard a \u00e9t\u00e9 actionn\u00e9 par&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-13T00:15:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/03\/jh-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"479\" \/>\n\t<meta property=\"og:image:height\" content=\"303\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hope Jzr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hope Jzr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\\\/\"},\"author\":{\"name\":\"Hope Jzr\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\"},\"headline\":\"La France et ses relents coloniaux : Gallimard, la l\u00e9gion \u00e9trang\u00e8re des lettres et les combats d&#8217;arri\u00e8re-garde\",\"datePublished\":\"2025-03-13T00:15:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\\\/\"},\"wordCount\":755,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/jh-5.jpg\",\"articleSection\":[\"Articles en vedette\",\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\\\/\",\"name\":\"La France et ses relents coloniaux : Gallimard, la l\u00e9gion \u00e9trang\u00e8re des lettres et les combats d'arri\u00e8re-garde - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/jh-5.jpg\",\"datePublished\":\"2025-03-13T00:15:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/jh-5.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/jh-5.jpg\",\"width\":479,\"height\":303},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La France et ses relents coloniaux : Gallimard, la l\u00e9gion \u00e9trang\u00e8re des lettres et les combats d&#8217;arri\u00e8re-garde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\",\"name\":\"Hope Jzr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"caption\":\"Hope Jzr\"},\"description\":\"\u00c0 propos de Hope&amp;ChaDia Hope&amp;ChaDia n\u2019est pas un pseudonyme, mais une m\u00e9thode de travail. Hope : l\u2019id\u00e9e, l\u2019esprit, la structure, la vision. C\u2019est l\u2019impulsion humaine qui choisit l\u2019angle, trace la ligne \u00e9ditoriale et donne le sens. ChaDia : l\u2019assistante, qui met en forme, d\u00e9veloppe, affine le style et v\u00e9rifie les faits. Une aide technologique qui amplifie mais ne cr\u00e9e pas. Ensemble, Hope&amp;ChaDia produisent des textes hybrides : profond\u00e9ment humains dans leur inspiration, rigoureux et pr\u00e9cis dans leur r\u00e9alisation. . . SUPPORTEZ JAZAIRHOPE ET FAITES CONNA\u00ceTRE LE PATRIMOINE ET L\u2019HISTOIRE DE L\u2019ALG\u00c9RIE, EN ACHETANT LE LIVRE DE JAZAIRHOPE POUR VOUS OU POUR L\u2019OFFRIR A VOS PROCHES, ICI : https:\\\/\\\/jazairhope.org\\\/fr\\\/ebook\\\/ CEUX EN ALG\u00c9RIE ET CEUX QUI PEUVENT PAS L\u2019ACHETER ON OFFRE UNE COPIE DIGITALE GRATUITE, POUR CELA ENVOYEZ UN EMAIL \u00c0 : INFO@JAZAIRHOPE.ORG\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/hope-jazair\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La France et ses relents coloniaux : Gallimard, la l\u00e9gion \u00e9trang\u00e8re des lettres et les combats d'arri\u00e8re-garde - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/","og_locale":"fr_FR","og_type":"article","og_title":"La France et ses relents coloniaux : Gallimard, la l\u00e9gion \u00e9trang\u00e8re des lettres et les combats d'arri\u00e8re-garde - AAH.JZR","og_description":"Gallimard et la l\u00e9gion \u00e9trang\u00e8re du nouveau r\u00e9giment des harkis, le bras arm\u00e9 de l&#8217;extr\u00eame droite fran\u00e7aise. Gallimard a \u00e9t\u00e9 actionn\u00e9 par&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2025-03-13T00:15:54+00:00","og_image":[{"width":479,"height":303,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/03\/jh-5.jpg","type":"image\/jpeg"}],"author":"Hope Jzr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Hope Jzr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/"},"author":{"name":"Hope Jzr","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d"},"headline":"La France et ses relents coloniaux : Gallimard, la l\u00e9gion \u00e9trang\u00e8re des lettres et les combats d&#8217;arri\u00e8re-garde","datePublished":"2025-03-13T00:15:54+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/"},"wordCount":755,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/03\/jh-5.jpg","articleSection":["Articles en vedette","Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/","url":"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/","name":"La France et ses relents coloniaux : Gallimard, la l\u00e9gion \u00e9trang\u00e8re des lettres et les combats d'arri\u00e8re-garde - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/03\/jh-5.jpg","datePublished":"2025-03-13T00:15:54+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/03\/jh-5.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/03\/jh-5.jpg","width":479,"height":303},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/la-france-et-ses-relents-coloniaux-gallimard-la-legion-etrangere-des-lettres-et-les-combats-darriere-garde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"La France et ses relents coloniaux : Gallimard, la l\u00e9gion \u00e9trang\u00e8re des lettres et les combats d&#8217;arri\u00e8re-garde"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d","name":"Hope Jzr","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","caption":"Hope Jzr"},"description":"\u00c0 propos de Hope&amp;ChaDia Hope&amp;ChaDia n\u2019est pas un pseudonyme, mais une m\u00e9thode de travail. Hope : l\u2019id\u00e9e, l\u2019esprit, la structure, la vision. C\u2019est l\u2019impulsion humaine qui choisit l\u2019angle, trace la ligne \u00e9ditoriale et donne le sens. ChaDia : l\u2019assistante, qui met en forme, d\u00e9veloppe, affine le style et v\u00e9rifie les faits. Une aide technologique qui amplifie mais ne cr\u00e9e pas. Ensemble, Hope&amp;ChaDia produisent des textes hybrides : profond\u00e9ment humains dans leur inspiration, rigoureux et pr\u00e9cis dans leur r\u00e9alisation. . . SUPPORTEZ JAZAIRHOPE ET FAITES CONNA\u00ceTRE LE PATRIMOINE ET L\u2019HISTOIRE DE L\u2019ALG\u00c9RIE, EN ACHETANT LE LIVRE DE JAZAIRHOPE POUR VOUS OU POUR L\u2019OFFRIR A VOS PROCHES, ICI : https:\/\/jazairhope.org\/fr\/ebook\/ CEUX EN ALG\u00c9RIE ET CEUX QUI PEUVENT PAS L\u2019ACHETER ON OFFRE UNE COPIE DIGITALE GRATUITE, POUR CELA ENVOYEZ UN EMAIL \u00c0 : INFO@JAZAIRHOPE.ORG","url":"https:\/\/jazairhope.org\/fr\/author\/hope-jazair\/"}]}},"views":315,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/113949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=113949"}],"version-history":[{"count":1,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/113949\/revisions"}],"predecessor-version":[{"id":113953,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/113949\/revisions\/113953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/113950"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=113949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=113949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=113949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}