{"id":115913,"date":"2025-06-18T13:50:32","date_gmt":"2025-06-18T12:50:32","guid":{"rendered":"https:\/\/jazairhope.org\/?p=115913"},"modified":"2025-06-18T13:50:32","modified_gmt":"2025-06-18T12:50:32","slug":"en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/","title":{"rendered":"En Isra\u00ebl tout le monde n&#8217;est pas sioniste, mais le sionisme y est, \u00e7a suffit pour vivre avec autant de haine et de frustration ?"},"content":{"rendered":"<p>Certains intellectuels juifs reconnaissent aujourd\u2019hui que c\u2019\u00e9tait une \u00e9norme erreur d\u2019accorder \u00e0 l\u2019id\u00e9ologie sioniste un territoire vol\u00e9 par les colons aux palestiniens et que cet Etat n\u2019avait aucun droit \u00e0 l\u2019existence, pas plus que les T\u00e9moins de J\u00e9hovah ou les v\u00e9g\u00e9tariens n\u2019ont leur pays. L\u2019essentiel de la population juive vivait en paix \u00e0 travers le monde aujourd\u2019hui dans l\u2019\u00e9tat sioniste d\u2019Isra\u00ebl c\u2019est une soci\u00e9t\u00e9 divis\u00e9e et in\u00e9galitaire qui souffre d\u2019\u00eatre assimil\u00e9e \u00e0 cette bande de supr\u00e9macistes et fanatiques.<\/p>\n<p>La population Isra\u00e9lienne sioniste soutient massivement ce que fait le gouvernement, elle est donc comptable des cons\u00e9quences de cette politique meurtri\u00e8re et envahissante pour plus de 70 ann\u00e9es de colonisation d\u2019un r\u00e9gime d\u00e9bile, tr\u00e8s certainement il est bien le temps pour le monde d\u2019aujourd\u2019hui de se\u00a0 \u00a0d\u00e9barrasser de ces malades mentaux<\/p>\n<p>Ce qui est comique Netanyahou avait foment\u00e9 un plan diabolique d&#8217;\u00e9limination des habitants de Gaza qu&#8217;il souhaite ne plus les voir ni en Cisjordanie ni \u00e0 Gaza, alors il avait bien aim\u00e9 d\u2019aller jusqu\u2019\u00e0 la capitulation finale et compl\u00e8te de l&#8217;ennemi, pareillement les nazis\u00a0 ont tout fait pour appliquer ce pr\u00e9cepte a la lettre, ainsi il est permis au monde de constater que l\u2019Etat h\u00e9breu de Netanyahou <strong>\u00a0<\/strong>se livre \u00e0 une op\u00e9ration de nettoyage ethnique dont le caract\u00e8re g\u00e9nocidaire sans pr\u00e9c\u00e9dent au d\u00e9triment des Palestiniens ne fait plus de doute. Chaque jour, des hommes, des femmes, des enfants, des vieillards sont massacr\u00e9s par l\u2019arm\u00e9e isra\u00e9lienne. La guerre est, pour Netanyahou, l&#8217;occasion de poursuivre ses op\u00e9rations g\u00e9nocidaires avec la d\u00e9portation et son objectif poursuivi est clair: \u00e9radiquer de sa terre le peuple DE Gaza.<\/p>\n<p>C&#8217;est que Netanyahou est un gagne petit, se hisse au niveau des Pol Pot, des Mao, des Staline qui n&#8217;ont jamais manqu\u00e9 d&#8217;encenser de leur vivant et n\u2019avaient pas dans leur charte l&#8217;an\u00e9antissement d&#8217;un autre peuple. Ils \u00e9taient \u00a0agressifs, ils mena\u00e7aient mais n&#8217;en sont pas au stade d\u2019Isra\u00ebl et Netanyahou un composite russo-polonais-lituanien qui se fait passer pour un juif \u00e9ternel<strong> avec <\/strong>\u00a0une tare ineffa\u00e7able:<\/p>\n<p>Donc le Netanyahou \u00a0un sinistre criminel maladive de sa cruaut\u00e9, de son plaisir de la vengeance restera une image d\u2019un Pol Pot, une image d\u2019Hitler dans sa col\u00e8re, une image d\u2019un Staline qui n\u2019admettez jamais ses erreurs apr\u00e8s son slogan \u00a0lanc\u00e9:\u00a0<em>\u00ab Liquidons les koulaks en tant que classe \u00bb<\/em>, d\u2019un L\u00e9opold\u00a0II \u00e9tait le roi de Belgique le Congo \u00e9tait consid\u00e9r\u00e9 comme sa propri\u00e9t\u00e9 personnelle et enfin celui de l\u2019image du tristement c\u00e9l\u00e8bre Henry Kissinger.<\/p>\n<p>Netanyahou en criminel av\u00e9r\u00e9 n\u2019est pas la cons\u00e9quence de l\u2019intervention du 7 Octobre par la r\u00e9sistance palestinienne de mani\u00e8re parfaitement l\u00e9gitime, cependant Netanyahou restera que la cons\u00e9quence de l\u2019occupation isra\u00e9lienne de la Palestine. Bien s\u00fbr, un tel dirigeant qui con\u00e7oit une politique sur la guerre et le g\u00e9nocide, sur la terreur et le mensonge, et enfin sur la pr\u00e9tention \u00e0 cr\u00e9er un\u00a0<em>\u00ab<strong>Grand Isra\u00ebl<\/strong>\u00bb<\/em>\u00a0relevait du d\u00e9lire mental\u00a0de voir que leur indignation s\u00e9lective est un d\u00e9ni de justice, cautionne l\u2019hostilit\u00e9 la plus brutale tant qu\u2019elle est dirig\u00e9e par Isra\u00ebl avec une\u00a0d\u00e9mesur\u00e9e disproportion des ripostes, Isra\u00ebl bombarde un immeuble entier, pour tuer\u00a0 des familles enti\u00e8res, au motif qu\u2019un r\u00e9sistant du Hamas y serait cach\u00e9, et Isra\u00ebl\u00a0 d\u00e9truit un quartier entier en pr\u00e9tendant que s\u2019y dissimule un groupe de combattants ennemis, la soci\u00e9t\u00e9 juive d\u2019Isra\u00ebl ferme les yeux sur les appels aux meurtres, aux incitations \u00e0 la haine, aux id\u00e9ologies th\u00e9ocratiques, aux crimes commis au nom d\u2019un sionisme qui n\u2019est qu\u2019un masque, il s&#8217;agit de haine d\u00e9cha\u00een\u00e9e et de d\u00e9sir de meurtre, qui ne se soucie ni des faits ni de la logique ni de la raison ni de l\u2019histoire. C&#8217;est une haine d\u00e9r\u00e9elle, qui n&#8217;a aucun rapport avec les faits. Et de toute \u00e9vidence, c&#8217;est la forme moderne de la haine.<\/p>\n<p>Le rejet en bloc du Palestinien, sa d\u00e9shumanisation syst\u00e9matique, sa diabolisation obsessionnelle n\u2019ont plus grand-chose \u00e0 voir avec une critique de la colonisation, Il s\u2019agit de nier le droit d\u2019un peuple \u00e0 disposer de lui-m\u00eame. Il s\u2019agit de contester la l\u00e9gitimit\u00e9 m\u00eame de l\u2019existence du Palestinien.<\/p>\n<p>Il nous faudrait bien rappeler que le sionisme radical n\u2019est pas une simple option d\u2019\u00c9tat. C\u2019est un comportement id\u00e9ologique, supr\u00e9matiste, rigide, sourde aux faits, imperm\u00e9able \u00e0 la raison. C\u2019est une tendance haineuse, construite sur une image id\u00e9alis\u00e9e du Juif-victime, toujours plac\u00e9e au centre du dispositif victimaire il ne serait jamais lav\u00e9\u00a0 de ses tares originelles o\u00f9 toute nuance est abolie cette haine est totale, syst\u00e9mique, d\u00e9connect\u00e9e du sentiment humanitaire et cautionn\u00e9e par une l\u2019hostilit\u00e9 la plus brutale tant qu\u2019elle est dirig\u00e9e contre l\u2019ennemie \u00a0qu\u2019un sophisme appel\u00e9 \u00ab <strong><em>argumentum ad personam<\/em><\/strong> \u00bb.<\/p>\n<p>Les dirigeants politiques \u00e0 l\u2019instar de Netanyahou se sont l\u00e2ch\u00e9s et clament ouvertement leur\u00a0haine des Palestiniens, ces \u00ab\u00a0animaux humains\u00a0\u00bb, comme les qualifiait l\u2019ex-ministre de la D\u00e9fense. Sans vergogne, ils ass\u00e8nent leur projet de les \u00e9radiquer de la nouvelle Terre promise \u00e0 laquelle ils aspirent d\u00e9sormais sans complexe. Cela passe par un\u00a0nettoyage ethnique\u00a0assum\u00e9 par le ministre supr\u00e9maciste de la S\u00e9curit\u00e9 int\u00e9rieure, lequel veut que soit mise en \u0153uvre \u00ab\u00a0l\u2019\u00e9migration de centaines de milliers de Palestiniens de Gaza\u00a0\u00bb. Une perspective approuv\u00e9e par le ministre ultrareligieux des Finances\u00a0\u00a0: \u00ab\u00a0<em>Dans quelques mois (&#8230;)\u00a0Gaza sera totalement d\u00e9truite\u00a0\u00bb,\u00a0<\/em><\/p>\n<p>Or, cette exasp\u00e9ration s\u00e9lective, presque hyst\u00e9rique, d\u2019Isra\u00ebl de Netanyahou, trahit une haine obsessionnelle, un besoin g\u00e9nocidaire, aujourd\u2019hui dans la soci\u00e9t\u00e9 Isra\u00e9lienne de culture essentiellement religieuse, plus de 85% de sa population conservent un passeport \u00e9tranger qui leur permettra de quitter \u00e0 tout moment le pays. Isra\u00ebl ne constitue donc pas un \u00c9tat \u00e0 proprement parler et une \u00e9conomie artificielle mais un \u00e9tat militaire faisant fonction d\u2019une base militaire des USA, un satellite de l\u2019Oncle Sam \u00e0 qui il doit tout, m\u00eame les victoires dans les guerres d\u2019Isra\u00ebl.<\/p>\n<p>L\u2019Etat d\u2019Isra\u00ebl terroriste et fanatique, de caract\u00e8re sioniste ne dispose d\u2019aucune constitution, Isra\u00ebl a recouru \u00e0 ce qu\u2019il appelle les \u00abLois fondamentales\u00bb, guid\u00e9es par l\u2019engagement de l\u2019\u00c9tat \u00e0 la supr\u00e9matie raciale pour un apartheid juif isra\u00e9lien Ashk\u00e9naze.<\/p>\n<p>A cela s\u2019ajoute des faits historiques qui rapportent \u00a0nous apprend que ce qui a \u00e9nerve les \u00c9gyptiens les Romains, les \u00a0Babyloniens, les Perses, l\u2019\u00c9glise Catholique et son Juif Perfide, les Musulmans, les Espagnols, les Nazis et les Sovi\u00e9tiques continue \u00e0 \u00e9nerver le monde entier aujourd&#8217;hui, tous ont voulu \u00a0d\u00e9noncer, expulser ou exterminer les Juifs&#8230;<\/p>\n<p>Face \u00e0 des nettoyages ethniques successifs et ces attaques g\u00e9nocidaires inflig\u00e9es, le peuple palestinien est l\u00e9gitimement en droit de r\u00e9sistance \u00e0 l\u2019oppression\u00a0qui reste un des droits naturels et imprescriptibles. Isra\u00ebl n\u2019est nullement en mesure de supporter la critique de sa politique criminelle de Netanyahu qui compte tout de m\u00eame des membres explicitement Kahaniste, h\u00e9ritier d\u2019une formation interdite dans les ann\u00e9es 1980 pour terrorisme,\u00a0qui pr\u00eachent dans \u00a0leur programme depuis des dizaines d\u2019ann\u00e9es, l&#8217;an\u00e9antissement des palestiniens.<\/p>\n<p>Mais Gaza et son peuple nullement dominateur, peuple repoussant les dominations tout simplement sur ce je pense que les natifs de la Palestine historique c&#8217;est-\u00e0-dire le peuple Palestinien a la responsabilit\u00e9 et le devoir de faire clairement le choix de la r\u00e9sistance contre le colonialisme isra\u00e9lien. S\u2019il ne le fait pas, d\u2019autres ne le feront pas \u00e0 sa place sans doute.\u00a0Par ailleurs il faut souligner que certains Juifs profond\u00e9ment religieux, condamnent au nom de leur foi la cr\u00e9ation d\u2019un Etat juif, par suite d\u2019une colonisation de la Palestine en vue de la mise en place d\u2019un \u00ab\u00a0<strong><em>Foyer Juif\u00a0<\/em><\/strong>\u00bb tout en mettant \u00a0\u00e0 l\u2019\u00e9cart du\u00a0 peuple de Palestine et son extermination programm\u00e9e, en toute \u00e9vidence.<\/p>\n<p>Il ne fait aucun doute que la r\u00e9sistance Palestinienne remporte m\u00e9thodiquement, prudemment et avec vigilance la guerre contre l\u2019Isra\u00ebl \u00e0 Gaza. L&#8217;assaut lent, prudent et laborieux men\u00e9 par la r\u00e9sistance des Palestiniens \u00a0est un spectacle \u00e0 ne pas manquer en effet les Isra\u00e9liens sont des nazis, et leur credo est le m\u00eame que les architectes de la &#8220;solution finale\u00bb. Gaza tient bon et le peuple Palestinien se bat \u00e0 fond pour extirper une fois pour toutes les nazis d\u2019Isra\u00ebl.<\/p>\n<p>Les Palestiniens sont ma\u00eetres chez eux et ont le droit de le rester.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Certains intellectuels juifs reconnaissent aujourd\u2019hui que c\u2019\u00e9tait une \u00e9norme erreur d\u2019accorder \u00e0 l\u2019id\u00e9ologie sioniste un territoire vol\u00e9 par les colons aux palestiniens&hellip;<\/p>\n","protected":false},"author":1,"featured_media":115915,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","footnotes":""},"categories":[39,49],"tags":[],"class_list":["post-115913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-en-vedette","category-politique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En Isra\u00ebl tout le monde n&#039;est pas sioniste, mais le sionisme y est, \u00e7a suffit pour vivre avec autant de haine et de frustration ? - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Isra\u00ebl tout le monde n&#039;est pas sioniste, mais le sionisme y est, \u00e7a suffit pour vivre avec autant de haine et de frustration ? - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Certains intellectuels juifs reconnaissent aujourd\u2019hui que c\u2019\u00e9tait une \u00e9norme erreur d\u2019accorder \u00e0 l\u2019id\u00e9ologie sioniste un territoire vol\u00e9 par les colons aux palestiniens&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-18T12:50:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/06\/image_1488922_20250614_ob_b9ff1f_yartimacronisraeliran05-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"523\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ssuperadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ssuperadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\\\/\"},\"author\":{\"name\":\"Ssuperadmin\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/43650ebd889d8960700b5456ed9264c4\"},\"headline\":\"En Isra\u00ebl tout le monde n&#8217;est pas sioniste, mais le sionisme y est, \u00e7a suffit pour vivre avec autant de haine et de frustration ?\",\"datePublished\":\"2025-06-18T12:50:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\\\/\"},\"wordCount\":1549,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/image_1488922_20250614_ob_b9ff1f_yartimacronisraeliran05-1.jpg\",\"articleSection\":[\"Articles en vedette\",\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\\\/\",\"name\":\"En Isra\u00ebl tout le monde n'est pas sioniste, mais le sionisme y est, \u00e7a suffit pour vivre avec autant de haine et de frustration ? - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/image_1488922_20250614_ob_b9ff1f_yartimacronisraeliran05-1.jpg\",\"datePublished\":\"2025-06-18T12:50:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/43650ebd889d8960700b5456ed9264c4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/image_1488922_20250614_ob_b9ff1f_yartimacronisraeliran05-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/image_1488922_20250614_ob_b9ff1f_yartimacronisraeliran05-1.jpg\",\"width\":640,\"height\":523},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Isra\u00ebl tout le monde n&#8217;est pas sioniste, mais le sionisme y est, \u00e7a suffit pour vivre avec autant de haine et de frustration ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/43650ebd889d8960700b5456ed9264c4\",\"name\":\"Ssuperadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g\",\"caption\":\"Ssuperadmin\"},\"sameAs\":[\"https:\\\/\\\/jazairhope.org\"],\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/superadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Isra\u00ebl tout le monde n'est pas sioniste, mais le sionisme y est, \u00e7a suffit pour vivre avec autant de haine et de frustration ? - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/","og_locale":"fr_FR","og_type":"article","og_title":"En Isra\u00ebl tout le monde n'est pas sioniste, mais le sionisme y est, \u00e7a suffit pour vivre avec autant de haine et de frustration ? - AAH.JZR","og_description":"Certains intellectuels juifs reconnaissent aujourd\u2019hui que c\u2019\u00e9tait une \u00e9norme erreur d\u2019accorder \u00e0 l\u2019id\u00e9ologie sioniste un territoire vol\u00e9 par les colons aux palestiniens&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2025-06-18T12:50:32+00:00","og_image":[{"width":640,"height":523,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/06\/image_1488922_20250614_ob_b9ff1f_yartimacronisraeliran05-1.jpg","type":"image\/jpeg"}],"author":"Ssuperadmin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ssuperadmin","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/"},"author":{"name":"Ssuperadmin","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/43650ebd889d8960700b5456ed9264c4"},"headline":"En Isra\u00ebl tout le monde n&#8217;est pas sioniste, mais le sionisme y est, \u00e7a suffit pour vivre avec autant de haine et de frustration ?","datePublished":"2025-06-18T12:50:32+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/"},"wordCount":1549,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/06\/image_1488922_20250614_ob_b9ff1f_yartimacronisraeliran05-1.jpg","articleSection":["Articles en vedette","Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/","url":"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/","name":"En Isra\u00ebl tout le monde n'est pas sioniste, mais le sionisme y est, \u00e7a suffit pour vivre avec autant de haine et de frustration ? - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/06\/image_1488922_20250614_ob_b9ff1f_yartimacronisraeliran05-1.jpg","datePublished":"2025-06-18T12:50:32+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/43650ebd889d8960700b5456ed9264c4"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/06\/image_1488922_20250614_ob_b9ff1f_yartimacronisraeliran05-1.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/06\/image_1488922_20250614_ob_b9ff1f_yartimacronisraeliran05-1.jpg","width":640,"height":523},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/en-israel-tout-le-monde-nest-pas-sioniste-mais-le-sionisme-y-est-ca-suffit-pour-vivre-avec-autant-de-haine-et-de-frustration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"En Isra\u00ebl tout le monde n&#8217;est pas sioniste, mais le sionisme y est, \u00e7a suffit pour vivre avec autant de haine et de frustration ?"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/43650ebd889d8960700b5456ed9264c4","name":"Ssuperadmin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g","caption":"Ssuperadmin"},"sameAs":["https:\/\/jazairhope.org"],"url":"https:\/\/jazairhope.org\/fr\/author\/superadmin\/"}]}},"views":475,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/115913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=115913"}],"version-history":[{"count":1,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/115913\/revisions"}],"predecessor-version":[{"id":115914,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/115913\/revisions\/115914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/115915"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=115913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=115913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=115913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}