{"id":117220,"date":"2025-11-11T13:28:00","date_gmt":"2025-11-11T12:28:00","guid":{"rendered":"https:\/\/jazairhope.org\/?p=117220"},"modified":"2025-11-11T15:33:02","modified_gmt":"2025-11-11T14:33:02","slug":"quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/","title":{"rendered":"QUAND BERLIN VEUT QU\u2019ALGER GRACIE CE QU\u2019ELLE-M\u00caME POURSUIT \u2014 LE PARADOXE DES FRONTI\u00c8RES ET DES MOTS"},"content":{"rendered":"<p data-start=\"106\" data-end=\"130\">Lettre ouverte \u00e0 Monsieur Frank-Walter Steinmeier, Pr\u00e9sident de la R\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne<\/p>\n<p>Monsieur le Pr\u00e9sident,<\/p>\n<p data-start=\"132\" data-end=\"601\">Votre r\u00e9cente d\u00e9marche aupr\u00e8s du pr\u00e9sident Abdelmadjid Tebboune, sollicitant une gr\u00e2ce humanitaire pour l\u2019\u00e9crivain Boualem Sansal, a \u00e9t\u00e9 rendue publique par la Pr\u00e9sidence de la R\u00e9publique alg\u00e9rienne. Ce geste, pr\u00e9sent\u00e9 comme humanitaire, intervient alors que M. Sansal a \u00e9t\u00e9 condamn\u00e9 \u00e0 cinq ans de prison pour avoir remis en cause les fronti\u00e8res internationalement reconnues de l\u2019Alg\u00e9rie, affirmant qu\u2019une partie de son territoire appartenait historiquement au Maroc.<\/p>\n<p data-start=\"603\" data-end=\"1780\">Avant de revenir \u00e0 ce cas, il est utile de rappeler deux affaires r\u00e9centes survenues dans votre propre pays.<br data-start=\"711\" data-end=\"714\" \/>En ao\u00fbt 2024, la justice allemande a condamn\u00e9 la citoyenne <strong data-start=\"773\" data-end=\"788\">Ava Moayeri<\/strong>, \u00e9tudiante de 22 ans, \u00e0 une amende pour avoir scand\u00e9 le slogan <em data-start=\"852\" data-end=\"907\">\u00ab From the river to the sea, Palestine will be free \u00bb<\/em> lors d\u2019une manifestation \u00e0 Berlin. Ce slogan, rappelons-le, se r\u00e9f\u00e8re \u00e0 un territoire <strong data-start=\"994\" data-end=\"1038\">dont les fronti\u00e8res ne sont pas d\u00e9finies<\/strong> par le droit international et dont le statut reste en litige devant les Nations Unies.<br data-start=\"1125\" data-end=\"1128\" \/>Et quelques semaines plus t\u00f4t, en mai 2024, une autre \u00e9tudiante, <strong data-start=\"1193\" data-end=\"1205\">Alina T.<\/strong>, avait vu son domicile perquisitionn\u00e9 par le LKA et le SEK pour avoir publi\u00e9 le m\u00eame slogan sur son compte Facebook. Elle a \u00e9t\u00e9 plac\u00e9e sous enqu\u00eate pour usage de symboles anticonstitutionnels, en vertu d\u2019une directive du minist\u00e8re f\u00e9d\u00e9ral de l\u2019Int\u00e9rieur assimilant cette phrase \u00e0 un signe de la Hamas.<\/p>\n<blockquote>\n<h3 data-start=\"106\" data-end=\"186\"><strong data-start=\"113\" data-end=\"186\">Selon la presse allemande, ces affaires ne sont pas isol\u00e9es<\/strong><\/h3>\n<p data-start=\"188\" data-end=\"512\"><a href=\"https:\/\/www.tagesschau.de\/inland\/gesellschaft\/antisemitismus-216.html\">D\u2019apr\u00e8s une enqu\u00eate publi\u00e9e le <strong data-start=\"219\" data-end=\"239\">1\u1d49\u02b3 juillet 2024<\/strong> par <strong data-start=\"244\" data-end=\"270\">l\u2019ARD Hauptstadtstudio<\/strong><\/a> (service politique de la t\u00e9l\u00e9vision publique allemande), les poursuites li\u00e9es au slogan <em data-start=\"359\" data-end=\"414\">\u00ab From the river to the sea, Palestine will be free \u00bb<\/em> concernent <strong data-start=\"426\" data-end=\"476\">des centaines, voire des milliers de personnes<\/strong> en Allemagne depuis octobre 2023.<\/p>\n<p data-start=\"514\" data-end=\"585\">L\u2019article cite <strong data-start=\"529\" data-end=\"552\">Me Benjamin D\u00fcsberg<\/strong>, avocat au barreau de Berlin :<\/p>\n<p data-start=\"588\" data-end=\"787\"><strong>\u00ab Ce seul slogan a conduit en quelques mois \u00e0 un grand nombre de proc\u00e9dures p\u00e9nales. J\u2019estime qu\u2019il y en a plusieurs centaines, voire plus d\u2019un millier dans tout le pays depuis le 7 octobre 2023. \u00bb<\/strong><\/p>\n<p data-start=\"789\" data-end=\"1080\">Selon le m\u00eame rapport, cette vague d\u2019enqu\u00eates d\u00e9coule d\u2019une <strong data-start=\"849\" data-end=\"914\">directive du minist\u00e8re f\u00e9d\u00e9ral de l\u2019Int\u00e9rieur (novembre 2023)<\/strong> assimilant par d\u00e9faut ce slogan \u00e0 un signe de la Hamas, ce qui a entra\u00een\u00e9 <strong data-start=\"989\" data-end=\"1055\">perquisitions, arrestations et interdictions de rassemblements<\/strong> dans plusieurs L\u00e4nder.<\/p>\n<p data-start=\"1082\" data-end=\"1374\">Le <strong data-start=\"1085\" data-end=\"1118\">tribunal r\u00e9gional de Mannheim<\/strong>, statuant en <strong data-start=\"1132\" data-end=\"1178\">deuxi\u00e8me et derni\u00e8re instance en juin 2024<\/strong>, a toutefois jug\u00e9 que cette expression restait <em data-start=\"1226\" data-end=\"1267\">\u00ab g\u00e9n\u00e9rale et historiquement complexe \u00bb<\/em> et <strong data-start=\"1271\" data-end=\"1309\">ne constituait pas un d\u00e9lit en soi<\/strong>, cr\u00e9ant un <strong data-start=\"1321\" data-end=\"1371\">pr\u00e9c\u00e9dent en faveur de la libert\u00e9 d\u2019expression<\/strong>.<\/p>\n<\/blockquote>\n<p data-start=\"1782\" data-end=\"2391\">Pour m\u00e9moire, <strong data-start=\"1796\" data-end=\"1814\">Boualem Sansal<\/strong>, 76 ans, \u00e9crivain alg\u00e9rien reconnu, ancien haut fonctionnaire, a \u00e9t\u00e9 condamn\u00e9 \u00e0 cinq ans de prison pour avoir remis en cause les fronti\u00e8res reconnues de son pays.<br data-start=\"1977\" data-end=\"1980\" \/>\u00c0 l\u2019inverse, <strong data-start=\"1993\" data-end=\"2008\">Ava Moayeri<\/strong>, 22 ans, \u00e9tudiante allemande sans engagement militant av\u00e9r\u00e9, a \u00e9t\u00e9 condamn\u00e9e pour avoir prononc\u00e9 une phrase relative \u00e0 un territoire aux fronti\u00e8res encore ind\u00e9termin\u00e9es. Et <strong data-start=\"2184\" data-end=\"2196\">Alina T.<\/strong>, \u00e9galement \u00e9tudiante, a subi une perquisition \u00e0 son domicile pour la simple publication du m\u00eame slogan.<\/p>\n<p data-start=\"2393\" data-end=\"2494\">Ainsi, dans un laps de temps tr\u00e8s court, trois affaires ont r\u00e9v\u00e9l\u00e9 un double standard pr\u00e9occupant :<\/p>\n<ul data-start=\"2495\" data-end=\"2841\">\n<li data-start=\"2495\" data-end=\"2635\">\n<p data-start=\"2497\" data-end=\"2635\">D\u2019un c\u00f4t\u00e9, un pr\u00e9sident europ\u00e9en plaide pour la cl\u00e9mence envers un \u00e9crivain condamn\u00e9 pour avoir ni\u00e9 les fronti\u00e8res d\u2019un \u00c9tat souverain ;<\/p>\n<\/li>\n<li data-start=\"2636\" data-end=\"2841\">\n<p data-start=\"2638\" data-end=\"2841\">De l\u2019autre, ce m\u00eame pr\u00e9sident dirige un pays o\u00f9 la justice poursuit, perquisitionne ou condamne des citoyennes pour avoir \u00e9voqu\u00e9 un territoire dont les fronti\u00e8res demeurent juridiquement ind\u00e9termin\u00e9es.<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"2843\" data-end=\"3298\">Ce parall\u00e8le interroge. Il ne s\u2019agit pas d\u2019opposer deux syst\u00e8mes judiciaires ni de hi\u00e9rarchiser les causes, mais de souligner une incoh\u00e9rence fondamentale dans la d\u00e9fense des libert\u00e9s. Lorsqu\u2019un \u00c9tat europ\u00e9en en appelle \u00e0 la tol\u00e9rance \u00e0 l\u2019\u00e9tranger, tout en restreignant chez lui des expressions politiques li\u00e9es \u00e0 une question encore d\u00e9battue par la communaut\u00e9 internationale, il compromet la cr\u00e9dibilit\u00e9 de son propre discours sur les droits humains.<\/p>\n<p data-start=\"3300\" data-end=\"3712\">Monsieur le Pr\u00e9sident,<br data-start=\"3322\" data-end=\"3325\" \/>La libert\u00e9 d\u2019opinion n\u2019a de sens que si elle est d\u00e9fendue partout, sans s\u00e9lectivit\u00e9 g\u00e9opolitique. Si vous consid\u00e9rez que Boualem Sansal m\u00e9rite la gr\u00e2ce au nom de la libert\u00e9 d\u2019expression, alors la m\u00eame logique devrait vous conduire \u00e0 d\u00e9fendre le droit d\u2019Ava Moayeri et d\u2019Alina T. d\u2019exprimer pacifiquement leur opinion sur la Palestine, sans condamnation p\u00e9nale ni intrusion polici\u00e8re.<\/p>\n<p data-start=\"3714\" data-end=\"3874\">Nous esp\u00e9rons que cette r\u00e9flexion contribuera \u00e0 une position plus coh\u00e9rente, fond\u00e9e non sur la sensibilit\u00e9 des alliances, mais sur la constance des principes.<\/p>\n<p data-start=\"3876\" data-end=\"3913\" data-is-last-node=\"\" data-is-only-node=\"\">Respectueusement,<br data-start=\"3893\" data-end=\"3896\" \/><strong data-start=\"3896\" data-end=\"3913\" data-is-last-node=\"\">Hope &amp; ChaDia<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lettre ouverte \u00e0 Monsieur Frank-Walter Steinmeier, Pr\u00e9sident de la R\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne Monsieur le Pr\u00e9sident, Votre r\u00e9cente d\u00e9marche aupr\u00e8s du pr\u00e9sident Abdelmadjid&hellip;<\/p>\n","protected":false},"author":50,"featured_media":117221,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","footnotes":""},"categories":[39,49],"tags":[],"class_list":["post-117220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-en-vedette","category-politique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>QUAND BERLIN VEUT QU\u2019ALGER GRACIE CE QU\u2019ELLE-M\u00caME POURSUIT \u2014 LE PARADOXE DES FRONTI\u00c8RES ET DES MOTS - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QUAND BERLIN VEUT QU\u2019ALGER GRACIE CE QU\u2019ELLE-M\u00caME POURSUIT \u2014 LE PARADOXE DES FRONTI\u00c8RES ET DES MOTS - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Lettre ouverte \u00e0 Monsieur Frank-Walter Steinmeier, Pr\u00e9sident de la R\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne Monsieur le Pr\u00e9sident, Votre r\u00e9cente d\u00e9marche aupr\u00e8s du pr\u00e9sident Abdelmadjid&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-11T12:28:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T14:33:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/11\/featured-37.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hope Jzr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hope Jzr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\\\/\"},\"author\":{\"name\":\"Hope Jzr\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\"},\"headline\":\"QUAND BERLIN VEUT QU\u2019ALGER GRACIE CE QU\u2019ELLE-M\u00caME POURSUIT \u2014 LE PARADOXE DES FRONTI\u00c8RES ET DES MOTS\",\"datePublished\":\"2025-11-11T12:28:00+00:00\",\"dateModified\":\"2025-11-11T14:33:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\\\/\"},\"wordCount\":844,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/featured-37.jpg\",\"articleSection\":[\"Articles en vedette\",\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\\\/\",\"name\":\"QUAND BERLIN VEUT QU\u2019ALGER GRACIE CE QU\u2019ELLE-M\u00caME POURSUIT \u2014 LE PARADOXE DES FRONTI\u00c8RES ET DES MOTS - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/featured-37.jpg\",\"datePublished\":\"2025-11-11T12:28:00+00:00\",\"dateModified\":\"2025-11-11T14:33:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/featured-37.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/featured-37.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"QUAND BERLIN VEUT QU\u2019ALGER GRACIE CE QU\u2019ELLE-M\u00caME POURSUIT \u2014 LE PARADOXE DES FRONTI\u00c8RES ET DES MOTS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\",\"name\":\"Hope Jzr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"caption\":\"Hope Jzr\"},\"description\":\"\u00c0 propos de Hope&amp;ChaDia Hope&amp;ChaDia n\u2019est pas un pseudonyme, mais une m\u00e9thode de travail. Hope : l\u2019id\u00e9e, l\u2019esprit, la structure, la vision. C\u2019est l\u2019impulsion humaine qui choisit l\u2019angle, trace la ligne \u00e9ditoriale et donne le sens. ChaDia : l\u2019assistante, qui met en forme, d\u00e9veloppe, affine le style et v\u00e9rifie les faits. Une aide technologique qui amplifie mais ne cr\u00e9e pas. Ensemble, Hope&amp;ChaDia produisent des textes hybrides : profond\u00e9ment humains dans leur inspiration, rigoureux et pr\u00e9cis dans leur r\u00e9alisation. . . SUPPORTEZ JAZAIRHOPE ET FAITES CONNA\u00ceTRE LE PATRIMOINE ET L\u2019HISTOIRE DE L\u2019ALG\u00c9RIE, EN ACHETANT LE LIVRE DE JAZAIRHOPE POUR VOUS OU POUR L\u2019OFFRIR A VOS PROCHES, ICI : https:\\\/\\\/jazairhope.org\\\/fr\\\/ebook\\\/ CEUX EN ALG\u00c9RIE ET CEUX QUI PEUVENT PAS L\u2019ACHETER ON OFFRE UNE COPIE DIGITALE GRATUITE, POUR CELA ENVOYEZ UN EMAIL \u00c0 : INFO@JAZAIRHOPE.ORG\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/hope-jazair\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QUAND BERLIN VEUT QU\u2019ALGER GRACIE CE QU\u2019ELLE-M\u00caME POURSUIT \u2014 LE PARADOXE DES FRONTI\u00c8RES ET DES MOTS - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/","og_locale":"fr_FR","og_type":"article","og_title":"QUAND BERLIN VEUT QU\u2019ALGER GRACIE CE QU\u2019ELLE-M\u00caME POURSUIT \u2014 LE PARADOXE DES FRONTI\u00c8RES ET DES MOTS - AAH.JZR","og_description":"Lettre ouverte \u00e0 Monsieur Frank-Walter Steinmeier, Pr\u00e9sident de la R\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne Monsieur le Pr\u00e9sident, Votre r\u00e9cente d\u00e9marche aupr\u00e8s du pr\u00e9sident Abdelmadjid&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2025-11-11T12:28:00+00:00","article_modified_time":"2025-11-11T14:33:02+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/11\/featured-37.jpg","type":"image\/jpeg"}],"author":"Hope Jzr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Hope Jzr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/"},"author":{"name":"Hope Jzr","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d"},"headline":"QUAND BERLIN VEUT QU\u2019ALGER GRACIE CE QU\u2019ELLE-M\u00caME POURSUIT \u2014 LE PARADOXE DES FRONTI\u00c8RES ET DES MOTS","datePublished":"2025-11-11T12:28:00+00:00","dateModified":"2025-11-11T14:33:02+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/"},"wordCount":844,"commentCount":1,"image":{"@id":"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/11\/featured-37.jpg","articleSection":["Articles en vedette","Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/","url":"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/","name":"QUAND BERLIN VEUT QU\u2019ALGER GRACIE CE QU\u2019ELLE-M\u00caME POURSUIT \u2014 LE PARADOXE DES FRONTI\u00c8RES ET DES MOTS - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/11\/featured-37.jpg","datePublished":"2025-11-11T12:28:00+00:00","dateModified":"2025-11-11T14:33:02+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/11\/featured-37.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/11\/featured-37.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/quand-berlin-veut-qualger-gracie-ce-quelle-meme-poursuit-le-paradoxe-des-frontieres-et-des-mots\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"QUAND BERLIN VEUT QU\u2019ALGER GRACIE CE QU\u2019ELLE-M\u00caME POURSUIT \u2014 LE PARADOXE DES FRONTI\u00c8RES ET DES MOTS"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d","name":"Hope Jzr","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","caption":"Hope Jzr"},"description":"\u00c0 propos de Hope&amp;ChaDia Hope&amp;ChaDia n\u2019est pas un pseudonyme, mais une m\u00e9thode de travail. Hope : l\u2019id\u00e9e, l\u2019esprit, la structure, la vision. C\u2019est l\u2019impulsion humaine qui choisit l\u2019angle, trace la ligne \u00e9ditoriale et donne le sens. ChaDia : l\u2019assistante, qui met en forme, d\u00e9veloppe, affine le style et v\u00e9rifie les faits. Une aide technologique qui amplifie mais ne cr\u00e9e pas. Ensemble, Hope&amp;ChaDia produisent des textes hybrides : profond\u00e9ment humains dans leur inspiration, rigoureux et pr\u00e9cis dans leur r\u00e9alisation. . . SUPPORTEZ JAZAIRHOPE ET FAITES CONNA\u00ceTRE LE PATRIMOINE ET L\u2019HISTOIRE DE L\u2019ALG\u00c9RIE, EN ACHETANT LE LIVRE DE JAZAIRHOPE POUR VOUS OU POUR L\u2019OFFRIR A VOS PROCHES, ICI : https:\/\/jazairhope.org\/fr\/ebook\/ CEUX EN ALG\u00c9RIE ET CEUX QUI PEUVENT PAS L\u2019ACHETER ON OFFRE UNE COPIE DIGITALE GRATUITE, POUR CELA ENVOYEZ UN EMAIL \u00c0 : INFO@JAZAIRHOPE.ORG","url":"https:\/\/jazairhope.org\/fr\/author\/hope-jazair\/"}]}},"views":462,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/117220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=117220"}],"version-history":[{"count":2,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/117220\/revisions"}],"predecessor-version":[{"id":117225,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/117220\/revisions\/117225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/117221"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=117220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=117220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=117220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}