{"id":117329,"date":"2025-12-11T14:58:41","date_gmt":"2025-12-11T13:58:41","guid":{"rendered":"https:\/\/jazairhope.org\/?p=117329"},"modified":"2025-12-11T14:58:41","modified_gmt":"2025-12-11T13:58:41","slug":"quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/","title":{"rendered":"Quand l\u2019Histoire percute l\u2019actualit\u00e9 : les manifestations alg\u00e9riennes du 11 d\u00e9cembre 1960 \u00e0 Alger. Par Benjamin Stora."},"content":{"rendered":"<p>Quand l\u2019histoire de la guerre d\u2019ind\u00e9pendance alg\u00e9rienne vient percuter l\u2019actualit\u00e9 r\u00e9cente de l\u2019Alg\u00e9rie\u2026.. Le 12 d\u00e9cembre 2029 auront lieu des \u00e9lections pr\u00e9sidentielles en Alg\u00e9rie. Mais la veille, le 11 d\u00e9cembre, les Alg\u00e9riens se souviendront surtout de ce qui s\u2019est pass\u00e9 \u2026 \u00a0le 11 d\u00e9cembre 1960.<\/p>\n<p>En ce jour de d\u00e9cembre 1960 \u00e0 Alger, les masses alg\u00e9riennes vont faire irruption sur le devant de la sc\u00e8ne, et \u00ab\u00a0faire\u00a0\u00bb l\u2019histoire. Dans la capitale de l\u2019Alg\u00e9rie encore fran\u00e7aise, ce sont les ouvriers et les \u00e9tudiants, les sans droits et les ch\u00f4meurs qui vont tenter de s\u2019emparer du centre des grandes villes d\u2019o\u00f9 ils sont exclus. Prendre possession des espaces citadins, c\u2019est d\u00e9j\u00e0 acc\u00e9der \u00e0 une forme de modernit\u00e9, vouloir peser sur les d\u00e9cisions politiques, utiliser les villes comme des \u00ab\u00a0caisses de r\u00e9sonance\u00a0\u00bb pour faire valoir sa cause et ses frustrations.<\/p>\n<p>La \u00ab\u00a0r\u00e9volution alg\u00e9rienne\u00a0\u00bb quitte donc les campagnes et se dirige vers les villes. Retour donc sur les grandes manifestations d\u2019Alger en d\u00e9cembre 1960, moment annonciateur de l\u2019ind\u00e9pendance qui arrive. Au moment o\u00f9 se d\u00e9roulent sous nos yeux une \u00ab\u00a0nouvelle r\u00e9volution alg\u00e9rienne\u00a0\u00bb, commenc\u00e9e le 22 f\u00e9vrier 2019 par la demande de d\u00e9part d\u2019Abdelaziz Bouteflika, il est int\u00e9ressant de voir comment les masses alg\u00e9riennes sont descendues dans la rue en d\u00e9cembre 1960, pour montrer leur volont\u00e9 d\u2019acc\u00e9der \u00e0 la naissance d\u2019une R\u00e9publique Alg\u00e9rienne.<\/p>\n<p><strong>Avant le 11 d\u00e9cembre 1960.<\/strong><\/p>\n<p>Dans son allocution radiot\u00e9l\u00e9vis\u00e9e du 4 novembre 1960, le g\u00e9n\u00e9ral De Gaulle, apr\u00e8s avoir renouvel\u00e9 sa proposition d\u2019une \u00ab\u00a0paix des braves\u00a0\u00bb, promet un meilleur niveau de vie par des r\u00e9formes sociales et \u00e9conomiques \u00e0 travers le \u00ab\u00a0Plan de Constantine\u00a0\u00bb et \u00ab\u00a0les mille villages\u00a0\u00bb. Il \u00e9voque ensuite \u00ab\u00a0une R\u00e9publique Alg\u00e9rienne\u00a0\u00bb dont le projet sera soumis \u00e0 un r\u00e9f\u00e9rendum le 8 Janvier 1961. Pour lui l\u2019affaire est d\u00e9licate, et\u00a0 il tient \u00e0 \u00e9valuer les r\u00e9actions de sa politique aupr\u00e8s de la communaut\u00e9 europ\u00e9enne et de l\u2019arm\u00e9e fran\u00e7aise en Alg\u00e9rie, \u00e0 travers un voyage de \u00ab\u00a0sondage\u00a0\u00bb qu\u2019il entreprend du 9 au 12 d\u00e9cembre 1960. De leur c\u00f4t\u00e9, conscients de la gravit\u00e9 de la d\u00e9cision du chef de l\u2019Etat, les partisans de l\u2019Alg\u00e9rie fran\u00e7aise mobilisent pour la pr\u00e9servation du statut quo colonial.<\/p>\n<p>Les organisations extr\u00e9mistes comme le Front de l\u2019Alg\u00e9rie Fran\u00e7aise\u00a0 (le F.A. F). et quelques unit\u00e9s de l\u2019arm\u00e9e sous la houlette du g\u00e9n\u00e9ral Jouhaud \u00e9tablissent un programme d\u2019action \u00e0 cette occasion. Ils entendent accueillir le Chef de l\u2019Etat fran\u00e7ais par une gr\u00e8ve g\u00e9n\u00e9rale, des manifestations hostiles \u00e0 sa politique et ils veulent faire participer les Alg\u00e9riens musulmans \u00e0 ces manifestations, comme une sorte de r\u00e9p\u00e9tition du 13 mai 1958. Le 9 d\u00e9cembre De Gaulle est effectivement mal accueilli \u00e0 A\u00efn T\u00e9mouchent, dans l\u2019ouest alg\u00e9rien, premi\u00e8re \u00e9tape de son voyage. Des manifestants \u00ab\u00a0pieds-Noirs\u00a0\u00bb se pr\u00e9parent \u00e0 l\u2019action \u00e0 Alger et lancent un mot d\u2019ordre de gr\u00e8ve g\u00e9n\u00e9rale. La ville est paralys\u00e9e, des magasins sont saccag\u00e9s, des milliers de litres d\u2019huile de vidange d\u00e9vers\u00e9s sur la chauss\u00e9e. Le tout aux cris de \u00ab\u00a0Alg\u00e9rie fran\u00e7aise\u00a0!\u00a0\u00bb, \u00ab\u00a0De Gaulle au poteau\u00a0!\u00a0\u00bb\u2026 Cherchant \u00e0 provoquer l\u2019intervention de l\u2019arm\u00e9e fran\u00e7aise en leur faveur, les manifestants se rendent dans les quartiers arabes, incitant les Alg\u00e9riens \u00e0 se joindre \u00e0 eux en mena\u00e7ant certains les armes \u00e0 la main. Mais la \u00ab\u00a0Fraternisation\u00a0\u00bb du 13 mai 1958 est bien loin d\u00e9sormais. Le lendemain, 10 d\u00e9cembre 1961, alors que rien n\u2019annon\u00e7ait l\u2019\u00e9v\u00e9nement, des milliers Alg\u00e9riens d\u00e9filent, mais pas du tout dans le sens esp\u00e9r\u00e9 des partisans de l\u2019Alg\u00e9rie fran\u00e7aise\u2026<\/p>\n<p><strong>\u00a0Alger, le 10 d\u00e9cembre.<\/strong><\/p>\n<p>Le samedi apr\u00e8s-midi du 10 d\u00e9cembre 1960 \u00e0 16h 45, \u00e0 hauteur du \u00ab\u00a0Monoprix\u00a0\u00bb de la rue d\u2019Isly \u00e0 Alger, une bagarre &#8211; la premi\u00e8re &#8211; \u00e9clate entre \u00ab\u00a0Fran\u00e7ais de souche\u00a0\u00bb et \u00ab\u00a0musulmans\u00a0\u00bb. A 18 h, dans la nuit humide qui avance sur Alger avec un rideau de pluie, les passants voient une course vers le quartier Belcourt. Comme un torrent dans un tumulte, qui donne le frisson, \u00ab\u00a0la foule, arborant des drapeaux F.L.N. d\u00e9vale la colline o\u00f9 sont accroch\u00e9s les bidonvilles. Elle se rue dans la rue de Lyon d\u00e9vastant les magasins, faisant effondrer les vitrines dans un bruit de verre bris\u00e9. Des fen\u00eatres soudain, des coups de feu claquent. Deux hommes et un enfant tombent mortellement frapp\u00e9s\u00a0: un Europ\u00e9en pris de panique, venait de tirer de son balcon\u00a0\u00bb, note le quotidien fran\u00e7ais\u00a0<strong><em>Lib\u00e9ration<\/em>.<\/strong>\u00a0Des jeunes form\u00e9s en plusieurs groupes dont quelques-uns d\u00e9ploient rapidement des drapeaux vert et blanc du F.L.N. avancent aux cris de \u00ab\u00a0Alg\u00e9rie musulmane\u00a0\u00bb, \u00ab\u00a0Abbas au pouvoir\u00a0\u00bb, \u00ab\u00a0Lib\u00e9rer Ben Bella\u00a0\u00bb, \u00ab\u00a0Lagaillarde au poteau\u00a0\u00bb. Des renforts de gendarmes mobiles les arr\u00eatent et ils n\u2019insistent pas. Cependant, vers 19h 30, d\u2019immenses flammes s\u2019\u00e9l\u00e8vent dans tout le quartier jusqu\u2019\u00e0 ce que les pompiers aient r\u00e9ussi \u00e0 circonscrire le sinistre. Un jeune alg\u00e9rien musulman qui se trouve \u00e0 la t\u00eate d\u2019un groupe en prend la parole\u00a0: \u00ab\u00a0Nous ne nous attaquons pas au service d\u2019ordre mais nous manifestons contre les Europ\u00e9ens qui veulent nous obliger \u00e0 fermer nos magasins et \u00e0 d\u00e9fendre avec eux l\u2019Alg\u00e9rie fran\u00e7aise, alors que nous voulons l\u2019Alg\u00e9rie musulmane\u00a0\u00bb.<\/p>\n<p>Au m\u00eame moment, plusieurs milliers de musulmans descendent du clos Salembier (banlieue d\u2019Alger) par le ravin de la Femme Sauvage avec, \u00e0 leur t\u00eate, des femmes poussant des you-you et criant \u00ab\u00a0Alg\u00e9rie alg\u00e9rienne\u00a0\u00bb. Beaucoup d\u2019entre eux, arm\u00e9s de gourdins, de barres de fer, de planches et de cha\u00eenes de bicyclette, remontent la rue de Lyon et attaquent la plupart des magasins situ\u00e9s entre la rue Musset et la rue Fernand-Costes. Quelques Europ\u00e9ens, arm\u00e9s d\u2019armes \u00e0 feu tirent au revolver dans leur direction et, \u00e0 l\u2019angle de la rue de Lyon et de la rue Bigoni. Un musulman est lynch\u00e9. A 19 h 45, le service d\u2019ordre attaque les musulmans \u00e0 coups de grenades lacrymog\u00e8nes et de grenades offensives. Des forces militaires consid\u00e9rables, chars, automitrailleuses, camions charg\u00e9s de gendarmes mobiles, descendent des hauts d\u2019Alger vers Belcourt et le Ruisseau. Une vague de manifestants musulmans s\u2019abat entre 21h 30 et 22 heures sur Diar El Mah\u00e7oul, brisant les voitures lapidant et d\u00e9fon\u00e7ant les boutiques.<\/p>\n<p><strong>11 d\u00e9cembre 1960, journ\u00e9e d\u00e9cisive.<\/strong><\/p>\n<p>Le dimanche matin du 11 d\u00e9cembre, une pluie fine continue de tomber sur la ville. Les manifestations reprennent \u00e0 Belcourt. Elles sont le fait de groupes de cent \u00e0 deux cents tr\u00e8s jeunes musulmans qui arborent des drapeaux verts du F.L.N. et scandent \u00ab\u00a0Lagaillarde au poteau\u00a0!\u00a0\u00bb \u00ab\u00a0Abbas au pouvoir\u00a0\u00bb \u00ab\u00a0Rencontre Abbas-De Gaulle\u00a0!\u00a0\u00bb A 10 h, dix mille musulmans sont mass\u00e9s dans les rues de la Petite Casbah. Ils frappent des pieds sur les toits de t\u00f4le des baraques pour scander les slogans. Ils agitent au bout de perches une demi-douzaine de drapeaux F.L.N. Les you-you stridents des femmes percent \u00e0 travers ce fracas. Les manifestations sont difficilement contenues par\u00a0 de puissants cordons de C.R.S. Un d\u00e9tachement de parachutistes b\u00e9ret rouge, command\u00e9 par le colonel Massot, vient prendre position l\u2019arme au pied, face aux ruelles bond\u00e9es de manifestants. A midi, les cris continuent , malgr\u00e9 les exhortations des hauts parleurs de la police \u00e0 terminer cette manifestation.<\/p>\n<p>L\u2019hebdomadaire\u00a0<strong><em>France Observateur<\/em><\/strong>\u00a0(en date du 15 d\u00e9cembre) raconte la sc\u00e8ne, cette fois vue du c\u00f4t\u00e9 des Europ\u00e9ens. \u00ab\u00a0Dimanche matin, vers 10 heures. Rue de Lyon (quartier Belcourt). Un groupe de jeunes pieds noirs d\u2019une vingtaine d\u2019ann\u00e9es ( certains portent l\u2019insigne Jeunes Nation) discutent. Sur le trottoir des flaques de sang frais. Ils parlent des contre-manifestants de la veille\u00a0: \u00ab\u00a0C\u2019est une honte. Quand on pense qu\u2019ils sont venus hier soir jusqu\u2019ici avec les drapeaux des felouses\u00a0! Et l\u2019arm\u00e9e qui n\u2019a rien fait\u00a0! Nous on \u00e9tait rue Michelet. On s\u2019attendait pas \u00e0 \u00e7a. Quand on est arriv\u00e9s, on a appris ce qui s\u2019\u00e9tait pass\u00e9. Heureusement, il y a des Fran\u00e7ais qui ont tir\u00e9 des fen\u00eatres. Les ratons se sont sauv\u00e9s comme des lapins. Ils ont eu six morts. Quand aux t\u00e2ches de sang frais sur lesquelles nous pi\u00e9tinons, ils en expliquent ainsi l\u2019origine. \u00ab\u00a0Celui l\u00e0 on l\u2019a eu tout \u00e0 l\u2019heure. On l\u2019a pouss\u00e9 dans l\u2019encoignure de la porte, le fumier, et il a eu son compte. Je comprends ainsi que le malheureux a \u00e9t\u00e9 tu\u00e9 et qu\u2019il n\u2019y a pas eu besoin pour cela de revolver. A 150 m\u00e8tres de l\u00e0, un cadavre sur un trottoir\u00a0; celui d\u2019un ouvrier musulman avec des bottes, une large t\u00e2che de sang sur la poitrine, la t\u00eate recouverte par sa veste. Il vient d\u2019\u00eatre tu\u00e9, une balle \u00e0 bout portant en plein c\u0153ur. Autour du cadavre, une centaine de pieds noirs discutent. Un homme d\u2019une soixantaine d\u2019ann\u00e9es, cheveux blancs, retrait\u00e9 ou petit rentier, montre la pointe de son parapluie\u00a0: \u00ab\u00a0Je l\u2019ai enfonc\u00e9 dans la t\u00eate des melons\u00a0\u00bb dit il avec fiert\u00e9\u00a0\u00bb.<\/p>\n<p>De l\u2019autre c\u00f4t\u00e9, dans les rangs des Alg\u00e9riens musulmans, les revendications se veulent plus explicites, il faut montrer sa force, dire que les souvenirs de \u00ab\u00a0La bataille d\u2019Alger\u00a0\u00bb de l\u2019ann\u00e9e 1957 sont maintenant effac\u00e9s. L\u2019initiative est d\u00e9sormais reprise par le FLN. Un reporter de\u00a0<strong><em>France Soir<\/em><\/strong>\u00a0(paru le 13 d\u00e9cembre) rencontre un dirigeant du FLN d\u2019Alger\u00a0: \u00ab\u00a0 Je descends une ruelle \u00e9troite \u00e0 la pente abrupte et doit me frayer un passage parmi la foule compacte\u00a0: femmes voil\u00e9es, hommes et enfants. Devant moi \u00e0 quelques dizaines de m\u00e8tres une petite barricade derri\u00e8re laquelle se pressent 200 ou 300 personnes qui hurlent \u00e0 tue-t\u00eate. Encore un peu plus loin, j\u2019aper\u00e7ois les casques des C.R.S qui restent impassibles. Un caf\u00e9 maure. A l\u2019int\u00e9rieur, beaucoup de monde attabl\u00e9. Les gens sont calmes. Certains m\u00eame sourient. On me prie d\u2019entrer. On me pousse dans l\u2019arri\u00e8re-salle. (\u2026) Les meneurs me donnent leur version des incidents qui ont fini par tourner au tragique\u00a0: \u00ab\u00a0Lorsque le g\u00e9n\u00e9ral De Gaulle est venu en Alg\u00e9rie, les Europ\u00e9ens ont manifest\u00e9, mais nous, on est rest\u00e9s tranquilles chez nous. Ce sont eux qui sont venus nous chercher. Ils ont envahi notre quartier. Ils nous ont oblig\u00e9s \u00e0 fermer les caf\u00e9s, le revolver \u00e0 la main. On a voulu r\u00e9sister. Ils se sont mis \u00e0 tirer. Hier nous avons eu six morts. Aujourd\u2019hui cinq. Et les musulmans ajoutent\u00a0: \u00ab\u00a0 Nous sommes tous pour le F.L.N., nous n\u2019avons jamais voulu bouger, mais maintenant nous sommes lass\u00e9s de ce qui se passe en Alg\u00e9rie. Nous ne sommes pas pour le g\u00e9n\u00e9ral De Gaulle, car dans l\u2019\u00e9tat actuel des choses, il n\u2019y a que deux solutions\u00a0: ou une Alg\u00e9rie fasciste ou une Alg\u00e9rie ind\u00e9pendante.\u00a0\u00bb<\/p>\n<p>En fin de matin\u00e9e de ce dimanche 11 d\u00e9cembre 1960, la masse des manifestants musulmans ne cesse de grossir. Des Europ\u00e9ens tirent. D\u2019autres jettent des grenades d\u2019un balcon sur des groupes de jeunes Arabes. La temp\u00e9rature monte.\u00a0 Des manifestants brandissent l\u2019embl\u00e8me ensanglant\u00e9 et crient\u00a0: \u00ab\u00a0Messieurs les journalistes, il y a beaucoup trop de sang sur notre drapeau. Un million d\u2019Alg\u00e9riens sont morts pour l\u2019ind\u00e9pendance\u2026\u00a0\u00bb Des applaudissements, des coups de sifflet, des cris, des you-yous soulignent cette profession de foi. Les manifestants l\u00e8vent au-dessus de leur t\u00eate des b\u00e2tons, des cannes, des parapluies. C\u2019est un tumulte extraordinaire. Une nouvelle pancarte improvis\u00e9e appara\u00eet au-dessus de la masse d\u00e9cha\u00een\u00e9e. Elle proclame\u00a0: \u00ab\u00a0Vive l\u2019Alg\u00e9rie ind\u00e9pendante\u00a0! Vive l\u2019Arm\u00e9e de Lib\u00e9ration Nationale\u00a0! Vive le F.L.N.\u00a0\u00bb Des plaques de t\u00f4le arrach\u00e9es aux baraquements sont, de minute en minute, couvertes d\u2019inscriptions nationalistes.<\/p>\n<p>La manifestation musulmane se d\u00e9place vers les hauteurs du quartier de Diar El Mah\u00e7oul, boulevard de l\u2019Amiral Gu\u00e9pratte. Les manifestants continuent \u00e0 renverser et \u00e0 briser les voitures qu\u2019ils rencontrent sur leur passage. Les militaires fran\u00e7ais demandent aux Europ\u00e9ens arm\u00e9s \u00e0 la lisi\u00e8re du quartier du Hamma de se disperser et de rentrer chez eux. A Diar El Mah\u00e7oul les manifestants s\u2019attaquent aux parcs de voitures, brisant certaines d\u2019entres elles et s\u2019emparent d\u2019autres. Deux jeunes filles musulmanes habill\u00e9es de vert et de blanc et portant le calot de l\u2019A.L.N. chantent l\u2019hymne du F.L.N. et des chants du maquis. Des \u00e9changes de coups de feu ont lieu entre les manifestants musulmans, toujours soutenus pas les \u00ab\u00a0you you\u00a0\u00bb des femmes, et les habitants d\u2019immeubles proches de l\u2019\u00e9glise St Jean-au-Ruisseau. Les paras du 18\u00e9me R\u00e9giment prennent place aux d\u00e9bouch\u00e9s de la Casbah. A Belcourt les manifestants musulmans parvenus \u00e0 proximit\u00e9 imm\u00e9diate d\u2019un d\u00e9tachement militaire jettent des pierres sur ce dernier. Les militaires ripostent et l\u2019un des manifestants est gri\u00e8vement bless\u00e9. A midi, sur la route du ravin de la \u00ab\u00a0Femme Sauvage\u00a0\u00bb, un inspecteur de police des renseignements g\u00e9n\u00e9raux est \u00e9gorg\u00e9. Sa voiture est incendi\u00e9e.<\/p>\n<p>Du c\u00e9l\u00e8bre quartier populaire de Bab-el-Oued parviennent des nouvelles alarmantes. Des heurts opposent \u00ab\u00a0Fran\u00e7ais de souche\u00a0\u00bb et musulmans au carrefour de la Rampe-Vall\u00e9e et rue Mizon. Place des Trois-Horloges, o\u00f9 les parachutistes viennent de prendre position, deux cadavres s\u2019offrent aux yeux des passants. Ceux de deux musulmans tu\u00e9s par balles. Le premier g\u00eet dans le caniveau, le dos au sol, les yeux encore ouverts. Il a \u00e9t\u00e9 touch\u00e9 \u00e0 la t\u00eate. Le second est recroquevill\u00e9 au milieu de la chauss\u00e9e. Les ambulances qui sillonnent sans arr\u00eat les rues de la ville ne sont pas encore venus enlever les corps. On s\u2019occupe d\u2019abord des bless\u00e9s.<\/p>\n<p>A 13h, la Casbah est encercl\u00e9e par les zouaves. Elle est compl\u00e8tement ferm\u00e9e par des r\u00e9seaux de barbel\u00e9s et chevaux de frise. Il est interdit d\u2019en sortir et tout musulman qui veut y p\u00e9n\u00e9trer doit prouver qu\u2019il y habite en pr\u00e9sentant sa carte d\u2019identit\u00e9.<\/p>\n<p>C\u2019est le d\u00e9but de l\u2019apr\u00e8s-midi dans le quartier Belcourt. 40 camions charg\u00e9s de C.R.S et de gendarmes descendent le long de l\u2019agglom\u00e9ration musulmane du Clos Salembier, o\u00f9 il y a notamment un bidonville musulman extr\u00eamement important.<\/p>\n<p>Soudain alors que la pression se fait plus forte \u00e0 la hauteur de la place du Gouvernement, des coups de feu \u00e9clatent. Plusieurs personnes tombent \u00e0 terre. Hommes, femmes, enfants se mettent \u00e0 courir dans tous les sens, tandis qu\u2019en quelques minutes des ambulances arrivaient sur les lieux.<\/p>\n<p>Tr\u00e8s rapidement, les manifestants musulmans remont\u00e8rent vers la Casbah boucl\u00e9e par le service des jeunes brandissant toujours des drapeaux F.L.N. continu\u00e8rent \u00e0 parcourir les rues \u00e9troites sous les acclamations des femmes musulmanes mass\u00e9es aux fen\u00eatres.<\/p>\n<p>Le journal\u00a0<strong><em>Lib\u00e9ration<\/em><\/strong>\u00a0note dans son \u00e9dition du 12 d\u00e9cembre\u00a0: \u00ab\u00a0Apr\u00e8s le recoupement de plusieurs t\u00e9moignages, il appara\u00eet que la plupart des musulmans tu\u00e9s au cours de cet apr\u00e8s-midi tragique l\u2019ont \u00e9t\u00e9 pendant cette fusillade de Bab-El-Oued, les uns par les forces de l\u2019ordre, les autres par les Europ\u00e9ens qui se sont livr\u00e9s \u00e0 des exc\u00e8s. Plusieurs musulmans ont \u00e9t\u00e9 lynch\u00e9s dont deux dans un caf\u00e9 maure. Plusieurs autres ont \u00e9t\u00e9 abattus alors qu\u2019ils s\u2019enfuyaient apr\u00e8s les premiers coups de feu\u00a0\u00bb.<\/p>\n<p>De son c\u00f4t\u00e9\u00a0<strong><em>France observateur<\/em><\/strong>\u00a0\u00e9crit\u00a0: \u00ab\u00a0Une centaine de musulmans au moins ont trouv\u00e9 la mort \u00e0 cet instant. Et cela parce que Bab-el-Oued soudain, a eu peur. L\u2019arm\u00e9e, certes a tir\u00e9, ou tout au moins certaines de ses unit\u00e9s. Au Ruisseau, par exemple, les parachutistes ont \u00ab\u00a0nettoy\u00e9\u00a0\u00bb \u00e0 la mitraillette. Mais l\u2019autopsie des corps, ordonn\u00e9 par la D\u00e9l\u00e9gation g\u00e9n\u00e9rale, contre l\u2019avis semble-t-il des militaires, a d\u00e9montr\u00e9 que la majorit\u00e9 des musulmans tu\u00e9s l\u2019avaient \u00e9t\u00e9 par de simples balles de revolver, c\u2019est \u00e0 dire par des balles tir\u00e9es par des Europ\u00e9ens\u00a0\u00bb.<\/p>\n<p>A 15h, L\u2019arm\u00e9e ouvre le feu sur les \u00e9meutiers musulmans rassembl\u00e9s place du Gouvernement, en bas de la Casbah. \u00c0 l\u2019autre bout de la ville, dans le quartier du Ruisseau, les parachutistes tirent avec des armes automatiques. Premier bilan\u00a0: cinq morts et plus de cent bless\u00e9s. Au d\u00e9but de l\u2019apr\u00e8s-midi, des parachutistes arrivant de l\u2019int\u00e9rieur, en provenance de T\u00e9l\u00e9rgma \u00e0 bord d\u2019avions qui se posent sur l\u2019a\u00e9rodrome de Maison Blanche toutes les dix minutes, ont entrepris le \u00ab\u00a0nettoyage\u00a0\u00bb des barricades. Pourtant les manifestations se poursuivent. Deux mille musulmans portant des drapeaux F.L.N. sont rassembl\u00e9s \u00e0 500 m\u00e8tres en contrebas de la\u00a0 cit\u00e9 de Diar-El-Mah\u00e7oul. Des paras les contiennent. Un porteur de drapeau F.L.N manque de peu d\u2019\u00eatre lynch\u00e9 par des Europ\u00e9ens.<\/p>\n<p>A 16 h, le drapeau F.L.N. flotte sur la Casbah et sur une synagogue d\u00e9saffect\u00e9e.<\/p>\n<p>Un combat de rue a lieu entre Europ\u00e9ens et musulmans dans le quartier de la rue de Lyon, \u00e0 la hauteur du boulevard Auguste-Compte. De nombreux coups de feu sont tir\u00e9s par les Europ\u00e9ens. Quarante gardiens de la paix et un commissaire de police parlementent avec les musulmans qui demandent \u00e0 faire constater que parmi eux il y a les bless\u00e9s par balles, et sans doutes des morts.<\/p>\n<p>Les dirigeants de la manifestation F.L.N. entourent un journaliste de\u00a0<strong><em>Paris Jour\u00a0<\/em><\/strong>: \u00ab\u00a0Je dois dire qu\u2019ils \u00e9taient tr\u00e8s calmes et fort courtois.<\/p>\n<ul>\n<li>Vous \u00eates journaliste\u00a0?<\/li>\n<li>Oui<\/li>\n<li>Vous \u00eates de Paris\u00a0?<\/li>\n<li>Oui<\/li>\n<li>Alors, voici ce que nous avons \u00e0 dire et \u00e0 faire savoir. Nous attendions ce moment depuis des ann\u00e9es. Nous nous rappelons une chose\u00a0: les 45 000 morts musulmans des \u00e9meutes de S\u00e9tif en 1945. Ces massacres ont \u00e9t\u00e9 ordonn\u00e9s par De Gaulle qui \u00e9tait alors chef du gouvernement. A pr\u00e9sent, ce que nous voulons c\u2019est l\u2019ind\u00e9pendance. Il faut n\u00e9gocier avec Ferhat Abbas, avec le F.L.N..<\/li>\n<li>Et le prochain r\u00e9f\u00e9rendum\u00a0?<\/li>\n<li>C\u2019est du bluff\u00a0!<\/li>\n<\/ul>\n<p>L\u2019un des jeunes musulmans m\u2019entra\u00eene vers le \u00ab\u00a0Bastion\u00a0\u00bb. Il me montre un drapeau vert sur lequel on aper\u00e7oit de grands t\u00e2ches rouge\u00e2tres.<\/p>\n<ul>\n<li>Regardez ce drapeau. Eh bien ce que vous voyez dessus c\u2019est du sang, le sang de nos camarades qui ont \u00e9t\u00e9 bless\u00e9s ce matin par des Europ\u00e9ens\u00a0\u00bb.<\/li>\n<\/ul>\n<p>Le journaliste de\u00a0<strong><em>France Observateur<\/em><\/strong>\u00a0\u00e9crit, le soir de cette manifestation\u00a0:<\/p>\n<p>\u00ab\u00a0Le 11 D\u00e9cembre 1960, \u00e0 Alger et sans doute aussi au m\u00eame moment \u00e0 Oran et dans d\u2019autres villes r\u00e9put\u00e9es pacifi\u00e9es, la peur a chang\u00e9 de camp\u00a0\u00bb. Et son article se termine ainsi, par des phrases prononc\u00e9es par de jeunes Alg\u00e9riens\u00a0:<\/p>\n<ul>\n<li>\u00ab\u00a0Cela ne pouvait plus durer. Mon mari a disparu depuis 1957. Nous sommes des centaines dans le m\u00eame cas\u2026Il faut que cela finisse\u2026<\/li>\n<\/ul>\n<ul>\n<li>Nous ne sommes pas contre la France, nous ne sommes pas contre De Gaulle. Nous sommes contre le F.A.F et nous voulons que De Gaulle n\u00e9gocie avec le G.P.R.A.<\/li>\n<\/ul>\n<ul>\n<li>Quel \u00e2ge avez-vous\u00a0?<\/li>\n<li>Dix-neuf ans, bient\u00f4t celui du service militaire.<\/li>\n<li>Lequel\u00a0?<\/li>\n<li>Vous ne le saurez pas\u00a0\u00bb.<\/li>\n<\/ul>\n<p>Dans son\u00a0<strong><em>Journal,<\/em><\/strong>\u00a0en date du 11 d\u00e9cembre 1960, le grand \u00e9crivain alg\u00e9rien, Mouloud Feraoun (qui sera assassin\u00e9 en mars 1962 par l\u2019OAS),\u00a0 \u00e9crit\u00a0:<\/p>\n<p>\u00ab\u00a0Aujourd\u2019hui donc, sortie des Arabes dans la rue. Il s\u2019agit des gens de \u00ab\u00a0chez moi\u00a0\u00bb, c\u2019est \u00e0 dire du Clos. Ils ont investi Mah\u00e7oul et Saada (Diar-el-Mah\u00e7oul et Diar-el-Saada, deux cit\u00e9s \u00ab\u00a0nouvelles\u00a0\u00bb au dessus de Belcourt). Ceux de Belcourt, du Ruisseau aussi. Il y avail les bidonvilles Nador, Scala, El Amal, Bodez, Abulker, tous. Il y avait Kouba. La kasbah, Bal el Oued ont voulu sortir aussi. Que s\u2019est il produit en fin de compte\u00a0? C\u2019\u00e9tait facile \u00e0 pr\u00e9voir, les Europ\u00e9ens se sont affol\u00e9s, l\u2019arm\u00e9e s\u2019est affol\u00e9e ou a fait semblant de l\u2019\u00eatre. Il s\u2019agissait ne de gouailler, ni de s\u2019amuser, ni de jeter des bonbons. Il fallait mitrailler. La D.Q annonce \u00e0 22h cinquante et un morts dont quarante cinq musulmans. L\u2019arm\u00e9e a tir\u00e9 dessus. Ou les civils.<\/p>\n<p>Ainsi la situation est claire\u00a0: les Arabes, que personne n\u2019a pouss\u00e9s, exc\u00e9d\u00e9s seulement par les fanfaronnades des pieds-noirs, sortent pour crier leur exasp\u00e9ration, ceux qui pr\u00e9tendaient les d\u00e9fendre, les couver, fraterniser avec eux leur tirent dessus. Bas les maques, Messieurs\u00a0! Vous pouvez tous les massacrer \u00e0 pr\u00e9sent, vous \u00eates fichus.<\/p>\n<p>(\u2026) Pour demain, les \u00e9coles sont ferm\u00e9es, il y aura probablement les Arabes dans la rue et les soldats pour les descendre. La Kasbah, Hussein Dey, Maison Carr\u00e9e, ect\u2026. N\u2019ont pas encore dit leur dernier mot. Ce soir, j\u2019ai d\u00fb faire un d\u00e9tour de trente kilom\u00eatres pour rentrer alors que je me trouvais \u00e0 deux kilom\u00e8tres de la maison, \u00e0 Bouzar\u00e9ah. Les Militaires bouclaient la ville. Evidemment, il sera facile de reprendre la situation en main, lorsqu\u2019on aura affaire qu\u2019aux Arabes parce que, avec les Arabes, on se sent fort et on use de sa force. N\u2019emp\u00eache que ces m\u00eames Arabes ont fichu un sacr\u00e9 coup \u00e0 deux ann\u00e9es laborieuses de pseudo-pacification. On se croirait replong\u00e9 dans les jours les plus sombres de 1957.<\/p>\n<p>Ajoutons enfin, pour terminer, que le travail de l\u2019ONU devrait \u00eatre facilit\u00e9 par de telles drames. Il n\u2019y a plus moyen de farder la v\u00e9rit\u00e9\u00a0: un peuple sous le joug souffre depuis six ans la plus injuste des souffrances, peut-on lui porter secours ou le laissera-t-on d\u00e9truire\u00a0?\u00a0\u00bb<a id=\"_ftnref1\" href=\"https:\/\/benjaminstora.univ-paris13.fr\/index.php\/actualites\/638-quand-l-histoire-percute-l-actualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora.html#_ftn1\">[1]<\/a>.<\/p>\n<p><strong>Bilans et interpr\u00e9tations.<\/strong><\/p>\n<p>Les cris et slogans hostiles \u00e0 l\u2019Alg\u00e9rie fran\u00e7aise, les drapeaux vite confectionn\u00e9s et brandis sous le nez de l\u2019arm\u00e9e, constituent une grande surprise pour les Europ\u00e9ens habitu\u00e9s au \u00ab\u00a0calme\u00a0\u00bb des Alg\u00e9riens depuis la terrible \u00ab\u00a0Bataille d\u2019Alger\u00a0\u00bb de l\u2019ann\u00e9e 1957. Ils sont donc sid\u00e9r\u00e9s par l\u2019irruption inattendue de ce peuple. Une r\u00e9alit\u00e9 nouvelle fait brusquement irruption devant leurs yeux.\u00a0 Les \u00ab\u00a0forces de l\u2019ordre\u00a0\u00bb fran\u00e7aises interviennent plusieurs fois, tirent dans la foule.\u00a0 Mais malgr\u00e9 la mort qui fauche hommes, femmes et enfants, les manifestants alg\u00e9riens, malgr\u00e9 le carnage, restent sourds aux rafales des soldats parachutistes. Certaines unit\u00e9s fran\u00e7aises, demeur\u00e9es loyales au gouvernement, s\u2019interposent entre Alg\u00e9riens et parachutistes, emp\u00eachant ces derniers de profiter de la situation. Terrifi\u00e9s par la spontan\u00e9it\u00e9 des \u00e9v\u00e9nements, certains \u00ab\u00a0pieds-noirs\u00a0\u00bb se barricadent chez eux, non sans en profiter pour tirer sur les Alg\u00e9riens \u00e0 partir des terrasses et des balcons. Durant cinq jours, les manifestations alg\u00e9riennes se poursuivront \u00e0 Alger et dans d\u2019autres villes. On \u00e9value aujourd\u2019hui \u00e0 pr\u00e8s de deux cents le nombre de victimes alg\u00e9riennes, parmi lesquelles des femmes et des enfants. Un bilan officiel fait \u00e9tat de cent douze morts musulmans \u00e0 Alger.<\/p>\n<p>Sur les causes de cette manifestation, plusieurs interpr\u00e9tations ont \u00e9t\u00e9 avanc\u00e9es. Certains journalistes fran\u00e7ais, comme Claude Paillat dans ses\u00a0<strong><em>Dossiers secrets de l\u2019Alg\u00e9rie<\/em><\/strong>\u00a0ou Yves Courri\u00e8re dans son histoire de\u00a0<strong><em>La guerre d\u2019Alg\u00e9rie<\/em><\/strong>\u00a0ont avanc\u00e9 l\u2019hypoth\u00e8se que des services policiers ou militaires fran\u00e7ais, favorables \u00e0 la politique du g\u00e9n\u00e9ral De Gaulle, et d\u00e9sireux de contrer le mouvement pied-noir qui quelques mois plus tard allait donner naissance \u00e0 l\u2019OAS, ont favoris\u00e9 les manifestations alg\u00e9riennes. Pour l\u2019historien alg\u00e9rien Messaoud Maadad,\u00a0 \u00ab\u00a0beaucoup d\u2019informations contradictoires entourent cet \u00e9v\u00e9nement, laissant comprendre parfois que le mot d\u2019ordre venait de certaines autorit\u00e9s militaires fran\u00e7aises qui voulaient contrecarrer les projets extr\u00e9mistes.\u00a0 D\u2019autres disent que les mots d\u2019ordre venaient du F.L.N. qui voulait secouer l\u2019opinion internationale \u00e0 la veille de la XV\u00e8 session de l\u2019O.N.U.\u00a0 Il est difficile de conna\u00eetre la v\u00e9rit\u00e9 sur l\u2019origine du mot d\u2019ordre, tant les affirmations de part et d\u2019autre sont nettes et fermes et surtout ne contredisent pas les faits. Cependant la spontan\u00e9it\u00e9, la brutalit\u00e9 de l\u2019intervention des masses dans la rue, militent \u00e0 notre sens pour la prise de d\u00e9cision \u00ab\u00a0inn\u00e9e\u00a0\u00bb de ces masses pour faire valoir son \u00ab\u00a0mot \u00e0 dire\u00a0\u00bb. (\u2026) Les manifestations dites du \u00ab\u00a011 d\u00e9cembre\u00a0\u00bb furent, \u00e0 notre avis, l\u2019expression d\u2019une r\u00e9volte au sein m\u00eame de la R\u00e9volution, car exc\u00e9d\u00e9es par les man\u0153uvres politiques, les promesses de paix, les illusions de bonheur, fatigu\u00e9es d\u2019un conflit o\u00f9 seule compte la force brutale, les masses alg\u00e9riennes profit\u00e8rent de la pr\u00e9sence du chez d\u2019Etat fran\u00e7ais sur le sol alg\u00e9rien pour dire \u00ab\u00a0Assez\u00a0!\u00a0\u00bb par dessus la menace de cette force brutale.\u00a0\u00bb<\/p>\n<p>Et il est vrai que, quelque soit les man\u0153uvres venant de toutes parts,\u00a0 une bataille d\u00e9cisive est gagn\u00e9e par le GPRA. Il sera difficile d\u00e9sormais de parler de populations alg\u00e9riennes rest\u00e9s en masse fid\u00e8les \u00e0 la France. L\u2019illusion de \u00ab\u00a0fran\u00e7ais musulmans\u00a0encadr\u00e9s par la terreur du F.L.N.\u00a0\u00bb s\u2019effondre. A la fin de l\u2019ann\u00e9e 1960 en Alg\u00e9rie, les Europ\u00e9ens et le haut commandement sont fix\u00e9s\u00a0: l\u2019Alg\u00e9rie \u00ab\u00a0de papa\u00a0\u00bb est bien morte, et le FLN a regagn\u00e9 sur la sc\u00e8ne politique et diplomatique tout le terrain perdu par les armes.<\/p>\n<p><strong>L\u2019appel de Ferhat Abbas.<\/strong><\/p>\n<p>Le 16 d\u00e9cembre 1960, \u00e0 13 heures, le pr\u00e9sident du GPRA, Ferhat Abbas lance un appel au peuple et reproduit dans\u00a0<em>El Moudjahid<\/em>\u00a0N\u00b0 75, du 19 d\u00e9cembre 1960\u00a0:<\/p>\n<p>\u00ab\u00a0Alg\u00e9riens et Alg\u00e9riennes, qui avez affront\u00e9 avec abn\u00e9gation, la fureur des ultras et de l\u2019arm\u00e9e fran\u00e7aise, nous vous adressons l\u2019expression \u00e9mue de notre admiration\u00a0! (\u2026) Fr\u00e8res et s\u0153urs d\u2019Alg\u00e9rie\u00a0! Vous avez \u00e9crit, avec le sang de nos martyrs, une page glorieuse de notre Histoire. En acceptant une mort h\u00e9ro\u00efque, vous avez affirm\u00e9 votre droit \u00e0 la vie, vous avez gagn\u00e9 le droit \u00e0 la dignit\u00e9, vous avez m\u00e9rit\u00e9 votre libert\u00e9. Quelle le\u00e7on aux imb\u00e9ciles agit\u00e9s de la rue Michelet\u00a0! Quelle le\u00e7on aux apprentis fascistes et aux \u00e9ternels racistes, qui, s\u00fbrs de la police et de l\u2019arm\u00e9e fran\u00e7aises, se livrent impun\u00e9ment depuis six ans aux lynchages et aux tueries des patriotes, de ceux qu\u2019ils devraient respecter parce qu\u2019ils sont dignes de respect. Enfin quelle terrible le\u00e7on aux attard\u00e9s de la \u00ab\u00a0pacification\u00a0\u00bb, \u00e0 ceux qui nourrissent encore l\u2019illusion de s\u00e9parer notre peuple de son arm\u00e9e et de son gouvernement. (\u2026) Nous vivons un moment crucial de notre Histoire. Nous traversons de grandes \u00e9preuves. La bataille que vous venez d\u2019engager \u00e0 pris une grande ampleur. Le monde entier l\u2019a enregistr\u00e9 comme une \u00e9clatante victoire de notre lutte de lib\u00e9ration nationale. Cette bataille doit maintenant prendre fin. Elle n\u2019est pas la derni\u00e8re. D\u2019autres \u00e9preuves nous attendent\u00a0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p><a id=\"_ftn1\" href=\"https:\/\/benjaminstora.univ-paris13.fr\/index.php\/actualites\/638-quand-l-histoire-percute-l-actualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora.html#_ftnref1\">[1]<\/a>\u00a0Mouloud Feraoun,\u00a0<strong><em>Journal,<\/em><\/strong>\u00a0pages 308, 309, Paris Ed Seuil, 1962.<\/p>\n<p>Source: <a href=\"https:\/\/benjaminstora.univ-paris13.fr\/index.php\/actualites\/638-quand-l-histoire-percute-l-actualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora.html\">Benjamin Stora &#8211; Quand l\u2019Histoire percute l\u2019actualit\u00e9 : les manifestations alg\u00e9riennes du 11 d\u00e9cembre 1960 \u00e0 Alger. Par Benjamin Stora.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand l\u2019histoire de la guerre d\u2019ind\u00e9pendance alg\u00e9rienne vient percuter l\u2019actualit\u00e9 r\u00e9cente de l\u2019Alg\u00e9rie\u2026.. Le 12 d\u00e9cembre 2029 auront lieu des \u00e9lections pr\u00e9sidentielles&hellip;<\/p>\n","protected":false},"author":50,"featured_media":117330,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[39,42,49],"tags":[],"class_list":["post-117329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-en-vedette","category-histoire-et-patrimoine","category-politique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quand l\u2019Histoire percute l\u2019actualit\u00e9 : les manifestations alg\u00e9riennes du 11 d\u00e9cembre 1960 \u00e0 Alger. Par Benjamin Stora. - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quand l\u2019Histoire percute l\u2019actualit\u00e9 : les manifestations alg\u00e9riennes du 11 d\u00e9cembre 1960 \u00e0 Alger. Par Benjamin Stora. - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Quand l\u2019histoire de la guerre d\u2019ind\u00e9pendance alg\u00e9rienne vient percuter l\u2019actualit\u00e9 r\u00e9cente de l\u2019Alg\u00e9rie\u2026.. Le 12 d\u00e9cembre 2029 auront lieu des \u00e9lections pr\u00e9sidentielles&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-11T13:58:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/12\/1jh-3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"749\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hope Jzr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hope Jzr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\\\/\"},\"author\":{\"name\":\"Hope Jzr\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\"},\"headline\":\"Quand l\u2019Histoire percute l\u2019actualit\u00e9 : les manifestations alg\u00e9riennes du 11 d\u00e9cembre 1960 \u00e0 Alger. Par Benjamin Stora.\",\"datePublished\":\"2025-12-11T13:58:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\\\/\"},\"wordCount\":4668,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1jh-3.jpeg\",\"articleSection\":[\"Articles en vedette\",\"Histoire et Patrimoine\",\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\\\/\",\"name\":\"Quand l\u2019Histoire percute l\u2019actualit\u00e9 : les manifestations alg\u00e9riennes du 11 d\u00e9cembre 1960 \u00e0 Alger. Par Benjamin Stora. - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1jh-3.jpeg\",\"datePublished\":\"2025-12-11T13:58:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1jh-3.jpeg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1jh-3.jpeg\",\"width\":749,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quand l\u2019Histoire percute l\u2019actualit\u00e9 : les manifestations alg\u00e9riennes du 11 d\u00e9cembre 1960 \u00e0 Alger. Par Benjamin Stora.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/0b50f60fad840cf92313307e38c9d20d\",\"name\":\"Hope Jzr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g\",\"caption\":\"Hope Jzr\"},\"description\":\"\u00c0 propos de Hope&amp;ChaDia Hope&amp;ChaDia n\u2019est pas un pseudonyme, mais une m\u00e9thode de travail. Hope : l\u2019id\u00e9e, l\u2019esprit, la structure, la vision. C\u2019est l\u2019impulsion humaine qui choisit l\u2019angle, trace la ligne \u00e9ditoriale et donne le sens. ChaDia : l\u2019assistante, qui met en forme, d\u00e9veloppe, affine le style et v\u00e9rifie les faits. Une aide technologique qui amplifie mais ne cr\u00e9e pas. Ensemble, Hope&amp;ChaDia produisent des textes hybrides : profond\u00e9ment humains dans leur inspiration, rigoureux et pr\u00e9cis dans leur r\u00e9alisation. . . SUPPORTEZ JAZAIRHOPE ET FAITES CONNA\u00ceTRE LE PATRIMOINE ET L\u2019HISTOIRE DE L\u2019ALG\u00c9RIE, EN ACHETANT LE LIVRE DE JAZAIRHOPE POUR VOUS OU POUR L\u2019OFFRIR A VOS PROCHES, ICI : https:\\\/\\\/jazairhope.org\\\/fr\\\/ebook\\\/ CEUX EN ALG\u00c9RIE ET CEUX QUI PEUVENT PAS L\u2019ACHETER ON OFFRE UNE COPIE DIGITALE GRATUITE, POUR CELA ENVOYEZ UN EMAIL \u00c0 : INFO@JAZAIRHOPE.ORG\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/hope-jazair\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quand l\u2019Histoire percute l\u2019actualit\u00e9 : les manifestations alg\u00e9riennes du 11 d\u00e9cembre 1960 \u00e0 Alger. Par Benjamin Stora. - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/","og_locale":"fr_FR","og_type":"article","og_title":"Quand l\u2019Histoire percute l\u2019actualit\u00e9 : les manifestations alg\u00e9riennes du 11 d\u00e9cembre 1960 \u00e0 Alger. Par Benjamin Stora. - AAH.JZR","og_description":"Quand l\u2019histoire de la guerre d\u2019ind\u00e9pendance alg\u00e9rienne vient percuter l\u2019actualit\u00e9 r\u00e9cente de l\u2019Alg\u00e9rie\u2026.. Le 12 d\u00e9cembre 2029 auront lieu des \u00e9lections pr\u00e9sidentielles&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2025-12-11T13:58:41+00:00","og_image":[{"width":749,"height":470,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/12\/1jh-3.jpeg","type":"image\/jpeg"}],"author":"Hope Jzr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Hope Jzr","Dur\u00e9e de lecture estim\u00e9e":"19 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/"},"author":{"name":"Hope Jzr","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d"},"headline":"Quand l\u2019Histoire percute l\u2019actualit\u00e9 : les manifestations alg\u00e9riennes du 11 d\u00e9cembre 1960 \u00e0 Alger. Par Benjamin Stora.","datePublished":"2025-12-11T13:58:41+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/"},"wordCount":4668,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/12\/1jh-3.jpeg","articleSection":["Articles en vedette","Histoire et Patrimoine","Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/","url":"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/","name":"Quand l\u2019Histoire percute l\u2019actualit\u00e9 : les manifestations alg\u00e9riennes du 11 d\u00e9cembre 1960 \u00e0 Alger. Par Benjamin Stora. - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/12\/1jh-3.jpeg","datePublished":"2025-12-11T13:58:41+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/12\/1jh-3.jpeg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2025\/12\/1jh-3.jpeg","width":749,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/quand-lhistoire-percute-lactualite-les-manifestations-algeriennes-du-11-decembre-1960-a-alger-par-benjamin-stora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Quand l\u2019Histoire percute l\u2019actualit\u00e9 : les manifestations alg\u00e9riennes du 11 d\u00e9cembre 1960 \u00e0 Alger. Par Benjamin Stora."}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/0b50f60fad840cf92313307e38c9d20d","name":"Hope Jzr","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a42f66f14ba94b77f351f3bb2f3b9389c4063acb1697ffb32f5d3944782d3e7?s=96&d=mm&r=g","caption":"Hope Jzr"},"description":"\u00c0 propos de Hope&amp;ChaDia Hope&amp;ChaDia n\u2019est pas un pseudonyme, mais une m\u00e9thode de travail. Hope : l\u2019id\u00e9e, l\u2019esprit, la structure, la vision. C\u2019est l\u2019impulsion humaine qui choisit l\u2019angle, trace la ligne \u00e9ditoriale et donne le sens. ChaDia : l\u2019assistante, qui met en forme, d\u00e9veloppe, affine le style et v\u00e9rifie les faits. Une aide technologique qui amplifie mais ne cr\u00e9e pas. Ensemble, Hope&amp;ChaDia produisent des textes hybrides : profond\u00e9ment humains dans leur inspiration, rigoureux et pr\u00e9cis dans leur r\u00e9alisation. . . SUPPORTEZ JAZAIRHOPE ET FAITES CONNA\u00ceTRE LE PATRIMOINE ET L\u2019HISTOIRE DE L\u2019ALG\u00c9RIE, EN ACHETANT LE LIVRE DE JAZAIRHOPE POUR VOUS OU POUR L\u2019OFFRIR A VOS PROCHES, ICI : https:\/\/jazairhope.org\/fr\/ebook\/ CEUX EN ALG\u00c9RIE ET CEUX QUI PEUVENT PAS L\u2019ACHETER ON OFFRE UNE COPIE DIGITALE GRATUITE, POUR CELA ENVOYEZ UN EMAIL \u00c0 : INFO@JAZAIRHOPE.ORG","url":"https:\/\/jazairhope.org\/fr\/author\/hope-jazair\/"}]}},"views":301,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/117329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=117329"}],"version-history":[{"count":1,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/117329\/revisions"}],"predecessor-version":[{"id":117333,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/117329\/revisions\/117333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/117330"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=117329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=117329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=117329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}