{"id":19297,"date":"2021-06-04T12:30:39","date_gmt":"2021-06-04T17:30:39","guid":{"rendered":"https:\/\/jazairhope.org\/?p=19297"},"modified":"2021-06-04T12:30:39","modified_gmt":"2021-06-04T17:30:39","slug":"classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/","title":{"rendered":"Classement des 500 premi\u00e8res entreprises en 2021  Sonatrach tr\u00f4ne sur l\u2019Afrique"},"content":{"rendered":"<p>\u00c0 tout seigneur, tout honneur. Cette ann\u00e9e encore, c&#8217;est l&#8217;ind\u00e9tr\u00f4nable Sonatrach qui occupe le rang de plus grande entreprise du continent. Premier groupe d&#8217;hydrocarbures en Afrique, la compagnie publique des hydrocarbures, Sonatrach, demeure leader des entreprises implant\u00e9es sur le continent africain.<\/p>\n<blockquote><p><strong> Selon le classement 2021 des \u00ab500 meilleures entreprises africaines\u00bb, r\u00e9alis\u00e9 par le magazine Jeune Afrique, la palme de meilleure entreprise revient \u00e0 Sonatrach, qui vient d&#8217;\u00eatre class\u00e9e au premier rang dans le Top 500 des meilleures entreprises africaines, en 2021. Un classement publi\u00e9 dans un contexte particulier, celui de la crise mondiale du coronavirus, m\u00eame si l&#8217;effet d\u00e9pressif de cette pand\u00e9mie sur l&#8217;activit\u00e9 des soci\u00e9t\u00e9s pour 2021 et au-del\u00e0, reste encore inconnu. Pour mesurer toute l&#8217;ampleur de la crise, il faudra attendre le classement de 2022, listant les comptes de 2021.<\/strong><\/p><\/blockquote>\n<p>En effet, toujours sous l&#8217;emprise des tensions mon\u00e9taires et du yoyo des mati\u00e8res premi\u00e8res, l&#8217;activit\u00e9 des champions du continent a recul\u00e9 pour la deuxi\u00e8me ann\u00e9e cons\u00e9cutive, note la publication. N\u00e9anmoins, Sonatrach tire son \u00e9pingle du jeu en restant num\u00e9ro un, comme ce fut le cas pour les classements pr\u00e9c\u00e9dents, en termes de chiffre d&#8217;affaires, mais aussi de b\u00e9n\u00e9fices. Elle s&#8217;en sort, m\u00eame, plut\u00f4t bien, au moment o\u00f9 les groupes leaders du continent ont globalement vu leur activit\u00e9 marquer le pas.<br \/>\nLe Groupe Sonatrach reste de loin le champion toutes cat\u00e9gories. La palme du plus gros b\u00e9n\u00e9fice en valeur absolue, lui revient encore cette ann\u00e9e (3,9 milliards de dollars) en d\u00e9pit d&#8217;une nouvelle baisse (-0,98%) du chiffre d&#8217;affaires total des entreprises, tandis que le chiffre d&#8217;affaires des \u00ab500 entreprises\u00bb a augment\u00e9 d&#8217;\u00e0 peine 5% depuis 2009. Cette distinction, fort justifi\u00e9e et m\u00e9rit\u00e9e, vient s&#8217;ajouter \u00e0 celle, attribu\u00e9e au pr\u00e9sident-directeur g\u00e9n\u00e9ral de Sonatrach, Toufik Hakkar, qui a \u00e9t\u00e9 class\u00e9, par la revue sp\u00e9cialis\u00e9e Forbes Middle East, comme \u00abcinqui\u00e8me meilleur P-DG dans la liste annuelle des patrons les plus puissants du Moyen-Orient de l&#8217;ann\u00e9e 2021, en reconnaissance \u00e0 leurs \u00abcontributions significatives\u00bb aux \u00e9conomies de la r\u00e9gion. Le classement de Forbes a concern\u00e9 les dirigeants d&#8217;entreprises issus de 24 nationalit\u00e9s, repr\u00e9sentant 21 secteurs. L&#8217;Arabie saoudite est arriv\u00e9e en t\u00eate de liste avec 18 pr\u00e9sident-directeurs g\u00e9n\u00e9raux, suivie des Emirats arabes unis et de l&#8217;Egypte, avec 16 P-DG chacun. Dans son classement, le magazine a tenu compte du fait que Hakkar dirige les projets de Sonatrach, visant \u00e0 investir 40 milliards de dollars au cours des cinq prochaines ann\u00e9es et ce pour augmenter ses niveaux de production, au moment o\u00f9 l&#8217;Alg\u00e9rie cherche \u00e0 relancer son industrie p\u00e9troli\u00e8re. Le magazine Forbes rel\u00e8ve que le P-DG de Sonatrach est \u00e0 la t\u00eate d&#8217;un Groupe qui avait r\u00e9alis\u00e9 un chiffre d&#8217;affaires de 35 milliards de dollars et un b\u00e9n\u00e9fice net de 2,5 milliards de dollars en 2019 et qui compte plus de 200.000 employ\u00e9s, ainsi que 154 filiales, ce qui fait de Sonatrach la seule compagnie africaine \u00e0 d\u00e9velopper des activit\u00e9s depuis l&#8217;exploration p\u00e9troli\u00e8re jusqu&#8217;\u00e0 la pompe \u00e0 essence, a relev\u00e9 une \u00e9tude de l&#8217;Institut fran\u00e7ais des relations internationales (Ifri). Au plan national, Sonatrach, principale pourvoyeuse de devises de l&#8217;Alg\u00e9rie, a attribu\u00e9, en 2020, plus de 1100 contrats \u00e0 des soci\u00e9t\u00e9s locales. Ces contrats de sous-traitance essentiellement, couvrent entre autres, la r\u00e9alisation de r\u00e9seaux de collecteurs, l&#8217;installation de syst\u00e8mes de s\u00e9curit\u00e9 pour la production, la fourniture, l&#8217;installation et la mise en service de syst\u00e8mes de protection, etc. Selon Toufik Hakkar, ces 1.100 accords \u00abrefl\u00e8tent l&#8217;orientation du groupe vers l&#8217;ouverture de ses march\u00e9s et l&#8217;intensification de ses transactions, avec les op\u00e9rateurs locaux\u00bb. \u00c0 terme, cette strat\u00e9gie de la soci\u00e9t\u00e9 entra\u00eenera une meilleure application des normes du contenu local et participera \u00e0 rendre plus comp\u00e9titives les entreprises locales de services p\u00e9tro-gaziers.<\/p>\n<p>Smail Rouha<\/p>\n<p>lexpression.dz\u00a0 \u00a003.06.2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 tout seigneur, tout honneur. Cette ann\u00e9e encore, c&#8217;est l&#8217;ind\u00e9tr\u00f4nable Sonatrach qui occupe le rang de plus grande entreprise du continent. Premier&hellip;<\/p>\n","protected":false},"author":61,"featured_media":19298,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[35],"tags":[],"class_list":["post-19297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Classement des 500 premi\u00e8res entreprises en 2021 Sonatrach tr\u00f4ne sur l\u2019Afrique - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Classement des 500 premi\u00e8res entreprises en 2021 Sonatrach tr\u00f4ne sur l\u2019Afrique - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"\u00c0 tout seigneur, tout honneur. Cette ann\u00e9e encore, c&#8217;est l&#8217;ind\u00e9tr\u00f4nable Sonatrach qui occupe le rang de plus grande entreprise du continent. Premier&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-04T17:30:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/06\/1218157cf38c386523e0306b0f2b224d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Toufan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Toufan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\\\/\"},\"author\":{\"name\":\"Toufan\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\"},\"headline\":\"Classement des 500 premi\u00e8res entreprises en 2021 Sonatrach tr\u00f4ne sur l\u2019Afrique\",\"datePublished\":\"2021-06-04T17:30:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\\\/\"},\"wordCount\":691,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/1218157cf38c386523e0306b0f2b224d.jpg\",\"articleSection\":[\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\\\/\",\"name\":\"Classement des 500 premi\u00e8res entreprises en 2021 Sonatrach tr\u00f4ne sur l\u2019Afrique - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/1218157cf38c386523e0306b0f2b224d.jpg\",\"datePublished\":\"2021-06-04T17:30:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/1218157cf38c386523e0306b0f2b224d.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/1218157cf38c386523e0306b0f2b224d.jpg\",\"width\":850,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Classement des 500 premi\u00e8res entreprises en 2021 Sonatrach tr\u00f4ne sur l\u2019Afrique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\",\"name\":\"Toufan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"caption\":\"Toufan\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/toufan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Classement des 500 premi\u00e8res entreprises en 2021 Sonatrach tr\u00f4ne sur l\u2019Afrique - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/","og_locale":"fr_FR","og_type":"article","og_title":"Classement des 500 premi\u00e8res entreprises en 2021 Sonatrach tr\u00f4ne sur l\u2019Afrique - AAH.JZR","og_description":"\u00c0 tout seigneur, tout honneur. Cette ann\u00e9e encore, c&#8217;est l&#8217;ind\u00e9tr\u00f4nable Sonatrach qui occupe le rang de plus grande entreprise du continent. Premier&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2021-06-04T17:30:39+00:00","og_image":[{"width":850,"height":480,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/06\/1218157cf38c386523e0306b0f2b224d.jpg","type":"image\/jpeg"}],"author":"Toufan","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Toufan","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/"},"author":{"name":"Toufan","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f"},"headline":"Classement des 500 premi\u00e8res entreprises en 2021 Sonatrach tr\u00f4ne sur l\u2019Afrique","datePublished":"2021-06-04T17:30:39+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/"},"wordCount":691,"commentCount":1,"image":{"@id":"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/06\/1218157cf38c386523e0306b0f2b224d.jpg","articleSection":["\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/","url":"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/","name":"Classement des 500 premi\u00e8res entreprises en 2021 Sonatrach tr\u00f4ne sur l\u2019Afrique - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/06\/1218157cf38c386523e0306b0f2b224d.jpg","datePublished":"2021-06-04T17:30:39+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/06\/1218157cf38c386523e0306b0f2b224d.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/06\/1218157cf38c386523e0306b0f2b224d.jpg","width":850,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/classement-des-500-premieres-entreprises-en-2021-sonatrach-trone-sur-lafrique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Classement des 500 premi\u00e8res entreprises en 2021 Sonatrach tr\u00f4ne sur l\u2019Afrique"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f","name":"Toufan","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","caption":"Toufan"},"url":"https:\/\/jazairhope.org\/fr\/author\/toufan\/"}]}},"views":687,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/19297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=19297"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/19297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/19298"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=19297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=19297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=19297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}