{"id":22671,"date":"2021-07-07T13:43:04","date_gmt":"2021-07-07T13:43:04","guid":{"rendered":"https:\/\/jazairhope.org\/?p=22671"},"modified":"2021-07-07T13:43:04","modified_gmt":"2021-07-07T13:43:04","slug":"date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/","title":{"rendered":"Date d&#8217;anniversaire de Dahmane El Harrachi : La voix la plus rauque et la plus chaude de la musique alg\u00e9rienne"},"content":{"rendered":"<p><strong>Par Ali El Hadj Tahar<\/strong><\/p>\n<p>Et \u00e0 croire que tous les maitres du chaabi, cette musique sp\u00e9cifiquement alg\u00e9roise \u00e0 l\u2019origine, ne sont pas des Alg\u00e9rois. Qu\u2019on en juge\u00a0: Hamid Bedjaoui est de Bougie, El Hachemi Guerouabi est de Boudouaou, Amar Ezzahi est de Beni Yenni, Cheikh El Hasnaoui de Taazibt-Ihesnawen, Slimane Azem est d\u2019Agouni Gheghrane, en Kabylie, Matoub Loun\u00e8s de Taourirt Moussa et m\u00eame Kamel Messaoudi qui \u00e9voque la nostalgie d\u2019Alger, est de Fr\u00e9ha, en Kabylie\u2026 Le p\u00e8re d\u2019El Anka, celui de Hadj M\u2019rizek et celui de Boudjema\u00e2 El Ankis sont n\u00e9s en Kabylie. L\u2019ascendant kabyle domine donc largement dans le chaabi, cette musique populaire au vrai sens du terme, qui n\u2019a pas tard\u00e9 \u00e0 rayonner \u00e0 l\u2019\u00e9chelle nationale bien qu\u2019elle soit apparue au d\u00e9but du 20e si\u00e8cle, d\u2019un brassage de genres. Cela traduit on ne peut mieux le m\u00e9tissage et le refus des barri\u00e8res culturelles, aujourd\u2019hui \u00e9rig\u00e9es comme des murs d\u2019intol\u00e9rance. Dahmane El Harrachi va se retrouver dans le terroir m\u00eame de cette musique d\u00e8s son enfance, \u00e0 El Biar puis Belcourt. Mais d\u2019abord d\u00e9finissons ce qu\u2019est le chaabi\u00a0: c\u2019est un genre musical alg\u00e9rien, n\u00e9 \u00e0 Alger et d\u00e9rivant de la musique arabo-andalouse. Il doit son nom \u00e0 El Boudali Safir qui, en 1946, alors qu\u2019il \u00e9tait directeur litt\u00e9raire et artistique de Radio Alg\u00e9rie pour les \u00e9missions en langues arabe et kabyle, d\u00e9signa des musiques provinciales dont faisait partie le medh sous le nom g\u00e9n\u00e9rique de \u00ab populaire \u00bb, dans la langue fran\u00e7aise. Ce n\u2019est qu\u2019apr\u00e8s l\u2019ind\u00e9pendance, et pr\u00e9cis\u00e9ment lors du premier colloque national sur la musique alg\u00e9rienne qui s\u2019est tenu \u00e0 Alger en 1964 que la d\u00e9nomination officielle et d\u00e9finitive de cha\u00e2bi a \u00e9t\u00e9 adopt\u00e9e. Riche, le patrimoine lyrique alg\u00e9rois se composait du medh (chant religieux) qui est l\u2019anc\u00eatre du cha\u00e2bi, mais \u00e9galement d\u2019un autre genre populaire appel\u00e9 aroubi et qui puise ses modes dans la musique arabo-andalouse. Che\u00efkh Nador (d\u00e9c\u00e9d\u00e9 en 1926), \u00e9tait le plus c\u00e9l\u00e8bre de ces chanteurs mais il y avait une pl\u00e9iade de meddahine (interpr\u00e8tes du medh) tels que Mustapha Driou\u00e8che, Kouider Bensmain, El Ounas Khmissa, Mohamed Essafsafi, Sa\u00efd Derraz, Ahmed Meka\u00efssi, Sa\u00efd Laouar, Mahmoud Zaouche.<br \/>\nC\u2019est au d\u00e9but du 20e si\u00e8cle, dans les fumeries de la Casbah d\u2019Alger o\u00f9 des artistes interpr\u00e9taient des istikhbar (improvisation musicale et pr\u00e9lude vocal improvis\u00e9) dans les modes musicaux sika et sahli tout en s\u2019accompagnant d\u2019un guember, qu\u2019est apparu le chaabi. Au d\u00e9part, il s\u2019agissait de chants sacr\u00e9s du medh accompagn\u00e9s par des instruments \u00e0 percussion et des instruments \u00e0 vent. Dans les ann\u00e9es 1920, les textes puis\u00e9s dans les r\u00e9pertoires des po\u00e8tes du Melhoun a commenc\u00e9 \u00e0 dominer, tandis que certains meddah ont apport\u00e9 des notes nouvelles en introduisant des instruments \u00e0 cordes \u00e0 l\u2019image des orchestres du aroubi alg\u00e9rois. Par la suite, les artistes ont commenc\u00e9 \u00e0 adapter les textes et leur interpr\u00e9tation dans les modes andalous de l\u2019\u00e9cole alg\u00e9roise. Les premiers textes profanes sont de Che\u00efkh Sa\u00efd el Meddah de son vrai nom Malek Sa\u00efd qui a r\u00e9alis\u00e9 quatre enregistrements qui datent de 1924 et qui sont gard\u00e9s par la phonoth\u00e8que de la radio alg\u00e9rienne. Apr\u00e8s le d\u00e9c\u00e8s de Che\u00efkh Nador, c\u2019est son \u00e9l\u00e8ve M\u2019hamed El Anka qui prend l\u2019ascendant de l\u2019art musical alg\u00e9rois alors qu\u2019il n\u2019a que 19 ans. El Anka introduit le mandole alg\u00e9rien et devient vite le maitre du medh, \u00e0 l\u2019avantage des moyens techniques modernes du phonographe et de la diffusion radiophonique. Il jouera un r\u00f4le fondamental dans la cr\u00e9ation du chaabi, qui est issu d\u2019un brassage entre trois sources principales : la m\u00e9lodie arabo-andalouse, le melhoun et la po\u00e9sie amoureuse. Il est ind\u00e9niable aussi que ce genre a subi d\u2019autres influences berb\u00e8res, arabe, africaine.<\/p>\n<p><div class=\"ose-youtube ose-uid-e21fe4abca09ad899bcd05ed37534119 ose-embedpress-responsive\" style=\"width:600px; height:550px; max-height:550px; max-width:100%; display:inline-block;\" data-embed-type=\"Youtube\"><iframe allowFullScreen=\"true\" title=\"Dahmane El Harrachi - Ya Rayah \/ \u062f\u062d\u0645\u0627\u0646 \u0627\u0644\u062d\u0631\u0627\u0634\u064a - \u0627\u063a\u0646\u064a\u0629 \u064a\u0627 \u0631\u0627\u064a\u062d \u0648\u064a\u0646 \u0645\u0633\u0627\u0641\u0631\" width=\"600\" height=\"550\" src=\"https:\/\/www.youtube.com\/embed\/kvkRVx16FAI?feature=oembed&color=red&rel=0&controls=1&start=&end=&fs=0&iv_load_policy=0&autoplay=0&mute=0&modestbranding=0&cc_load_policy=1&playsinline=1\" frameborder=\"0\" allow=\"accelerometer; encrypted-media;accelerometer;autoplay;clipboard-write;gyroscope;picture-in-picture clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/p>\n<p><strong>Un petit dipl\u00f4me\u00a0et un banjo\u00a0en bandouli\u00e8re<\/strong><br \/>\nDahmane (diminutif d\u2019Abderrahmane), est n\u00e9 le 7 juillet 1926 \u00e0 El Biar. Son p\u00e8re, Cheikh EI-Amrani, issu du village Djellal dans la wilaya de Khenchela, s\u2019est install\u00e9 \u00e0 Alger en 1920 o\u00f9 il devient muezzin \u00e0 la Grande Mosqu\u00e9e. Apr\u00e8s la naissance de Dahmane, la famille d\u00e9m\u00e9nage \u00e0 Belcourt, rue Maret, avant de s\u2019installer d\u00e9finitivement \u00e0 El Harrach. Benjamin d\u2019une famille de onze enfants, l\u2019enfant poursuit ses \u00e9tudes jusqu\u2019\u00e0 l\u2019obtention du certificat d\u2019\u00e9tudes, un dipl\u00f4me qui sanctionnait la fin des \u00e9tudes pour la majorit\u00e9 des Alg\u00e9riens qui ont pu aller \u00e0 l\u2019\u00e9cole et qui pr\u00e9parait au march\u00e9 de l\u2019emploi. Le certificat d\u2019\u00e9tudes en poche, il gagne sa vie en tant que cordonnier puis, pendant sept ans, comme receveur de tramway sur la ligne reliant Maison Carr\u00e9e \u00e0 Bab El-Oued. Mais il ne perd pas son temps et s\u2019initie tr\u00e8s t\u00f4t au banjo, subissant l\u2019influence du chanteur cha\u00e2bi Khelifa Belkacem qui, lui, est n\u00e9 \u00e0 Kol\u00e9a et a d\u00e9c\u00e9d\u00e9 en 1951. \u00c0 16 ans, il aimait interpr\u00e9ter les chansons de ce dernier et c\u2019est ce qui lui vaut d\u2019int\u00e9grer une troupe d\u2019amateurs avec laquelle il donnait des concerts un peu partout en Alg\u00e9rie. Puis celui qui prendra le surnom de Dahmane El Harrachi, en r\u00e9f\u00e9rence \u00e0 sa commune de r\u00e9sidence, devient vite un virtuose du banjo que beaucoup de chanteurs cha\u00e2bi des ann\u00e9es quarante sollicitent pour les accompagner, notamment Hadj Menouar, Che\u00efkh Bourahla, Che\u00efkh Larbi el Annabi, Abdelkader Ouchala et surtout Cheikh El Hasnaoui avec qui il se produit pour la premi\u00e8re fois au Caf\u00e9 des artistes, rue de Charonne \u00e0 Paris en 1952. Conscient que sa carri\u00e8re est artistique, Dahmane se rend en m\u00e9tropole en 1949 et s\u2019installe \u00e0 Lille, puis \u00e0 Marseille et enfin \u00e0 Paris, ville o\u00f9 il prend racine, vu l\u2019importance de la communaut\u00e9 alg\u00e9rienne. Quand il traitera de l\u2019\u00e9migration c\u2019est donc en connaissance de cause, et quand il aborde des probl\u00e8mes d\u2019ordre social, c\u2019est parce qu\u2019il a v\u00e9cu pareilles situations. Durant toutes les ann\u00e9es o\u00f9 il se produisait dans les caf\u00e9s maghr\u00e9bins des villes de France, il interpr\u00e9tait le r\u00e9pertoire cha\u00e2bi en s\u2019accompagnant d\u2019un banjo. En confrontant le r\u00e9pertoire ancien du chaabi issu du melhoun \u00e9crit entre le 16e et le 19e si\u00e8cles, El Harrachi en d\u00e9couvre le d\u00e9calage par rapport \u00e0 la r\u00e9alit\u00e9 de l\u2019immigration et de la langue daridja pratiqu\u00e9e par les Alg\u00e9riens. Il commence alors \u00e0 \u00e9crire ses propres textes, pour se mettre ne symbiose avec ses auditeurs, en puisant dans leur vie, leurs traditions, leurs habitudes, leurs pr\u00e9occupations et probl\u00e8mes. C\u2019est un nouveau langage musical et po\u00e9tique qui nait alors sous la plume et l\u2019inspiration de Dahmane, pendant que d\u2019autres chanteurs continuant \u00e0 maintenir le chaabi dans le pass\u00e9, sans se soucier de leur \u00e9loignement par rapport \u00e0 la r\u00e9alit\u00e9 socioculturelle et \u00e9conomique. C\u2019est un parler nouveau, abordable, compr\u00e9hensible, serti de paraboles et de tirades bien alg\u00e9eienne qu\u2019introduit Dahmane, pas uniquement une th\u00e9matique actuelle. Ces changements lui permettent d\u2019\u00e9tablir une communication en temps r\u00e9el pas uniquement avec les \u00e9migr\u00e9s alg\u00e9riens mais avec toute la communaut\u00e9 maghr\u00e9bine install\u00e9e en France. En 1956, il enregistre son premier disque chez Path\u00e9 Marconi, alors que la guerre d\u2019ind\u00e9pendance faisait rage. La chanson a pour titre Behdja baydha ma t\u2019houl (Alger la blanche ne perd jamais de son \u00e9clat) et indique son attachement \u00e0 son pays. Si le banjo et le mandole sont des instruments courants dans le chaabi, Dahmane leur donne des sonorit\u00e9s personnelles, sans ces envol\u00e9es lyriques d\u2019un El Anka mais avec une tonalit\u00e9 plus intime et p\u00e9n\u00e9trante. Le r\u00e9pertoire de Dahmane est constitu\u00e9 de pr\u00e8s de 500 chansons dont il est l\u2019auteur. Cette prolixit\u00e9 donne un cachet particulier \u00e0 une \u0153uvre o\u00f9 la parole est incisive, parfois moralisatrice. Tant\u00f4t solennelle, tant\u00f4t ironique, elle met en garde contre l\u2019opportuniste, le menteur, le profiteur\u2026 Elle donne des le\u00e7ons de vie, \u00e0 un moment o\u00f9 la soci\u00e9t\u00e9 \u00e9tait en train de changer et que les brassages unissaient le riche et le pauvre, le citadin et le rural, le cultiv\u00e9 et l\u2019analphab\u00e8te\u2026 Ainsi, elle donne la mesure de changements socioculturels qui font passer d\u2019une \u00e9poque \u00e0 une autre. Ces bouleversements vont s\u2019accentuer \u00e0 l\u2019ind\u00e9pendance, et c\u2019est la morale sociale qu\u2019El Harrachi interpr\u00e8te avec cette voix rocailleuse qui se pr\u00eate tr\u00e8s bien \u00e0 une th\u00e9matique tr\u00e8s vaste qui passe de la nostalgie du pays, aux souffrances de l\u2019exil ou de la s\u00e9paration avec l\u2019aim\u00e9e, de la passion pour sa ville natale \u00e0 l\u2019amiti\u00e9, des ravages de l\u2019alcoolisme au mauvais voisin, de la jalousie aux vicissitudes et d\u00e9boires amoureux\u2026<\/p>\n<p><div class=\"ose-youtube ose-uid-6ae3cc4c18ce7565bdd20fc65a94cb53 ose-embedpress-responsive\" style=\"width:600px; height:550px; max-height:550px; max-width:100%; display:inline-block;\" data-embed-type=\"Youtube\"><iframe allowFullScreen=\"true\" title=\"Dahmane El Harrachi -  bahdja baida\" width=\"600\" height=\"550\" src=\"https:\/\/www.youtube.com\/embed\/v8jhGdavzAY?feature=oembed&color=red&rel=0&controls=1&start=&end=&fs=0&iv_load_policy=0&autoplay=0&mute=0&modestbranding=0&cc_load_policy=1&playsinline=1\" frameborder=\"0\" allow=\"accelerometer; encrypted-media;accelerometer;autoplay;clipboard-write;gyroscope;picture-in-picture clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/p>\n<p><strong>La voix la plus chaude du chaabi<\/strong><br \/>\nJoie de la vie se m\u00ealent \u00e0 ses al\u00e9as dans cette \u0153uvre qui pr\u00eache la droiture, la rigueur morale, la sagesse, la patience et la tol\u00e9rance, et qui ne manque pas de fustiger la malhonn\u00eatet\u00e9, l\u2019hypocrisie, l\u2019ingratitude et la mauvaise foi. En France, la vie n\u2019\u00e9tait pas facile pour la premi\u00e8re g\u00e9n\u00e9ration d\u2019\u00e9migr\u00e9s puisqu\u2019ils vivaient dans des foyers, des bidonvilles. Les mari\u00e9s ne pouvaient pas ramener leurs femmes ni leurs enfants, laiss\u00e9s en Alg\u00e9rie.\u00a0C\u2019est pour cette cat\u00e9gorie d\u2019ouvriers solitaires et frustr\u00e9s que Dahmane va chanter, pour \u00e9gayer leurs soir\u00e9es dans des caf\u00e9s et autres espaces underground. C\u2019est toute leur souffrance qui est condens\u00e9e dans son \u0153uvre mais aussi leur fiert\u00e9, leur attachement au pays, et leur patriotisme puisqu\u2019aucun expatri\u00e9 de cette p\u00e9riode-l\u00e0 ne pensait \u00e0 prendre la nationalit\u00e9 fran\u00e7aise, \u00e0 se naturaliser, \u00e0 \u00ab\u00a0tourner\u00a0\u00bb, comme on disait \u00e0 l\u2019\u00e9poque. Dahmane a pratiquement fait toute sa carri\u00e8re artistique en France et n\u2019a pas manqu\u00e9 de conqu\u00e9rir le public alg\u00e9rien d\u00e8s les ann\u00e9es 1960. C\u2019est surtout apr\u00e8s le Festival de la Musique maghr\u00e9bine qui s\u2019est tenu au d\u00e9but des ann\u00e9es 1970 \u00e0 La Villette que son \u0153uvre d\u00e9barque en force en Alg\u00e9rie. Il ne se produit en public qu\u2019en 1974 \u00e0 la salle Atlas d\u2019Alger o\u00f9 il remporte un franc succ\u00e8s. La t\u00e9l\u00e9vision alg\u00e9rienne ne manque pas de l\u2019enregistrer par trois fois, comme elle lui a consacr\u00e9 un t\u00e9l\u00e9film qui a pour titre saha Dahmane (Salut Dahmane) o\u00f9 il joue son propre r\u00f4le de chanteur cha\u00e2bi. Ce film de Hadj Rahim a \u00e9t\u00e9 tourn\u00e9 juste avant sa disparition dans un accident de la route survenu le 31 ao\u00fbt 1980 \u00e0 A\u00efn Benian. Contrairement \u00e0 ce qui s\u2019\u00e9crit \u00e7a et l\u00e0, Dahmane n\u2019\u00e9tait pas consid\u00e9r\u00e9 comme un paria politique, et ses chansons \u2014 ni celles d\u2019Ahmed Saber \u2014 n\u2019ont \u00e9t\u00e9 censur\u00e9es ou interdites, que ce soit sous Benbella ou sous Boumedi\u00e8ne. Le parcours artistique d\u2019El Harrachi se confond avec son itin\u00e9raire dans la vie, avec son exp\u00e9rience d\u2019artiste confiant en ses capacit\u00e9s et auquel le public a vite r\u00e9pondu, adoptant et la voix originale et la musique qui n\u2019est pas rest\u00e9e fig\u00e9e dans les modes du chaabi mais qui l\u2019a adapt\u00e9 \u00e0 sa th\u00e9matique. De plus, El Harrachi la chanson d\u2019El Harrachi se r\u00e9sume \u00e0 quelques minutes, alors que tous les autres chanteurs \u00e9taient encore prisonniers des longues qacidates. Cette voix originale, dissonante par rapport aux belles voix douces et fluettes, qui n\u2019a son \u00e9quivalent que dans le blues am\u00e9ricain ou dans la pop music et le rock plus tard, n\u2019a pas \u00e9t\u00e9 du gout du producteur La voix du Globe qui a cru que le chanteur \u00e9tait enrhum\u00e9. Ce n\u2019est que plus tard qu\u2019Ahmed Hachelaf, responsable \u00e0 l\u2019\u00e9poque chez Path\u00e9 Marconi, \u00e0 Paris, produira le disque en 1956. C\u2019est en tout cas ce que dit le po\u00e8te Kamel Hamadi dans le documentaire consacr\u00e9 \u00e0 l\u2019artiste et intitul\u00e9 Thawratou El Harrachi\u00a0 (La r\u00e9volution d\u2019El Harrachi), film \u00e9crit et con\u00e7u par l\u2019Alg\u00e9rien Mourad Ouabbas et r\u00e9alis\u00e9 par la Libanaise Farah Alame. Rabbi blani bi ettassa (Dieu m\u2019a afflig\u00e9 du vice de l\u2019alcool), ya kassi alache rak zayed li fi eddemar (O verre pourquoi tu en ajoutes \u00e0 mon affliction\u00a0?) ne sont pas les seules chansons sur ce sujet, mais contrairement aux autres chansons andalouses ou chaabie, o\u00f9 l\u2019ivresse est une source d\u2019inspiration et d\u2019oubli, Dahmane en \u00e9voque les fl\u00e9aux, la d\u00e9pendance, la perte de temps et d\u2019argent\u2026 L\u2019\u00e9migration a la part du lion chez cet artiste, et l\u2019une des plus connues sur ce th\u00e8me est Ya Rayah (\u00d4 partant), qui a connu un grand succ\u00e8s \u00e0 sa sortie en France en 1973. Elle est l\u2019une des chansons les plus reprises, notamment par Rachid Taha en 1997, mais aussi la plus traduite de la chanson alg\u00e9rienne. Le style El Harrachi se confond avec l\u2019homme. La voix la plus chaude du chaabi est celle d\u2019un r\u00e9pertoire o\u00f9 l\u2019amour est souvent contrari\u00e9, malchanceux, o\u00f9 l\u2019homme se juge par ses valeurs humaines\u2026 El Harrachi a fait du chaabi une \u00e9cole de vie et d\u2019enseignement de principes fondamentaux \u00e0 une \u00e9poque o\u00f9 l\u2019art avait fonction \u00e9thique et esth\u00e9tique en m\u00eame temps. Dahmane El-Harrachi, ce joyeux et triste bonhomme, est mort le 31 ao\u00fbt 1980 dans un accident de la circulation sur la c\u00f4te alg\u00e9roise.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=9QxzM-MY2Nw<br \/>\n<strong><em>A.E.T.<\/em><\/strong><\/p>\n<p>lecourier-dalgerie.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Ali El Hadj Tahar Et \u00e0 croire que tous les maitres du chaabi, cette musique sp\u00e9cifiquement alg\u00e9roise \u00e0 l\u2019origine, ne sont&hellip;<\/p>\n","protected":false},"author":61,"featured_media":22672,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[32,34,42],"tags":[],"class_list":["post-22671","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-algerie","category-art-fr","category-histoire-et-patrimoine","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Date d&#039;anniversaire de Dahmane El Harrachi : La voix la plus rauque et la plus chaude de la musique alg\u00e9rienne - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Date d&#039;anniversaire de Dahmane El Harrachi : La voix la plus rauque et la plus chaude de la musique alg\u00e9rienne - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Par Ali El Hadj Tahar Et \u00e0 croire que tous les maitres du chaabi, cette musique sp\u00e9cifiquement alg\u00e9roise \u00e0 l\u2019origine, ne sont&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-07T13:43:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/Dahmane-El-Harrachi-502x330-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"502\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Toufan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Toufan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\\\/\"},\"author\":{\"name\":\"Toufan\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\"},\"headline\":\"Date d&#8217;anniversaire de Dahmane El Harrachi : La voix la plus rauque et la plus chaude de la musique alg\u00e9rienne\",\"datePublished\":\"2021-07-07T13:43:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\\\/\"},\"wordCount\":2401,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Dahmane-El-Harrachi-502x330-1.jpg\",\"articleSection\":[\"Alg\u00e9rie Alg\u00e9rienne\",\"Art &amp; Culture\",\"Histoire et Patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\\\/\",\"name\":\"Date d'anniversaire de Dahmane El Harrachi : La voix la plus rauque et la plus chaude de la musique alg\u00e9rienne - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Dahmane-El-Harrachi-502x330-1.jpg\",\"datePublished\":\"2021-07-07T13:43:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Dahmane-El-Harrachi-502x330-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Dahmane-El-Harrachi-502x330-1.jpg\",\"width\":502,\"height\":330},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Date d&rsquo;anniversaire de Dahmane El Harrachi : La voix la plus rauque et la plus chaude de la musique alg\u00e9rienne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7307bafab49aeb129fb6fc80d18d5a4f\",\"name\":\"Toufan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g\",\"caption\":\"Toufan\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/toufan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Date d'anniversaire de Dahmane El Harrachi : La voix la plus rauque et la plus chaude de la musique alg\u00e9rienne - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/","og_locale":"fr_FR","og_type":"article","og_title":"Date d'anniversaire de Dahmane El Harrachi : La voix la plus rauque et la plus chaude de la musique alg\u00e9rienne - AAH.JZR","og_description":"Par Ali El Hadj Tahar Et \u00e0 croire que tous les maitres du chaabi, cette musique sp\u00e9cifiquement alg\u00e9roise \u00e0 l\u2019origine, ne sont&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2021-07-07T13:43:04+00:00","og_image":[{"width":502,"height":330,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/Dahmane-El-Harrachi-502x330-1.jpg","type":"image\/jpeg"}],"author":"Toufan","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Toufan","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/"},"author":{"name":"Toufan","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f"},"headline":"Date d&#8217;anniversaire de Dahmane El Harrachi : La voix la plus rauque et la plus chaude de la musique alg\u00e9rienne","datePublished":"2021-07-07T13:43:04+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/"},"wordCount":2401,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/Dahmane-El-Harrachi-502x330-1.jpg","articleSection":["Alg\u00e9rie Alg\u00e9rienne","Art &amp; Culture","Histoire et Patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/","url":"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/","name":"Date d'anniversaire de Dahmane El Harrachi : La voix la plus rauque et la plus chaude de la musique alg\u00e9rienne - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/Dahmane-El-Harrachi-502x330-1.jpg","datePublished":"2021-07-07T13:43:04+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/Dahmane-El-Harrachi-502x330-1.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/Dahmane-El-Harrachi-502x330-1.jpg","width":502,"height":330},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/date-danniversaire-de-dahmane-el-harrachi-la-voix-la-plus-rauque-et-la-plus-chaude-de-la-musique-algerienne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Date d&rsquo;anniversaire de Dahmane El Harrachi : La voix la plus rauque et la plus chaude de la musique alg\u00e9rienne"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7307bafab49aeb129fb6fc80d18d5a4f","name":"Toufan","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6356c3a1b9302a43412244ff56ef2d8361d6ade233460e836f432cc74fa7c2f?s=96&d=mm&r=g","caption":"Toufan"},"url":"https:\/\/jazairhope.org\/fr\/author\/toufan\/"}]}},"views":684,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/22671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=22671"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/22671\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/22672"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=22671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=22671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=22671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}