{"id":24851,"date":"2021-07-24T16:29:06","date_gmt":"2021-07-24T16:29:06","guid":{"rendered":"https:\/\/jazairhope.org\/?p=24851"},"modified":"2021-07-24T16:29:06","modified_gmt":"2021-07-24T16:29:06","slug":"lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/","title":{"rendered":"l&#8217;Alg\u00e9rie savait ce que se pr\u00e9parait \u00e0 nos fronti\u00e8re Ouest"},"content":{"rendered":"<p style=\"text-align: left\"><strong>M.Ammar belhimer avait accord\u00e9 le mois de F\u00e9vrier dernier un entretient avec le journal echoroukonline et ce pour parler de guerre cybern\u00e9tique qui se pr\u00e9parait \u00e0 nos fronti\u00e8re Ouest dont les acteurs principaux sont l&#8217;ennemi sioniste, bien entendu et nos &#8220;fr\u00e8res&#8221; marocains&#8230;.fournissant leurs terres entant que base g\u00e9ante et ce pour les besoins des n\u00e9o- imp\u00e9rialistes afin de d\u00e9truire l&#8217;un des dernier remparts qui r\u00e9siste encore \u00e0 leur h\u00e9g\u00e9monie: L&#8217;Alg\u00e9rie\u00a0<\/strong><\/p>\n<p><strong>Mais la question qui se pose: pourquoi monsieur le ministre porte parole du gouvernement divulgua ce genre d&#8217;informations;\u00a0 est ce le peuple alg\u00e9rien qui \u00e9tait cibl\u00e9 ?? je ne pense pas , il parlait s&#8217;adossant \u00e0 des rapports top secret qui lui \u00e9taient donn\u00e9s par le renseignement alg\u00e9rien &#8230;..et pourquoi on apprend maintenant, six mois apr\u00e8s, que ce que disait le ministre \u00e9tait enfin pris aux s\u00e9rieux par les \u00e9tats , d\u00e9velopp\u00e9s ou pas, et se sont enfin mis \u00e0 d\u00e9fendre leur int\u00e9r\u00eats , chacun \u00e0 sa fa\u00e7on ??? Est ce que l&#8217;Alg\u00e9rie poss\u00e9derait les preuves desdits \u00e9coutes-espionnage et les a mises \u00e0 disposition de ceux qui en veulent ??<\/strong><br \/>\n<b>Les 6 mois , depuis l\u2019Alerte jusqu&#8217;\u00e0 pr\u00e9sent, n&#8217;\u00e9taient que chantage diplomatique entrepris par Alger et ce pour pousser\u00a0 Rabat \u00e0 c\u00e9der &#8230;Mais les enjeux \u00e9taient de tailles pour ces derniers et leurs ma\u00eetres\u00a0 &#8230;.ils ont pr\u00e9f\u00e9r\u00e9 pousser le bouchon encore plus loins, en guise d&#8217;ffensive plein puissance et le r\u00e9sultat est l\u00e0 : \u00e9chec total aux Sionistes, fran\u00e7ais &#8230;. et enfin le makhzen.<\/b><\/p>\n<p><strong>\u00a0Mohamed Redha Chettibi\u00a0<\/strong><\/p>\n<h2 style=\"text-align: right\"><span style=\"color: #000000\"><strong>:\u0641\u064a\u0645\u0627 \u064a\u0644\u064a \u0627\u0644\u062d\u0648\u0627\u0631 \u0627\u0644\u0643\u0627\u0645<\/strong>\u0644<\/span><\/h2>\n<p style=\"text-align: right\"><strong>\u0642\u062f\u0645 \u0648\u0632\u064a\u0631 \u0627\u0644\u0627\u062a\u0635\u0627\u0644\u060c \u0627\u0644\u0646\u0627\u0637\u0642 \u0628\u0627\u0633\u0645 \u0627\u0644\u062d\u0643\u0648\u0645\u0629\u060c \u0639\u0645\u0627\u0631 \u0628\u0644\u062d\u064a\u0645\u0631\u060c \u062a\u0641\u0627\u0635\u064a\u0644 \u0645\u062b\u064a\u0631\u0629 \u0639\u0646 \u0627\u0644\u062d\u0631\u0628 \u0627\u0644\u0633\u064a\u0628\u0631\u0627\u0646\u064a\u0629 \u0627\u0644\u062a\u064a \u064a\u0642\u0648\u062f\u0647\u0627 \u0627\u0644\u0643\u064a\u0627\u0646 \u0627\u0644\u0635\u0647\u064a\u0648\u0646\u064a \u0648\u0623\u0639\u0648\u0627\u0646 \u0627\u0644\u0646\u0638\u0627\u0645 \u0627\u0644\u0645\u063a\u0631\u0628\u064a \u0636\u062f \u0627\u0644\u062c\u0632\u0627\u0626\u0631\u060c \u0645\u0646 \u062e\u0644\u0627\u0644 \u062d\u062f\u064a\u062b\u0647 \u0639\u0646 \u062d\u0627\u0644\u0629 \u0645\u0648\u0642\u0639 \u201c\u0627\u0644\u0634\u0631\u0648\u0642 \u0623\u0648\u0646 \u0644\u0627\u064a\u0646\u201d \u0627\u0644\u0630\u064a \u064a\u062a\u0639\u0631\u0636 \u0625\u0644\u0649 \u0647\u062c\u0648\u0645 \u0645\u0643\u062b\u0641 \u0641\u064a \u0627\u0644\u0641\u062a\u0631\u0629 \u0627\u0644\u0623\u062e\u064a\u0631\u0629 \u0645\u0646\u0630 \u062a\u062c\u062f\u062f \u0627\u0644\u062a\u0648\u062a\u0631 \u0641\u064a \u0645\u0646\u0637\u0642\u0629 \u0627\u0644\u0643\u0631\u0643\u0631\u0627\u062a.<\/strong><\/p>\n<p style=\"text-align: right\"><strong>\u0648\u0643\u0634\u0641 \u0641\u064a \u062d\u0648\u0627\u0631 \u0645\u0639 \u201c\u0627\u0644\u0634\u0631\u0648\u0642\u201d \u0628\u0627\u0644\u0623\u0631\u0642\u0627\u0645 \u0648\u0627\u0644\u0645\u0624\u0634\u0631\u0627\u062a \u0639\u0646 \u062d\u0642\u0627\u0626\u0642 \u0627\u0644\u062d\u0631\u0628 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629 \u0636\u062f \u0627\u0644\u0645\u0624\u0633\u0633\u0629\u060c \u0648\u0645\u0627 \u064a\u0642\u0648\u0645 \u0628\u0647 \u0627\u0644\u0643\u064a\u0627\u0646 \u0627\u0644\u0635\u0647\u064a\u0648\u0646\u064a \u0645\u0646 \u0623\u0628\u062d\u0627\u062b \u0639\u0633\u0643\u0631\u064a\u0629 \u0641\u064a \u0627\u0644\u0628\u0631\u0645\u062c\u064a\u0627\u062a \u0627\u0644\u0647\u062c\u0648\u0645\u064a\u0629 \u0648\u062a\u0637\u0628\u064a\u0642\u0627\u062a\u0647\u0627 \u0627\u0644\u0645\u062f\u0646\u064a\u0629 \u0641\u064a \u0627\u0644\u0641\u0636\u0627\u0621 \u0627\u0644\u0633\u064a\u0628\u064a\u0631\u0627\u0646\u064a\u060c \u0648\u0627\u0644\u062a\u064a \u064a\u062a\u0645 \u0628\u064a\u0639\u0647\u0627 \u0644\u0644\u062f\u0648\u0644 \u0627\u0644\u062a\u064a \u062a\u0631\u063a\u0628 \u0641\u064a \u0627\u0644\u062a\u062c\u0633\u0633 \u0639\u0644\u0649 \u0645\u0648\u0627\u0637\u0646\u064a\u0647\u0627 \u0648\u0643\u0630\u0627 \u0644\u0644\u062f\u0648\u0644 \u0627\u0644\u0645\u062a\u0646\u0627\u0632\u0639\u0629\u060c \u0648\u0641\u064a \u0645\u0642\u062f\u0645\u062a\u0647\u0627 \u0627\u0644\u0645\u063a\u0631\u0628.<\/strong><\/p>\n<p style=\"text-align: right\"><img decoding=\"async\" class=\"aligncenter wp-image-595952 lazy entered loaded\" src=\"https:\/\/www.echoroukonline.com\/2017-wp-content\/uploads\/2021\/02\/ech.jpg\" alt=\"\" width=\"690\" \/><\/p>\n<p style=\"text-align: right\"><strong>\u0648\u0633\u0639\u064a\u0627 \u0625\u0644\u0649 \u0627\u0644\u062a\u0635\u062f\u064a \u0644\u0645\u062b\u0644 \u0647\u0630\u0647 \u0627\u0644\u0627\u062e\u062a\u0631\u0627\u0642\u0627\u062a \u0648\u0643\u0627\u0641\u0629 \u0627\u0644\u0645\u062e\u0627\u0637\u0631 \u0648\u0627\u0644\u062a\u0647\u062f\u064a\u062f\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u062d\u0645\u0644\u0647\u0627 \u0627\u0644\u0639\u0627\u0644\u0645 \u0627\u0644\u0633\u064a\u0628\u0631\u064a\u0627\u0646\u064a\u060c \u0623\u0643\u062f \u0627\u0644\u0648\u0632\u064a\u0631 \u0623\u0646 \u0627\u0644\u062c\u0632\u0627\u0626\u0631 \u062a\u0639\u0645\u0644 \u0628\u062c\u062f \u0639\u0644\u0649 \u0645\u0648\u0627\u062c\u0647\u0629 \u0647\u0630\u0647 \u0627\u0644\u0638\u0627\u0647\u0631\u0629\u060c \u0644\u0627\u0633\u064a\u0645\u0627 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0625\u0646\u062a\u0627\u062c \u0645\u062d\u062a\u0648\u0649 \u0648\u0637\u0646\u064a \u0646\u0648\u0639\u064a \u0639\u0644\u0649 \u0627\u0644\u0645\u0648\u0627\u0642\u0639 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629 \u0627\u0644\u0625\u0639\u0644\u0627\u0645\u064a\u0629 \u0648\u0627\u0644\u0623\u0631\u0636\u064a\u0627\u062a \u0627\u0644\u0639\u0644\u0645\u064a\u0629\u060c \u0648\u064a\u0634\u0645\u0644 \u0647\u0630\u0627 \u0627\u0644\u0645\u0633\u0639\u0649 \u0623\u064a\u0636\u0627 \u062a\u0623\u0645\u064a\u0646 \u0627\u0644\u0634\u0628\u0643\u0629 \u062a\u0643\u0631\u064a\u0633\u0627 \u0644\u0633\u064a\u0627\u062f\u0629 \u0627\u0644\u062f\u0648\u0644\u0629 \u0639\u0644\u0649 \u0645\u062c\u0627\u0644 \u0627\u0644\u0631\u0642\u0645\u0646\u0629.<\/strong><br \/>\n<strong>\u0643\u0645\u0627 \u0634\u062f\u0651\u062f \u0639\u0644\u0649 \u0623\u0646 \u0645\u0627 \u062a\u062d\u0630\u0631 \u0645\u0646\u0647 \u0627\u0644\u0633\u0644\u0637\u0627\u062a \u0628\u0647\u0630\u0627 \u0627\u0644\u0635\u062f\u062f \u0644\u064a\u0633 \u0646\u0633\u062c\u064b\u0627 \u0645\u0646 \u0627\u0644\u062e\u064a\u0627\u0644\u060c \u0648\u0644\u0627 \u0627\u062c\u062a\u0631\u0627\u0631\u0627 \u0644\u0645\u0627 \u064a\u0639\u0631\u0641 \u0628\u0640\u201d\u0627\u0644\u0639\u062f\u0648 \u0627\u0644\u062e\u0627\u0631\u062c\u064a\u201d \u0633\u0639\u064a\u0627 \u0625\u0644\u0649 \u0627\u0644\u062d\u064a\u0644\u0648\u0644\u0629 \u062f\u0648\u0646 \u062a\u0645\u0643\u064a\u0646 \u0645\u0627 \u064a\u0633\u0645\u0649 \u0628\u0627\u0644\u062f\u064a\u0645\u0642\u0631\u0627\u0637\u064a\u064a\u0646 \u0645\u0646 \u0627\u0644\u062a\u0638\u0627\u0647\u0631\u060c \u0644\u0623\u0646 \u0627\u0644\u062a\u0638\u0627\u0647\u0631 \u062d\u0642 \u0645\u0643\u0631\u0633 \u062f\u0633\u062a\u0648\u0631\u064a\u064b\u0627 \u0648\u0645\u0624\u0637\u0631 \u0642\u0627\u0646\u0648\u0646\u0627\u060c \u0639\u0644\u0649 \u062d\u062f \u062a\u0639\u0628\u064a\u0631\u0647.<\/strong><\/p>\n<p style=\"text-align: right\"><strong>\u0645\u0646 \u062c\u0647\u0629 \u0623\u062e\u0631\u0649\u060c \u0623\u0639\u0631\u0628 \u0639\u0646 \u062a\u0623\u064a\u064a\u062f\u0647 \u0634\u062e\u0635\u064a\u0627 \u0644\u062a\u0639\u0632\u064a\u0632 \u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u062d\u064a\u0627\u0629 \u0627\u0644\u062e\u0627\u0635\u0629 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0633\u0646\u0651 \u0623\u0642\u0635\u0649 \u0627\u0644\u0639\u0642\u0648\u0628\u0627\u062a \u0628\u063a\u0636 \u0627\u0644\u0646\u0638\u0631 \u0639\u0646 \u062f\u0648\u0627\u0641\u0639 \u0627\u0644\u0645\u0639\u062a\u062f\u064a \u0648\u0645\u0631\u0643\u0632\u0647 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639<\/strong>\u064a.<\/p>\n<h4 style=\"text-align: right\"><strong>\u0643\u062b\u0631 \u062d\u062f\u064a\u062b\u0643\u0645 \u0639\u0646 \u0627\u0644\u062d\u0631\u0628 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629 \u0648\u0639\u0646 \u0627\u0644\u062a\u0647\u062f\u064a\u062f\u0627\u062a \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629 \u0644\u0644\u0633\u064a\u0627\u062f\u0629 \u0648\u0627\u0644\u0623\u0645\u0646 \u0648\u0627\u0644\u0646\u0638\u0627\u0645 \u0627\u0644\u0639\u0627\u0645\u060c \u0623\u0644\u0627 \u062a\u0631\u0648\u0646 \u0623\u0646 \u0647\u0646\u0627\u0643 \u0645\u0628\u0627\u0644\u063a\u0629 \u0641\u064a \u0627\u0644\u0645\u0648\u0636\u0648\u0639\u061f<\/strong><\/h4>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-595941 lazy entered loaded\" src=\"https:\/\/www.echoroukonline.com\/2017-wp-content\/uploads\/2021\/02\/MAM_7608.jpg\" alt=\"\" width=\"690\" \/><\/p>\n<p style=\"text-align: right\">\u0625<strong>\u0646 \u0645\u0627 \u0646\u062d\u0630\u0631 \u0645\u0646\u0647 \u0644\u064a\u0633 \u0646\u0633\u062c\u064b\u0627 \u0645\u0646 \u0627\u0644\u062e\u064a\u0627\u0644\u060c \u0648\u0644\u0627 \u0627\u062c\u062a\u0631\u0627\u0631\u0627 \u0644\u0645\u0627 \u064a\u0639\u0631\u0641 \u0628\u0640\u201d\u0627\u0644\u0639\u062f\u0648 \u0627\u0644\u062e\u0627\u0631\u062c\u064a\u201d \u0633\u0639\u064a\u0627 \u0625\u0644\u0649 \u0627\u0644\u062d\u064a\u0644\u0648\u0644\u0629 \u062f\u0648\u0646 \u062a\u0645\u0643\u064a\u0646 \u0645\u0627 \u064a\u0633\u0645\u0649 \u0628\u0627\u0644\u062f\u064a\u0645\u0642\u0631\u0627\u0637\u064a\u064a\u0646 \u0645\u0646 \u0627\u0644\u062a\u0638\u0627\u0647\u0631\u060c \u0644\u0623\u0646 \u0627\u0644\u062a\u0638\u0627\u0647\u0631 \u062d\u0642 \u0645\u0643\u0631\u0633 \u0633\u062a\u0648\u0631\u064a\u064b\u0627 \u0648\u0645\u0624\u0637\u0631 \u0642\u0627\u0646\u0648\u0646\u0627.\u0641\u0627\u0644\u0642\u0627\u0646\u0648\u0646 \u0627\u0644\u0641\u0631\u0646\u0633\u064a\u060c \u0645\u062b\u0644\u0627\u060c \u064a\u064f\u0639\u0631\u0651\u0641 \u0627\u0644\u0641\u0636\u0627\u0621 \u0627\u0644\u0633\u064a\u0628\u0631\u064a\u0627\u0646\u064a \u0628\u0628\u0633\u0627\u0637\u0629 \u0628\u0643\u0648\u0646\u0647: \u201c\u0627\u0644\u0641\u0636\u0627\u0621 \u0627\u0644\u0645\u0643\u0648\u0646 \u0645\u0646 \u0628\u0646\u0649 \u062a\u062d\u062a\u064a\u0629 \u0645\u062a\u0631\u0627\u0628\u0637\u0629 \u062a\u062a\u0639\u0644\u0642 \u0628\u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0627 \u0627\u0644\u0625\u0639\u0644\u0627\u0645\u060c \u0648\u0644\u0627 \u0633\u064a\u0645\u0627 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a\u060c \u0648\u0628\u0627\u0644\u0645\u0639\u0637\u064a\u0627\u062a \u0627\u0644\u062a\u064a \u062a \u0645\u0639\u0627\u0644\u062c\u062a\u0647\u0627 \u0639\u0644\u0649 \u0647\u0630\u0627 \u0627\u0644\u0645\u0633\u062a\u0648\u0649\u201d.<\/strong><br \/>\n<strong>\u0648\u064a\u0648\u062c\u062f \u0647\u0630\u0627 \u0627\u0644\u0641\u0636\u0627\u0621 \u0641\u064a \u0642\u0644\u0628 \u0643\u0627\u0641\u0629 \u0627\u0644\u0623\u0637\u0645\u0627\u0639 \u0627\u0644\u0631\u0627\u0645\u064a\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u064a\u0637\u0631\u0629 \u0639\u0644\u064a\u0647 \u0644\u0633\u0628\u0628 \u0631\u0626\u064a\u0633 \u064a\u062a\u0645\u062b\u0644 \u0641\u064a\u0645\u0627 \u064a\u062a\u0645\u062a\u0639 \u0628\u0647 \u0645\u0646 \u0642\u0648\u0629 \u0627\u0633\u062a\u0642\u0637\u0627\u0628 \u0644\u062f\u0649 \u0627\u0644\u0645\u0648\u0627\u0637\u0646\u064a\u0646 \u0644\u0627\u0633\u064a\u0645\u0627 \u0641\u0626\u0629 \u0627\u0644\u0634\u0628\u0627\u0628. \u0641\u0641\u064a \u0633\u0646\u0629 2020\u060c \u0627\u0633\u062a\u0642\u0637\u0628 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a \u0645\u0627 \u064a\u0642\u0631\u0628 60\u066a \u0645\u0646 \u0633\u0643\u0627\u0646 \u0627\u0644\u0639\u0627\u0644\u0645\u060c \u0648\u0647\u0648 \u0645\u0627 \u064a\u0645\u062b\u0644 4.5 \u0645\u0644\u064a\u0627\u0631 \u0634\u062e\u0635\u060c \u0645\u0646\u0647\u0645 3.8 \u0645\u0644\u064a\u0627\u0631 \u064a\u0645\u062a\u0644\u0643\u0648\u0646 \u062d\u0633\u0627\u0628\u0627\u062a \u0639\u0644\u0649 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a.<\/strong><br \/>\n<strong>\u0641\u0627\u0644\u064a\u0648\u0645 \u062c\u0645\u064a\u0639 \u0627\u0644\u062f\u0648\u0644 \u062a\u062a\u0645\u062a\u0639 \u0628\u0639\u0642\u064a\u062f\u0629 \u0631\u0633\u0645\u064a\u0629 \u062e\u0627\u0635\u0629 \u0628\u0627\u0644\u0645\u062d\u0627\u0631\u0628\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629 \u0627\u0644\u0631\u0633\u0645\u064a\u0629\/Lutte informatique officielle(LIO) \u062a\u0647\u062f\u0641 \u0625\u0644\u0649 \u062a\u0623\u0637\u064a\u0631 \u0627\u0644\u0646\u0634\u0627\u0637\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u062a\u0645 \u0627\u062a\u062e\u0627\u0630\u0647\u0627 \u0641\u064a \u0627\u0644\u0641\u0636\u0627\u0621 \u0627\u0644\u0633\u064a\u0628\u0631\u064a\u0627\u0646\u064a\u060c \u0642\u0635\u062f \u0627\u0644\u062a\u0623\u062b\u064a\u0631 \u0639\u0644\u0649 \u0627\u0644\u0623\u0646\u0638\u0645\u0629 \u0627\u0644\u0645\u0639\u0627\u062f\u064a\u0629\u060c \u0648\u0627\u0644\u0645\u0633\u0627\u0633 \u0628\u0648\u0641\u0631\u0629 \u0623\u0648 \u0633\u0631\u064a\u0629 \u0627\u0644\u0645\u0639\u0637\u064a\u0627\u062a.<\/strong><br \/>\n<strong>\u0625\u0646 \u0627\u0644\u0633\u064a\u0637\u0631\u0629 \u0627\u0644\u0645\u0630\u0643\u0648\u0631\u0629 \u062a\u062a\u0639\u0644\u0642 \u0628\u0631\u0647\u0627\u0646\u0627\u062a \u0627\u0644\u0637\u0628\u0642\u0627\u062a \u0627\u0644\u062b\u0644\u0627\u062b \u0644\u0644\u0641\u0636\u0627\u0621 \u0627\u0644\u0633\u064a\u0628\u0631\u0627\u0646\u064a:<\/strong><br \/>\n<strong>\u2013 \u0627\u0644\u0637\u0628\u0642\u0629 \u0627\u0644\u0645\u0627\u062f\u064a\u0629 \u0627\u0644\u0645\u0643\u0648\u0646\u0629 \u0645\u0646 \u0627\u0644\u0628\u0646\u064a\u0629 \u0627\u0644\u062a\u062d\u062a\u064a\u0629 \u0648\u0645\u0639\u062f\u0627\u062a \u0627\u0644\u0645\u0639\u0627\u0644\u062c\u0629 \u0627\u0644\u0622\u0644\u064a\u0629 \u0648\u0627\u0644\u0623\u0634\u064a\u0627\u0621 (\u0627\u0644\u0643\u0627\u0628\u0644\u0627\u062a \u0648\u0627\u0644\u062e\u0648\u0627\u062f\u0645 \u0648\u0623\u062c\u0647\u0632\u0629 \u0627\u0644\u0643\u0645\u0628\u064a\u0648\u062a\u0631 \u0648\u0645\u0627 \u0625\u0644\u0649 \u0630\u0644\u0643)\u061b<\/strong><br \/>\n<strong>\u2013 \u0637\u0628\u0642\u0629 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0627\u0644\u0631\u0642\u0645\u064a\u0629 \u0648\u0648\u0633\u0627\u0626\u0644 \u0646\u0642\u0644\u0647\u0627 \u0641\u064a \u0627\u0644\u0634\u0628\u0643\u0627\u062a (\u0628\u0631\u0648\u062a\u0648\u0643\u0648\u0644\u0627\u062a\u060c \u062a\u0637\u0628\u064a\u0642\u0627\u062a\u060c \u0648\u0627\u062c\u0647\u0627\u062a\u060c \u0625\u0644\u062e)\u061b<\/strong><br \/>\n<strong>\u2013 \u0627\u0644\u0637\u0628\u0642\u0629 \u0627\u0644\u062f\u0644\u0627\u0644\u064a\u0629 \u0648\u062a\u0634\u0645\u0644 \u0627\u0644\u0645\u0633\u062a\u062e\u062f\u0645\u064a\u0646 \u0648\u0627\u0644\u0645\u0628\u0627\u062f\u0644\u0627\u062a \u0641\u064a \u0627\u0644\u0648\u0642\u062a \u0627\u0644\u0641\u0639\u0644\u064a \u0648\u0627\u0644\u0634\u0628\u0643\u0627\u062a \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a\u0629 \u0648\u0627\u0644\u0645\u062d\u062a\u0648\u064a\u0627\u062a \u0627\u0644\u0645\u062a\u062f\u0627\u0648\u0644\u0629 \u0639\u0644\u0649 \u0647\u0630\u0627 \u0627\u0644\u0645\u0633\u062a\u0648\u0649.<\/strong><br \/>\n<strong>\u0625\u0646 \u0627\u0644\u0639\u0645\u0644\u064a\u0627\u062a \u0627\u0644\u0633\u0631\u064a\u0629 \u0641\u064a \u0627\u0644\u0641\u0636\u0627\u0621 \u0627\u0644\u0633\u064a\u0628\u0631\u0627\u0646\u064a \u062a\u062a\u0639\u0644\u0642 \u0628\u0627\u0644\u062c\u0648\u0633\u0633\u0629 \u0648\u0627\u0644\u062a\u062e\u0631\u064a\u0628\u060c \u0648\u0643\u0630\u0627 \u0627\u0644\u062a\u062f\u0645\u064a\u0631 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u062f\u0639\u0627\u064a\u0629 \u0648\u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0627\u0644\u0645\u063a\u0631\u0636\u0629\u060c \u0628\u0642\u0635\u062f \u062a\u0642\u0648\u064a\u0636 \u0623\u0633\u0633 \u0627\u0644\u0633\u0644\u0637\u0629 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0645\u0647\u0627\u062c\u0645\u062a\u0647\u0627 \u0648\u062a\u0634\u0648\u064a\u0647 \u0633\u0645\u0639\u062a\u0647\u0627 \u0641\u064a \u0645\u062c\u0627\u0644 \u0627\u0644\u0642\u064a\u0645 \u0648\u062a\u062c\u0631\u064a\u062f\u0647\u0627 \u0645\u0646 \u0627\u0644\u0634\u0631\u0639\u064a\u0629.<\/strong><br \/>\n<strong>\u0644\u062a\u062d\u0642\u064a\u0642 \u0630\u0644\u0643\u060c \u0641\u0625\u0646\u0647\u0645 \u064a\u0633\u0644\u0643\u0648\u0646 \u0645\u0633\u0627\u0631\u0627\u062a \u0644\u0627 \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u0631\u0627\u0642\u0647\u0627. \u0641\u0625\u0630\u0627 \u0627\u0633\u062a\u062e\u062f\u0645\u062a \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0625\u0639\u0644\u0627\u0645 \u0627\u0644\u062a\u0642\u0644\u064a\u062f\u064a\u0629 \u0627\u0644\u0628\u0634\u0631 \u0644\u0625\u0646\u062a\u0627\u062c \u0648\u0646\u0634\u0631 \u0631\u0633\u0627\u0626\u0644\u0647\u0645 \u0645\u0639 \u0627\u062d\u062a\u0631\u0627\u0645 \u0627\u0644\u0642\u0648\u0627\u0646\u064a\u0646 \u0648\u0627\u0644\u062a\u0646\u0638\u064a\u0645\u0627\u062a\u060c \u0648\u0642\u0648\u0627\u0639\u062f \u0627\u0644\u0623\u062e\u0644\u0627\u0642 \u0623\u0648 \u0627\u0644\u0623\u0639\u0631\u0627\u0641\u060c \u0648\u0647\u0648 \u0645\u0627 \u064a\u062d\u0642\u0642 \u062f\u0631\u062c\u0629 \u0645\u0633\u0624\u0648\u0644\u064a\u0629 \u0645\u0637\u0645\u0626\u0646\u0629\u060c \u0641\u0625\u0646 \u0627\u0644\u0623\u0645\u0631 \u0644\u0645 \u064a\u0639\u062f \u0643\u0630\u0644\u0643 \u0645\u0639 \u0627\u0644\u0645\u062e\u0632\u0646\u0627\u062a \u0627\u0644\u062a\u0627\u0628\u0639\u0629 \u0644\u0645\u0633\u064a\u0631\u064a \u0627\u0644\u062e\u0648\u0627\u0631\u0632\u0645\u064a\u0629 \u0644\u0644\u0631\u0648\u0628\u0648\u062a \u0641\u064a Facebook \u2013 Google-Twitter\u060c \u0627\u0644\u0645\u0633\u064a\u0631\u0629 \u062a\u0644\u0642\u0627\u0626\u064a\u0627 \u0641\u064a \u0648\u0636\u0639 \u0634\u0628\u064a\u0647 \u0628\u0627\u0644\u0637\u0627\u0626\u0631\u0627\u062a \u062f\u0648\u0646 \u0637\u064a\u0627\u0631 \u0639\u0646\u062f\u0645\u0627 \u062a\u0633\u062a\u062e\u062f\u0645 \u0641\u064a \u0639\u0645\u0644\u064a\u0627\u062a \u0642\u062a\u0644\u060c \u0644\u0643\u0646 \u062f\u0648\u0646 \u0623\u0646 \u064a\u062a\u062d\u0645\u0644 \u0623\u064a \u0645\u0646 \u0627\u0644\u0628\u0634\u0631 \u0645\u0633\u0624\u0648\u0644\u064a\u0629 \u0630\u0644\u0643.<\/strong><br \/>\n<strong>\u0641\u0641\u064a\u0633\u0628\u0648\u0643 Facebook \u0644\u0648\u062d\u062f\u0647 \u064a\u0633\u062c\u0644 \u064a\u0648\u0645\u064a\u0627 \u0623\u0643\u062b\u0631 \u0645\u0646 100 \u0645\u0644\u064a\u0627\u0631 \u0645\u062d\u062a\u0648\u0649\u060c \u0648\u0647\u0648 \u0628\u0645\u062b\u0627\u0628\u0629 \u0637\u0648\u0641\u0627\u0646 \u0644\u0627 \u062a\u0633\u062a\u0637\u064a\u0639 \u062e\u0648\u0627\u0631\u0632\u0645\u064a\u0627\u062a\u0647 \u0648\u0644\u0627 \u062c\u064a\u0634\u0647 \u0627\u0644\u0635\u063a\u064a\u0631 \u0645\u0646 \u0627\u0644\u0645\u0631\u0634\u062f\u064a\u0646 \u0648\u0627\u0644\u0645\u062f\u0631\u0628\u064a\u0646 \u0627\u062d\u062a\u0648\u0627\u0621\u0647 \u0628\u0634\u0643\u0644 \u0648\u0627\u0642\u0639\u064a.<\/strong><br \/>\n<strong>\u0648\u064a\u0639\u062f Facebook \u0623\u0643\u0628\u0631 \u0634\u0631\u0643\u0629 \u0625\u0639\u0644\u0627\u0645 \u0641\u064a \u062a\u0627\u0631\u064a\u062e \u0627\u0644\u0639\u0627\u0644\u0645\u060c \u0648\u0647\u0648 \u0623\u064a\u0636\u0627 \u0646\u0627\u0634\u0631 \u0648\u0645\u0630\u064a\u0639 \u0641\u064a \u0646\u0641\u0633 \u0627\u0644\u0648\u0642\u062a\u060c \u0644\u0647 \u062d\u0648\u0627\u0644\u064a 2.6 \u0645\u0644\u064a\u0627\u0631 \u0645\u0633\u062a\u062e\u062f\u0645 \u0645\u0646\u062a\u0638\u0645\u060c \u0648\u0645\u0644\u0627\u064a\u064a\u0631 \u0622\u062e\u0631\u064a\u0646 \u0639\u0644\u0649 \u062a\u0637\u0628\u064a\u0642\u0627\u062a WhatsApp \u0648 Instagram.<\/strong><br \/>\n<strong>\u0645\u0646\u0630 \u0623\u0648\u062c\u062f\u062a \u0645\u0646\u0635\u0627\u062a \u0627\u0644\u0625\u0639\u0644\u0627\u0645 \u0627\u0644\u0631\u0642\u0645\u064a \u0642\u0628\u0644 15 \u0639\u0627\u0645\u064b\u0627 \u0645\u0646 \u0627\u0644\u0622\u0646 \u0645\u0627 \u0627\u0635\u0637\u0644\u062d \u0639\u0644\u0649 \u062a\u0633\u0645\u064a\u062a\u0647 \u0628\u0634\u0643\u0644 \u0645\u0641\u0631\u0637 \u0648\u0628\u0644\u0645\u0633\u0629 \u062d\u0645\u064a\u0645\u0629 \u0628\u0634\u0628\u0643\u0629 \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a \u0628\u0627\u0639\u062a\u0628\u0627\u0631\u0647 \u0646\u0627\u0642\u0644\u064b\u0627 \u0631\u0626\u064a\u0633\u064a\u064b\u0627 \u0644\u0644\u0645\u0639\u0644\u0648\u0645\u0629\u060c \u0641\u0625\u0646 \u0643\u0644 \u0627\u0644\u062f\u064a\u0645\u0642\u0631\u0627\u0637\u064a\u0627\u062a \u062a\u0639\u0631\u0641 \u062a\u0628\u0639\u064a\u0629 \u0644\u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0627\u062a \u0627\u0644\u0627\u062a\u0635\u0627\u0644 \u0627\u0644\u0631\u0642\u0645\u064a \u0627\u0644\u062a\u064a \u062a\u0633\u0645\u062d \u0628\u062a\u0634\u0643\u064a\u0644 \u0645\u0646\u0637\u0642\u0629 \u0639\u0627\u0644\u0645\u064a\u0629 \u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u062a\u063a\u0628\u064a\u0631 \u063a\u064a\u0631 \u0645\u062d\u062f\u062f\u0629 \u0627\u0644\u062d\u062c\u0645 \u0645\u0642\u0631\u0648\u0646\u0629 \u0628\u0644\u0627 \u0645\u0633\u0624\u0648\u0644\u064a\u0629 \u062e\u0648\u0627\u0631\u0632\u0645\u064a\u0629 \u062a\u0645\u064a\u0632\u0647\u0627 \u0643\u0645\u064a\u0627\u062a \u0647\u0627\u0626\u0644\u0629 \u0645\u0646 \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0627\u0644\u0645\u063a\u0644\u0648\u0637\u0629 \u0627\u0644\u062a\u064a \u062a\u0646\u062a\u0634\u0631 \u0628\u0633\u0647\u0648\u0644\u0629 \u063a\u064a\u0631 \u0645\u0633\u0628\u0648\u0642\u0629.<\/strong><\/p>\n<h4 style=\"text-align: right\"><strong>\u064a\u0628\u062f\u0648 \u0623\u0646\u0643\u0645 \u0639\u0627\u062c\u0632\u0648\u0646 \u0639\u0646 \u0645\u0648\u0627\u062c\u0647\u0629 \u0647\u0630\u0647 \u0627\u0644\u0648\u0636\u0639\u064a\u0629\u061f<\/strong><\/h4>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-595942 lazy entered loaded\" src=\"https:\/\/www.echoroukonline.com\/2017-wp-content\/uploads\/2021\/02\/MAM_7631.jpg\" alt=\"\" width=\"690\" \/><\/p>\n<p style=\"text-align: right\">\u0625<strong>\u0646 \u0631\u062f \u0641\u0639\u0644 \u0627\u0644\u062f\u0648\u0644 \u0644\u064a\u0633 \u062f\u0627\u0626\u0645\u0627 \u0641\u064a \u0645\u0633\u062a\u0648\u0649 \u0627\u0644\u062a\u062d\u062f\u064a\u0627\u062a. \u0644\u0642\u062f \u0627\u0643\u062a\u0633\u0628 \u0627\u0644\u0627\u062a\u062d\u0627\u062f \u0627\u0644\u0623\u0648\u0631\u0648\u0628\u064a \u0633\u0645\u0639\u0629 \u0643\u0623\u0648\u0644 \u0647\u064a\u0626\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u062a\u0646\u0638\u064a\u0645 \u0623\u0643\u0628\u0631 \u0634\u0631\u0643\u0627\u062a \u0627\u0644\u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0627 \u0641\u064a \u0627\u0644\u0639\u0627\u0644\u0645. \u0648\u0645\u0646 \u0622\u062e\u0631 \u0625\u0635\u062f\u0627\u0631\u0627\u062a\u0647 \u0642\u0627\u0646\u0648\u0646 \u0627\u0644\u062e\u062f\u0645\u0627\u062a \u0627\u0644\u0631\u0642\u0645\u064a\u0629 (DSA) \u0648\u0627\u0644\u0642\u0627\u0646\u0648\u0646 \u0627\u0644\u0645\u062a\u0639\u0644\u0642 \u0628\u0627\u0644\u0623\u0633\u0648\u0627\u0642 \u0627\u0644\u0631\u0642\u0645\u064a\u0629 (DMA) \u0627\u0644\u0630\u064a \u062a\u0645 \u0627\u0642\u062a\u0631\u0627\u062d\u0647 \u0645\u0624\u062e\u0631\u064b\u0627. \u062a\u062a\u0645\u062b\u0644 \u0627\u0644\u0623\u0647\u062f\u0627\u0641 \u0627\u0644\u0645\u0639\u0644\u0646\u0629 \u0644\u0640\u0647\u0630\u0647 \u0627\u0644\u0642\u0648\u0627\u0646\u064a\u0646 \u0641\u064a \u201c\u062a\u0634\u062c\u064a\u0639 \u0627\u0644\u0627\u0628\u062a\u0643\u0627\u0631 \u0648\u0627\u0644\u0646\u0645\u0648 \u0648\u0627\u0644\u062a\u0646\u0627\u0641\u0633\u064a\u0629\u201d \u0648\u0636\u0645\u0627\u0646 \u201c\u062d\u0635\u0648\u0644 \u0627\u0644\u0645\u0628\u062a\u0643\u0631\u064a\u0646 \u0648\u0627\u0644\u0634\u0631\u0643\u0627\u062a \u0627\u0644\u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0629 \u0627\u0644\u0646\u0627\u0634\u0626\u0629 \u0639\u0644\u0649 \u0641\u0631\u0635 \u062c\u062f\u064a\u062f\u0629\u201d.<\/strong><br \/>\n<strong>\u0644\u0643\u0646 \u0648\u0644\u0644\u0623\u0633\u0641\u060c \u0641\u0625\u0646 \u0645\u0642\u0627\u0631\u0628\u0629 \u0647\u0630\u0647 \u0627\u0644\u0642\u0648\u0627\u0646\u064a\u0646 \u062a\u0634\u0643\u0648 \u0645\u0646 \u0633\u0648\u0621 \u0627\u0644\u062a\u062c\u0647\u064a\u0632 \u0644\u0645\u0648\u0627\u062c\u0647\u0629 \u0627\u0644\u0645\u062e\u0627\u0637\u0631 \u0623\u0648 \u201c\u0627\u0644\u0633\u0645\u0648\u0645 \u0627\u0644\u0645\u0639\u062a\u0628\u0631\u0629\u201d \u0627\u0644\u062a\u064a \u062a\u0639\u062a\u0628\u0631 \u0645\u0646\u0635\u0627\u062a \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0625\u0639\u0644\u0627\u0645 \u0627\u0644\u0631\u0642\u0645\u064a \u0645\u062c\u0627\u0644\u0627 \u0644\u0647\u0627.<\/strong><br \/>\n<strong>\u0648\u0641\u064a \u0625\u0637\u0627\u0631 \u0630\u0627\u062a \u0627\u0644\u0645\u0642\u0627\u0631\u0628\u0629\u060c \u0641\u0625\u0646 \u0627\u0644\u0645\u0646\u0635\u0627\u062a \u0627\u0644\u0643\u0628\u064a\u0631\u0629 \u062a\u062a\u0639\u0631\u0636 \u0644\u063a\u0631\u0627\u0645\u0627\u062a \u0645\u0627\u0644\u064a\u0629 \u0628\u0633\u0628\u0628 \u0628\u0639\u0636 \u0645\u0645\u0627\u0631\u0633\u0627\u062a \u0627\u0644\u0645\u0646\u0627\u0641\u0633\u0629 \u063a\u064a\u0631 \u0627\u0644\u0634\u0631\u064a\u0641\u0629\u060c \u0644\u0643\u0646 \u0648\u0628\u0645\u0627 \u0623\u0646 \u0627\u0644\u0645\u0628\u0644\u063a \u0627\u0644\u0623\u0642\u0635\u0649 \u0644\u0644\u063a\u0631\u0627\u0645\u0629 \u0644\u0627 \u064a\u062a\u0639\u062f\u0649 10 \u0628\u0627\u0644\u0645\u0627\u0626\u0629 \u0645\u0646 \u0627\u0644\u0625\u064a\u0631\u0627\u062f\u0627\u062a \u0641\u0625\u0646\u0647 \u0644\u0646 \u064a\u0643\u0648\u0646 \u0643\u0627\u0641\u064a\u0627\u064b \u0644\u062a\u062d\u0642\u064a\u0642 \u0627\u0644\u0631\u062f\u0639 \u0627\u0644\u0645\u0637\u0644\u0648\u0628.<\/strong><br \/>\n<strong>\u0625\u0646 \u0647\u0630\u0627 \u0627\u0644\u0645\u0633\u0639\u0649 \u0627\u0644\u062c\u062f\u064a\u062f \u0644\u0644\u0627\u062a\u062d\u0627\u062f \u0627\u0644\u0623\u0648\u0631\u0648\u0628\u064a \u062c\u0627\u0621 \u0628\u0639\u062f \u062a\u0641\u0639\u064a\u0644 \u0627\u0644\u0646\u0638\u0627\u0645 \u0627\u0644\u0639\u0627\u0645 \u062d\u0648\u0644 \u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0627\u0644\u062a\u064a \u062f\u062e\u0644\u062a \u062d\u064a\u0632 \u0627\u0644\u062a\u0646\u0641\u064a\u0630 \u0628\u062a\u0627\u0631\u064a\u062e 25 \u0645\u0627\u064a 2019.<\/strong><br \/>\n<strong>\u0648\u062a\u0633\u062a\u0641\u064a\u062f \u0627\u0644\u0633\u0644\u0637\u0627\u062a \u0627\u0644\u0645\u0639\u0646\u064a\u0629 \u0628\u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0645\u0639\u0637\u064a\u0627\u062a \u0645\u0646 \u0648\u0633\u0627\u0626\u0644 \u0642\u0627\u0646\u0648\u0646\u064a\u0629 \u0644\u0631\u062f\u0639 \u0648\u0628\u0634\u062f\u0629 \u0627\u0644\u0645\u0624\u0633\u0633\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u062e\u062a\u0631\u0642 \u0627\u0644\u0642\u0648\u0627\u0646\u064a\u0646 \u0627\u0644\u0623\u0648\u0631\u0648\u0628\u064a\u0629 \u0643\u0645\u0627 \u062d\u062f\u062f \u0627\u0644\u0646\u0638\u0627\u0645 \u0627\u0644\u0623\u0648\u0631\u0648\u0628\u064a \u0633\u0642\u0641 %4 \u0645\u0646 \u0631\u0642\u0645 \u0627\u0644\u0623\u0639\u0645\u0627\u0644 \u0641\u064a \u062d\u0627\u0644\u0629 \u0639\u062f\u0645 \u0627\u0644\u0645\u0637\u0627\u0628\u0642\u0629.<\/strong><br \/>\n<strong>\u0648\u064a\u0639\u0642\u0628 \u0627\u0644\u062e\u0628\u0631\u0627\u0621 \u0627\u0644\u0645\u062e\u062a\u0635\u0648\u0646 \u0639\u0644\u0649 \u0647\u0630\u0627 \u0628\u0627\u0644\u062a\u0623\u0643\u064a\u062f \u0639\u0644\u0649 \u0623\u0646 \u201c\u0627\u0644\u0648\u0642\u062a \u0642\u062f \u062d\u0627\u0646 \u0644\u0644\u0642\u064a\u0627\u0645 \u0628\u0625\u0639\u0627\u062f\u0629 \u0636\u0628\u0637 \u0643\u0628\u0631\u0649\u060c \u0644\u064a\u0633 \u0645\u0646 \u0623\u062c\u0644 \u0625\u0646\u0642\u0627\u0630 \u062f\u064a\u0645\u0642\u0631\u0627\u0637\u064a\u0627\u062a\u0646\u0627 \u0641\u062d\u0633\u0628\u060c \u0648\u0644\u0643\u0646 \u0623\u064a\u0636\u064b\u0627 \u0644\u062a\u0648\u0641\u064a\u0631 \u0627\u0644\u0641\u0631\u0635 \u0627\u0644\u0645\u062b\u0644\u0649 \u0644\u0625\u0639\u0627\u062f\u0629 \u0627\u0644\u062a\u0641\u0643\u064a\u0631 \u0641\u064a \u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0627\u062a \u0627\u0644\u0648\u0633\u0627\u0626\u0637 \u0627\u0644\u0631\u0642\u0645\u064a\u0629\u060c \u0648\u0647\u0630\u0627 \u062d\u062a\u0649 \u0646\u062a\u0645\u0643\u0646 \u0645\u0646 \u0625\u0639\u0627\u062f\u0629 \u0627\u0643\u062a\u0634\u0627\u0641 \u0627\u0644\u0648\u0639\u0648\u062f \u0627\u0644\u062a\u064a \u062d\u0645\u0644\u062a\u0647\u0627 \u0639\u0646\u062f \u0638\u0647\u0648\u0631\u0647\u0627 \u0648\u062a\u0642\u0644\u064a\u0644 \u0627\u0644\u0645\u062e\u0627\u0637\u0631 \u0627\u0644\u062a\u064a \u0638\u0647\u0631\u062a \u0623\u062b\u0646\u0627\u0621 \u0645\u0645\u0627\u0631\u0633\u062a\u0647\u0627 \u0648\u062a\u0637\u0628\u064a\u0642\u0647\u0627\u201d.<\/strong><\/p>\n<h4 style=\"text-align: right\"><strong>\u064a\u0628\u062f\u0648 \u0623\u0646 \u0627\u0644\u0642\u0627\u0646\u0648\u0646 \u0644\u0645 \u064a\u062a\u0645\u0643\u0646 \u0645\u0646 \u0645\u0633\u0627\u064a\u0631\u0629 \u0627\u0644\u062a\u0642\u0646\u064a\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u0632\u062f\u0627\u062f \u062a\u0639\u0642\u064a\u062f\u0627 \u0628\u0627\u0644\u0646\u0633\u0628\u0629 \u0644\u0627\u0646\u062a\u0647\u0627\u0643 \u0627\u0644\u062e\u0635\u0648\u0635\u064a\u0629\u060c \u0623\u0648 \u0628\u0634\u0643\u0644 \u0639\u0627\u0645 \u0627\u0644\u062d\u064a\u0627\u0629 \u0641\u064a \u201c\u0645\u062c\u062a\u0645\u0639 \u062f\u064a\u0645\u0642\u0631\u0627\u0637\u064a\u201d\u061f<\/strong><\/h4>\n<p style=\"text-align: right\"><strong>\u0641\u064a \u0627\u0644\u062f\u064a\u0645\u0642\u0631\u0627\u0637\u064a\u0627\u062a \u0627\u0644\u0646\u0627\u0634\u0626\u0629\u060c \u0648\u0627\u0644\u0633\u0627\u0639\u064a\u0629 \u0625\u0644\u0649 \u0625\u0631\u0633\u0627\u0621 \u062f\u0648\u0644\u0629 \u0627\u0644\u0642\u0627\u0646\u0648\u0646\u060c \u0641\u0625\u0646 \u063a\u064a\u0627\u0628 \u0627\u0644\u0645\u0639\u0627\u064a\u064a\u0631 \u0627\u0644\u0631\u062f\u0639\u064a\u0629\u060c \u0644\u0627\u0639\u062a\u0631\u0627\u0636 \u0648\u0646\u0634\u0631 \u0627\u0644\u0645\u062d\u0627\u062f\u062b\u0627\u062a \u0627\u0644\u062e\u0627\u0635\u0629 \u064a\u0639\u0631\u0636 \u0627\u0644\u062d\u064a\u0627\u0629 \u0627\u0644\u062e\u0627\u0635\u0629 \u0644\u0644\u0646\u0627\u0633 \u0644\u0627\u0645\u062a\u062d\u0627\u0646 \u0639\u0635\u064a\u0628\u060c \u062e\u0627\u0635\u0629 \u0627\u0644\u0623\u0634\u062e\u0627\u0635 \u0627\u0644\u0645\u0639\u0631\u0636\u064a\u0646 \u0623\u0643\u062b\u0631 \u0644\u0644\u062e\u0637\u0631 \u0628\u062d\u0643\u0645 \u0623\u0646\u0634\u0637\u062a\u0647\u0645 \u0627\u0644\u0639\u0627\u0645\u0629\u060c \u0641\u064a \u0623\u062c\u0647\u0632\u0629 \u0627\u0644\u062f\u0648\u0644\u0629 \u0643\u0645\u0627 \u0641\u064a \u0627\u0644\u0645\u0639\u0627\u0631\u0636\u0629.<\/strong><br \/>\n<strong>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0647\u0630\u0627\u060c \u0641\u0625\u0646 \u063a\u064a\u0627\u0628 \u0645\u0624\u0633\u0633\u0627\u062a \u062f\u064a\u0645\u0642\u0631\u0627\u0637\u064a\u0629 \u0648\u062a\u0645\u062b\u064a\u0644\u064a\u0629 \u062a\u062d\u062a\u0636\u0646 \u0627\u0644\u0646\u0642\u0627\u0634\u0627\u062a \u0627\u0644\u062d\u0636\u0627\u0631\u064a\u0629\u060c \u0648\u0627\u0644\u062d\u0648\u0627\u0631 \u0627\u0644\u0633\u0644\u0645\u064a\u060c \u0648\u0627\u0644\u0648\u0633\u0627\u0637\u0627\u062a \u0627\u0644\u0641\u0639\u0627\u0644\u0629\u060c \u0648\u0627\u0644\u062a\u062d\u0643\u064a\u0645 \u0627\u0644\u0645\u062b\u0645\u0631\u060c \u0627\u0644\u0645\u0637\u0644\u0648\u0628 \u0644\u062a\u062d\u0642\u064a\u0642 \u062a\u0639\u0627\u064a\u0634 \u0627\u0644\u0645\u0635\u0627\u0644\u062d \u0627\u0644\u0642\u0627\u0626\u0645\u0629\u060c \u0641\u0625\u0646 \u0625\u062b\u0627\u0631\u0629 \u0627\u0644\u0634\u063a\u0628 \u062a\u0635\u0628\u062d \u062e\u064a\u0627\u0631\u0627 \u0623\u0648 \u0645\u0644\u062c\u0623 \u0644\u0644\u0641\u0627\u0639\u0644\u064a\u0646 \u0627\u0644\u0633\u064a\u0627\u0633\u064a\u064a\u0646 \u0648\u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a\u064a\u0646\u060c \u062e\u0627\u0635\u0629 \u0648\u0623\u0646\u0647 \u064a\u062a\u0633\u0645 \u0628\u0627\u0644\u062c\u0630\u0628 \u0648\u0627\u0644\u0625\u0642\u0628\u0627\u0644 \u0648\u0623\u0646 \u0622\u062b\u0627\u0631\u0647 \u062a\u0643\u0648\u0646 \u0641\u0648\u0631\u064a\u0629.<\/strong><br \/>\n<strong>\u063a\u0627\u0644\u0628\u064b\u0627 \u0645\u0627 \u062a\u0646\u0633\u0649 \u0623\u0648 \u062a\u063a\u0641\u0644 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0625\u0639\u0644\u0627\u0645 \u0648\u0627\u0644\u0642\u0627\u062f\u0629 \u0627\u0644\u0633\u064a\u0627\u0633\u064a\u0648\u0646 \u0648\u0627\u0644\u062c\u0627\u0645\u0639\u064a\u0648\u0646 \u0648\u0627\u0644\u062c\u0645\u0647\u0648\u0631 \u0627\u0644\u0648\u0627\u0633\u0639 \u0648\u0636\u0639 \u062f\u0648\u0627\u0645\u0629 \u0627\u0644\u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u064a\u0648\u0645\u064a\u0629 \u0641\u064a \u0633\u064a\u0627\u0642 \u062a\u0627\u0631\u064a\u062e\u064a\u061b \u0645\u0641\u0636\u0644\u064a\u0646 \u0645\u062a\u0627\u0628\u0639\u0629 \u0622\u062e\u0631 \u0627\u0644\u0623\u062d\u062f\u0627\u062b \u0648\u0627\u0644\u0623\u0632\u0645\u0627\u062a \u0639\u0628\u0631 \u0627\u0644\u0634\u0628\u0643\u0629.<\/strong><br \/>\n<strong>\u0648\u0645\u0646 \u0623\u062c\u0644 \u0648\u0636\u0639 \u0627\u0644\u0623\u0645\u0648\u0631 \u0641\u064a \u0646\u0635\u0627\u0628\u0647\u0627 \u0645\u0646\u0630 \u0627\u0644\u0648\u0635\u0648\u0644 \u0627\u0644\u0645\u0643\u062b\u0641 \u0644\u0645\u0648\u0627\u0642\u0639 \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0627\u0627\u0631\u062c\u062a\u0645\u0627\u0639\u064a: \u0623\u0641\u0636\u0644 \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u0647\u0630\u0647 \u0627\u0644\u0639\u0628\u0627\u0631\u0629 \u0639\u0644\u0649 \u062a\u0644\u0643 \u0627\u0644\u0633\u0627\u0626\u062f\u0629\u060c \u062a\u0646\u0635 \u0627\u0644\u0645\u0627\u062f\u0629 39 \u0627\u0644\u0641\u0642\u0631\u0629 1 \u0645\u0646 \u0627\u0644\u062f\u0633\u062a\u0648\u0631 \u0627\u0644\u062c\u0632\u0627\u0626\u0631\u064a \u0644\u0639\u0627\u0645 2016 \u0639\u0644\u0649 \u0623\u0646 \u201c\u062e\u0635\u0648\u0635\u064a\u0629 \u0627\u0644\u0645\u0648\u0627\u0637\u0646\u064a\u0646 \u0648\u0634\u0631\u0641\u0647\u0645 \u0645\u0635\u0648\u0646\u0627\u0646 \u0628\u0645\u0648\u062c\u0628 \u0627\u0644\u0642\u0627\u0646\u0648\u0646\u201d.<\/strong><br \/>\n<strong>\u0641\u064a\u0645\u0627 \u062a\u0633\u064a\u0631 \u0627\u0644\u0641\u0642\u0631\u0629 2 \u0641\u064a \u0646\u0641\u0633 \u0627\u0644\u0627\u062a\u062c\u0627\u0647 \u0628\u0627\u0644\u0646\u0635 \u0639\u0644\u0649 \u0623\u0646: \u201c\u0633\u0631\u064a\u0629 \u0627\u0644\u0645\u0631\u0627\u0633\u0644\u0627\u062a \u0648\u0627\u0644\u0627\u062a\u0635\u0627\u0644\u0627\u062a \u0627\u0644\u062e\u0627\u0635\u0629\u060c \u0628\u062c\u0645\u064a\u0639 \u0623\u0634\u0643\u0627\u0644\u0647\u0627\u060c \u0645\u0636\u0645\u0648\u0646\u0629\u201d.<\/strong><br \/>\n<strong>\u0648\u0642\u062f \u0643\u0631\u0633 \u0627\u0644\u062f\u0633\u062a\u0648\u0631 \u0627\u0644\u062c\u062f\u064a\u062f \u0627\u0644\u0645\u0639\u062a\u0645\u062f \u0641\u064a \u0646\u0648\u0641\u0645\u0628\u0631 2020 \u0647\u0627\u062a\u0627\u0646 \u0627\u0644\u0641\u0626\u062a\u0627\u0646 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u062a\u0627\u0646 \u0645\u0646 \u0627\u0644\u062d\u0642\u0648\u0642 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u0644\u0645\u0627\u062f\u0629 47 \u0627\u0644\u062a\u064a \u062c\u0627\u0621\u062a \u0639\u0644\u0649 \u0627\u0644\u0646\u062d\u0648 \u0627\u0644\u062a\u0627\u0644\u064a:<\/strong><br \/>\n<strong>\u201c\u0644\u0643\u0644 \u0641\u0631\u062f \u0627\u0644\u062d\u0642 \u0641\u064a \u062d\u0645\u0627\u064a\u0629 \u062e\u0635\u0648\u0635\u064a\u062a\u0647 \u0648\u0634\u0631\u0641\u0647.<\/strong><br \/>\n<strong>\u0644\u0643\u0644 \u0641\u0631\u062f \u0627\u0644\u062d\u0642 \u0641\u064a \u0633\u0631\u064a\u0629 \u0645\u0631\u0627\u0633\u0644\u0627\u062a\u0647 \u0648\u0627\u062a\u0635\u0627\u0644\u0627\u062a\u0647 \u0627\u0644\u062e\u0627\u0635\u0629 \u0628\u062c\u0645\u064a\u0639 \u0623\u0634\u0643\u0627\u0644\u0647\u0627\u201d.<\/strong><br \/>\n<strong>\u0623\u062f\u0631\u062c\u062a \u0627\u0644\u0645\u0627\u062f\u0629 47 \u0646\u0641\u0633\u0647\u0627 \u0641\u0642\u0631\u062a\u064a\u0646 \u062c\u062f\u064a\u062f\u062a\u064a\u0646\u060c 3 \u06484\u060c \u062a\u0642\u0636\u064a\u0627\u0646 \u0628\u0623\u0646:<\/strong><br \/>\n<strong>\u201c\u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0623\u0641\u0631\u0627\u062f \u0641\u064a \u0645\u0639\u0627\u0644\u062c\u0629 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0627\u0644\u0634\u062e\u0635\u064a\u0629 \u062d\u0642 \u0623\u0633\u0627\u0633\u064a.<\/strong><br \/>\n<strong>\u064a\u0639\u0627\u0642\u0628 \u0627\u0644\u0642\u0627\u0646\u0648\u0646 \u0639\u0644\u0649 \u0623\u064a \u0627\u0646\u062a\u0647\u0627\u0643 \u0644\u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0645\u0630\u0643\u0648\u0631\u0629 \u0623\u0639\u0644\u0627\u0647\u0651\u201d.<\/strong><br \/>\n<strong>\u0644\u0644\u0625\u0634\u0627\u0631\u0629 \u0641\u0625\u0646 \u0627\u0644\u0642\u0627\u0646\u0648\u0646\u060c \u064a\u0628\u0646\u064a \u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u062d\u064a\u0627\u0629 \u0627\u0644\u062e\u0627\u0635\u0629 \u0639\u0644\u0649 \u062b\u0644\u0627\u062b\u0629 \u0639\u0646\u0627\u0635\u0631 \u0644\u0635\u064a\u0642\u0629 \u0628\u0634\u062e\u0635\u064a\u0629 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 \u0648\u0647\u064a: \u0627\u062d\u062a\u0631\u0627\u0645 \u0627\u0644\u0633\u0644\u0648\u0643\u060c \u0627\u0644\u0633\u0631\u064a\u0629 \u0648\u0627\u0644\u0639\u0644\u0627\u0642\u0627\u062a \u0627\u0644\u062e\u0627\u0635\u0629.<\/strong><br \/>\n<strong>\u0648\u0628\u0647\u0630\u0627 \u0627\u0644\u062e\u0635\u0648\u0635 \u0623\u0624\u064a\u062f \u0634\u062e\u0635\u064a\u0627 \u062a\u0639\u0632\u064a\u0632 \u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u062d\u064a\u0627\u0629 \u0627\u0644\u062e\u0627\u0635\u0629 \u0639\u0646 \u0637\u0631\u0642 \u0633\u0646 \u0623\u0642\u0635\u0649 \u0627\u0644\u0639\u0642\u0648\u0628\u0627\u062a \u0628\u063a\u0636 \u0627\u0644\u0646\u0638\u0631 \u0639\u0646 \u062f\u0648\u0627\u0641\u0639 \u0627\u0644\u0645\u0639\u062a\u062f\u064a \u0648\u0645\u0631\u0643\u0632\u0647 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a.<\/strong><\/p>\n<p style=\"text-align: right\"><strong>\u0625\u0646 \u0647\u0630\u0627 \u0627\u0644\u0625\u062c\u0631\u0627\u0621 \u064a\u0639\u062f \u0636\u0631\u0648\u0631\u064a\u0627 \u0646\u0638\u0631\u0627 \u0644\u0643\u0648\u0646 \u0638\u0627\u0647\u0631\u0629 \u0627\u0644\u0645\u0633\u0627\u0633 \u0628\u062d\u064a\u0627\u0629 \u0627\u0644\u0623\u0634\u062e\u0627\u0635 \u0644\u0627 \u062a\u0633\u062a\u062b\u0646\u064a \u0623\u062d\u062f\u0627 \u0648\u062a\u062a\u062e\u0630 \u0623\u0628\u0639\u0627\u062f\u0627 \u0645\u0642\u0644\u0642\u0629.<\/strong><br \/>\n<strong>\u0641\u0628\u0639\u062f \u0627\u0644\u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u0643\u0627\u0630\u0628\u0629 \u201cFakenews\u201d \u0648\u0647\u0648 \u062a\u0639\u0628\u064a\u0631 \u0625\u0646\u062c\u0644\u064a\u0632\u064a \u064a\u0639\u0646\u064a \u0627\u0644\u0625\u0634\u0627\u0639\u0629\u060c \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0627\u0644\u0645\u063a\u0644\u0648\u0637\u0629 \u0623\u0648 \u0627\u0644\u0623\u062e\u0628\u0627\u0631 \u0627\u0644\u0643\u0627\u0630\u0628\u0629 \u0627\u0644\u0645\u0633\u062a\u0639\u0645\u0644\u0629 \u0641\u064a \u0645\u062d\u0627\u0648\u0644\u0627\u062a \u0627\u0644\u062a\u0636\u0644\u064a\u0644 \u0623\u062a\u0649 \u0639\u0647\u062f \u201cDeepfakes\u201d\u060c \u0627\u0644\u062a\u064a \u062a\u0644\u0642\u0649 \u0631\u0648\u0627\u062c\u0627 \u0639\u0646\u062f\u0646\u0627 \u0648\u0647\u064a \u0639\u0628\u0627\u0631\u0629 \u0639\u0646 \u062a\u0642\u0646\u064a\u0629 \u062a\u0642\u0648\u0645 \u0639\u0644\u0649 \u062a\u062c\u0645\u064a\u0639 \u0627\u0644\u0635\u0648\u0631 \u0648\u0627\u0644\u062a\u0635\u0631\u0641 \u0633\u0644\u0628\u0627 \u0641\u064a \u0623\u0634\u0643\u0627\u0644 \u0648\u0648\u062c\u0648\u0647 \u0627\u0644\u0646\u0627\u0633 \u0648\u0630\u0644\u0643 \u0628\u0627\u0644\u0627\u0639\u062a\u0645\u0627\u062f \u0639\u0644\u0649 \u0627\u0644\u0630\u0643\u0627\u0621 \u0627\u0644\u0627\u0635\u0637\u0646\u0627\u0639\u064a \u0644\u0644\u062a\u062d\u0631\u064a\u0641 \u0648\u0627\u0644\u062a\u0632\u064a\u064a\u0641 \u0642\u0635\u062f \u0627\u0644\u0625\u0633\u0627\u0621\u0629 \u0644\u0644\u0636\u062d\u064a\u0629.<\/strong><\/p>\n<p style=\"text-align: right\"><strong>\u062a\u064f\u0633\u062a\u062e\u062f\u0645 \u0647\u0630\u0647 \u0627\u0644\u062a\u0642\u0646\u064a\u0629 \u0628\u0634\u0643\u0644 \u0623\u0633\u0627\u0633\u064a \u0644\u062a\u0631\u0643\u064a\u0628 \u0627\u0644\u0635\u0648\u0631 \u0648\u0645\u0642\u0627\u0637\u0639 \u0627\u0644\u0641\u064a\u062f\u064a\u0648 \u0627\u0644\u0645\u0648\u062c\u0648\u062f\u0629 \u0641\u0648\u0642 \u0627\u0644\u0635\u0648\u0631 \u0648\/ \u0623\u0648 \u0645\u0642\u0627\u0637\u0639 \u0627\u0644\u0641\u064a\u062f\u064a\u0648 \u0627\u0644\u0623\u062e\u0631\u0649 \u0628\u0647\u062f\u0641 \u0627\u0644\u0645\u0633\u0627\u0633 \u0628\u0645\u0635\u062f\u0627\u0642\u064a\u0629 \u0627\u0644\u0634\u062e\u0635\u064a\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u0646\u062a\u0645\u064a \u0644\u0639\u0627\u0644\u0645 \u0627\u0644\u0633\u064a\u0627\u0633\u0629 \u0623\u0648 \u0627\u0644\u062b\u0642\u0627\u0641\u0629.<\/strong><\/p>\n<p style=\"text-align: right\"><strong>\u0625\u0646\u0651 Deepfakes \u0647\u064a \u0639\u0628\u0627\u0631\u0629 \u0639\u0646 \u0645\u0642\u0627\u0637\u0639 \u0641\u064a\u062f\u064a\u0648 \u0645\u0632\u064a\u0641\u0629 \u062a\u0633\u062a\u062e\u062f\u0645 \u0641\u064a\u0647\u0627 \u062a\u0642\u0646\u064a\u0629 \u0623\u0648 \u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0627 \u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0627\u0644\u0648\u062c\u0647 \u0644\u0625\u062d\u062f\u0627\u062b \u062a\u063a\u064a\u064a\u0631 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u064a\u0629 \u064a\u0635\u0639\u0628 \u0645\u0639\u0647 \u0627\u0644\u062a\u0634\u0643\u064a\u0643 \u0641\u064a \u0639\u062f\u0645 \u0635\u062d\u0629 \u0627\u0644\u0635\u0648\u0631\u0629 \u0623\u0648 \u0627\u0644\u0647\u0648\u064a\u0629 \u0627\u0644\u0645\u0641\u0628\u0631\u0643\u0629.<\/strong><\/p>\n<h4 style=\"text-align: right\"><strong>\u062a\u0631\u0643\u0632\u0648\u0646 \u063a\u0627\u0644\u0628\u064b\u0627 \u0639\u0644\u0649 \u201c\u0627\u0644\u0639\u062f\u0648 \u0627\u0644\u0635\u0647\u064a\u0648\u0646\u064a\u201d \u0641\u064a \u0627\u0644\u0641\u0636\u0627\u0621 \u0627\u0644\u0633\u064a\u0628\u064a\u0631\u0627\u0646\u064a.. \u0623\u0644\u0627 \u062a\u0639\u0637\u0648\u0646\u0647 \u0623\u0647\u0645\u064a\u0629 \u0632\u0627\u0626\u062f\u0629\u061f<\/strong><\/h4>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-595943 lazy entered loaded\" src=\"https:\/\/www.echoroukonline.com\/2017-wp-content\/uploads\/2021\/02\/MAM_7651.jpg\" alt=\"\" width=\"690\" \/><\/p>\n<p style=\"text-align: right\">\u0625\u0646 \u0645\u0627<strong> \u064a\u0642\u0648\u0645 \u0628\u0647 \u0627\u0644\u0643\u064a\u0627\u0646 \u0627\u0644\u0635\u0647\u064a\u0648\u0646\u064a \u0645\u0646 \u0623\u0628\u062d\u0627\u062b \u0639\u0633\u0643\u0631\u064a\u0629 \u0648\u062a\u0637\u0628\u064a\u0642\u0627\u062a\u0647\u0627 \u0627\u0644\u0645\u062f\u0646\u064a\u0629 \u064a\u0639\u062a\u0628\u0631 \u0627\u0644\u0645\u0627\u062f\u0629 \u0627\u0644\u062a\u064a \u062a\u063a\u0630\u064a \u0628\u0633\u062e\u0627\u0621 \u0648\u0628\u062a\u0643\u0644\u0641\u0629 \u0645\u0631\u062a\u0641\u0639\u0629 \u0627\u0644\u0634\u0631\u0643\u0627\u062a \u0627\u0644\u0639\u0627\u0645\u0644\u0629 \u0641\u064a \u0627\u0644\u0641\u0636\u0627\u0621 \u0627\u0644\u0633\u064a\u0628\u064a\u0631\u0627\u0646\u064a.<\/strong><br \/>\n<strong>\u0648\u062a\u0638\u0644 \u0628\u0639\u0636 \u0627\u0644\u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0627\u062a \u0627\u0644\u0623\u0643\u062b\u0631 \u0633\u0631\u064a\u0629 \u0627\u0644\u062a\u064a \u0623\u0646\u062a\u062c\u0647\u0627 \u0645\u0637\u0648\u0631\u0648 \u0647\u0630\u0627 \u0627\u0644\u0643\u064a\u0627\u0646 \u0623\u0643\u062b\u0631 \u0642\u0631\u0628\u0627 \u0628\u0646\u0633\u062e\u0647\u0627 \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629 \u0627\u0644\u0623\u0635\u0644\u064a\u0629. \u0647\u0630\u0627 \u0647\u0648 \u062d\u0627\u0644 \u0623\u062d\u062f \u0627\u0644\u0628\u0631\u0645\u062c\u064a\u0627\u062a \u0627\u0644\u0647\u062c\u0648\u0645\u064a\u0629\u0627\u0644\u062a\u064a \u064a\u062a\u0645 \u0628\u064a\u0639\u0647\u0627 \u0644\u0644\u062f\u0648\u0644 \u0627\u0644\u062a\u064a \u062a\u0631\u063a\u0628 \u0641\u064a \u0627\u0644\u062a\u062c\u0633\u0633 \u0639\u0644\u0649 \u0645\u0648\u0627\u0637\u0646\u064a\u0647\u0627 \u0648\u0643\u0630\u0627 \u0644\u0644\u062f\u0648\u0644 \u0627\u0644\u0645\u062a\u0646\u0627\u0632\u0639\u0629\u060c \u0648\u0644\u0644\u0634\u0631\u0643\u0627\u062a \u0627\u0644\u062e\u0627\u0635\u0629 \u0627\u0644\u062a\u064a \u062a\u0623\u0645\u0644 \u0641\u064a \u0627\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u0645\u064a\u0632\u0629 \u0623\u0648 \u062a\u0641\u0648\u0642 \u0639\u0644\u0649 \u0645\u0646\u0627\u0641\u0633\u064a\u0647\u0627 \u0623\u0648 \u0636\u0645\u0627\u0646 \u062d\u0633\u0646 \u0627\u0633\u062a\u063a\u0644\u0627\u0644 \u0632\u0628\u0627\u0626\u0646\u0647\u0627 \u0648\u0627\u0644\u062a\u0623\u062b\u064a\u0631 \u0639\u0644\u064a\u0647\u0645 \u0648\u062a\u0648\u062c\u064a\u0647 \u062e\u064a\u0627\u0631\u0627\u062a\u0647\u0645 \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629.<\/strong><br \/>\n<strong>\u0648\u0628\u0645\u062c\u0631\u062f \u0625\u062f\u0645\u0627\u062c \u0647\u0630\u0647 \u0627\u0644\u0628\u0631\u0645\u062c\u064a\u0627\u062a \u0641\u064a \u0645\u0646\u0635\u0627\u062a \u0627\u0644\u0648\u0633\u0627\u0626\u0637 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a\u0629 \u0627\u0644\u062a\u064a \u064a\u0633\u062a\u0639\u0645\u0644\u0647\u0627 \u0645\u0644\u0627\u064a\u064a\u0631 \u0627\u0644\u0645\u0633\u062a\u062e\u062f\u0645\u064a\u0646\u060c \u0641\u0625\u0646 \u0647\u0630\u0647 \u0627\u0644\u0628\u0631\u0645\u062c\u064a\u0627\u062a \u0627\u0644\u062c\u0627\u0633\u0648\u0633\u064a\u0629 \u062a\u0648\u0641\u0631 \u0644\u0645\u0635\u0627\u0644\u062d \u0627\u0644\u0627\u0633\u062a\u0639\u0644\u0627\u0645\u0627\u062a \u0644\u0644\u062f\u0648\u0644 \u0627\u0644\u0645\u0639\u0646\u064a\u0629 \u0628\u0639\u062f\u0627 \u064a\u0643\u0627\u062f \u064a\u0643\u0648\u0646 \u0639\u0627\u0644\u0645\u064a\u0627.<\/strong><br \/>\n<strong>\u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0633\u064a\u0627\u0642 \u0641\u0625\u0646 WhatsAp\u0648\u0647\u064a \u0645\u0646\u0635\u0629 \u0644\u0644\u062a\u0648\u0627\u0635\u0644 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a \u0645\u0645\u0644\u0648\u0643\u0629 \u0644\u0640Facebook\u060c \u0631\u0641\u0639\u062a \u0623\u0648\u0644 \u062f\u0639\u0648\u0649 \u0642\u0636\u0627\u0626\u064a\u0629 \u0623\u0645\u0627\u0645 \u0645\u062d\u0643\u0645\u0629 \u0643\u0627\u0644\u064a\u0641\u0648\u0631\u0646\u064a\u0627 \u0636\u062f <span style=\"color: #ff0000\">NSO<\/span>\u060c \u0648\u0647\u064a \u0623\u0643\u0628\u0631 \u0634\u0631\u0643\u0629 \u0645\u0631\u0627\u0642\u0628\u0629 \u0625\u0633\u0631\u0627\u0626\u064a\u0644\u064a\u0629 \u2013 \u0623\u0633\u0633\u0647\u0627 \u0639\u0627\u0645 2010 \u0643\u0644 \u0645\u0646 \u201c\u0639\u0645\u0631\u064a \u0644\u0627\u0641\u064a\u201d \u0648\u201d\u0634\u0627\u0644\u064a\u0641\u0647\u0648\u0644\u064a\u0648\u201d\u060c \u0648\u0647\u0645\u0627 \u0645\u0646 \u062e\u0631\u064a\u062c\u064a \u0645\u0627 \u064a\u0639\u0631\u0641 \u0628\u0648\u062d\u062f\u0629 \u0627\u0644\u062c\u0648\u0633\u0633\u0629 \u0627\u0644\u0625\u0633\u0631\u0627\u0626\u064a\u0644\u064a\u0629 \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629 8200.<\/strong><br \/>\n<strong>\u0648\u0628\u0645\u0648\u062c\u0628 \u0647\u0630\u0647 \u0627\u0644\u062f\u0639\u0648\u0649 \u0641\u0625\u0646 WhatsApp\u064a\u062a\u0647\u0645 NSO \u0628\u062a\u0646\u0641\u064a\u0630 \u0647\u062c\u0645\u0627\u062a \u0633\u064a\u0628\u0631\u064a\u0627\u0646\u064a\u0629\u060c\u0627\u0633\u062a\u0647\u062f\u0641\u062a \u0627\u0644\u0647\u0648\u0627\u062a\u0641 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\u0629 \u0644\u0623\u0643\u062b\u0631 \u0645\u0646 1400 \u0645\u0633\u062a\u062e\u062f\u0645 \u0641\u064a 20 \u062f\u0648\u0644\u0629.<\/strong><\/p>\n<p style=\"text-align: right\"><strong>\u0648\u0642\u0627\u0645 NSO \u0641\u064a \u062a\u0646\u0641\u064a\u0630 \u0627\u0639\u062a\u062f\u0627\u0626\u0647 \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0628\u0631\u0646\u0627\u0645\u062c \u0627\u0644\u062a\u062c\u0633\u0633\u060c \u0627\u0644\u0645\u0633\u0645\u0649 <span style=\"color: #ff0000\">Pegasus<\/span>\u060c \u0627\u0644\u0630\u064a \u0627\u0633\u062a\u062e\u062f\u0645 \u0628\u0627\u0644\u0645\u0646\u0627\u0633\u0628\u0629 \u0636\u062f \u0627\u0644\u0645\u062f\u0627\u0641\u0639\u064a\u0646 \u0639\u0646 \u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 \u0648\u0627\u0644\u0645\u062d\u0627\u0645\u064a\u0646 \u0648\u0627\u0644\u0632\u0639\u0645\u0627\u0621 \u0627\u0644\u062f\u064a\u0646\u064a\u064a\u0646 \u0648\u0627\u0644\u0635\u062d\u0641\u064a\u064a\u0646 \u0648\u0639\u0645\u0627\u0644 \u0627\u0644\u0625\u063a\u0627\u062b\u0629.<\/strong><\/p>\n<p style=\"text-align: right\"><strong>\u0643\u0645\u0627 \u0645\u0646\u062d NSO \u0631\u062e\u0635\u0629 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0647\u0630\u0627 \u0627\u0644\u0628\u0631\u0646\u0627\u0645\u062c \u0644\u0639\u0634\u0631\u0627\u062a \u0627\u0644\u062d\u0643\u0648\u0645\u0627\u062a\u060c \u0644\u0627\u0633\u064a\u0645\u0627 \u0645\u0646\u0647\u0627 \u0627\u0644\u0623\u0646\u0638\u0645\u0629 \u0627\u0644\u062a\u064a \u0644\u0627 \u062a\u062a\u0645\u062a\u0639 \u0628\u0633\u0645\u0639\u0629 \u0637\u064a\u0628\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u0627\u062d\u062a\u0631\u0627\u0645 \u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646\u060c \u0645\u062b\u0644 \u0627\u0644\u0645\u063a\u0631\u0628 \u0627\u0644\u062a\u064a \u062a\u0639\u062f \u062b\u0627\u0646\u064a \u062f\u0648\u0644\u0629 \u0645\u0646 \u0646\u0627\u062d\u064a\u0629 \u0639\u062f\u062f \u0627\u0644\u0632\u0627\u0626\u0631\u064a\u0646 \u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u0634\u0631\u0648\u0642 \u0623\u0648\u0646\u0644\u0627\u064a\u0646 \u0628\u0639\u062f \u0627\u0644\u062c\u0632\u0627\u0626\u0631 \u062b\u0645 \u0641\u0631\u0646\u0633\u0627 \u0641\u064a \u0627\u0644\u0645\u0631\u062a\u0628\u0629 \u0627\u0644\u062b\u0627\u0644\u062b\u0629.<\/strong><\/p>\n<p style=\"text-align: right\"><strong>\u0644\u0642\u062f \u062a\u0639\u0631\u0636 \u0647\u0630\u0627 \u0627\u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u062c\u0632\u0627\u0626\u0631\u064a \u0645\u0624\u062e\u0631\u0627 \u0644\u0647\u062c\u0645\u0627\u062a \u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629 \u0645\u063a\u0631\u0628\u064a\u0629\u060c \u0639\u0644\u0645\u0627 \u0623\u0646 \u062a\u0641\u0627\u0639\u0644 \u0627\u0644\u0645\u063a\u0627\u0631\u0628\u0629 \u0645\u0639 \u0627\u0644\u0645\u0648\u0627\u0636\u064a\u0639 \u0627\u0644\u0635\u062d\u0641\u064a\u0629 \u0641\u064a \u0645\u0648\u0642\u0639 \u0627\u0644\u0634\u0631\u0648\u0642 \u0623\u0648\u0646\u0644\u0627\u064a\u0646 \u0643\u0628\u064a\u0631 \u062c\u062f\u0627 \u0637\u0648\u0627\u0644 \u0627\u0644\u0633\u0646\u0629\u060c\u0645\u0639 \u062a\u0633\u062c\u064a\u0644 \u0627\u0631\u062a\u0641\u0627\u0639 \u0645\u062d\u0633\u0648\u0633 \u0641\u064a \u0646\u0633\u0628\u0629 \u0645\u062a\u0627\u0628\u0639\u0629 \u0627\u0644\u0645\u063a\u0627\u0631\u0628\u0629 \u0644\u0644\u0645\u0648\u0642\u0639 \u0645\u0646\u0630 \u0627\u0639\u062a\u062f\u0627\u0621 \u201c\u0627\u0644\u0643\u0631\u0643\u0631\u0627\u062a\u201d\u060c \u062d\u064a\u062b \u0623\u0635\u0628\u062d\u062a \u0632\u064a\u0627\u0631\u0627\u062a\u0647\u0645 \u0648\u062a\u0641\u0627\u0639\u0644\u0647\u0645 \u0623\u0643\u062b\u0631 \u0643\u062b\u0627\u0641\u0629\u060c \u0628\u0644 \u064a\u0635\u0644 \u0627\u0644\u0623\u0645\u0631 \u0628\u0647\u0645 \u0623\u062d\u064a\u0627\u0646\u0627 \u0625\u0644\u0649 \u0645\u062d\u0627\u0648\u0644\u0629 \u0625\u063a\u0631\u0627\u0642 \u0627\u0644\u0645\u0648\u0642\u0639 \u0645\u0646 \u062e\u0644\u0627\u0644 \u062a\u0633\u062c\u064a\u0644 \u0623\u0643\u062b\u0631 \u0645\u0646 100 \u0632\u064a\u0627\u0631\u0629 \u0641\u064a \u0627\u0644\u062b\u0627\u0646\u064a\u0629 \u0644\u0641\u062a\u062d \u062b\u063a\u0631\u0627\u062a \u0639\u0644\u0649 \u0645\u0633\u062a\u0648\u0649 \u0627\u0644\u062e\u0627\u062f\u0645 (Serveur)\u060c \u0648\u0647\u064a \u0627\u0644\u0645\u062d\u0627\u0648\u0644\u0627\u062a \u0627\u0644\u062a\u064a \u0628\u0627\u0621\u062a \u062c\u0645\u064a\u0639\u0647\u0627 \u0628\u0627\u0644\u0641\u0634\u0644 \u0646\u0638\u0631\u0627 \u0644\u0623\u0646\u0638\u0645\u0629 \u0627\u0644\u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0645\u062a\u0639\u062f\u062f\u0629 \u0648\u0627\u0644\u0646\u0627\u062c\u0639\u0629 \u0627\u0644\u062a\u064a \u064a\u0648\u0641\u0631\u0647\u0627 \u0645\u0648\u0642\u0639 \u0627\u0644\u0634\u0631\u0648\u0642 \u0627\u0648\u0646\u0644\u0627\u064a\u0646.<\/strong><br \/>\n<strong>\u0643\u0645\u0627 \u0623\u0646 \u0627\u0644\u0642\u0627\u0626\u0645\u064a\u0646 \u0639\u0644\u0649 \u0647\u0630\u0647 \u0627\u0644\u0639\u0645\u0644\u064a\u0629\u060c \u064a\u062a\u0639\u0627\u0645\u0644\u0648\u0646 \u0628\u0634\u0643\u0644 \u0627\u062d\u062a\u0631\u0627\u0641\u064a \u0645\u0639 \u0627\u0644\u0645\u0648\u0636\u0648\u0639\u060c \u0625\u0630 \u064a\u0645\u0646\u0639 \u062f\u062e\u0648\u0644 \u0627\u0644\u0645\u0633\u062a\u062e\u062f\u0645\u064a\u0646 \u0627\u0644\u0625\u062f\u0627\u0631\u064a\u064a\u0646 \u0627\u0644\u0622\u062f\u0645\u064a\u064a\u0646 \u0645\u0646 \u0623\u062c\u0647\u0632\u062a\u0647\u0645 \u0627\u0644\u0634\u062e\u0635\u064a\u0629 \u0623\u0648 \u0645\u0646 \u0627\u0644\u0628\u064a\u062a \u062a\u0641\u0627\u062f\u064a\u0627 \u0644\u0623\u064a\u0629 \u062b\u063a\u0631\u0629 \u0642\u062f \u064a\u062a\u0645 \u0627\u0633\u062a\u063a\u0644\u0627\u0644\u0647\u0627.<\/strong><\/p>\n<p style=\"text-align: right\"><strong>\u0648\u0628\u0644\u063a\u0629 \u0627\u0644\u0623\u0631\u0642\u0627\u0645\u060c \u0641\u0625\u0646 \u0623\u0647\u0645 \u0627\u0644\u0647\u062c\u0645\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u0639\u0631\u0636 \u0644\u0647\u0627 \u0627\u0644\u062e\u0627\u062f\u0645 \u0627\u0644\u0645\u062d\u0644\u064a \u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u0634\u0631\u0648\u0642 \u0623\u0648\u0646 \u0644\u0627\u064a\u0646 \u0641\u064a \u0627\u0644\u0634\u0647\u0648\u0631 \u0627\u0644\u0623\u062e\u064a\u0631\u0629 \u062c\u0627\u0621\u062a \u0643\u0627\u0644\u062a\u0627\u0644\u064a:<\/strong><\/p>\n<p style=\"text-align: right\"><strong>\u2013 \u0628\u062a\u0627\u0631\u064a\u062e 12 \u0641\u064a\u0641\u0631\u064a 2021 \u062a\u0639\u0631\u0636 \u0627\u0644\u062e\u0627\u062f\u0645 \u0644\u0645\u062d\u0627\u0648\u0644\u0629 \u0631\u0641\u0639 shell \u0639\u0646 \u0637\u0631\u064a\u0642 \u0641\u062a\u062d \u0628\u0648\u0631\u062a 8080 \u0641\u064a virtuel server \u062f\u0627\u062e\u0644 \u0627\u0644\u0631\u0648\u062a\u0648\u0631 \u0648\u0645\u062d\u0627\u0648\u0644\u0629 \u062a\u062c\u0627\u0648\u0632 \u0627\u0644\u062d\u0645\u0627\u064a\u0629\u060c<\/strong><br \/>\n<strong>\u2013 \u0642\u0628\u0644 \u0634\u0647\u0631\u064a\u0646 \u062a\u0645\u062a \u0645\u062d\u0627\u0648\u0644\u0629 \u0625\u063a\u0631\u0627\u0642 \u0627\u0644\u0640iP \u0639\u0646 \u0637\u0631\u064a\u0642 PING<\/strong><br \/>\n<strong>\u2013 \u0643\u0645\u0627 \u062a\u0645 \u062a\u0633\u062c\u064a\u0644 \u201c\u062a\u0631\u0627\u0641\u064a\u0643\u201d \u0636\u062e\u0645 \u0628\u0639\u0634\u0631\u0627\u062a \u0627\u0644\u0622\u0644\u0627\u0641 \u0641\u064a \u0646\u0641\u0633 \u0627\u0644\u0648\u0642\u062a \u0648\u0643\u0627\u0646\u062a \u0647\u0646\u0627\u0643 \u0645\u062d\u0627\u0648\u0644\u0629 \u0644\u0627\u062e\u062a\u0631\u0627\u0642 \u0627\u0644\u062e\u0627\u062f\u0645 \u0627\u0644\u0645\u062d\u0644\u064a \u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u062e\u062a\u0631\u0627\u0642 \u0627\u0644\u0625\u064a\u0628\u064a \u0648\u0641\u062a\u062d \u0628\u0648\u0631\u062a 21 \u0627\u0644\u062e\u0627\u0635 \u0628\u0627\u0644\u0640 ftp\u0645\u0646 \u0623\u062c\u0644 \u0627\u0644\u062a\u062d\u0643\u0645 \u0627\u0644\u0643\u0627\u0645\u0644 \u0641\u064a \u0627\u0644\u062e\u0627\u062f\u0645 \u0645\u0646 \u062d\u064a\u062b \u0627\u0644\u0645\u0627\u062f\u0629 \u0648\u062c\u0644\u0633\u0627\u062a \u0627\u0644\u0645\u0633\u062a\u062e\u062f\u0645\u064a\u0646 \u0627\u0644\u0635\u062d\u0641\u064a\u064a\u0646 \u0639\u0646 \u0637\u0631\u064a\u0642 Metasploit\u0640 \u0627\u0644\u062a\u064a \u0647\u064a \u0639\u0628\u0627\u0631\u0629 \u0639\u0646 \u0645\u062d\u0627\u0648\u0644\u0627\u062a \u0645\u062a\u0643\u0631\u0631\u0629 \u0644\u0627\u062e\u062a\u0631\u0627\u0642 \u0627\u0644\u0623\u062c\u0647\u0632\u0629 \u0627\u0644\u0634\u062e\u0635\u064a\u0629 \u0644\u0644\u0635\u062d\u0641\u064a\u064a\u0646 \u0648\u0627\u0644\u0645\u0633\u0624\u0648\u0644\u064a\u0646 \u0648\u0645\u062d\u064a\u0637\u0647\u0645 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a \u0628\u0645\u0627 \u064a\u0639\u0631\u0641 \u0628\u0640\u201d\u0627\u0644\u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a\u0629\u201d \u0645\u0646 \u062e\u0644\u0627\u0644 \u0637\u0631\u0642 \u0627\u0633\u062a\u062f\u0631\u0627\u062c \u0645\u062e\u062a\u0644\u0641\u0629.<\/strong><br \/>\n<strong>\u0647\u0630\u0627 \u0645\u0627 \u062a\u0645 \u062a\u0633\u062c\u064a\u0644\u0647 \u0639\u0644\u0649 \u0645\u0633\u062a\u0648\u0649 \u0627\u0644\u062e\u0627\u062f\u0645 \u0627\u0644\u0645\u062d\u0644\u064a \u0641\u064a \u0627\u0644\u0645\u0642\u0631\u060c \u0644\u0643\u0646 \u062a\u0628\u0642\u0649 \u0623\u0643\u062b\u0631 \u0627\u0644\u0645\u062d\u0627\u0648\u0644\u0627\u062a \u064a\u062a\u0645 \u0635\u062f\u0647\u0627 \u0639\u0644\u0649 \u0645\u0633\u062a\u0648\u0649 \u0627\u0644\u0645\u0624\u0633\u0633\u0629 \u0627\u0644\u0645\u0633\u062a\u0636\u064a\u0641\u0629 \u0644\u0644\u0645\u0648\u0642\u0639.<\/strong><\/p>\n<p style=\"text-align: right\"><strong>\u0648\u0633\u0639\u064a\u0627 \u0625\u0644\u0649 \u0627\u0644\u062a\u0635\u062f\u064a \u0644\u0645\u062b\u0644 \u0647\u0630\u0647 \u0627\u0644\u0625\u062e\u062a\u0631\u0627\u0642\u0627\u062a \u0648\u0643\u0627\u0641\u0629 \u0627\u0644\u0645\u062e\u0627\u0637\u0631 \u0648\u0627\u0644\u062a\u0647\u062f\u064a\u062f\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u062d\u0645\u0644\u0647\u0627 \u0627\u0644\u0639\u0627\u0644\u0645 \u0627\u0644\u0633\u064a\u0628\u0631\u064a\u0627\u0646\u064a \u062a\u0639\u0645\u0644 \u0628\u0644\u0627\u062f\u0646\u0627 \u0628\u062c\u062f \u0639\u0644\u0649 \u0645\u0648\u0627\u062c\u0647\u0629 \u0647\u0630\u0647 \u0627\u0644\u0638\u0627\u0647\u0631\u0629 \u0644\u0627\u0633\u064a\u0645\u0627 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u0646\u062a\u0627\u062c \u0645\u062d\u062a\u0648\u0649 \u0648\u0637\u0646\u064a \u0646\u0648\u0639\u064a \u0639\u0644\u0649 \u0627\u0644\u0645\u0648\u0627\u0642\u0639 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629 \u0627\u0644\u0625\u0639\u0644\u0627\u0645\u064a\u0629 \u0648\u0627\u0644\u0623\u0631\u0636\u064a\u0627\u062a \u0627\u0644\u0639\u0644\u0645\u064a\u0629 \u0648\u064a\u0634\u0645\u0644 \u0647\u0630\u0627 \u0627\u0644\u0645\u0633\u0639\u0649 \u0623\u064a\u0636\u0627 \u062a\u0623\u0645\u064a\u0646 \u0627\u0644\u0634\u0628\u0643\u0629 \u062a\u0643\u0631\u064a\u0633\u0627 \u0644\u0633\u064a\u0627\u062f\u0629 \u0627\u0644\u062f\u0648\u0644\u0629 \u0639\u0644\u0649 \u0645\u062c\u0627\u0644 \u0627\u0644\u0631\u0642\u0645\u0646\u0629 \u0648\u0647\u0648 \u0645\u0627 \u062d\u0631\u0635\u062a \u0648\u0632\u0627\u0631\u0629 \u0627\u0644\u0627\u062a\u0635\u0627\u0644 \u0639\u0644\u0649 \u062a\u062c\u0633\u064a\u062f\u0647 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u0634\u062a\u0631\u0627\u0637 \u0627\u0644\u062a\u0648\u0637\u064a\u0646 \u0641\u064a \u0646\u0637\u0627\u0642 DZ \u0628\u0627\u0644\u0646\u0633\u0628\u0629 \u0644\u0644\u0645\u0648\u0627\u0642\u0639 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629 \u0627\u0644\u0646\u0627\u0634\u0637\u0629 \u0641\u064a \u0625\u0637\u0627\u0631 \u0627\u0644\u0645\u0631\u0633\u0648\u0645 \u0627\u0644\u062a\u0646\u0641\u064a\u0630\u064a \u0627\u0644\u0645\u0633\u062a\u062d\u062f\u062b \u0648\u0627\u0644\u0645\u062a\u0639\u0644\u0642 \u0628\u0646\u0634\u0627\u0637 \u0627\u0644\u0625\u0639\u0644\u0627\u0645 \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a \u0648\u062d\u0642 \u0627\u0644\u0631\u062f \u0648\u0627\u0644\u062a\u0635\u062d\u064a\u062d.<\/strong><br \/>\n<strong>\u0625\u0646 \u0623\u062f\u0648\u0627\u062a \u062a\u0623\u0645\u064a\u0646 \u0645\u0648\u0627\u0642\u0639 \u0627\u0644\u0648\u064a\u0628 \u062a\u0643\u0627\u062f \u062a\u062a\u0639\u062f\u062f \u0628\u062a\u0639\u062f\u062f \u0623\u0633\u0627\u0644\u064a\u0628 \u0627\u0644\u062c\u0631\u064a\u0645\u0629 \u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629 \u0648\u0644\u0639\u0644 \u0645\u0646 \u0623\u0628\u0631\u0632 \u0647\u0630\u0647 \u0627\u0644\u0623\u062f\u0648\u0627\u062a \u0645\u0627 \u064a\u0639\u0631\u0641 \u201c\u0628\u0634\u0647\u0627\u062f\u0629 SSL\u201d \u0623\u0648 \u201c\u0634\u0647\u0627\u062f\u0629 \u0627\u0644\u0645\u0641\u062a\u0627\u062d \u0627\u0644\u0639\u0645\u0648\u0645\u064a\u201d \u0627\u0644\u062a\u064a \u062a\u0639\u062a\u0628\u0631 \u0643\u0628\u0637\u0627\u0642\u0629 \u0647\u0648\u064a\u0629 \u0631\u0642\u0645\u064a\u0629 \u062a\u0633\u0645\u062d \u0628\u0627\u0644\u062a\u062d\u0642\u0642 \u0645\u0646 \u0647\u0648\u064a\u0629 \u0627\u0644\u0634\u062e\u0635 \u0623\u0648 \u0627\u0644\u0645\u0646\u0638\u0645\u0629 \u0623\u0648 \u0627\u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a \u0648\u0643\u0630\u0627 \u0628\u062a\u0634\u0641\u064a\u0631 \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0648\u0627\u0644\u0645\u0628\u0627\u062f\u0644\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u062d\u062a\u0648\u064a\u0647\u0627 \u062c\u0647\u0627\u0632 \u0627\u0644\u062e\u0627\u062f\u0645.<\/strong><br \/>\n<strong>\u0644\u0643\u0646 \u0648\u0631\u063a\u0645 \u0623\u0647\u0645\u064a\u0629 \u0634\u0647\u0627\u062f\u0629 SSL \u0625\u0644\u0627 \u0623\u0646 85% \u0645\u0646 \u0627\u0644\u0645\u0648\u0627\u0642\u0639 \u0627\u0644\u062c\u0632\u0627\u0626\u0631\u064a\u0629 \u0627\u0644\u0645\u0634\u0645\u0648\u0644\u0629 \u0628\u0627\u0644\u062f\u0631\u0627\u0633\u0629 \u0627\u0644\u0645\u0630\u0643\u0648\u0631\u0629 \u0644\u0627 \u062a\u062a\u0648\u0641\u0631 \u0639\u0644\u0649 \u0647\u0630\u0647\u00a0<a href=\"https:\/\/www.echoroukonline.com\/%D8%A8%D9%84%D8%AD%D9%8A%D9%85%D8%B1-%D8%A7%D9%84%D8%AC%D8%B2%D8%A7%D8%A6%D8%B1-%D8%AA%D8%AA%D8%B9%D8%B1%D8%B6-%D9%84%D8%AD%D9%85%D9%84%D8%A9-%D8%A8%D8%B3%D8%A8%D8%A8-%D8%B1%D9%81%D8%B6%D9%87%D8%A7\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u0627\u0644\u0634\u0647\u0627\u062f\u0629<\/a>.<\/strong><\/p>\n<p style=\"text-align: right\"><strong> https:\/\/www.echoroukonline.com\/\u0645\u0635\u062f\u0631<\/strong><\/p>\n<p style=\"text-align: right\">\n","protected":false},"excerpt":{"rendered":"<p>M.Ammar belhimer avait accord\u00e9 le mois de F\u00e9vrier dernier un entretient avec le journal echoroukonline et ce pour parler de guerre cybern\u00e9tique&hellip;<\/p>\n","protected":false},"author":58,"featured_media":24858,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[79,49],"tags":[],"class_list":["post-24851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-important","category-politique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>l&#039;Alg\u00e9rie savait ce que se pr\u00e9parait \u00e0 nos fronti\u00e8re Ouest - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"l&#039;Alg\u00e9rie savait ce que se pr\u00e9parait \u00e0 nos fronti\u00e8re Ouest - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"M.Ammar belhimer avait accord\u00e9 le mois de F\u00e9vrier dernier un entretient avec le journal echoroukonline et ce pour parler de guerre cybern\u00e9tique&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-24T16:29:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/20180326_ukraine-master_20001-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"712\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mohamed Redha Chettibi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mohamed Redha Chettibi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\\\/\"},\"author\":{\"name\":\"Mohamed Redha Chettibi\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\"},\"headline\":\"l&#8217;Alg\u00e9rie savait ce que se pr\u00e9parait \u00e0 nos fronti\u00e8re Ouest\",\"datePublished\":\"2021-07-24T16:29:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\\\/\"},\"wordCount\":325,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/20180326_ukraine-master_20001-1.jpg\",\"articleSection\":[\"Important\",\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\\\/\",\"name\":\"l'Alg\u00e9rie savait ce que se pr\u00e9parait \u00e0 nos fronti\u00e8re Ouest - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/20180326_ukraine-master_20001-1.jpg\",\"datePublished\":\"2021-07-24T16:29:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/20180326_ukraine-master_20001-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/20180326_ukraine-master_20001-1.jpg\",\"width\":712,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"l&rsquo;Alg\u00e9rie savait ce que se pr\u00e9parait \u00e0 nos fronti\u00e8re Ouest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\",\"name\":\"Mohamed Redha Chettibi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"caption\":\"Mohamed Redha Chettibi\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/mrc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"l'Alg\u00e9rie savait ce que se pr\u00e9parait \u00e0 nos fronti\u00e8re Ouest - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/","og_locale":"fr_FR","og_type":"article","og_title":"l'Alg\u00e9rie savait ce que se pr\u00e9parait \u00e0 nos fronti\u00e8re Ouest - AAH.JZR","og_description":"M.Ammar belhimer avait accord\u00e9 le mois de F\u00e9vrier dernier un entretient avec le journal echoroukonline et ce pour parler de guerre cybern\u00e9tique&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2021-07-24T16:29:06+00:00","og_image":[{"width":712,"height":400,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/20180326_ukraine-master_20001-1.jpg","type":"image\/jpeg"}],"author":"Mohamed Redha Chettibi","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mohamed Redha Chettibi","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/"},"author":{"name":"Mohamed Redha Chettibi","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77"},"headline":"l&#8217;Alg\u00e9rie savait ce que se pr\u00e9parait \u00e0 nos fronti\u00e8re Ouest","datePublished":"2021-07-24T16:29:06+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/"},"wordCount":325,"commentCount":2,"image":{"@id":"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/20180326_ukraine-master_20001-1.jpg","articleSection":["Important","Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/","url":"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/","name":"l'Alg\u00e9rie savait ce que se pr\u00e9parait \u00e0 nos fronti\u00e8re Ouest - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/20180326_ukraine-master_20001-1.jpg","datePublished":"2021-07-24T16:29:06+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/20180326_ukraine-master_20001-1.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/20180326_ukraine-master_20001-1.jpg","width":712,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/lalgerie-savait-ce-que-se-preparait-a-nos-frontiere-ouest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"l&rsquo;Alg\u00e9rie savait ce que se pr\u00e9parait \u00e0 nos fronti\u00e8re Ouest"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77","name":"Mohamed Redha Chettibi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","caption":"Mohamed Redha Chettibi"},"url":"https:\/\/jazairhope.org\/fr\/author\/mrc\/"}]}},"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/24851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=24851"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/24851\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/24858"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=24851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=24851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=24851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}