{"id":25179,"date":"2021-07-27T03:15:02","date_gmt":"2021-07-27T03:15:02","guid":{"rendered":"https:\/\/jazairhope.org\/?p=25179"},"modified":"2021-07-27T04:01:59","modified_gmt":"2021-07-27T04:01:59","slug":"pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/","title":{"rendered":"Pegasus, RSF et les journalistes \u00ab autoproclam\u00e9s \u00bb du Hirak alg\u00e9rien"},"content":{"rendered":"<p><span class=\"createdate\"><span class=\"createby\"><strong>Dr Ahmed Bensaada<\/strong> ,<\/span>\u00a0<strong>Lundi, 26 Juillet 2021 19:17\u00a0<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Selon la mythologie grecque, Pegasus (P\u00e9gase en fran\u00e7ais) est un cheval ail\u00e9 qui \u00e9tait charg\u00e9 d\u2019acheminer le tonnerre et les \u00e9clairs sur l\u2019Olympe. Il avait aussi comme pouvoir de faire jaillir les sources d\u2019un coup de sabot. Et comme son homologue mythologique, le pauvre hongre sorti des laboratoires de l\u2019entreprise isra\u00e9lienne NSO a non seulement r\u00e9ussi \u00e0 faire tomber la foudre et le tonnerre sur la t\u00eate de certains pays, en particulier le Maroc, mais a aussi permis de confirmer la compromission de certains \u00ab\u00a0journalistes autoproclam\u00e9s du Hirak\u00a0\u00bb et de leurs employeurs et soutiens \u00e9trangers.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.ahmedbensaada.com\/images\/stories\/Images\/Pegasus_Drareni_RSF\/drareni_journaliste_autopro.jpg\" width=\"358\" height=\"337\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"https:\/\/www.theguardian.com\/world\/2021\/jul\/18\/revealed-leak-uncovers-global-abuse-of-cyber-surveillance-weapon-nso-group-pegasus\">L\u2019enqu\u00eate sur la gigantesque affaire d\u2019espionnage<\/a><\/span>\u00a0du logiciel Pegasus a montr\u00e9 que plus de 50\u00a0000 personnes ont \u00e9t\u00e9 cibl\u00e9es \u00e0 travers le monde. Activistes, journalistes, avocats et politiciens ont \u00e9t\u00e9 \u00e9lectroniquement espionn\u00e9s par, au moins,<span style=\"color: #0000ff\">\u00a0<a style=\"color: #0000ff\" href=\"https:\/\/www.amnesty.org\/en\/latest\/news\/2021\/07\/the-pegasus-project\/\">les onze pays suivants<\/a><\/span><a href=\"https:\/\/www.amnesty.org\/en\/latest\/news\/2021\/07\/the-pegasus-project\/\">\u00a0<\/a>: Arabie Saoudite, Azerba\u00efdjan, Bahre\u00efn, \u00c9mirats Arabes Unis, Hongrie, Inde, Kazakhstan, Maroc,\u00a0Mexique, Rwanda et Togo. Il est tr\u00e8s important de noter que NSO, la firme qui commercialise le logiciel ne peut vendre son produit<span style=\"color: #0000ff\">\u00a0<a style=\"color: #0000ff\" href=\"https:\/\/www.timesofisrael.com\/israeli-hacking-firm-nso-group-offered-saudis-cellphone-spy-tools-report\/\">sans l\u2019aval du Minist\u00e8re de la d\u00e9fense isra\u00e9lien<\/a><\/span>, ce qui en dit long sur les m\u00e9thodes et l\u2019\u00e9thique de l\u2019entit\u00e9 sioniste.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.ahmedbensaada.com\/images\/stories\/Images\/Pegasus_Drareni_RSF\/pegasus_amnesty.jpg\" width=\"723\" height=\"722\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ce vaste scandale, aussi n\u00e9faste soit-il, a permis de mettre la lumi\u00e8re sur deux aspects importants de la g\u00e9opolitique et des relations internationales. Primo, il a d\u00e9montr\u00e9 que l\u2019ing\u00e9rence \u00e9trang\u00e8re, si d\u00e9cri\u00e9e \u00e0 l\u2019occasion du Hirak (et bien avant), n\u2019est pas uniquement une vue de l\u2019esprit mais belle et bien r\u00e9elle. Secundo, il a confirm\u00e9 que les relations s\u00e9curitaires, commerciales et politiques entre l\u2019\u00c9tat h\u00e9breu et certains pays arabes ne datent pas d\u2019hier et ont pr\u00e9c\u00e9d\u00e9 les r\u00e9centes normalisations (Maroc et \u00c9mirats) ou celles pressenties dans le futur (Arabie Saoudite).<\/strong><\/p>\n<p><strong>Le Maroc, \u00e0 lui seul, a cibl\u00e9 plus de 10\u00a0000 num\u00e9ros de t\u00e9l\u00e9phone, soit pr\u00e8s du cinqui\u00e8me du total.\u00a0<span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"https:\/\/www.theguardian.com\/world\/2021\/jul\/18\/revealed-leak-uncovers-global-abuse-of-cyber-surveillance-weapon-nso-group-pegasus\">60% de ces cibles (6000) ont \u00e9t\u00e9 localis\u00e9es en Alg\u00e9rie<\/a><\/span>, montrant \u00e0 quel point le consid\u00e9rable espionnage du Royaume ch\u00e9rifien est focalis\u00e9 vers l\u2019Alg\u00e9rie d\u00e9voilant les intentions belliqueuses de ce pays envers son voisin.<\/strong><\/p>\n<p><strong>L\u2019exposition de l\u2019Alg\u00e9rie \u00e0 cette cybercriminalit\u00e9 a \u00e9t\u00e9 souvent \u00e9voqu\u00e9e par le Ministre de la Communication, M. Ammar Belhimer, dans l\u2019incr\u00e9dulit\u00e9 (la mauvaise foi?) ambiante de celles et ceux qui ont all\u00e9grement surf\u00e9 sur le Hirak. Diff\u00e9rents<span style=\"color: #0000ff\">\u00a0<a style=\"color: #0000ff\" href=\"https:\/\/www.lesoirdalgerie.com\/a-fonds-perdus\/loeil-du-mossad-34216\">articles<\/a><\/span>\u00a0et\u00a0<span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"https:\/\/www.dzair-tube.dz\/fr\/8524-2\/\">interviews<\/a><\/span>\u00a0y ont \u00e9t\u00e9 consacr\u00e9s indiquant la perspicacit\u00e9 de son analyse.\u00a0<span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"https:\/\/www.i24news.tv\/fr\/actu\/international\/1613656642-israel-et-le-maroc-ont-mene-une-cyber-guerre-contre-nous-ministre-algerien\">Certaines d\u00e9clarations<\/a><\/span>\u00a0ont \u00e9t\u00e9 m\u00eame tr\u00e8s largement reprises par la chaine isra\u00e9lienne I24.<\/strong><\/p>\n<p><strong>C\u2019est au milieu de ce tintamarre m\u00e9diatique provoqu\u00e9 par cette gigantesque affaire d\u2019espionnage, que Reporters Sans Fronti\u00e8res (RSF), rebaptis\u00e9 Ragotards Sans Foi (ni loi), tenta de poursuivre sa mission de d\u00e9nigrement de l\u2019Alg\u00e9rie. Rappelons que depuis le d\u00e9but du Hirak, elle n\u2019a cess\u00e9 d\u2019user de m\u00e9disance, de d\u00e9nigrement et de diffamation contre l\u2019Alg\u00e9rie. On se souviendra de\u00a0<span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"https:\/\/francais.rt.com\/opinions\/81330-algerie-face-union-europeenne-et-ses-lobbys-ahmed-bensaada\">son implication dans la r\u00e9solution de l\u2019Union europ\u00e9enne<\/a><\/span>\u00a0fin novembre 2020 et de ses nombreuses d\u00e9clarations incendiaires concernant l\u2019Alg\u00e9rie.<\/strong><\/p>\n<p><strong>Toute honte bue,<span style=\"color: #0000ff\">\u00a0<a style=\"color: #0000ff\" href=\"https:\/\/web.archive.org\/web\/20210719203549\/https:\/rsf.org\/fr\/actualites\/pegasus-un-outil-repugnant-et-sordide-prise-par-les-predateurs-de-la-liberte-de-la-presse\">RSF publia un article<\/a>\u00a0<\/span>dans lequel elle accusa nomm\u00e9ment l\u2019Alg\u00e9rie d\u2019\u00eatre un client de NSO et donc un utilisateur du logiciel espion Pegasus.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.ahmedbensaada.com\/images\/stories\/Images\/Pegasus_Drareni_RSF\/rsf_pegasus_avec_algerie.jpg\" width=\"519\" height=\"145\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Khaled Drareni, journaliste \u00ab\u00a0autoproclam\u00e9\u00a0\u00bb du Hirak et, accessoirement correspondant de RSF, relaya \u00e9videmment cet article, comme tout employ\u00e9 au service de son employeur.<\/strong><\/p>\n<p><strong>Celui qui a \u00e9t\u00e9 pr\u00e9sent\u00e9 comme un \u00ab\u00a0grand\u00a0\u00bb et \u00ab\u00a0\u00e9minent\u00a0\u00bb journaliste devant l\u2019\u00e9ternel n\u2019a pas essay\u00e9 de lire toutes les multiples enqu\u00eates (pour une fois!) bien document\u00e9es publi\u00e9es par les m\u00e9dias, en particulier anglosaxons, dans lesquelles l\u2019Alg\u00e9rie a \u00e9t\u00e9 pr\u00e9sent\u00e9e comme une victime de l\u2019espionnage marocain et non coupable. Il a d\u00fb jubiler \u00e0 l\u2019id\u00e9e que l\u2019Alg\u00e9rie soit impliqu\u00e9e dans l\u2019espionnage des \u00ab\u00a0d\u00e9mocrates\u00a0\u00bb ongistes, des islamawistes offshore ou des makistes s\u00e9paratistes qu\u2019il d\u00e9fend bec et ongles. Il a d\u00fb fouiner longtemps \u00e0 la recherche de son num\u00e9ro dans la liste de ceux qui ont \u00e9t\u00e9 espionn\u00e9s pour donner de l\u2019eau au moulin aux flots de bobards de RSF.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.ahmedbensaada.com\/images\/stories\/Images\/Pegasus_Drareni_RSF\/drareni_tweet_rsf.jpg\" width=\"370\" height=\"535\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left\"><strong>Les commentaires des internautes ne se firent pas attendre.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.ahmedbensaada.com\/images\/stories\/Images\/Pegasus_Drareni_RSF\/drareni_tweet_kamel.jpg\" width=\"403\" height=\"225\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.ahmedbensaada.com\/images\/stories\/Images\/Pegasus_Drareni_RSF\/drareni_tweet_bilel.jpg\" width=\"413\" height=\"179\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.ahmedbensaada.com\/images\/stories\/Images\/Pegasus_Drareni_RSF\/drareni_tweet_aksil.jpg\" width=\"393\" height=\"319\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.ahmedbensaada.com\/images\/stories\/Images\/Pegasus_Drareni_RSF\/drareni_tweet_regente.jpg\" width=\"394\" height=\"271\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Un autre fait qui confirme l\u2019instrumentalisation de Khaled Drareni par RSF contre l\u2019Alg\u00e9rie\u00a0: l\u2019histoire de sa banderole. Alors que le journaliste \u00ab\u00a0autoproclam\u00e9\u00a0\u00bb du Hirak a \u00e9t\u00e9 lib\u00e9r\u00e9 en f\u00e9vrier 2021, la \u00ab\u00a0publicit\u00e9\u00a0\u00bb de son incarc\u00e9ration est encore visible aujourd\u2019hui \u00e0 Paris.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.ahmedbensaada.com\/images\/stories\/Images\/Pegasus_Drareni_RSF\/drareni3_bsmall.jpg\" width=\"538\" height=\"704\" \/><\/strong><\/p>\n<div style=\"width: 534px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ahmedbensaada.com\/images\/stories\/Images\/Pegasus_Drareni_RSF\/drareni1_small.jpg\" alt=\"\" width=\"524\" height=\"488\" \/><p class=\"wp-caption-text\"><strong>Banderole g\u00e9ante de Khaled Drareni sponsoris\u00e9e par RSF Photos prises par<span style=\"color: #ff0000\"> B. Snaoui<\/span>, le 26 juillet 2021 vers 23h au 25 Quai d\u2019Ivry, Paris (75013)<\/strong><\/p><\/div>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"text-align: left\"><strong>Est-ce que RSF peut nous expliquer ce que fait une telle propagande mensong\u00e8re dans les rues de Paris? Le hashtag #Freekhaled serait-il encore d\u2019actualit\u00e9 et nous ne serions pas au courant? Ou est-ce juste une autre fa\u00e7on de baver son venin sur l\u2019Alg\u00e9rie?<\/strong><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p><strong>Drareni n\u2019a \u00e9videmment pas \u00e9t\u00e9 le seul dans cette entreprise de calomnie. Son acolyte Hamdi Baala est venu \u00e0 la rescousse, demandant \u00e0 RSF (sic!) si leur information \u00e9tait correcte alors qu\u2019elle \u00e9tait contraire \u00e0 l\u2019ensemble de ce qui avait \u00e9t\u00e9 publi\u00e9 par les m\u00e9dias internationaux!<\/strong><\/p>\n<blockquote><p><strong>H\u00e9! M. Baala, si RSF le dit, c\u2019est que c\u2019est vrai, non?<\/strong><\/p>\n<p><strong>Et vous, RSF, confirmez-lui la nouvelle pour qu\u2019il puisse s\u2019en donner \u00e0 c\u0153ur-joie et se rouler dans la fange de la compromission qu\u2019il semble affectionner tout particuli\u00e8rement!<\/strong><\/p>\n<p>&nbsp;<\/p><\/blockquote>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.ahmedbensaada.com\/images\/stories\/Images\/Pegasus_Drareni_RSF\/baala_tweet_rsf_1.jpg\" width=\"494\" height=\"711\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mais la r\u00e9ponse n\u2019\u00e9tait pas \u00e0 la hauteur des esp\u00e9rances. Zut, alors!<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Comme expliqu\u00e9 dans<span style=\"color: #0000ff\">\u00a0<a style=\"color: #0000ff\" href=\"https:\/\/www.ahmedbensaada.com\/index.php?option=com_content&amp;view=article&amp;id=558:2021-05-11-12-23-18&amp;catid=46:qprintemps-arabeq&amp;Itemid=119\">des articles pr\u00e9c\u00e9dents<\/a><\/span>, Hamdi Baala et Khaled Drareni sont tous deux collaborateurs de Radio M,\u00a0 <span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"https:\/\/www.ahmedbensaada.com\/index.php?option=com_content&amp;view=article&amp;id=555:hirak-la-barbouzerie-de-radio-m&amp;catid=46:qprintemps-arabeq&amp;Itemid=119\">m\u00e9dia barbouze financ\u00e9 par le Quai d\u2019Orsay<\/a>\u00a0<\/span>et ont des relations privil\u00e9gi\u00e9es avec CFI (Canal France International), un organisme lui aussi financ\u00e9 par le minist\u00e8re des Affaires \u00e9trang\u00e8res fran\u00e7ais. On comprend bien alors pourquoi ils s\u2019entendent comme larrons en foire.<\/strong><\/p>\n<p><strong>L\u2019article a donc \u00e9t\u00e9 modifi\u00e9 par RSF et l\u2019Alg\u00e9rie a \u00e9t\u00e9 retir\u00e9e de la liste des clients de NSO au grand regret du \u00ab\u00a0larron\u00a0\u00bb Baala.<\/strong><\/p>\n<p><strong>La tentation \u00e9tait si forte que des journaleux comme Drareni ou Baala ne purent y r\u00e9sister. La ficelle \u00e9tait exag\u00e9r\u00e9ment grosse, mais le mal a \u00e9t\u00e9 fait. Il faut dire que la haine est trop visc\u00e9rale et ne peut que consumer de l\u2019int\u00e9rieur. De temps \u00e0 autre, elle perce et projette des fumerolles aux relents de soufre, l\u2019odeur f\u00e9tide de Satan.<\/strong><\/p>\n<p><strong>Un internaute n\u2019a pas h\u00e9sit\u00e9 \u00e0 les confronter avec la r\u00e9alit\u00e9 en les accusant d\u2019avoir d\u00e9tourn\u00e9 une information erron\u00e9e pour leurs desseins id\u00e9ologiques.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.ahmedbensaada.com\/images\/stories\/Images\/Pegasus_Drareni_RSF\/baala_tweet_rsf.jpg\" width=\"398\" height=\"559\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><strong>Le 23 juillet 2021, l\u2019ambassadeur d\u2019Alg\u00e9rie en France a d\u00e9pos\u00e9<span style=\"color: #0000ff\">\u00a0<a style=\"color: #0000ff\" href=\"https:\/\/fr.calameo.com\/read\/0003668466f65f3f54944\">une plainte pour diffamation<\/a><\/span>\u00a0\u00e0 l\u2019encontre de RSF. On pouvait y lire\u00a0:<\/strong><\/p>\n<p><strong>\u00ab\u00a0<em>Outre le caract\u00e8re diffamatoire et mensonger, ces all\u00e9gations inadmissibles rel\u00e8vent de la manipulation de RSF connue pour son acharnement vis-\u00e0-vis de l\u2019Alg\u00e9rie<\/em>\u00a0\u00bb.<\/strong><\/p>\n<p>&nbsp;<\/p><\/blockquote>\n<p><strong>De quel bord se placeront les \u00ab\u00a0larrons\u00a0\u00bb Drareni et Baala? Du c\u00f4t\u00e9 l\u00e9gal de l\u2019Alg\u00e9rie ou de celui calomnieux de RSF?<\/strong><\/p>\n<p><strong>Mais poser la question, c\u2019est y r\u00e9pondre, n\u2019est-ce pas?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Source: \/www.ahmedbensaada.com<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dr Ahmed Bensaada ,\u00a0Lundi, 26 Juillet 2021 19:17\u00a0 &nbsp; Selon la mythologie grecque, Pegasus (P\u00e9gase en fran\u00e7ais) est un cheval ail\u00e9 qui&hellip;<\/p>\n","protected":false},"author":58,"featured_media":25180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[32,79,49],"tags":[],"class_list":["post-25179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-algerie","category-important","category-politique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pegasus, RSF et les journalistes \u00ab autoproclam\u00e9s \u00bb du Hirak alg\u00e9rien - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pegasus, RSF et les journalistes \u00ab autoproclam\u00e9s \u00bb du Hirak alg\u00e9rien - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Dr Ahmed Bensaada ,\u00a0Lundi, 26 Juillet 2021 19:17\u00a0 &nbsp; Selon la mythologie grecque, Pegasus (P\u00e9gase en fran\u00e7ais) est un cheval ail\u00e9 qui&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-27T03:15:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-27T04:01:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/pegasus_cellphones.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mohamed Redha Chettibi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mohamed Redha Chettibi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\\\/\"},\"author\":{\"name\":\"Mohamed Redha Chettibi\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\"},\"headline\":\"Pegasus, RSF et les journalistes \u00ab autoproclam\u00e9s \u00bb du Hirak alg\u00e9rien\",\"datePublished\":\"2021-07-27T03:15:02+00:00\",\"dateModified\":\"2021-07-27T04:01:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\\\/\"},\"wordCount\":1305,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/pegasus_cellphones.jpg\",\"articleSection\":[\"Alg\u00e9rie Alg\u00e9rienne\",\"Important\",\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\\\/\",\"name\":\"Pegasus, RSF et les journalistes \u00ab autoproclam\u00e9s \u00bb du Hirak alg\u00e9rien - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/pegasus_cellphones.jpg\",\"datePublished\":\"2021-07-27T03:15:02+00:00\",\"dateModified\":\"2021-07-27T04:01:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/pegasus_cellphones.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/pegasus_cellphones.jpg\",\"width\":700,\"height\":467},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pegasus, RSF et les journalistes \u00ab autoproclam\u00e9s \u00bb du Hirak alg\u00e9rien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\",\"name\":\"Mohamed Redha Chettibi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"caption\":\"Mohamed Redha Chettibi\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/mrc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pegasus, RSF et les journalistes \u00ab autoproclam\u00e9s \u00bb du Hirak alg\u00e9rien - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/","og_locale":"fr_FR","og_type":"article","og_title":"Pegasus, RSF et les journalistes \u00ab autoproclam\u00e9s \u00bb du Hirak alg\u00e9rien - AAH.JZR","og_description":"Dr Ahmed Bensaada ,\u00a0Lundi, 26 Juillet 2021 19:17\u00a0 &nbsp; Selon la mythologie grecque, Pegasus (P\u00e9gase en fran\u00e7ais) est un cheval ail\u00e9 qui&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2021-07-27T03:15:02+00:00","article_modified_time":"2021-07-27T04:01:59+00:00","og_image":[{"width":700,"height":467,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/pegasus_cellphones.jpg","type":"image\/jpeg"}],"author":"Mohamed Redha Chettibi","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mohamed Redha Chettibi","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/"},"author":{"name":"Mohamed Redha Chettibi","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77"},"headline":"Pegasus, RSF et les journalistes \u00ab autoproclam\u00e9s \u00bb du Hirak alg\u00e9rien","datePublished":"2021-07-27T03:15:02+00:00","dateModified":"2021-07-27T04:01:59+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/"},"wordCount":1305,"commentCount":2,"image":{"@id":"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/pegasus_cellphones.jpg","articleSection":["Alg\u00e9rie Alg\u00e9rienne","Important","Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/","url":"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/","name":"Pegasus, RSF et les journalistes \u00ab autoproclam\u00e9s \u00bb du Hirak alg\u00e9rien - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/pegasus_cellphones.jpg","datePublished":"2021-07-27T03:15:02+00:00","dateModified":"2021-07-27T04:01:59+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/pegasus_cellphones.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/07\/pegasus_cellphones.jpg","width":700,"height":467},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/pegasus-rsf-et-les-journalistes-autoproclames-du-hirak-algerien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Pegasus, RSF et les journalistes \u00ab autoproclam\u00e9s \u00bb du Hirak alg\u00e9rien"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77","name":"Mohamed Redha Chettibi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","caption":"Mohamed Redha Chettibi"},"url":"https:\/\/jazairhope.org\/fr\/author\/mrc\/"}]}},"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/25179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=25179"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/25179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/25180"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=25179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=25179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=25179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}