{"id":29098,"date":"2021-09-05T09:43:21","date_gmt":"2021-09-05T09:43:21","guid":{"rendered":"https:\/\/jazairhope.org\/?p=29098"},"modified":"2021-09-05T09:43:21","modified_gmt":"2021-09-05T09:43:21","slug":"plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/","title":{"rendered":"Plus de 100 mille logements attribu\u00e9s depuis le 5 juillet 2021"},"content":{"rendered":"<p><span style=\"color: #003366\"><strong>La Radio d\u2019Oran a programm\u00e9 et anim\u00e9, ce samedi apr\u00e8s midi, une \u00e9mission d\u00e9di\u00e9e \u00e0 \u00ab\u00a0la plus grande op\u00e9ration de distribution de logements\u00bb r\u00e9alis\u00e9e cette ann\u00e9e 2021, \u00e0 travers le pays. D\u2019une dur\u00e9e de deux heures, cette \u00e9mission sp\u00e9ciale a \u00e9t\u00e9 diffus\u00e9e, en simultan\u00e9, sur la Radio Chaine 1 et l\u2019ensemble des radios locales sur le territoire. Plusieurs cadres du minist\u00e8re de l\u2019Habitat, de l\u2019urbanisme et de la ville ont \u00e9t\u00e9 convi\u00e9s au studio pour d\u00e9battre de ces r\u00e9alisations.<\/strong><\/span><\/p>\n<p><span style=\"color: #003366\">\u00ab\u00a0Le r\u00e8glement de la crise du logement compte parmi les engagements du pr\u00e9sident de la R\u00e9publique, Abdelmadjid Tebboune, qui connait bien ce secteur et ses capacit\u00e9s colossales\u00a0\u00bb, rappelle l\u2019animateur dans son introduction avant d\u2019annonce que \u00ab\u00a0ce sont plus de 100 mille logements qui ont \u00e9t\u00e9 attribu\u00e9s depuis le 5 juillet 2021. Des unit\u00e9s de diff\u00e9rents programmes de logement dont ont b\u00e9n\u00e9fici\u00e9 plus de 500 mille personnes \u00e0 travers 53 wilayas, dans ce qui repr\u00e9sente la plus grande op\u00e9ration de distribution de logements qu\u2019a connu l\u2019Alg\u00e9rie.\u00bb<\/span><\/p>\n<blockquote><p><strong><span style=\"color: #003366\">\u00ab\u00a0En plus du programme de plus de 930 mille logements d\u00e9j\u00e0 en cours d\u2019administration par le minist\u00e8re de l\u2019Habitat, s\u2019ajoute un programme d\u2019un million de logement au titre du programme quinquennal 2020-2024\u00a0\u00bb, affirme Ismail Loumi, directeur g\u00e9n\u00e9ral du logement au minist\u00e8re de l\u2019Habitat qui estime que cela \u00ab\u00a0d\u00e9montre les nombreux efforts consentis par l\u2019Etat pour la promotion et l\u2019accompagnement de ce secteur, dans le but de rendre accessibles des logements dignes aux citoyens\u00a0.\u00bb<\/span><\/strong><\/p><\/blockquote>\n<p><span style=\"color: #003366\">\u00ab\u00a0Cette derni\u00e8re op\u00e9ration est consid\u00e9r\u00e9e comme l\u2019une des plus grandes op\u00e9rations d\u2019attribution de logements jamais organis\u00e9e et a concern\u00e9 53 wilayas sur les 58 et entre dans le cadre du programme du pr\u00e9sident de la R\u00e9publique que nous nous effor\u00e7ons \u00e0 mettre en \u0153uvre\u00a0\u00bb, indique le responsable avant de d\u00e9tailler les diff\u00e9rentes formules de logements distribu\u00e9s\u00a0: \u00ab\u00a0plus de 19 mille unit\u00e9s de logement public locatif et 2757 unit\u00e9s de logement participatif, 2416 unit\u00e9s de logement promotionnel public et plus de 13 mille unit\u00e9s en logement rural.\u00bb<\/span><\/p>\n<p><span style=\"color: #003366\">Ismail Loumi pr\u00e9cise que le logement AADL prend \u00ab\u00a0la part du lion avec plus de 61 milles unit\u00e9s\u00a0\u00bb, ce qui est \u00ab\u00a0une premi\u00e8re\u00bb, selon ce responsable, qui rappelle que cette op\u00e9ration a eu lieu \u00e0 l\u2019occasion de la c\u00e9l\u00e9bration du double anniversaire de la f\u00eate de l\u2019ind\u00e9pendance et de la jeunesse. \u00ab\u00a0Une op\u00e9ration d\u2019envergure, qui n\u2019a pas \u00e9t\u00e9 facilit\u00e9e par le contexte sanitaire li\u00e9 \u00e0 la pand\u00e9mie de Covid-19\u00a0\u00bb, rel\u00e8ve Faycel Zitouni, DG de l\u2019AADL.<\/span><\/p>\n<p><span style=\"color: #003366\">Rien que pour la wilaya d\u2019Oran, ce sont plus de 28 mille unit\u00e9s de logements qui ont \u00e9t\u00e9 attribu\u00e9s. Durant cette \u00e9mission sp\u00e9ciale, les auditeurs ont \u00e9galement pu \u00e9couter des t\u00e9moignages d\u2019heureux b\u00e9n\u00e9ficiaires.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\"><strong>Source: https:\/\/algerie54.dz\/<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Radio d\u2019Oran a programm\u00e9 et anim\u00e9, ce samedi apr\u00e8s midi, une \u00e9mission d\u00e9di\u00e9e \u00e0 \u00ab\u00a0la plus grande op\u00e9ration de distribution de&hellip;<\/p>\n","protected":false},"author":58,"featured_media":29099,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[79],"tags":[],"class_list":["post-29098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-important"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plus de 100 mille logements attribu\u00e9s depuis le 5 juillet 2021 - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plus de 100 mille logements attribu\u00e9s depuis le 5 juillet 2021 - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"La Radio d\u2019Oran a programm\u00e9 et anim\u00e9, ce samedi apr\u00e8s midi, une \u00e9mission d\u00e9di\u00e9e \u00e0 \u00ab\u00a0la plus grande op\u00e9ration de distribution de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-05T09:43:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/09\/AADL-FINAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"428\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mohamed Redha Chettibi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mohamed Redha Chettibi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\\\/\"},\"author\":{\"name\":\"Mohamed Redha Chettibi\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\"},\"headline\":\"Plus de 100 mille logements attribu\u00e9s depuis le 5 juillet 2021\",\"datePublished\":\"2021-09-05T09:43:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\\\/\"},\"wordCount\":514,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/AADL-FINAL.jpg\",\"articleSection\":[\"Important\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\\\/\",\"name\":\"Plus de 100 mille logements attribu\u00e9s depuis le 5 juillet 2021 - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/AADL-FINAL.jpg\",\"datePublished\":\"2021-09-05T09:43:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/AADL-FINAL.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/AADL-FINAL.jpg\",\"width\":428,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plus de 100 mille logements attribu\u00e9s depuis le 5 juillet 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\",\"name\":\"Mohamed Redha Chettibi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"caption\":\"Mohamed Redha Chettibi\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/mrc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plus de 100 mille logements attribu\u00e9s depuis le 5 juillet 2021 - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"Plus de 100 mille logements attribu\u00e9s depuis le 5 juillet 2021 - AAH.JZR","og_description":"La Radio d\u2019Oran a programm\u00e9 et anim\u00e9, ce samedi apr\u00e8s midi, une \u00e9mission d\u00e9di\u00e9e \u00e0 \u00ab\u00a0la plus grande op\u00e9ration de distribution de&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2021-09-05T09:43:21+00:00","og_image":[{"width":428,"height":200,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/09\/AADL-FINAL.jpg","type":"image\/jpeg"}],"author":"Mohamed Redha Chettibi","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mohamed Redha Chettibi","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/"},"author":{"name":"Mohamed Redha Chettibi","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77"},"headline":"Plus de 100 mille logements attribu\u00e9s depuis le 5 juillet 2021","datePublished":"2021-09-05T09:43:21+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/"},"wordCount":514,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/09\/AADL-FINAL.jpg","articleSection":["Important"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/","url":"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/","name":"Plus de 100 mille logements attribu\u00e9s depuis le 5 juillet 2021 - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/09\/AADL-FINAL.jpg","datePublished":"2021-09-05T09:43:21+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/09\/AADL-FINAL.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/09\/AADL-FINAL.jpg","width":428,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/plus-de-100-mille-logements-attribues-depuis-le-5-juillet-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Plus de 100 mille logements attribu\u00e9s depuis le 5 juillet 2021"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77","name":"Mohamed Redha Chettibi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","caption":"Mohamed Redha Chettibi"},"url":"https:\/\/jazairhope.org\/fr\/author\/mrc\/"}]}},"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/29098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=29098"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/29098\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/29099"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=29098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=29098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=29098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}