{"id":39003,"date":"2021-12-10T10:46:05","date_gmt":"2021-12-10T10:46:05","guid":{"rendered":"https:\/\/jazairhope.org\/?p=39003"},"modified":"2021-12-10T00:48:07","modified_gmt":"2021-12-10T00:48:07","slug":"supplement-a-un-pourvoi-en-justice","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/","title":{"rendered":"Suppl\u00e9ment \u00e0 un pourvoi en justice"},"content":{"rendered":"<div>\n<p style=\"text-align: center\"><span style=\"color: #003366\"><strong>Par Abdellali Merdaci<\/strong><\/span><\/p>\n<p><span style=\"color: #003366\"><strong><em>Dans l\u2019interpellation en justice \u00e0 laquelle m\u2019assigne le couple Chaulet-Zelig-Mouffok, qui n\u2019en finit pas de battre le rappel de sa claque de gougnafiers, il y a des aspects qui m\u00e9ritent de sortir de l\u2019ombre. Je voudrais \u2013 \u00ab\u00a0benoitement\u00a0\u00bb, comme cela m\u2019est reproch\u00e9 \u2013 apporter quelques pr\u00e9cisions afin que nul n\u2019en ignore. Le n\u0153ud de cette affaire est d\u2019avoir marqu\u00e9 la proximit\u00e9 des Zelig-Mouffok avec le n\u00e9o-hirak, ce qui constitue de leur point de vue un \u00ab\u00a0d\u00e9lit\u00a0\u00bb de \u00ab\u00a0diffamation\u00a0\u00bb. Des milliers d\u2019Alg\u00e9riens publient sur le pr\u00e9sident de la R\u00e9publique et sur les hauts responsables de l\u2019\u00c9tat toutes sortes de textes dans la presse et sur les r\u00e9seaux sociaux, sans que cela constitue un d\u00e9lit relevant des lois. Pourquoi les Zelig-Mouffok devraient-ils marquer une ligne rouge\u00a0? Dans une prose fielleuse, ils m\u2019accusent de leur avoir taill\u00e9s des costumes sur mesure\u00a0:\u00a0<\/em><\/strong><strong><em>\u00ab\u00a0Ce qui est toujours \u00e9tonnant avec cette n\u00e9o-\u00e9criture qui est devenue la signature des n\u00e9o-nationalistes, c&#8217;est la disproportion entre la gravit\u00e9 des accusations, du \u201cmal\u00e9fique projet\u201d, de sa \u201cfurie destructrice\u201d, \u201cs\u00e9paratiste\u201d, et la l\u00e9g\u00e8ret\u00e9 des preuves, puisque l\u2019universitaire se veut \u00e0 la fois procureur, garde des sceaux et ministre de l\u2019Interieur, avec un tel z\u00e8le qu\u2019on pourrait m\u00eame l\u2019accuser d\u2019usurpation de fonctions\u00a0\u00bb (1). C\u2019est ironique\u00a0? Non, b\u00eatifiant et d\u2019une insurmontable cr\u00e9tinerie\u00a0: appeler le discr\u00e9dit sur un adversaire en le traitant de \u00ab\u00a0procureur\u00a0\u00bb, de \u00ab\u00a0garde des sceaux\u00a0\u00bb et de \u00ab\u00a0ministre de l\u2019int\u00e9rieur\u00a0\u00bb.<\/em><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\">Je ne retire rien de ce que j\u2019ai \u00e9crit sur le n\u00e9o-hirak\u00a0: avec ses organisations officiellement reconnues terroristes par l\u2019\u00c9tat alg\u00e9rien, Rachad et le MAK, qui en assurent la direction, il court derri\u00e8re un \u00ab\u00a0mal\u00e9fique projet\u00a0\u00bb, dans une \u00ab\u00a0furie destructrice\u00a0\u00bb et \u00ab\u00a0s\u00e9paratiste\u00a0\u00bb. Est-ce faux\u00a0? Mais le n\u00e9o-hirak, ce sont aussi des agents de l\u2019imp\u00e9rialisme am\u00e9ricain stipendi\u00e9s par la NED (2), des bobos de toutes extractions, des communistes et des trotskystes, des amis d\u2019El Kadi Ihs\u00e8ne regroup\u00e9s autour de Radio M, des \u00ab\u00a0ouvri\u00e9ristes\u00a0\u00bb et des petits-bourgeois de tout acabit qui y recherchent un souffle d\u2019aventure. Omar Zelig et Ghania Mouffok n\u2019ont pas le courage d\u2019assumer leur pr\u00e9sence et leur activisme politique dans cette mouvance terroriste et insurrectionnelle. Ils invoquent une \u00ab\u00a0l\u00e9g\u00e8ret\u00e9 des preuves\u00a0\u00bb. Allons-donc sur le terrain des preuves puisqu\u2019ils m\u2019y convoquent.<\/span><\/p>\n<p><span style=\"color: #003366\">Leur margouillis sur Facebook, mod\u00e8le de communication biais\u00e9e, adress\u00e9 sp\u00e9cialement \u00e0 leurs soutiens, comporte de nombreux trous, qu\u2019il faut n\u00e9cessairement combler.<\/span><\/p>\n<p><span style=\"color: #003366\">Auparavant, j\u2019apporte de n\u00e9cessaires clarifications.<\/span><\/p>\n<p><span style=\"color: #003366\">1\u00b0) J\u2019ai toujours pris l\u2019enti\u00e8re responsabilit\u00e9 de mes \u00e9crits devant mes lecteurs et devant les lois de l\u2019\u00c9tat. Je ne suis jamais apparu sous un quelconque masque et je signe de mon nom ce que j\u2019\u00e9cris et en corrobore la \u00ab\u00a0trace\u00a0\u00bb \u00e9thique, au sens que lui donne Jacques Derrida. Pourquoi Luc Chaulet a-t-il abandonn\u00e9 son \u00e9tat civil originel pour se projeter dans une c\u00e9sure historique et m\u00e9morielle et devenir Omar Zelig, d\u00e9clin\u00e9 en Zigomar par Ahmed Bensaada, sobriquet qui illustre sa tr\u00e9pidante bouffonnerie\u00a0? O\u00f9 cet effacement du nom originel produit-il sa signifiance\u00a0?<\/span><\/p>\n<p><span style=\"color: #003366\">2\u00b0) Les Zelig-Mouffok refusent clairement le d\u00e9bat contradictoire sur leurs propres engagements et actions publics, ainsi le r\u00e9cent post d\u2019Omar Zelig sur Ahmed Bensaada, qui est critiquable, alors que lui ne le serait pas. Cette quasi-immunit\u00e9 que le couple s\u2019attribue est l\u2019expression d\u2019une fragilit\u00e9 psychique et d\u2019un narcissisme exacerb\u00e9. Ce sont des \u00ab\u00a0fils de \u2026\u00a0\u00bb et \u00ab\u00a0belle-fille de\u2026\u00a0\u00bb.<\/span><\/p>\n<p><span style=\"color: #003366\">3\u00b0) J\u2019ai bien not\u00e9 que ne connais pas le couple Chaulet-Zelig-Mouffok et ce n\u2019est pas seulement une clause de style. Il n\u2019est pas de mon monde et je ne partage pas avec lui la plus infime \u00e9motion. Mon Alg\u00e9rie n\u2019est pas son Alg\u00e9rie. Cependant, \u00e0 l\u2019heure d\u2019Internet, qu\u2019est-ce que je saurais ignorer de ses turpitudes\u00a0? En pr\u00e9cisant que ce que j\u2019ai recueilli dans les moteurs de recherche ce sont des propos sign\u00e9s s\u00e9par\u00e9ment par Omar Zelig et Ghania Mouffok, des propos prouv\u00e9s qui ont force d\u2019engagement public, et non pas des supputations qui leurs seraient imprudemment pr\u00eat\u00e9es. Je n\u2019ai rien invent\u00e9 et \u00ab\u00a0tritur\u00e9\u00a0\u00bb. Il n\u2019y a rien de ce que j\u2019ai \u00e9crit sur les Zelig-Mouffok dans ma contribution du 21 novembre 2021 qui ne soit \u00e9tay\u00e9 (3). Si Internet est une poubelle, la pestilence du vomi provient de leurs tripotages. Lorsque le sieur Omar Zelig proclame l\u2019acte de d\u00e9c\u00e8s du hirak (4), cela reste\u00a0: cette fameuse trace ontique, judiciaris\u00e9e. Les Zelig-Mouffok n\u2019aiment pas \u00eatre confront\u00e9s \u00e0 leurs \u00e9crits, pour en r\u00e9pondre. Leurs mots leurs deviennent-ils du pataqu\u00e8s\u00a0?<\/span><\/p>\n<p><span style=\"color: #003366\">4\u00b0) C\u2019est bien en r\u00e9ponse \u00e0 un inconvenant post de Omar Zelig que j\u2019ai interpell\u00e9 les Omar Zelig- Ghania Mouffok dans un d\u00e9bat contradictoire dont ils ont refus\u00e9 le principe pour se complaire dans des faux-fuyants, l\u2019injure et l\u2019intimidation en guise d\u2019argument. Il faudra y revenir.<\/span><\/p>\n<p><span style=\"color: #003366\">Je pr\u00e9cise ceci afin de lever de f\u00e2cheuses insinuations, si ce n\u2019est de viles mises en cause de mes peu scrupuleux adversaires :<\/span><\/p>\n<p><span style=\"color: #003366\">&#8211; Je ne suis dans la client\u00e8le d\u2019aucun pouvoir d\u2019hier ou d\u2019aujourd\u2019hui. Il n\u2019y a pas d\u2019autre lieu de prof\u00e9ration de mes discours que mon alg\u00e9rianit\u00e9. Comment ne pas r\u00e9p\u00e9ter apr\u00e8s Terence\u00a0: \u00ab\u00a0Je suis alg\u00e9rien et tout ce qui est alg\u00e9rien ne m\u2019est pas \u00e9tranger\u00a0\u00bb.<\/span><\/p>\n<p><span style=\"color: #003366\">&#8211; Je ne suis demandeur de rien et je ne suis le \u00ab\u00a0t\u00e9nor autoproclam\u00e9\u00a0\u00bb d\u2019aucun \u00ab\u00a0n\u00e9o-nationalisme\u00a0\u00bb dont je m\u00e9connais l\u2019histoire et les doctrines. Serait-ce un avatar de la \u00ab\u00a0Badissia-Novembria\u00a0\u00bb\u00a0? Un cloaque.<\/span><\/p>\n<p><span style=\"color: #003366\">&#8211; Le hirak, je l\u2019ai \u00e9prouv\u00e9 avant bon nombre de ses h\u00e9rauts incendiaires actuels (5) Il n\u2019a pas \u00e9t\u00e9 en Alg\u00e9rie \u00e0 la mesure d\u2019un grand projet politique d\u00e9mocratique et c\u2019est aussi le cas pour le n\u00e9o-hirak, qui lui a succ\u00e9d\u00e9, qui s\u2019est projet\u00e9 en mouvement s\u00e9ditieux dont le seul objectif clair est de renverser le pouvoir actuel \u00e9lu r\u00e9guli\u00e8rement et l\u00e9galement. J\u2019ai fermement d\u00e9nonc\u00e9, dans plusieurs contributions, ce n\u00e9o-hirak, ses acteurs et sa volont\u00e9 de destruction de l\u2019\u00c9tat par toutes formes de violence terroriste. Je ne crois pas \u00e0 une alternance politique en dehors des urnes.<\/span><\/p>\n<p><span style=\"color: #003366\">&#8211; Ce mouvement, comme ses acteurs, \u00e0 l\u2019image des Zelig-Mouffok, a toujours manqu\u00e9 de maturit\u00e9.<\/span><\/p>\n<p><span style=\"color: #003366\">&#8211; C\u2019est dans un contexte de d\u00e9bat autour du n\u00e9o-hirak que j\u2019ai r\u00e9pondu au post de Omar Zelig sur les \u00ab\u00a0dommages collat\u00e9raux\u00a0\u00bb de l\u2019ancien ministre de la Communication Amar Belhimer, entre autres du \u00ab\u00a0type Bensaada\u00a0\u00bb, incriminant ceux qui reconnaissent, comme l\u2019auteur de ces lignes, la l\u00e9galit\u00e9 du pouvoir d\u2019\u00c9tat et de lois constitutionnelles qui r\u00e9gissent son fonctionnement.<\/span><\/p>\n<p><span style=\"color: #003366\">&#8211; Mais, r\u00e9p\u00e9tons-le, \u00e9crire sur les Chaulet-Zelig-Mouffok, n\u00e9s de la cuisse de Jupiter, est un d\u00e9lit. D\u00e9lirant, simplement d\u00e9lirant.<\/span><\/p>\n<p><span style=\"color: #003366\">Alors, tranchons dans le vif.<\/span><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\"><strong>I. PREMI\u00c8RE PREUVE.<\/strong><\/span><\/p>\n<p><span style=\"color: #003366\"><strong>Malheur dans la n\u00e9o-hirakie\u00a0: face \u00e0 Ihs\u00e8ne El Kadi et Radio M, les Zelig-Mouffok accul\u00e9s<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\">Je ne suis pas dans les cuisines f\u00e9tides du n\u00e9o-hirak, elles ne m\u2019int\u00e9ressent pas. Je ne sais pas quel est aujourd\u2019hui l\u2019\u00e9tat de la relation \u2013 suffisamment ancienne \u2013 entre Omar Zelig et Ihs\u00e8ne El Kadi, directeur du site \u00ab\u00a0Maghreb \u00e9mergent\u00a0\u00bb, de Radio M et acteur de premier plan du n\u00e9o-hirak. Dans ma contribution sur les Zelig-Mouffok, j\u2019ai rattach\u00e9 leur couple \u00e0 Ihs\u00e8ne El Kadi, sur lequel ils ont jet\u00e9 un voile dans leur Facebook. J\u2019ai observ\u00e9 que dans leur r\u00e9ponse \u00e0 mon texte, El Kadi est \u00e9voqu\u00e9 une seule fois, non pas directement, mais en me citant. Il ne faut pas \u00eatre grand clerc de l\u2019analyse du discours et de l\u2019herm\u00e9neutique pour comprendre que les Zelig-Mouffok accablent de leur m\u00e9pris El Kadi. \u00c9videmment, les raisons de leur discorde et de leur rupture leurs appartiennent.<\/span><\/p>\n<p><span style=\"color: #003366\">Omar Zelig et Ghania Mouffok peuvent snober, au mois de novembre 2021, El Kadi et caviarder son nom dans leur prose de Facebook. Mais, ils ont fait un bout de chemin ensemble dans le hirak, puis le n\u00e9o-hirak. Si ce n\u2019est pas le cas, qu\u2019ils aient le courage d\u2019en faire la proclamation publique.<\/span><\/p>\n<p><span style=\"color: #003366\">Omar Zelig ne peut faire l\u2019impasse sur le patron de presse qui lui a ouvert les portes de sa radio et de l\u2019underground alg\u00e9rois. Zelig a \u00e9t\u00e9 effectivement un employ\u00e9, et peu importe qu\u2019il y \u00e9tait salari\u00e9 ou b\u00e9n\u00e9vole, de Radio M. Il y a anim\u00e9 des \u00e9missions et il en reste sur les moteurs de recherche d\u2019Internet des liens audio de son \u00e9mission \u00ab\u00a0Mim\u00a0\u00bb sur Radio M et des vid\u00e9os de d\u00e9bats auxquels il a particip\u00e9, entre autres sur \u00ab\u00a0la l\u00e9galisation du cannabis en Alg\u00e9rie et l\u2019ouverture de la fronti\u00e8re avec le Maroc\u00a0\u00bb, qu\u2019il a soutenus personnellement, sont accessibles.<\/span><\/p>\n<p><span style=\"color: #003366\">Dans la configuration singuli\u00e8re du n\u00e9o-hirak, Ihs\u00e8ne El Kadi est certainement un leader, le principal animateur d\u2019un courant de pens\u00e9e, qui n\u2019est ni celui des bobos, pro-imp\u00e9rialistes\u00a0de la NED, ni des gauchistes encart\u00e9s du MDS ou du PST, ni d\u2019un improbable \u00ab\u00a0carr\u00e9 ouvri\u00e9riste\u00a0\u00bb, ni des islamistes et des makistes, qu\u2019il identifie et reconna\u00eet comme des alli\u00e9s. Or, si Omar Zelig est un \u00e9l\u00e9ment minoritaire du n\u00e9o-hirak, voire m\u00eame une pi\u00e8ce rapport\u00e9e, soup\u00e7onn\u00e9 de \u00ab\u00a0traitrise\u00a0\u00bb par ses camarades de la n\u00e9o-hirakie, sa compagne a pu y forger une voix et une pr\u00e9sence personnelles. Et attirer, pour diverses raisons, la mitraille de snippers n\u00e9o-hirakistes. \u00ab\u00a0Grande gueule\u00a0\u00bb, c\u2019est un m\u00e9tier.<\/span><\/p>\n<p><span style=\"color: #003366\">Les luttes internes du n\u00e9o-hirak, qui est, en dehors des factions islamistes de Rachad et s\u00e9paratistes du MAK mieux structur\u00e9es, une organisation disparate, sans aucune coh\u00e9rence, s\u2019\u00e9talent parfois dans les r\u00e9seaux sociaux. Il y a de fait une lassitude, une morne lassitude dans la n\u00e9o-hirakie. Plusieurs marcheurs d\u00e9sesp\u00e8rent d\u2019un mouvement qui n\u2019avance pas, frapp\u00e9 de catalepsie. Il y a beaucoup de pessimisme. Le d\u00e9bat est-il si d\u00e9courageant\u00a0? Les Zelig-Mouffok ne s\u2019en exemptent pas. Dans une r\u00e9ponse \u00e0 un article de Ghania Mouffok publi\u00e9 par \u00ab\u00a0Le Quotidien d\u2019Alg\u00e9rie\u00a0\u00bb \u2013 un site d\u2019information en ligne sur lequel on reviendra \u2013 un n\u00e9o-hirakiste, d\u00e9pit\u00e9, \u00e9crit\u00a0:<\/span><\/p>\n<p><span style=\"color: #003366\">\u00ab\u00a0De mon c\u00f4t\u00e9, je me souviens avoir dit sur les r\u00e9seaux sociaux que je suis farouchement contre l\u2019ind\u00e9pendance de la Kabylie, que je ne partage pas du tout les th\u00e8ses de Ferhat Mehenni, avoir dit aussi que je suis avec et du c\u00f4t\u00e9 le hirak du 22 f\u00e9vrier 2019 jusqu\u2019au 12 juin 2021, date des \u00e9lections l\u00e9gislatives, mais que si le pouvoir arrive \u00e0 imposer sa feuille de route co\u00fbte que co\u00fbte et bien je d\u00e9ciderai d\u2019arr\u00eater la lutte au sein du hirak du type 22 f\u00e9vrier 2019, celui des marches et les slogans seulement ! Bon je souhaite \u00e9videmment bonne route, du courage et bonne chance au hirak, mais moi \u00e0 force de d\u00e9sesp\u00e9rer compl\u00e8tement, car c\u2019est depuis 1962 j\u2019attends patiemment un changement de r\u00e9gime et de syst\u00e8me, eh bien je crois que c\u2019est peine perdu et je suis en train de penser \u00e0 mon plan \u2018\u2019B\u2019\u2019 \u00e0 moi : celui de rejoindre les ind\u00e9pendantistes ou les autonomistes kabyles au moins l\u00e0 avec eux leur feuille de route est claire, m\u00eame si je suis conscient que beaucoup la trouvent tr\u00e8s dangereuse pour le pays et que ce n\u2019est pas la bonne solution, et c\u2019est vrai quelque part ! Ok ce n\u2019est pas la bonne solution, mais elle est o\u00f9 alors la solution du c\u00f4t\u00e9 du hirak ??\u00a0\u00bb (6).<\/span><\/p>\n<p><span style=\"color: #003366\">Voil\u00e0, qui est dit sans ambages\u00a0: il y a le feu dans la maison de la n\u00e9o-hirakie. Et, une grande d\u00e9sesp\u00e9rance. S\u2019y rajoutent d\u2019intenables prises de bec entre ses clans d\u00e9boussol\u00e9s. Le couple Zelig-Mouffok est-il \u00e9loign\u00e9 de ces intemp\u00e9rances\u00a0?<\/span><\/p>\n<p><span style=\"color: #003366\">Des brouilles, d\u2019une sensibilit\u00e9 \u00e0 une autre du n\u00e9o-hirak, il y en a. Ghania Mouffok fait-elle l\u2019unanimit\u00e9 chez les marcheurs qui font du surplace et s\u2019entred\u00e9chirent comme des chiffonniers sur les r\u00e9seaux sociaux\u00a0? Et, distinctement, dans la famille de pens\u00e9e d\u2019El Kadi, qui selon un post sur Facebook du journaliste n\u00e9o-hirakiste Chabane Na\u00eft Mebarek (voir plus loin), l\u2019a mortifi\u00e9e. Omar Zelig a subi, comme sa compagne, ses avanies.<\/span><\/p>\n<p><span style=\"color: #003366\">Faut-il consid\u00e9rer sous cet \u00e9clairage le post de Omar Zelig sur le professeur Belhimer, Bensaada et les \u00ab\u00a0dommages collat\u00e9raux\u00a0\u00bb comme une tentative de sortie en force contre l\u2019isolement qui lui est impos\u00e9 dans la n\u00e9o-hirakie\u00a0?<\/span><\/p>\n<p><span style=\"color: #003366\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.ahmedbensaada.com\/images\/stories\/Images\/Zelig\/zelig%20post.jpg\" width=\"400\" \/><\/span><\/p>\n<p><span style=\"color: #003366\"><em>Post de Omar Zelig contre les \u00ab\u00a0dommages collat\u00e9raux\u00a0\u00bb du ministre Belhimer<\/em><\/span><\/p>\n<p><span style=\"color: #003366\">Mais, pourquoi Bensaada\u00a0? Il n\u2019y a pas formellement de casus-belli entre lui et Omar Zelig. Cependant, il est \u00e9tabli depuis de longs mois que l\u2019\u00e9m\u00e9rite publiciste et \u00e9crivain est la cible utile de la n\u00e9o-hirakie, de Montr\u00e9al \u00e0 Londres et Gen\u00e8ve, de Paris \u00e0 Alger. En toutes circonstances, cela pose un n\u00e9o-hirakiste de l\u2019agonir. Zelig y apporte son \u00e9cot qui lui d\u00e9coche sa banderille et profite de l\u2019occasion pour \u00ab\u00a0taper\u00a0\u00bb sur \u00ab\u00a0La Patrie News\u00a0\u00bb et ses anciens employeurs du boulevard des Martyrs, en leur jetant au visage leur \u00ab\u00a0parano\u00efa\u00a0\u00bb. Sauf que son post est maladroit et ambigu. C\u2019est bien M. Abdelmadjid Tebboune, pr\u00e9sident de la R\u00e9publique, qui a limog\u00e9 M. Belhimer\u00a0; et, c\u2019est implicitement \u00e0 lui, en sa qualit\u00e9 de d\u00e9tenteur du pouvoir r\u00e9galien, que Omar Zelig en appelle pour crucifier Bensaada et Cie.<\/span><\/p>\n<p><span style=\"color: #003366\">Contradiction, certainement. Lorsqu\u2019on est un n\u00e9o-hirakiste, on ne fait pas son march\u00e9 dans les arri\u00e8re-cours du syst\u00e8me et on ne lui adresse pas de mortelles \u00ab\u00a0chikayate\u00a0\u00bb contre ses propres adversaires politiques. Mais, auparavant, avant ce post, les Zelig-Mouffok ont accumul\u00e9 de nombreux contretemps pour h\u00e9risser leurs camarades\u00a0? Omar Zelig n\u2019avait-il pas r\u00e9pondu \u00e0 une invitation de la pr\u00e9sidence de la R\u00e9publique dans le cadre de la comm\u00e9moration solennelle du 1<sup>er<\/sup>-Novembre 1954\u00a0? Cela n\u2019est pas pass\u00e9 inaper\u00e7u dans les \u00ab\u00a0carr\u00e9s\u00a0\u00bb du n\u00e9o-hirak. Go\u00fbter les petits fours de la pr\u00e9sidence de la R\u00e9publique et lui demander le ch\u00e2timent de mauvais coucheurs de la contre-n\u00e9o-hirakie\u00a0? C\u2019est si mal vu pour provoquer un toll\u00e9 et faire parler la poudre.<\/span><\/p>\n<p><span style=\"color: #003366\">Le couple Zelig-Mouffok est loin de remonter la pente. Dans leur Facebook, ils utilisent le terme \u00ab\u00a0traitres\u00a0\u00bb, que pour ma part, je n\u2019ai pas utilis\u00e9 contre eux. Dans un plaidoyer pour Khaled Drareni, visiteur de l\u2019ambassade France \u00e0 Alger, Ghania Mouffok le sanctifie : \u00ab\u00a0On est tra\u00eetre ou on ne l\u2019est pas\u2026 Je soussign\u00e9 Ghania Mouffok, tra\u00eetre depuis cent ans, pour servir \u00e0 qui de droit\u00a0\u00bb (7). Ce vocable n\u2019est-il pas dans leur langage symptomatique et traumatique\u00a0? Si les Zelig-Mouffok n\u2019\u00e9taient pas pleinement imbriqu\u00e9s dans le n\u00e9o-hirak, aucun de ses membres ne les accuserait de \u00ab\u00a0traitrise\u00a0\u00bb. Traiteraient-ils ainsi un \u00ab\u00a0patriotard de la soupe\u00a0\u00bb et des \u00ab pseudo-nationalistes captiv\u00e9s par la mangeoire du pouvoir\u00a0\u00bb\u00a0?<\/span><\/p>\n<p><span style=\"color: #003366\"><strong>II. DEUXI\u00c8ME PREUVE.<\/strong><\/span><\/p>\n<p><span style=\"color: #003366\"><strong>Le bobo\u00efsme, un pied dans le pouvoir, un pied, dehors<\/strong><\/span><\/p>\n<p><span style=\"color: #003366\">Le bobo\u00efsme est une religion. \u00c0 Alger, il a ses chapelles, ses ma\u00eetres de c\u00e9r\u00e9monies et ses \u00ab\u00a0tipis\u00a0\u00bb (8). C\u2019est une chroniqueuse alg\u00e9roise, c\u00e9l\u00e8bre pour ses nuits mauves, qui en a fait la description la plus s\u00fbre dans les ann\u00e9es surann\u00e9es des d\u00e9funts pr\u00e9sidents Boumediene et Bendjedid. Refaire le monde jusqu\u2019\u00e0 l\u2019aube, pouss\u00e9s par de fines liqueurs et plus, si affinit\u00e9s\u2026 En 2021, l\u2019objectif des bobos en baskets, parfois ces messieurs en wesley et ces dames en louboutin, est de chasser la R\u00e9publique alg\u00e9rienne d\u00e9mocratique et populaire par le fricotage, entre autres dans les trav\u00e9es de l\u2019Assembl\u00e9e nationale fran\u00e7aise. Ils organisent ainsi des sauteries parisiennes et parlementaires avec Dame Georges Buffet, d\u00e9put\u00e9 communiste, qui a \u00e9t\u00e9 berc\u00e9e dans sa jeunesse militante par \u00ab\u00a0les chars de Moscou sur les Champs \u00c9lys\u00e9es, \u00e0 Paris\u00a0\u00bb, qui attend de faire d\u00e9filer ceux de la France, appuy\u00e9e par l\u2019OTAN, dans les rues d\u2019Alger. Jamais le n\u00e9ocolonialisme fran\u00e7ais et ses alli\u00e9s locaux n\u2019ont \u00e9t\u00e9 aussi vulgaires et transparents dans leurs pr\u00e9tentions.<\/span><\/p>\n<p><span style=\"color: #003366\">Les Zelig-Mouffok sont des bobos des beaux quartiers d\u2019Alger, avec jardin et \u00ab\u00a0tipi\u00a0\u00bb (merci Bensaada), m\u00eame s\u2019ils se r\u00e9clament \u00e9trangement de \u00ab\u00a0l\u2019ouvri\u00e9risme\u00a0\u00bb. Mais, ce n\u2019est pas exceptionnel que des rejetons de la bourgeoisie virent \u00e0 l\u2019ultra-gauchisme et \u00e0 l\u2019ouvri\u00e9risme. Ce n\u2019est pas nouveau et propre \u00e0 la soci\u00e9t\u00e9 alg\u00e9rienne. Les bobos ne sont pas francs du collier\u00a0: amis des n\u00e9o-hirakistes et amis du pouvoir. Zelig confirme cet \u00ab\u00a0entre-deux\u00a0\u00bb pr\u00e9judiciable, qui n\u2019\u00e9tait pour moi qu\u2019une d\u00e9marche empirique. J\u2019\u00e9crivais\u00a0: \u00ab\u00a0Cette situation n\u2019est pas exceptionnelle\u00a0: beaucoup de bobos d\u2019Alger ont un pied dans le pouvoir qu\u2019ils se font un devoir d\u2019\u00e9triper publiquement et un pied dans l\u2019opposition, quelle qu\u2019en soit la nature\u00a0; ils n\u2019en ont cure. Et, c\u2019est un trait inalt\u00e9rable de la sociologie politique des classes sup\u00e9rieures de la soci\u00e9t\u00e9 d\u2019Alger, certains bobos, quel que soit leur positionnement politique, sont intouchables. Et, parmi eux, les Zelig-Chaulet-Mouffok\u00a0?\u00a0\u00bb (9). Omar Zelig n\u2019en donne-t-il pas l\u2019exemple probant ? Dans ma contribution du 21 novembre, je n\u2019ai pas fait \u00e9tat d\u2019une invitation \u00e0 la pr\u00e9sidence de la R\u00e9publique honor\u00e9e par Luc Chaulet-Omar Zelig. J\u2019ignorais totalement cette invitation je ne la lui ai pas reproch\u00e9e. \u00c0 quel titre le ferais-je\u00a0? Ses amis du n\u00e9o-hirak s\u2019y pr\u00eatent, pour diverses raisons.<\/span><\/p>\n<p><span style=\"color: #003366\">Ne faut-il pas tirer la morale de cet \u00e9v\u00e9nement politico-mondain\u00a0? Comment Omar Zelig, l\u2019ami du n\u00e9faste Ali Bensaad, fourrier de la d\u00e9sinformation et de l\u2019opposition crapoteuse \u00e0 l\u2019\u00c9tat alg\u00e9rien, allant jusqu&#8217;\u00e0 faire douter sur les propos du pr\u00e9sident Tebboune relativement aux incendies en Kabylie de l\u2019\u00e9t\u00e9 2021 (10), pr\u00eatant all\u00e9geance \u00e0 la monarchie marocaine et la confortant dans son hostilit\u00e9 envers l\u2019Alg\u00e9rie et son peuple et, accessoirement, petit commissionnaire du pr\u00e9sident Macron dans la crise m\u00e9morielle qu\u2019il a provoqu\u00e9e entre son pays et l\u2019Alg\u00e9rie (11), peut-il se remplumer d\u2019avoir \u00e9t\u00e9 invit\u00e9 le 1<sup>er<\/sup>\u00a0novembre 2021 \u00e0 la pr\u00e9sidence de la R\u00e9publique\u00a0? C\u2019est vraiment tr\u00e8s secondaire de savoir \u00e0 quel titre le service du protocole de la pr\u00e9sidence de la R\u00e9publique a invit\u00e9 Luc Chaulet (alias Omar Zelig) \u00e0 un pince-fesses patriotique du 1<sup>er<\/sup>-Novembre 1954. \u00ab Date \u00e0 laquelle, dans le cadre des c\u00e9l\u00e9brations de l\u2019Etat alg\u00e9rien, incarn\u00e9 en la circonstance par le pr\u00e9sident A.Tebboune, Luc Chaulet a \u00e9t\u00e9 invit\u00e9 aux comm\u00e9morations officielles en tant que fils de Pierre et Claudine Chaulet\u2026\u00bb (12). Voil\u00e0 donc l\u2019\u00e9claircissement\u00a0: Luc Chaulet (alias Omar Zelig) \u00e9tait l\u2019invit\u00e9 de l\u2019\u00c9tat alg\u00e9rien \u00ab\u00a0incarn\u00e9\u00a0\u00bb par M. Tebboune. Imbattable nuance\u00a0?<\/span><\/p>\n<p><span style=\"color: #003366\">Omar Zelig, qui n\u2019a jamais \u00e9t\u00e9 plus loin que le lyc\u00e9e, qui n\u2019est qu\u2019un baratineur de radio, m\u2019accuse de ne pas faire le distinguo entre les concepts d\u2019\u00ab\u00a0\u00c9tat\u00a0\u00bb, de \u00ab\u00a0Nation\u00a0\u00bb et d\u2019\u00ab\u00a0\u00c9tat-Nation\u00a0\u00bb dans une sortie p\u00e9rilleuse pour faire oublier le \u00ab\u00a0Fils de\u2026\u00a0\u00bb, qu\u2019il est, et de faire accepter \u00e0 ses comparses n\u00e9o-hirakistes sa participations aux agapes de la pr\u00e9sidence de la R\u00e9publique, comm\u00e9morant le 1<sup>er<\/sup>-Novembre 1954. Comment se revendiquer du n\u00e9o-hirak et festoyer dans les salons de la R\u00e9publique \u00ab\u00a0honnie\u00a0\u00bb\u00a0? Ind\u00e9cent.<\/span><\/p>\n<p><span style=\"color: #003366\">Ainsi, Zelig, qui est f\u00e9ru des th\u00e9ories de l\u2019\u00c9tat, avertit qu\u2019il a r\u00e9pondu \u00e0 l\u2019invitation de l\u2019\u00c9tat, institution intemporelle et transcendante, \u00e9loign\u00e9e de toute compromission politique ou politicienne. Est-ce le cas en Alg\u00e9rie qui n\u2019est pas dot\u00e9 d\u2019un r\u00e9gime parlementaire o\u00f9 le pouvoir est d\u00e9volu au seul gouvernement\u00a0? La philosophie du droit, de Thomas Hobbes (\u00ab\u00a0Le L\u00e9viathan\u00a0\u00bb, 1651) \u00e0 Jean-Jacques Rousseau, de Raymond Carr\u00e9 de Malberg et de ses disciples, aux XIX<sup>e<\/sup>\u00a0et XX<sup>e<\/sup>\u00a0si\u00e8cles, \u00e0 celle, plus extensive, au XXI<sup>e<\/sup>\u00a0si\u00e8cle d\u2019Olivier Beaud, lie l\u2019\u00c9tat, qui n\u2019est pas un objet \u00e9vanescent surgissant ex abrupto, au \u00ab\u00a0pouvoir d\u2019\u00c9tat\u00a0\u00bb et \u00e0 ses structures institutionnelles. La m\u00eame position est d\u00e9fendue dans les sociologies contemporaines de Max Weber, Hannah Arendt, dans les th\u00e8ses marxistes et n\u00e9o-marxistes, notamment d\u2019Antonio Gramsci et de Louis Althusser, les plus \u00e9tudi\u00e9es dans l\u2019Universit\u00e9 alg\u00e9rienne. L\u2019\u00c9tat est le producteur de la violence l\u00e9gitime, caract\u00e9ris\u00e9e par la puissance r\u00e9galienne (arm\u00e9e, police, justice), il est aussi le producteur de lois coercitives qui s\u2019imposent \u00e0 tous ses citoyens \u2013 \u00ab\u00a0violence symbolique\u00a0\u00bb que Pierre Bourdieu appelle \u00ab\u00a0la magie de l\u2019\u00c9tat\u00a0\u00bb.<\/span><\/p>\n<p><span style=\"color: #003366\">L\u2019Alg\u00e9rie est un \u00c9tat-Nation sur le mod\u00e8le de la France et des r\u00e9publiques europ\u00e9ennes n\u00e9es au XIX<sup>e<\/sup>\u00a0si\u00e8cle. Son pr\u00e9sident \u00e9lu n\u2019a pas le statut symbolique de la Reine du Royaume-Uni, des pr\u00e9sidents de l\u2019Allemagne ou de l\u2019Italie. La phras\u00e9ologie ad reductio sur M. Tebboune, \u00ab\u00a0incarnation de l\u2019\u00c9tat\u00a0\u00bb, est franchement poisseuse. Dans l\u2019exp\u00e9rience alg\u00e9rienne, M. Tebboune n\u2019est pas seulement le chef de l\u2019\u00c9tat, il est aussi le pr\u00e9sident de la R\u00e9publique d\u00e9tenteur du pouvoir r\u00e9galien et le garant de la Nation alg\u00e9rienne\u00a0; et, convient-il de rappeler, c\u2019est en cette derni\u00e8re qualit\u00e9 qu\u2019il a port\u00e9 r\u00e9cemment le fer contre le pr\u00e9sident fran\u00e7ais Macron apr\u00e8s son algarade sur l\u2019historicit\u00e9 de l\u2019Alg\u00e9rie, de son peuple et de sa nation\u00a0? Il est aussi l\u2019incarnation morale de l\u2019\u00c9tat et de la souverainet\u00e9 de L\u2019\u00c9tat. M. Tebboune peut paraphraser le fameux mot de Flaubert et s\u2019\u00e9crier\u00a0: \u00ab\u00a0L\u2019Alg\u00e9rie, c\u2019est moi\u00a0!\u00a0\u00bb.<\/span><\/p>\n<p><span style=\"color: #003366\">Dans la situation de l\u2019Alg\u00e9rie d\u2019aujourd\u2019hui, le n\u00e9o-hirak, soumis \u00e0 Rachad et au MAK, n\u2019a d\u2019autre objectif que de briser l\u2019\u00c9tat alg\u00e9rien, n\u00e9 de la Guerre anticoloniale et de l\u2019Ind\u00e9pendance, pour le remplacer par un \u00c9tat islamique et un nouvel \u00c9tat kabyle sur un territoire disloqu\u00e9. Dans les th\u00e9ories classiques de l\u2019\u00c9tat, quatre crit\u00e8res sont conjugu\u00e9s\u00a0: un territoire\u00a0; une population permanente\u00a0; un gouvernement\u00a0; et, des relations avec des \u00c9tats voisins. Un seul manquerait, ce serait la d\u00e9structuration de l\u2019\u00c9tat. L\u2019objectif de renversement de l\u2019\u00c9tat r\u00e9publicain alg\u00e9rien par les groupes terroristes du n\u00e9o-hirak ne vise-t-il pas l\u2019\u00e9parpillement de sa population (ainsi l\u2019opposition Amazighs VS Arabes) et l\u2019\u00e9clatement de son territoire\u00a0?<\/span><\/p>\n<p><span style=\"color: #003366\">Qui pourrait soutenir que M. Abdelmadjid Tebboune, chef de l\u2019\u00c9tat, n\u2019est pas le premier d\u00e9fenseur de son unit\u00e9 contre les menaces internes et externes\u00a0? Les Constitutions alg\u00e9riennes, depuis les premiers mois de l\u2019ind\u00e9pendance, ont investi le pr\u00e9sident de la R\u00e9publique d\u2019une autorit\u00e9 r\u00e9galienne engageant les moyens de l\u2019\u00c9tat, tous les moyens de l\u2019\u00c9tat. Omar Zelig projette la fiction politique et constitutionnelle d\u2019un pr\u00e9sident de la R\u00e9publique alg\u00e9rienne d\u00e9mocratique et populaire limit\u00e9 aux missions de repr\u00e9sentation\u00a0; ce qui justifierait sa pr\u00e9sence \u00e0 la Mouradia. Mais M. Tebboune n\u2019est pas la Reine d\u2019Angleterre. Quelle crapulerie intellectuelle que cette feinte de Omar Zelig pour se prot\u00e9ger de ses amis n\u00e9o-hirakistes\u00a0! \u00ab\u00a0Non, fr\u00e8res du n\u00e9o-hirak, je n\u2019ai r\u00e9pondu qu\u2019\u00e0 l\u2019invitation de l\u2019\u00c9tat, pas du pouvoir d\u2019\u00c9tat\u2026\u00a0\u00bb. De surcro\u00eet, ce fin sp\u00e9cialiste des th\u00e9ories de l\u2019\u00c9tat tire son flingue lorsqu\u2019il entend parler de \u00ab\u00a0sociologie politique de classes sup\u00e9rieures de la soci\u00e9t\u00e9\u00a0\u00bb. Il s\u2019en absout\u00a0?<\/span><\/p>\n<p><span style=\"color: #003366\">III. TROISI\u00c8ME PREUVE.<\/span><\/p>\n<p><span style=\"color: #003366\"><strong>Ghania Mouffok par les textes\u00a0: \u00ab\u00a0d\u00e9gagisme\u00a0\u00bb forcen\u00e9 et engagement n\u00e9o-hirakiste au fer lamin\u00e9.<\/strong><\/span><\/p>\n<p><span style=\"color: #003366\">Il semble dans la m\u00e9phitique bouillie \u00ab\u00a0facebookienne\u00a0\u00bb des Zelig-Mouffok que sa compagne me poursuit devant les tribunaux de la R\u00e9publique \u00ab\u00a0en son nom\u00a0\u00bb. J\u2019ai \u00e9labor\u00e9, ce qui n\u2019est pas interdit s\u2019agissant d\u2019acteurs publics qui pr\u00e9tendent parler \u00e0 la soci\u00e9t\u00e9, son contre-portrait sur la base de son itin\u00e9raire reconnu et d\u2019un article qu\u2019elle a publi\u00e9 sur le site de la Ligue alg\u00e9rienne de d\u00e9fense des Droits de l\u2019Homme (13). S\u2019agit-il en l\u2019esp\u00e8ce, et encore une fois, d\u2019\u00ab\u00a0aller sur le net renifler ce qui pue\u00a0\u00bb, comme elle et son compagnon s\u2019en \u00e9meuvent\u00a0? Mais qu\u2019ils aient, enfin, l\u2019honn\u00eatet\u00e9 de ne pas fuir la responsabilit\u00e9 de ce qu\u2019ils y ont publi\u00e9, qui y est archiv\u00e9. C\u2019est toujours important devant l\u2019opinion publique ou une cour de justice.<\/span><\/p>\n<p><span style=\"color: #003366\">Ghania Mouffok, journaliste freelance et personnalit\u00e9 publique, publie en France des contributions strictement politiques dans une presse qui n\u2019est ni juste ni objective ni d\u00e9sint\u00e9ress\u00e9e relativement \u00e0 l\u2019Alg\u00e9rie, du \u00ab\u00a0Monde\u00a0\u00bb au \u00ab\u00a0Monde diplomatique\u00a0\u00bb et \u00e0 l\u2019infecte tourbi\u00e8re de \u00ab\u00a0Mondafrique\u00a0\u00bb. Mais aussi dans une peu honorable presse de l\u2019islamisme et du \u00a0n\u00e9o-hirak, notamment \u00ab\u00a0Le Quotidien d\u2019Alg\u00e9rie\u00a0\u00bb, un site en ligne \u00e9dit\u00e9 \u00e0 Paris, porte-parole de l\u2019opposition alg\u00e9rienne de tout poil, particuli\u00e8rement de l\u2019islamisme dans toutes ses variantes. Ce site, dont la ligne \u00e9ditoriale est anti-alg\u00e9rienne, serait selon plusieurs observateurs, proche de hauts-responsables des \u00ab\u00a0services\u00a0\u00bb fran\u00e7ais, sp\u00e9cialistes de l\u2019Alg\u00e9rie. Les publications de Ghania Mouffok sont bien dans les attentes et dans le ton venimeux de ce titre d\u2019opposition, qui en est encore \u00e0 comptabiliser des vendredis de marche, qui n\u2019existent que dans son imagerie de l\u2019Alg\u00e9rie, oiseuse et maladive.<\/span><\/p>\n<p><span style=\"color: #003366\">Relevons pour une personne dont le compagnon appr\u00e9cie les petites g\u00e2teries de la pr\u00e9sidence de la R\u00e9publique, qui cachent honteusement, l\u2019un et l\u2019autre, leur enr\u00f4lement dans le n\u00e9o-hirak, une mise en cause acrimonieuse des hauts responsables de l\u2019\u00c9tat, M. Tebboune, pr\u00e9sident de la R\u00e9publique, et M. Goudjil, pr\u00e9sident du Conseil de la Nation. Lisons soigneusement\u00a0:<\/span><\/p>\n<p><span style=\"color: #003366\">\u00ab\u00a0L\u2019impotence de A. Bouteflika n\u2019a \u00e0 l\u2019\u00e9vidence pas inspir\u00e9 leur imaginaire politique, alors que les lois de la biologie, de la nature auraient d\u00fb les convaincre que pour que leur mod\u00e8le de pouvoir hyper centralis\u00e9 puisse se reproduire le chef de l\u2019\u00e9tat en Alg\u00e9rie doit absolument \u00eatre dot\u00e9 d\u2019une sant\u00e9 de fer en guise de CV. Puisque le pr\u00e9sident n\u2019est qu\u2019un bouclier on aurait pu attendre des soldats protecteurs de la nation, de l\u2019int\u00e9grit\u00e9 territoriale, interdisant les attroupements non arm\u00e9s et autres menaces qu\u2019ils apprennent \u00e0 le choisir d\u2019acier.<\/span><\/p>\n<p><span style=\"color: #003366\">\u00ab\u00a0Non seulement ils n\u2019y ont pas pens\u00e9 en choisissant de faire \u00e9lire A. Tebboune, n\u00e9 en 1945 \u00e0 la fin de la deuxi\u00e8me guerre mondiale et ce en pleine pand\u00e9mie mondiale du corona qui avait mis au c\u0153ur du d\u00e9bat la sant\u00e9, la proximit\u00e9 de la mort, mais en plus ils ont install\u00e9 en guise de barri\u00e8re, au poste de deuxi\u00e8me homme, au- cas- ou\u2026 un ancien, au nom de \u201cla l\u00e9gitimit\u00e9 r\u00e9volutionnaire\u201d, n\u00e9 en 1931 en la personne de Salah Goudjil qui selon la loi et si les d\u00e9s du destin le veulent sera appel\u00e9 \u00e0 le remplacer le temps de voir \u2026avec cette fois-ci en guise de casse-t\u00eate suppl\u00e9mentaire qu\u2019il est Pr\u00e9sident du Conseil de la Nation\u2026par int\u00e9rim. Cela ne s\u2019invente pas. Il semblerait bien que ceux qui nous gouvernent n\u2019aient pas encore compris que les hommes y compris de pouvoir ne sont pas immortels, et qu\u2019\u00e0 cet \u00e2ge v\u00e9n\u00e9rable le temps est compt\u00e9, sans m\u00eame parler des capacit\u00e9s n\u00e9cessaires pour diriger un autre grand corps malade qu\u2019est devenue l\u2019Alg\u00e9rie, sans faire appel \u00e0 une troisi\u00e8me ambulance\u00a0\u00bb (14).<\/span><\/p>\n<p><span style=\"color: #003366\">Un air de \u00ab\u00a0d\u00e9gagisme\u00a0\u00bb et un humour plut\u00f4t lourdingue. Ghania Mouffok fait-elle de l\u2019esprit \u00e0 la mani\u00e8re de chansonniers de cabaret\u00a0? \u00a0Elle met d\u2019autorit\u00e9 MM. Tebboune et Goudjil dans des ambulances, une deuxi\u00e8me et une troisi\u00e8me, apr\u00e8s celle qui a convoy\u00e9 le pr\u00e9sident Bouteflika. Pensait-elle provoquer l\u2019hilarit\u00e9 des gogos\u00a0? Persiflage de mauvais go\u00fbt, en v\u00e9rit\u00e9\u00a0: M. Tebboune a \u00e9t\u00e9 \u00e9lu par les \u00e9lecteurs alg\u00e9riens au terme d\u2019une campagne pr\u00e9sidentielle et d\u2019un vote irr\u00e9prochables. D\u2019o\u00f9 tient-elle que l\u2019Arm\u00e9e nationale populaire, qui est une institution r\u00e9publicaine, raval\u00e9e en \u00ab\u00a0soldats protecteurs de la nation\u00a0\u00bb, l\u2019a choisi et fait \u00e9lire \u00e0 la fonction supr\u00eame de l\u2019\u00c9tat\u00a0? Ce serait donc une page d\u2019histoire in\u00e9dite, mais en dehors d\u2019un r\u00e9cit solidement document\u00e9, c\u2019est de la d\u00e9sinformation punie par la loi.<\/span><\/p>\n<p><span style=\"color: #003366\">Il est sid\u00e9rant d\u2019observer que Ghania Mouffok peut s\u2019autoriser \u00e0 \u00ab\u00a0taper\u00a0\u00bb sur le chef de l\u2019\u00c9tat, sur le pr\u00e9sident du Conseil de la Nation et sur l\u2019ANP et consid\u00e9rer qu\u2019\u00e9crire sur elle et sur son compagnon est un \u00ab\u00a0d\u00e9lit\u00a0\u00bb. Elle se situe nettement dans une opposition aux hauts-responsables de l\u2019\u00c9tat, MM. Tebboune et Goudjil. Elle croit enfoncer le clou, ajoutant avec beaucoup de certitude\u00a0: \u00ab\u00a0Cette situation d\u2019une ironie tragique, un malade remplace un malade, un avion ambulance remplace un avion ambulance dans l\u2019obscurit\u00e9 des soirs qui tombent, devrait enfin leur crever les yeux au moment de relire la nouvelle Constitution et avant de nous ordonner de l\u2019applaudir\u00a0\u00bb (15). Aucune compassion, au-del\u00e0 du pr\u00e9sident de la R\u00e9publique, pour sa personne. Invoque-t-elle dans son propos sibyllin sur la nouvelle Constitution une vacation du pouvoir\u00a0? Avec Omar Zelig, son compagnon, elle m\u2019accuse d\u2019\u00ab\u00a0apeupr\u00e9isme\u00a0\u00bb, tortueux n\u00e9ologisme : je lui retourne volontiers ce compliment et la d\u00e9fie, au nom de l\u2019honneur du m\u00e9tier de journaliste, d\u2019apporter la preuve de ses perfides insinuations sur le pr\u00e9sident de la R\u00e9publique. \u00c9tait-il, au cours de son hospitalisation, totalement coup\u00e9 du service de l\u2019\u00c9tat\u00a0? Ce serait encore un fait d\u2019histoire. En politique, la loyaut\u00e9, c\u2019est de s\u2019attaquer aux id\u00e9es plus qu\u2019aux personnes. Il fallait \u00ab\u00a0d\u00e9gager\u00a0\u00bb M. Tebboune parce qu\u2019il a \u00e9t\u00e9 se soigner, ce qui est le droit de toute personne humaine, fut-elle le pr\u00e9sident de la R\u00e9publique. Et, \u00e9taler la date de naissance de M. Goudjil pour le disqualifier.<\/span><\/p>\n<p><span style=\"color: #003366\">Faut-il continuer cette anthologie foutraque\u00a0? Le texte suivant, qui garde toute son importance pour comprendre le couple Zelig-Mouffok, date du 15 octobre 2021, exactement deux semaines avant la comm\u00e9moration du 1<sup>er<\/sup>-Novembre 1954. Ghania Mouffok \u00e9crit\u00a0:<\/span><\/p>\n<p><span style=\"color: #003366\">\u00ab\u00a0La classe \u00e9tat qui gouverne notre pays s\u2019invente des complots, des associations, des personnes, des personnalit\u00e9s qu\u2019elle habille de menaces fictives pour alimenter, produire et reproduire un \u00e9tat d\u2019urgence permanent face \u00e0 des dangers imminents, \u00e0 venir, qu\u2019elle feint de d\u00e9jouer dans une com\u00e9die de justice rod\u00e9e, organis\u00e9e, pay\u00e9e par l\u2019argent public. La classe \u00e9tat qui gouverne notre pays a pris go\u00fbt \u00e0 l\u2019\u00e9tat d\u2019urgence, l\u2019\u00e9tat de si\u00e8ge, elle a du mal \u00e0 se d\u00e9faire de cet \u00e9tat id\u00e9al pour faire autorit\u00e9 sur la soci\u00e9t\u00e9 et toutes les autres classes confondues, seule sa survie est au centre de cette strat\u00e9gie de gestion des nouvelles complexit\u00e9s d\u2019une soci\u00e9t\u00e9 en recomposition qui se questionne mal sur son avenir et ses ressources autant humaines que beno\u00eetement mat\u00e9rielles, sur ses richesses et leurs r\u00e9partitions\u00a0\u00bb (16). Quel insolite baragouin et une phrase de dix lignes\u00a0! Et, d\u00e9cid\u00e9ment, ce terme \u00ab\u00a0benoitement\u00a0\u00bb, tremp\u00e9 dans toutes les sauces. En savent-ils le sens et les usages\u00a0? Quelle langue\u00a0!<\/span><\/p>\n<p><span style=\"color: #003366\">Fichtre, \u00ab\u00a0la classe \u00e9tat\u00a0\u00bb, \u00e7a existe dans la sociologie politique\u00a0? Les doctrines marxistes \u00e9voquent une classe bourgeoise dominante, h\u00e9g\u00e9monique, qui exerce pour son compte le monopole de la violence l\u00e9gitime de l\u2019\u00c9tat contre le prol\u00e9tariat. Mais se confond-elle avec l\u2019\u00c9tat\u00a0? D\u2019o\u00f9 vient-elle cette \u00ab\u00a0classe \u00e9tat\u00a0\u00bb, sp\u00e9cifiquement alg\u00e9rienne ? D\u2019une lecture mal dig\u00e9r\u00e9e de Nicos Poulantzas, revue et corrig\u00e9e dans un bar \u00e0 bi\u00e8re ou sous un \u00ab\u00a0tipi\u00a0\u00bb des beaux quartiers de la capitale, au gr\u00e9 de halqas nocturnes\u00a0? Cette \u00ab\u00a0classe \u00e9tat\u00a0\u00bb aurait, d\u00e9nonce Ghania Mouffok, invent\u00e9 des complots et instrumentalis\u00e9 \u00ab\u00a0une com\u00e9die de justice rod\u00e9e, organis\u00e9e, pay\u00e9e par l\u2019argent public\u00a0\u00bb \u2013 la m\u00eame justice qu\u2019elle veut retourner contre l\u2019auteur de ces lignes. L\u2019Alg\u00e9rie des Zelig-Mouffok est une Alg\u00e9rie kafka\u00efenne, une version malheureuse du \u00ab\u00a0Proc\u00e8s\u00a0\u00bb de Frantz Kafka (1925). Continuons\u00a0:<\/span><\/p>\n<p><span style=\"color: #003366\">\u00ab\u00a0Le dressage \u00e0 la peur de la sanction arbitraire se fait d\u2019abord dans la rue du quotidien avant de devenir politique, retrait de permis, amende, arrestation, saisie de ta marchandise, prendre de ton temps longuement apr\u00e8s le salut de judas, salam, salam, ok qu\u2019est-ce que tu vas m\u2019inventer cette fois, prendre de ton temps devant l\u2019administration, reviens demain, on ne re\u00e7oit pas aujourd\u2019hui, non le directeur n\u2019est pas l\u00e0, elle se fait dans l\u2019usine, au travail, un syndicat, quel syndicat? de quoi tu parles? dans le priv\u00e9 ou dans le public, tais-toi et travaille, tu as vu le nombre de ch\u00f4meurs qui r\u00eavent de prendre ta place? t\u2019es pas d\u2019accord, je m\u2019en fous, tu es vir\u00e9, quoi la police? laquelle ? la justice ? tu me fais rire, elle est bonne celle-l\u00e0\u00a0\u00bb (17).<\/span><\/p>\n<p><span style=\"color: #003366\">Encore dix lignes mal fagot\u00e9es. C\u2019est \u00e9crit diablement, comme une chawarma de gargote pourrie, dans une syntaxe d\u00e9brid\u00e9e. C\u2019est cela le journalisme moderne\u00a0? Je pr\u00e9f\u00e8re la langue classique et sans pr\u00e9tention d\u2019\u00ab\u00a0El Moudjahid\u00a0\u00bb, qui ne souffre pas d\u2019\u00e9quivoque. Pr\u00e9cisons\u00a0: O\u00f9 s\u2019exprime Ghania Mouffok\u00a0? Dans \u00ab\u00a0Le Quotidien d\u2019Alg\u00e9rie\u00a0\u00bb, journal en ligne de l\u2019opposition islamiste et n\u00e9o-hirakiste. Pour porter quelles id\u00e9es\u00a0? Celle du \u00ab\u00a0d\u00e9gagisme\u00a0\u00bb du n\u00e9o-hirak. Le dire est une atteinte \u00e0 la vie priv\u00e9e du couple Zelig-Mouffok, une \u00ab\u00a0diffamation\u00a0\u00bb, un \u00ab\u00a0d\u00e9lit\u00a0\u00bb\u00a0? Que Ghania Mouffok ait le courage de ses convictions lorsqu\u2019elles ont d\u00e9j\u00e0 un caract\u00e8re public et se r\u00e9pandent inconsid\u00e9r\u00e9ment dans les pages sulfureuses du \u00ab\u00a0Quotidien d\u2019Alg\u00e9rie\u00a0\u00bb\u00a0?<\/span><\/p>\n<p><span style=\"color: #003366\">Mes contradicteurs m\u2019envoient dans la \u00ab\u00a0police politique\u00a0\u00bb parce que j\u2019ai relev\u00e9 qu\u2019ils \u00ab\u00a0militent vent debout contre le syst\u00e8me\u00a0\u00bb. Ce n\u2019est pas le cas lorsqu\u2019on patauge dans les boues de l\u2019ind\u00e9licat Ali B. et d\u2019autres sauriens de son mar\u00e9cage\u00a0? Je le prouve dans les \u00e9crits de Ghania Mouffok et le marquage \u00e0 l\u2019encre rouge que le couple Zelig-Mouffok veut m\u2019opposer ne tache que leurs plumes frelat\u00e9es. Je n\u2019ai pas tout dit, certes. Ce n\u2019est qu\u2019une pause. Toutefois, je n\u2019envisage pas pour reprendre Bensaada un \u00ab\u00a0Zigomar pour les Nuls\u00a0\u00bb. Dans sa sublime sagesse, l\u2019honorable pr\u00e9sident du Conseil de la Nation, M. Salah Goudjil, qui vaut mieux qu\u2019une ambulance, n\u2019accepterait pas de le pr\u00e9facer. Est-ce cela le monde des bobos d\u2019Alger et ses tristes moqueries\u00a0?<\/span><\/p>\n<p><span style=\"color: #003366\"><strong>IV. QUATRI\u00c8ME PREUVE.<\/strong><\/span><\/p>\n<p><span style=\"color: #003366\"><strong>L\u2019appartenance tr\u00e8s actuelle des Zelig-Mouffok au n\u00e9o-hirak et aux men\u00e9es subversives contre l\u2019\u00c9tat<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\">Dans leur texte sur Facebook, les Zelig-Mouffok posent cette terrible question\u00a0: \u00ab\u00a0Si quelqu\u2019un pouvait nous expliquer cette phrase qui chapeaute sa puissante pens\u00e9e, nous promettons de lui donner une poign\u00e9e de dollars que nous versent r\u00e9guli\u00e8rement la CIA, le SDECE,\u00a0Nicolas Joli, Momo le barbouze\u00a0: \u2018\u2018le[s] motif[s] du vif ressentiment de Luc Chaulet Ghania Mouffok envers A. Bensaada sont certainement connus et entendus dans le cercle de leurs amis, notamment ceux d\u2019Alger, depuis longtemps pouss\u00e9s dans le mouvement du n\u00e9o-hirak et dans une campagne \u00e9pouvantable contre le pouvoir de M. Tebboune et l\u2019unit\u00e9 de la nation aux c\u00f4t\u00e9s des islamistes de Rachad et des s\u00e9paratistes du MAK\u2019\u2019.\u00a0\u00bb<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\">Cette phrase, dans une langue appliqu\u00e9e, est donc incompr\u00e9hensible pour les Zelig-Mouffok. Je m\u2019attache \u00e0 l\u2019expliquer\u00a0:<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\">1\u00b0) Les Zelig-Mouffok font semblant de ne pas discerner le lien que je pose entre eux et les activistes du n\u00e9o-hirak\u00a0: ils s\u2019en d\u00e9faussent express\u00e9ment. Bis repetita\u00a0: a-t-on toujours dans ce monde-l\u00e0 le courage de ses opinions et de ses engagements\u00a0?<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\">2\u00b0) Sur leur Facebook, ceux qui leur apportent leur soutien sont des membres du n\u00e9o-hirak et certains d\u2019entre eux ont \u00e9t\u00e9 condamn\u00e9s par les tribunaux en raison d\u2019activit\u00e9s s\u00e9ditieuses de \u00ab\u00a0trouble de l\u2019ordre public\u00a0\u00bb. Et des sp\u00e9cimens typiques de marigot. J\u2019en prends un exemple\u00a0: Ali Bensaad, sa m\u00e8re la France qui l\u2019abrite et lui octroie des petits boulots pour son arm\u00e9e (18), ses couleurs bleu blanc rouge, les couleurs de l\u2019infamie. Parmi leurs appuis, des noms de repris de justice du n\u00e9o-hirak, habitu\u00e9s des colonnes de la presse bien-pensante d\u2019Alger, de \u00ab\u00a0droitsdelhommistes\u00a0\u00bb tordus comme un clou rouill\u00e9, de bobos baveux, de \u00ab\u00a0pagsistes\u00a0\u00bb ventriloques qui collectionnent les \u00e9tiquettes politiques, de trotskystes aux chausses crev\u00e9es, en bleu de chauffe, parfois tout droit sortis de l\u2019ouvri\u00e9risme des Chemins de fer d\u2019Alg\u00e9rie d\u2019antan. Des islamistes et des makistes aussi. Une incroyable faune. Tous r\u00eavent de mettre \u00e0 terre l\u2019\u00c9tat et son pouvoir l\u00e9gal.<\/span><\/p>\n<p><span style=\"color: #003366\">Tous ces protecteurs des Zelig-Mouffok ne m\u2019ont pas lu\u00a0: ils s\u2019en tiennent \u00e0 la seule religion de leurs amis. Il leur faut frapper leur contradicteur en groupe et sans discernement\u00a0: un lynch. Ce sont des crapules perverses, anim\u00e9es par un clanisme de l\u00e2ches. Dire qu\u2019ils aspirent \u00e0 prendre le pouvoir dans le pays\u00a0! Pauvre Alg\u00e9rie.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\">3\u00b0) Je n\u2019ai pas invent\u00e9 la consanguinit\u00e9 des Zelig-Mouffok avec le n\u00e9o-hirak et ses ambitions de d\u00e9truire l\u2019\u00c9tat. J\u2019en ai recueilli l\u2019indiscutable t\u00e9moignage. Parmi les messages qu\u2019ils ont re\u00e7us et publi\u00e9s sur leur page Facebook, il y a celui de Chabane Na\u00eft Mebarek, journaliste \u00e0 la cha\u00eene 3 de la radio alg\u00e9rienne, qui donne des informations tr\u00e8s pr\u00e9cises et in\u00e9dites sur l\u2019engagement du couple Zelig-Mouffok dans le n\u00e9o-hirak\u00a0; ce post, accessible \u00e0 tous les abonn\u00e9s de Facebook, dat\u00e9 du 23 novembre 2021, a un caract\u00e8re public. Je le cite int\u00e9gralement, dans sa transcription\u00a0:<\/span><\/p>\n<p><span style=\"color: #003366\">\u00ab\u00a0<strong>Chabane Na\u00eft Mebarek<\/strong><\/span><\/p>\n<p><span style=\"color: #003366\">\u00ab\u00a0Solidarit\u00e9<\/span><\/p>\n<p><span style=\"color: #003366\">Une campagne haineuse cible depuis quelques jours Ghania Mouffok . Apr\u00e8s les fl\u00e8ches venimeuses des changeurs de Radio M, des patriotards de la soupe la calomnient pour atteindre son compagnon, Luc, en lui attribuant honteusement des positions de &#8221;tra\u00eetrise&#8221; \u00e0 la nation et de soutien aux larbins pro-imperialistes.<\/span><\/p>\n<p><span style=\"color: #003366\">Il ne faut pas s&#8217;en \u00e9tonner, ce ne sont pas toujours ceux qui livrent bataille sur l&#8217;ar\u00e8ne du combat qui s&#8217;exhibent une fois les armes d\u00e9pos\u00e9es, mais ce sont plut\u00f4t ceux qui ont choisi le calcul mercantile et les cachettes confortables des palais qui s&#8217;y jettent pour r\u00e9colter les lauriers.<\/span><\/p>\n<p><span style=\"color: #003366\">\u00ab\u00a0Depuis ses alertes sur les jeunes d\u00e9tenus ignor\u00e9s par les serviteurs z\u00e9l\u00e9s des groupes rivaux qui se disputaient la direction du hirak, jusqu&#8217;\u00e0 sa d\u00e9nonciation de la r\u00e9pression de la manif du 8 mars 2021 par les rashadistes en passant par son engagement dans le carr\u00e9 du p\u00f4le de l&#8217;alternative ouvri\u00e8re et populaire, Ghania n&#8217;a cess\u00e9 de d\u00e9noncer les imposteurs qu&#8217;ils soient de droite ou qu&#8217;ils pr\u00e9tendent \u00eatre de gauche.<\/span><\/p>\n<p><span style=\"color: #003366\">\u00ab\u00a0Il est normale qu&#8217;elle soit la cible paradoxale, \u00e0 la fois invectiv\u00e9e par de pseudo-nationalistes captiv\u00e9s par la mangeoire du pouvoir et de leur rivaux, larbins de l&#8217;imp\u00e9rialisme en attente d&#8217;une intervention de L&#8217;OTAN.<\/span><\/p>\n<p><span style=\"color: #003366\">Ghania et ses \u00e9crits en t\u00e9moignent, avait le courage de ses id\u00e9es et elle ne les a jamais maquill\u00e9es, ni marchand\u00e9\u00e9s pour un si\u00e8ge sur les plateaux t\u00e9l\u00e9s ou pour un salaire de conseiller.<\/span><\/p>\n<p><span style=\"color: #003366\">\u00ab\u00a0Nos divergences avec Ghania \u00e9taient aussi nombreuses que f\u00e9condes, n\u00e9amoins, notre convergence, celle de la n\u00e9cessit\u00e9 de construire une alternative au r\u00e9gime et \u00e0 l&#8217;opposition droiti\u00e8re pro-imperialiste l&#8217;a toujours emport\u00e9 sur le reste. Ghania n&#8217;avait pas fait le choix de se cacher derri\u00e8re l&#8217;habit nationaliste pour affronter les imposteurs droitiers du hirak et n&#8217;avait pas non plus cherch\u00e9 la protection des ONG pour denoncer la r\u00e9pression et les attaques contre les acquis ch\u00e8rement arrach\u00e9s. Elle \u00e9tait sur le terrain \u00e0 tenter, contre vents et mar\u00e9es, de construire cette alternative avec une petite poign\u00e9e &#8221;d&#8217;ouvri\u00e9ristes&#8221;, lorsque les gauches r\u00e9pondaient aux siflets de leurs ma\u00eetres respectifs du PAD ou du r\u00e9gime.<\/span><\/p>\n<p><span style=\"color: #003366\">\u00ab\u00a0Je tiens \u00e0 t&#8217;assurer de mon enti\u00e8re solidarit\u00e9 Ghania. Que nos divergences fleurissent pour armer nos convergences.\u00a0\u00bb<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\">Qu\u2019est-ce que le lecteur apprend dans le post de ce journaliste du service public de la radio d\u2019\u00c9tat, cr\u00e2nement opposant, qui veut \u00ab\u00a0construire une alternative au r\u00e9gime\u00a0\u00bb\u00a0?<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\">1\u00b0) Que Ghania Mouffok a \u00e9t\u00e9 l\u2019objet \u00ab\u00a0depuis quelques jours\u00a0\u00bb d\u2019une \u00ab\u00a0campagne haineuse\u00a0\u00bb o\u00f9 sont associ\u00e9s \u00ab des changeurs de Radio M, des patriotards de la soupe\u00a0\u00bb, qui cherchent \u00e0 l\u2019affaiblir \u00e0 travers son compagnon Omar Zelig, formellement accus\u00e9 de \u00ab\u00a0traitrise\u00a0\u00bb. Les \u00ab\u00a0changeurs de Radio M\u00a0\u00bb \u2013 qu\u2019est-ce qui a \u00ab\u00a0chang\u00e9\u00a0\u00bb dans leur routine de n\u00e9o-hirakistes matois\u00a0? \u2013 sont connus, mais qui sont \u00ab\u00a0les patriotards de la soupe\u00a0\u00bb et les \u00ab\u00a0pseudo-nationalistes captiv\u00e9s par la mangeoire du pouvoir\u00a0\u00bb\u00a0? Il est vrai que ces derniers temps, Mouffok a le moral en berne face \u00e0 un n\u00e9o-hirak qui s\u2019est \u00e9gaill\u00e9 et d\u00e9gonfl\u00e9 au moment o\u00f9 il n\u2019y a pas de \u00ab\u00a0plan B\u00a0\u00bb \u00e0 l\u2019horizon\u00a0: elle en tire, pour ses ami(e)s ses conclusions d\u00e9\u00e7ues, en aga\u00e7ant la rh\u00e9torique, de l\u2019anaphore, \u00e0 l\u2019antiphrase et au paradoxe et \u00e0 la litote :<\/span><\/p>\n<p><span style=\"color: #003366\">\u00ab Merci \u00e0 nos \u00e9lites, que dis-je \u00e0 nos leaders \u00e9clair\u00e9s, \u00e0 nos grands timoniers et magnifiques timoni\u00e8res pour leur strat\u00e9gie rarement \u00e9gal\u00e9e, merci de jamais n\u2019avoir c\u00e9d\u00e9 au doute, de n\u2019avoir jamais \u00e9cout\u00e9 personne et d\u2019avoir tenu avec un sens politique remarquable qui fait l\u2019admiration de la plan\u00e8te toute enti\u00e8re le cap vers la victoire : elle arrive\u2026elle arrive\u2026elle arrive\u2026<\/span><\/p>\n<p><span style=\"color: #003366\">\u00ab\u00a0Merci d\u2019avoir compris alors que les idiots, les l\u00e2ches, les sans courage, les courtisans et les courtisanes pensaient \u00e0 l\u2019aveugle qu\u2019ils leur semblaient, si on y regardait bien, que la b\u00eate n\u2019\u00e9tait pas m\u00fbre, alors que vous, avec vos yeux de lynx -que Dieu vous garde- vous avez t\u00e2t\u00e9s le fruit et vous avez dit : il est pourri, bient\u00f4t il va tomber.<\/span><\/p>\n<p><span style=\"color: #003366\">\u00ab\u00a0Merci pour cette patience h\u00e9ro\u00efque \u00e0 d\u00e9foncer les portes ouvertes de l\u2019histoire sans jamais penser \u00e0 ouvrir les fen\u00eatres de vos balcons qui ne donnent que sur des voisins\u00a0\u00bb (19).<\/span><\/p>\n<p><span style=\"color: #003366\">Cruels d\u00e9sappointement et contrition (20). Le blues du n\u00e9o-hirak, \u00e0 l\u2019heure des r\u00e8glements de compte entre \u00ab\u00a0voisins\u00a0\u00bb.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\">2\u00b0) On est inform\u00e9 de la course des groupes \u00ab\u00a0rivaux\u00a0\u00bb pour la direction du n\u00e9o-hirak et on est instruit des arguments exp\u00e9ditifs de Rachad pour en discipliner les rangs. Dans le hourvari du n\u00e9o-hirak, Ghania Mouffok a pouss\u00e9 un coup de gueule pour rappeler \u00e0 chacun son devoir envers les \u00ab\u00a0jeunes d\u00e9tenus\u00a0\u00bb. En vain, un cri dans le d\u00e9sert.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\">3\u00b0) Elle est \u00ab\u00a0invectiv\u00e9e \u00bb par des \u00e9l\u00e9ments \u00ab\u00a0rivaux\u00a0\u00bb du n\u00e9o-hirak, mais aussi par des \u00ab\u00a0pseudo-nationalistes\u00a0\u00bb de \u00ab\u00a0 la mangeoire du pouvoir\u00a0\u00bb, d\u2019une part\u00a0; \u00ab\u00a0leur rivaux, larbins de l&#8217;imp\u00e9rialisme en attente d&#8217;une intervention de L&#8217;OTAN\u00a0\u00bb, de l\u2019autre. Cela fait du monde et on ne peut \u00eatre plus engag\u00e9 que cela dans la n\u00e9o-hirakie.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\">4\u00b0) Ghania Mouffok est, au m\u00eame titre que l\u2019auteur du post, dont il est difficile de situer \u00e0 quelle famille de la n\u00e9o-hirakie il appartient, partie prenante d\u2019un combat pour \u00ab\u00a0d\u00e9gager\u00a0\u00bb le r\u00e9gime\u00a0: \u00ab\u00a0construire une alternative\u00a0\u00bb, en effet.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\">5\u00b0) Il est aussi donn\u00e9 au lecteur de d\u00e9couvrir que Ghania Mouffok a mont\u00e9 dans les rangs du n\u00e9o-hirak un \u00ab\u00a0carr\u00e9\u00a0\u00bb \u00ab\u00a0ouvri\u00e9riste\u00a0\u00bb pour des lendemains r\u00e9volutionnaires qui chantent. \u00ab\u00a0C\u2019est la lutte finale\u2026\u00a0\u00bb<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\">\u00c0 l\u2019exclusion du MAK, qui n\u2019y est pas mentionn\u00e9, Chabane Na\u00eft Mebarek pr\u00e9figure la g\u00e9ographie du n\u00e9o-hirak en Alg\u00e9rie dans toutes ses composantes \u2013 y compris le PAD, ses communistes et ses trotskystes \u2013 et leurs bisbilles. Ghania Mouffok et son compagnon y prennent leur place. Dans \u00ab\u00a0le carr\u00e9 du p\u00f4le de l&#8217;alternative ouvri\u00e8re et populaire\u00a0\u00bb. Voil\u00e0, c\u2019est dit.<\/span><\/p>\n<p><span style=\"color: #003366\">Cette phrase o\u00f9 j\u2019implique leurs compagnons et eux-m\u00eames dans la n\u00e9o-hirakie est-elle lisible pour les Zelig-Mouffok ou faudrait-il reprendre l\u2019explication \u00e0 nouveaux frais comme pour un enfant de cinq ans\u00a0? Lorsque Omar Zelig publiait son post sur Bensaada et autres \u00ab\u00a0dommages collat\u00e9raux\u00a0\u00bb, les amis du couple dans la n\u00e9o-hirakie n\u2019en ignoraient pas le sens et la courte strat\u00e9gie de rachat. Simple observation\u00a0: dans leur Facebook, les Zelig-Mouffok ne mentionnent pas une seule fois le hirak ou le n\u00e9o-hirak, mais ils remercient des \u00ab\u00a0compagnes et compagnons de combats et d\u2019engagements\u00a0\u00bb. Mais qui sont ces \u00e9nigmatiques \u00ab\u00a0compagnes et compagnons\u00a0\u00bb de \u00ab\u00a0combat\u00a0\u00bb (mais quel combat\u00a0?) et d\u2019\u00ab\u00a0engagements\u00a0\u00bb (lesquels\u00a0?) des Zelig-Mouffok\u00a0? Ah\u00a0! la clandestinit\u00e9 et son parfum de romantisme r\u00e9volutionnaire\u2026 Qui aurait pu \u00e9crire\u00a0: \u00ab\u00a0On est du n\u00e9o-hirak ou on ne l\u2019est pas\u00a0\u00bb\u00a0?<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\"><strong>V. En attendant la confrontation au tribunal<\/strong><\/span><\/p>\n<p><span style=\"color: #003366\">Revenons aux motifs de la col\u00e8re haineuse des Zelig-Mouffok et de leur charge de malappris sur un \u00ab\u00a0pi\u00e8tre adversaire\u00a0\u00bb, \u00ab\u00a0m\u00e9diocre et inculte\u00a0\u00bb. L\u2019injure remplace-t-elle un bon argument, s\u2019il y en a\u00a0? J\u2019ai publi\u00e9 un texte mettant en relief leur relation avec Ihs\u00e8ne El Kadi, dor\u00e9navant r\u00e9volue ou gel\u00e9e, le n\u00e9o-hirak, ses factions et ses ambitions foudroyantes. Signe des temps qui changent, les id\u00e9es s\u2019\u00e9coulent en cent-quarante signes sur Facebook et Twitter. Le post de Omar Zelig, auquel je r\u00e9ponds, est de la politique \u2013 et, m\u00eame, de la basse politique, lorsqu\u2019il tire dans le dos de ses adversaires. Or, les Zelig-Mouffok m\u2019accusent d\u2019une confondante \u00ab\u00a0l\u00e9g\u00e8ret\u00e9 des preuves\u00a0\u00bb, en s\u2019affirmant d\u2019une blancheur (politique) virginale. Mensonge\u00a0! Mensonge\u00a0! Mensonge ! Dans leur texte \u00e0 trous, Ihs\u00e8ne El Kadi et le n\u00e9o-hirak sont proprement escamot\u00e9s. Ils les nient et les renient.<\/span><\/p>\n<p><span style=\"color: #003366\">\u00c0 d\u00e9faut d\u2019\u00eatre dans un d\u00e9bat contradictoire et loyal contre l\u2019adversaire (qui les a respect\u00e9s), ils s\u2019arrogent, pour complaire \u00e0 leur troupe d\u2019\u00e9cornifleurs, le droit de l\u2019injurier, de le menacer et de l\u2019intimider publiquement. Devrais-je me rabaisser \u00e0 leur indignit\u00e9 et \u00e0 leur vulgarit\u00e9 ? Me serais-je tromp\u00e9 sur ce qu\u2019ils sont r\u00e9ellement\u00a0? Et, pourtant nulle part dans mon texte je n\u2019ai \u00e9crit que Zelig Omar est un petit bateleur de radio et que sa compagne utilise des jurons de charretier ; je cite\u00a0: \u00ab\u00a0Ce putain de complot\u00a0\u00bb (21). Une belle langue acad\u00e9mique.<\/span><\/p>\n<p><span style=\"color: #003366\">Chabane Na\u00eft Mebarek \u00e9voque une \u00ab\u00a0campagne haineuse\u00a0\u00bb et des \u00ab\u00a0invectives\u00a0\u00bb contre Ghania Mouffok et son compagnon, de la part de leurs amis de la n\u00e9o-hirakie, qu\u2019ils ne poursuivront pas devant la justice. Le linge sale ne se lave-t-il pas en famille\u00a0? La justice alg\u00e9rienne, \u00e0 laquelle Ghania Mouffok ne croit pas et qu\u2019elle conspue, ils la r\u00e9servent, elle et son compagnon, exclusivement au contradicteur \u00e9tranger \u00e0 leur clique de conspirateurs, qui les a lus et confondus dans leur double-jeu. Qui est m\u00e9prisable en la circonstance\u00a0?<\/span><\/p>\n<p><span style=\"color: #003366\">J\u2019attends de la justice qu\u2019elle dise s\u2019il y a de la \u00ab\u00a0haine\u00a0\u00bb, des \u00ab\u00a0invectives\u00a0\u00bb et de la diffamation dans mon \u00e9crit. Dans le texte des Zelig-Mouffok, il y a six passages injurieux et diffamatoires envers ma personne, qui n\u2019ont rien \u00e0 voir avec un d\u00e9bat d\u2019id\u00e9es contradictoire et loyal, entre autres l\u2019accusation, \u00e0 la fois facile et grave, d\u2019antis\u00e9mitisme. Ils figureront dans le dossier que je soumettrai \u00e0 la justice, qui comporte mes preuves. Mais avant d\u2019aller au tribunal, le proc\u00e8s public avec ses exc\u00e8s et ses d\u00e9rapages est bel et bien ouvert sur Facebook par leurs amis. Ils en portent l\u2019enti\u00e8re responsabilit\u00e9.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\"><strong><em>Notes<\/em><\/strong><\/span><\/p>\n<p><span style=\"color: #003366\">1. \u00ab\u00a0Pour servir et valoir ce que de droit\u00a0\u00bb. Texte de Omar Zelig et Ghania Mouffok sur Facebook, nd.<\/span><\/p>\n<p><span style=\"color: #003366\">2. Voir Ahmed Bensaada, \u00ab\u00a0Qui sont ces t\u00e9nors autoproclam\u00e9s du hirak\u00a0?\u00a0\u00bb, Alger, \u00c9ditions APIC, 2020. La National Endownent for Democracy (NED) a repris les attributions de la CIA relativement au programme de \u00ab\u00a0d\u00e9mocratisation\u00a0\u00bb du Grand Moyen Orient.<\/span><\/p>\n<p><span style=\"color: #003366\">3. Abdellali Merdaci, \u00ab\u00a0Ahmed Bensaada et les \u2018\u2018dommages collat\u00e9raux\u2019\u2019. Les songes d\u2019une nuit d\u2019automne de Omar Zelig \u00bb, \u00ab\u00a0Alg\u00e9rie 54\u00a0\u00bb, 21 novembre 2021\u00a0; \u00ab\u00a0La Patrie News\u00a0\u00bb, 22 novembre 2021.<\/span><\/p>\n<p><span style=\"color: #003366\">4. Omar Zelig, \u00ab\u00a0Une symphonie alg\u00e9rienne inachev\u00e9e\u00a0\u00bb, \u00ab\u00a0El \u2018Arabi-El Safir\u00a0\u00bb, 15 janvier 2021. Texte publi\u00e9 avec le soutien du Rosa Luxembourg Institute.<\/span><\/p>\n<p><span style=\"color: #003366\">5. \u00ab\u00a0D\u00e9claration publique des fr\u00e8res Merdaci\u00a0\u00bb, dat\u00e9e du 7 avril 2019, reprise dans \u00ab\u00a0bouhamidimohamed.overblog\u00a0\u00bb. Le texte indique le professeur Mohamed Bouhamidi est \u00ab\u00a0publi\u00e9 pour que reste la m\u00e9moire de cette d\u00e9claration\u00a0\u00bb.<\/span><\/p>\n<p><span style=\"color: #003366\">6. Post de Mohamed Betache, suite \u00e0 l\u2019article de Ghania Mouffok, \u00ab\u00a0Dernier acte\u00a0: quelle surprenante surprise\u00a0\u00bb, \u00ab\u00a0Le Quotidien d\u2019Alg\u00e9rie\u00a0\u00bb, 13 juin 2021. R\u00e9pondant \u00e0 Betache, un d\u00e9nomm\u00e9 \u00ab\u00a0Dria\u00a0\u00bb \u00e9crit\u00a0: \u00ab\u00a0 Si vous \u00eates un vrai ind\u00e9pendantiste alors autant voir grand et reprendre le contr\u00f4le de toute la terre amazigh, l\u2019antique \u00ab\u00a0Tamazgha\u00a0\u00bb rebaptiser \u00ab\u00a0grand Maghreb arabe\u00a0\u00bb l\u00e0, au moins \u00e7a donne du poids \u00e0 la cause. En tant qu\u2019alg\u00e9rien et amazigh, c\u2019est la seule issue ind\u00e9pendantiste valable qui vaut le detour pour reprendre \u00e0 z\u00e9ro et red\u00e9marrer \u00e0 nouveau sur des bases solides, de gr\u00e2ce ne jouons pas avec le feu d\u2019autant plus qu\u2019il y a le feu en la demeure. Il n\u2019y a ni plan A ni plan B cot\u00e9 Hirak, il y a certes un combat \u00e0 poursuivre. Ce n\u2019est pas le moment de flancher, ni de douter, le prochain RDV \u00e9tant fixer par la majorit\u00e9 du peuple vers la f\u00eate de l\u2019ind\u00e9pendance, cap sur le 05 juillet ? Quelle que soit l\u2019 action d\u2019envergure qui se pr\u00e9pare, elle a pour but supr\u00eame et comme urgence la LIBERATION de tous les d\u00e9tenus afin d\u2019en faire une vraie f\u00eate d\u2019ind\u00e9pendance\u00a0\u00bb. O\u00f9 l\u2019on voit que Ghania Mouffok touille le brouet n\u00e9o-hirakiste.<\/span><\/p>\n<p><span style=\"color: #003366\">7. \u00ab\u00a0Un journaliste n\u2019est pas toujours un flic\u00a0\u00bb, Site de la Ligue alg\u00e9rienne de d\u00e9fense des Droits de l\u2019Homme (LADDH), 12 novembre 2020.<\/span><\/p>\n<p><span style=\"color: #003366\">8. Ahmed Bensaada, \u00ab\u00a0A\u00efe, maman\u00a0! Zelig Omar est f\u00e2ch\u00e9\u00a0\u00bb, \u00ab\u00a0La Patrie News\u00a0\u00bb, 26 novembre 2021.<\/span><\/p>\n<p><span style=\"color: #003366\">9. Abdellali Merdaci, \u00ab\u00a0Ahmed Bensaada et les \u2018\u2018dommages collat\u00e9raux\u2019\u2019. Les songes d\u2019une nuit d\u2019automne de Omar Zelig \u00bb, \u00ab\u00a0Alg\u00e9rie 54\u00a0\u00bb, art. cit\u00e9.<\/span><\/p>\n<p><span style=\"color: #003366\">10. Ali Bensaad \u00e0 propos du pr\u00e9sident Tebboune\u00a0: \u00ab\u00a0Ses propos avaient pour but de jeter de l\u2019huile sur le feu\u00a0\u00bb. D\u00e9claration \u00e0 \u00ab\u00a0Alg\u00e9rie Part\u00a0\u00bb [Paris], 20 ao\u00fbt 2021.<\/span><\/p>\n<p><span style=\"color: #003366\">11. Ali Bensaad, entretien avec RFI, le 1<sup>er<\/sup>\u00a0novembre 2021. Chronique\u00a0: \u00ab En Alg\u00e9rie, la pol\u00e9mique m\u00e9morielle cherche \u00e0 masquer l\u2019isolement et la fragilit\u00e9 d\u2019un r\u00e9gime\u00a0\u00bb, \u00ab\u00a0Le Monde\u00a0\u00bb (Paris), 19 octobre 2021.<\/span><\/p>\n<p><span style=\"color: #003366\">12. \u00ab\u00a0Pour servir et valoir ce que de droit\u00a0\u00bb. Facebook de Omar Zelig et Ghania Mouffok.<\/span><\/p>\n<p><span style=\"color: #003366\">13. Ghania Mouffok, \u00ab\u00a0Un journaliste n\u2019est pas toujours un flic\u00a0\u00bb, site de la Ligue alg\u00e9rienne de d\u00e9fense des Droits de l\u2019Homme (LADDH), art. cit\u00e9.<\/span><\/p>\n<p><span style=\"color: #003366\">14. G. Mouffok, \u00a0\u00ab\u00a0Y a-t-il une ambulance pour l\u2019Alg\u00e9rie\u00a0\u00bb, \u00ab\u00a0Le Quotidien d\u2019Alg\u00e9rie\u00a0\u00bb [Paris], 31 octobre 2020.<\/span><\/p>\n<p><span style=\"color: #003366\">15. Id.<\/span><\/p>\n<p><span style=\"color: #003366\">16. G. Mouffok, \u00ab\u00a0Petite histoire du culte de la vache au lait d\u2019or noir\u00a0\u00bb, \u00ab\u00a0Le Quotidien d\u2019Alg\u00e9rie\u00a0\u00bb, 15 octobre 2021.<\/span><\/p>\n<p><span style=\"color: #003366\">I7. Id<\/span><\/p>\n<p><span style=\"color: #003366\">18. Le chercheur fran\u00e7ais Yazid Ben Hounet, membre du CNRS, implique, preuves \u00e0 l\u2019appui, Ali Bensaad dans la proximit\u00e9 de l\u2019arm\u00e9e fran\u00e7aise et de ses bureaux d\u2019\u00e9tude\u00a0: \u00ab\u00a0[Ali Bensaad] travaille pr\u00e9cis\u00e9ment sur des sujets susceptibles d\u2019int\u00e9resser le Minist\u00e8res fran\u00e7ais des Affaires Etrang\u00e8res et celui de la D\u00e9fense Nationale. Qu\u2019il est en outre membre d\u2019un centre de recherche \u2013 GEODE \u2013 (ici\u00a0:\u00a0<a style=\"color: #003366\" href=\"https:\/\/geode.science\/team\/bensaad-ali\/\">https:\/\/geode.science\/team\/bensaad-ali\/<\/a>), partenaire du centre de recherche des \u00e9coles de Saint-Cyr Co\u00ebtquidan, relevant Minist\u00e8re fran\u00e7ais de la D\u00e9fense (ici\u00a0:\u00a0<a style=\"color: #003366\" href=\"https:\/\/geode.science\/partenariats\/\">https:\/\/geode.science\/partenariats\/<\/a>) et qu\u2019il est membre d\u2019honneur de l\u2019association EUROMED-IHEDN (ici\u00a0:\u00a0<a style=\"color: #003366\" href=\"https:\/\/www.euromed-ihedn.fr\/ils-ont-ecrit.html\">https:\/\/www.euromed-ihedn.fr\/ils-ont-ecrit.html<\/a>), li\u00e9e \u00e0 l\u2019Institut des Hautes Etudes de la D\u00e9fense Nationale (en France). Comme \u00e9crit sur le site de l\u2019IHEDN (ici\u00a0:\u00a0<a style=\"color: #003366\" href=\"https:\/\/www.ihedn.fr\/presentation-ihedn\">https:\/\/www.ihedn.fr\/presentation-ihedn<\/a>), ce dernier est un \u00ab\u00a0\u00c9tablissement public, \u00e0 dimension interminist\u00e9rielle, plac\u00e9 sous la tutelle du Premier ministre (\u2026). L\u2019Institut des hautes \u00e9tudes de d\u00e9fense nationale (IHEDN) a pour mission de d\u00e9velopper l\u2019esprit de d\u00e9fense et de sensibiliser aux questions internationales\u00a0\u00bb. Source\u00a0: blog de Radio M\u00a0: \u00ab\u00a0Affaire Khaled Drareni\u00a0: un chercheur r\u00e9pond \u00e0 Ali Bensaad\u00a0!\u00a0\u00bb, 24 ao\u00fbt 2020. Si Ali Bensaad est rest\u00e9 strictement alg\u00e9rien, cette proximit\u00e9 avec l\u2019arm\u00e9e fran\u00e7aise s\u2019appelle \u00ab\u00a0intelligence avec une puissance \u00e9trang\u00e8re\u00a0\u00bb.<\/span><\/p>\n<p><span style=\"color: #003366\">19. G. Mouffok, \u00ab\u00a0Dernier acte\u00a0: quelle surprenante surprise\u00a0\u00bb, \u00ab\u00a0Le Quotidien d\u2019Alg\u00e9rie\u00a0\u00bb, art. cit\u00e9.<\/span><\/p>\n<p><span style=\"color: #003366\">20. Sur son Facebook, Ghania Mouffok, publie en date du 30 avril 2021, \u00ab\u00a0La dictature des petits riens\u00a0\u00bb, un t\u00e9moignage sur son parcours dans le hirak et ses marges.<\/span><\/p>\n<p><span style=\"color: #003366\">21. G. Mouffok, \u00ab\u00a0Un journaliste n\u2019est pas toujours un flic\u00a0\u00bb, Site de la Ligue alg\u00e9rienne de d\u00e9fense des Droits de l\u2019Homme (LADDH, art. cit\u00e9.<\/span><\/p>\n<p><span style=\"color: #003366\">Source:<\/span> <strong><span style=\"color: #003366\">www.ahmedbensaada.com<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Abdellali Merdaci Dans l\u2019interpellation en justice \u00e0 laquelle m\u2019assigne le couple Chaulet-Zelig-Mouffok, qui n\u2019en finit pas de battre le rappel de&hellip;<\/p>\n","protected":false},"author":58,"featured_media":39009,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[79,49],"tags":[],"class_list":["post-39003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-important","category-politique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Suppl\u00e9ment \u00e0 un pourvoi en justice - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suppl\u00e9ment \u00e0 un pourvoi en justice - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Par Abdellali Merdaci Dans l\u2019interpellation en justice \u00e0 laquelle m\u2019assigne le couple Chaulet-Zelig-Mouffok, qui n\u2019en finit pas de battre le rappel de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-10T10:46:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/12\/zelig-bobo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"719\" \/>\n\t<meta property=\"og:image:height\" content=\"345\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mohamed Redha Chettibi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mohamed Redha Chettibi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"35 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/supplement-a-un-pourvoi-en-justice\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/supplement-a-un-pourvoi-en-justice\\\/\"},\"author\":{\"name\":\"Mohamed Redha Chettibi\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\"},\"headline\":\"Suppl\u00e9ment \u00e0 un pourvoi en justice\",\"datePublished\":\"2021-12-10T10:46:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/supplement-a-un-pourvoi-en-justice\\\/\"},\"wordCount\":9089,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/supplement-a-un-pourvoi-en-justice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/zelig-bobo.jpg\",\"articleSection\":[\"Important\",\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/supplement-a-un-pourvoi-en-justice\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/supplement-a-un-pourvoi-en-justice\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/supplement-a-un-pourvoi-en-justice\\\/\",\"name\":\"Suppl\u00e9ment \u00e0 un pourvoi en justice - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/supplement-a-un-pourvoi-en-justice\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/supplement-a-un-pourvoi-en-justice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/zelig-bobo.jpg\",\"datePublished\":\"2021-12-10T10:46:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/supplement-a-un-pourvoi-en-justice\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/supplement-a-un-pourvoi-en-justice\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/supplement-a-un-pourvoi-en-justice\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/zelig-bobo.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/zelig-bobo.jpg\",\"width\":719,\"height\":345},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/supplement-a-un-pourvoi-en-justice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Suppl\u00e9ment \u00e0 un pourvoi en justice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\",\"name\":\"Mohamed Redha Chettibi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"caption\":\"Mohamed Redha Chettibi\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/mrc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Suppl\u00e9ment \u00e0 un pourvoi en justice - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/","og_locale":"fr_FR","og_type":"article","og_title":"Suppl\u00e9ment \u00e0 un pourvoi en justice - AAH.JZR","og_description":"Par Abdellali Merdaci Dans l\u2019interpellation en justice \u00e0 laquelle m\u2019assigne le couple Chaulet-Zelig-Mouffok, qui n\u2019en finit pas de battre le rappel de&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2021-12-10T10:46:05+00:00","og_image":[{"width":719,"height":345,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/12\/zelig-bobo.jpg","type":"image\/jpeg"}],"author":"Mohamed Redha Chettibi","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mohamed Redha Chettibi","Dur\u00e9e de lecture estim\u00e9e":"35 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/"},"author":{"name":"Mohamed Redha Chettibi","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77"},"headline":"Suppl\u00e9ment \u00e0 un pourvoi en justice","datePublished":"2021-12-10T10:46:05+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/"},"wordCount":9089,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/12\/zelig-bobo.jpg","articleSection":["Important","Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/","url":"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/","name":"Suppl\u00e9ment \u00e0 un pourvoi en justice - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/12\/zelig-bobo.jpg","datePublished":"2021-12-10T10:46:05+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/12\/zelig-bobo.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2021\/12\/zelig-bobo.jpg","width":719,"height":345},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/supplement-a-un-pourvoi-en-justice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Suppl\u00e9ment \u00e0 un pourvoi en justice"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77","name":"Mohamed Redha Chettibi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","caption":"Mohamed Redha Chettibi"},"url":"https:\/\/jazairhope.org\/fr\/author\/mrc\/"}]}},"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/39003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=39003"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/39003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/39009"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=39003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=39003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=39003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}