{"id":50718,"date":"2022-04-16T17:00:07","date_gmt":"2022-04-16T16:00:07","guid":{"rendered":"https:\/\/jazairhope.org\/?p=50718"},"modified":"2022-04-16T17:27:34","modified_gmt":"2022-04-16T16:27:34","slug":"mohamed-amine-maache-un-libraire-pas-comme-les-autres","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/","title":{"rendered":"Mohamed Amine M\u00e2ache, un libraire pas comme les autres"},"content":{"rendered":"<p>Mohamed Amine M\u00e2ache, un jeune homme de Mostaganem, fait partie de ceux qui ont rapidement r\u00e9ussi \u00e0 transformer sa passion pour la lecture et les livres en un projet culturel, en s\u2019appuyant sur ses propres ressources et sa grande volont\u00e9 de r\u00e9aliser le r\u00eave. .\u00a0: ouvrez votre propre librairie.<\/p>\n<p>Ce jeune autodidacte a r\u00e9ussi \u00e0 faire de sa librairie \u00ab\u00a0Yasmine-El Gharb\u00a0\u00bb, situ\u00e9e au centre de Mostaganem, la destination des amoureux des livres et de ceux qui recherchent l\u2019aventure parmi les \u00e9tag\u00e8res, de diff\u00e9rentes r\u00e9gions du monde. Mohamed Amine M\u00e2ache veut, comme il le r\u00e9p\u00e8te, faire de cet espace un lieu de diversit\u00e9 culturelle et une porte d\u2019entr\u00e9e pour diff\u00e9rentes civilisations.<\/p>\n<p>Ce jeune homme de 29 ans a abandonn\u00e9 l\u2019\u00e9cole en 2010, alors qu\u2019il \u00e9tait en premi\u00e8re ann\u00e9e de lyc\u00e9e. Il a lanc\u00e9 son projet il y a quatre ans, s\u2019\u00e9loignant du chemin qu\u2019il avait pris apr\u00e8s l\u2019obtention d\u2019un dipl\u00f4me en p\u00e2tisserie et h\u00f4tellerie.<\/p>\n<p>Parmi ses nombreux passe-temps, dont l\u2019\u00e9levage d\u2019oiseaux, le dressage de chiens et la plong\u00e9e en apn\u00e9e, Mohamed Amine a choisi sa passion pour la lecture comme premier projet.<\/p>\n<p>L\u2019aventure de Mohamed Amine avec le livre a commenc\u00e9 en tant que marchand ambulant, qui s\u2019est transform\u00e9e en une envie in\u00e9branlable de lancer son propre projet lors de sa participation \u00e0 une exposition \u00e0 Laghouat.<\/p>\n<p>Mohamed pr\u00e9cise que l\u2019histoire a \u00e9t\u00e9 faite par le propri\u00e9taire d\u2019une librairie, apr\u00e8s avoir eu une exp\u00e9rience unique dans la vente de livres, s\u2019interrogeant sur le bonheur des lecteurs en achetant ces quantit\u00e9s de livres et leur plaisir \u00e0 emprunter les lignes noires, lui qui a trouv\u00e9 est dur \u00e0 suivre.<\/p>\n<p>c\u2019est un refuge pour les livres rares pr\u00e9cieux dans les domaines philosophiques et intellectuels.<\/p>\n<p>Il a avou\u00e9 que c\u2019est sa femme qui a choisi le nom \u00ab\u00a0Yasmine-El Gharb\u00a0\u00bb et embelli les \u00e9tag\u00e8res avec des dizaines de plantes, qui font d\u00e9sormais partie du d\u00e9cor de cet espace culturel, en plus des oiseaux qui donnent aux visiteurs la sensation d\u2019\u00eatre dans un jardin magique, \u00e0 la recherche d\u2019objets perdus entre les rayons.<\/p>\n<p>Au d\u00e9but, la librairie a relev\u00e9 le d\u00e9fi des lecteurs, mais sa pire bataille a \u00e9t\u00e9 la pand\u00e9mie de Coronavirus, qui a eu un impact majeur sur les ventes de livres, notamment pendant les longues p\u00e9riodes d\u2019isolement, amenant Mohamed Amine \u00e0 d\u00e9clarer un \u00ab\u00a0paquet\u00a0\u00bb et \u00e0 baisser le rideau .<\/p>\n<p>Cependant, encourag\u00e9 par de nombreux lecteurs, intellectuels et auteurs, qui ont tent\u00e9 d\u2019aider cet espace culturel \u00e0 perdurer, Mohamed Amine a repris son activit\u00e9, d\u2019autant que les pr\u00e9misses de la fin de la pand\u00e9mie commencent \u00e0 se profiler \u00e0 l\u2019horizon. , m\u00eame si la librairie croule sous le poids des dettes, \u00ab\u00a0le rachat du Covid-19\u00a0\u00bb, selon lui.<\/p>\n<p>Bien que la nouvelle librairie ne soit pas loin de l\u2019ancienne place, Mohamed Amine a cette fois adopt\u00e9 un nouveau plan pour maintenir son projet, s\u2019appuyant sur les r\u00e9seaux sociaux et l\u2019achat prudent des livres que les lecteurs demandent \u00e0 la librairie d\u2019\u00eatre toujours \u00e0 leur service, sans oublier les ouvrages r\u00e9serv\u00e9s \u00e0 la lecture et non destin\u00e9s \u00e0 la vente, \u00e0 travers lesquels ils entendent contribuer \u00e0 l\u2019incitation \u00e0 la lecture.<\/p>\n<p>Le lecteur avide a indiqu\u00e9 que la mission de la librairie de transmettre des connaissances et d\u2019\u00e9tablir des portes de la connaissance doit se poursuivre, m\u00eame sous d\u2019autres formes ou en adoptant de nouveaux environnements, en insistant sur la pers\u00e9v\u00e9rance, quelles que soient les circonstances, m\u00eame si les livres doivent \u00eatre vendus \u00e0 partir de distance ou en cr\u00e9ant un caf\u00e9 culturel o\u00f9 romans, pi\u00e8ces de th\u00e9\u00e2tre et litt\u00e9rature en g\u00e9n\u00e9ral font partie int\u00e9grante du carnet de commandes.<\/p>\n<div class=\"jeg_meta_author\"><span class=\"meta_text\">by<\/span>\u00a0Khalil Ressam<\/div>\n<div class=\"jeg_meta_date\">\u00a015 avril 2022<\/div>\n<div>dzairscoop.com<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mohamed Amine M\u00e2ache, un jeune homme de Mostaganem, fait partie de ceux qui ont rapidement r\u00e9ussi \u00e0 transformer sa passion pour la&hellip;<\/p>\n","protected":false},"author":70,"featured_media":50719,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[32,34,39,45],"tags":[],"class_list":["post-50718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-algerie","category-art-fr","category-articles-en-vedette","category-derniers-articles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mohamed Amine M\u00e2ache, un libraire pas comme les autres - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mohamed Amine M\u00e2ache, un libraire pas comme les autres - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Mohamed Amine M\u00e2ache, un jeune homme de Mostaganem, fait partie de ceux qui ont rapidement r\u00e9ussi \u00e0 transformer sa passion pour la&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-16T16:00:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-16T16:27:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/04\/Mohamed-Amine-Maache-un-libraire-pas-comme-les-autres.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CHRYSALIDE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CHRYSALIDE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\\\/\"},\"author\":{\"name\":\"CHRYSALIDE\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\"},\"headline\":\"Mohamed Amine M\u00e2ache, un libraire pas comme les autres\",\"datePublished\":\"2022-04-16T16:00:07+00:00\",\"dateModified\":\"2022-04-16T16:27:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\\\/\"},\"wordCount\":673,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Mohamed-Amine-Maache-un-libraire-pas-comme-les-autres.jpg\",\"articleSection\":[\"Alg\u00e9rie Alg\u00e9rienne\",\"Art &amp; Culture\",\"Articles en vedette\",\"Derniers articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\\\/\",\"name\":\"Mohamed Amine M\u00e2ache, un libraire pas comme les autres - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Mohamed-Amine-Maache-un-libraire-pas-comme-les-autres.jpg\",\"datePublished\":\"2022-04-16T16:00:07+00:00\",\"dateModified\":\"2022-04-16T16:27:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Mohamed-Amine-Maache-un-libraire-pas-comme-les-autres.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Mohamed-Amine-Maache-un-libraire-pas-comme-les-autres.jpg\",\"width\":580,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mohamed Amine M\u00e2ache, un libraire pas comme les autres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\",\"name\":\"CHRYSALIDE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"caption\":\"CHRYSALIDE\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/chrysalide\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mohamed Amine M\u00e2ache, un libraire pas comme les autres - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/","og_locale":"fr_FR","og_type":"article","og_title":"Mohamed Amine M\u00e2ache, un libraire pas comme les autres - AAH.JZR","og_description":"Mohamed Amine M\u00e2ache, un jeune homme de Mostaganem, fait partie de ceux qui ont rapidement r\u00e9ussi \u00e0 transformer sa passion pour la&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2022-04-16T16:00:07+00:00","article_modified_time":"2022-04-16T16:27:34+00:00","og_image":[{"width":580,"height":365,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/04\/Mohamed-Amine-Maache-un-libraire-pas-comme-les-autres.jpg","type":"image\/jpeg"}],"author":"CHRYSALIDE","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"CHRYSALIDE","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/"},"author":{"name":"CHRYSALIDE","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be"},"headline":"Mohamed Amine M\u00e2ache, un libraire pas comme les autres","datePublished":"2022-04-16T16:00:07+00:00","dateModified":"2022-04-16T16:27:34+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/"},"wordCount":673,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/04\/Mohamed-Amine-Maache-un-libraire-pas-comme-les-autres.jpg","articleSection":["Alg\u00e9rie Alg\u00e9rienne","Art &amp; Culture","Articles en vedette","Derniers articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/","url":"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/","name":"Mohamed Amine M\u00e2ache, un libraire pas comme les autres - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/04\/Mohamed-Amine-Maache-un-libraire-pas-comme-les-autres.jpg","datePublished":"2022-04-16T16:00:07+00:00","dateModified":"2022-04-16T16:27:34+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/04\/Mohamed-Amine-Maache-un-libraire-pas-comme-les-autres.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/04\/Mohamed-Amine-Maache-un-libraire-pas-comme-les-autres.jpg","width":580,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/mohamed-amine-maache-un-libraire-pas-comme-les-autres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Mohamed Amine M\u00e2ache, un libraire pas comme les autres"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be","name":"CHRYSALIDE","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","caption":"CHRYSALIDE"},"url":"https:\/\/jazairhope.org\/fr\/author\/chrysalide\/"}]}},"views":318,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/50718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=50718"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/50718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/50719"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=50718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=50718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=50718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}