{"id":51350,"date":"2022-04-26T11:00:34","date_gmt":"2022-04-26T10:00:34","guid":{"rendered":"https:\/\/jazairhope.org\/?p=51350"},"modified":"2022-04-25T23:38:07","modified_gmt":"2022-04-25T22:38:07","slug":"zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\/","title":{"rendered":"Zones d\u2019ombre \u00e0 Constantine : Ouverture de 10 nouvelles lignes de\u2008transport scolaire"},"content":{"rendered":"<div class=\"single-post-thumb\"><\/div>\n<div class=\"post-inner\">\n<div class=\"entry\">\n<div class=\"addtoany_share_save_container addtoany_content addtoany_content_top\">\n<div class=\"a2a_kit a2a_kit_size_32 addtoany_list\" data-a2a-url=\"http:\/\/lecourrier-dalgerie.com\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\/\" data-a2a-title=\"Zones d\u2019ombre \u00e0 Constantine : Ouverture de 10 nouvelles lignes de\u2008transport scolaire\"><span style=\"text-transform: initial;\">Le transport scolaire a \u00e9t\u00e9 renforc\u00e9 dans les communes de Beni H\u2019midane, Ibn Ziad, Messaoud Boujeriou et au chef-lieu de la wilaya de Constantine par l\u2019ouverture de 10 nouvelles lignes dans plusieurs zones d\u2019ombre afin d\u2019am\u00e9liorer les conditions de scolarisation des \u00e9l\u00e8ves, a-t-on appris mardi aupr\u00e8s de responsables de ces collectivit\u00e9s locales.<\/span><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Les efforts d\u00e9ploy\u00e9s par l\u2019Etat pour r\u00e9duire le probl\u00e8me de la d\u00e9perdition scolaire et assurer une meilleure prise en charge des scolaris\u00e9s dans toutes les communes de la wilaya, en particulier dans les zones d\u2019ombre, se sont traduits par l\u2019am\u00e9lioration de la restauration et du transport scolaire, a indiqu\u00e9 la m\u00eame source. Dans ce contexte, quatre (4) lignes ont \u00e9t\u00e9 affect\u00e9es au profit des communes de Constantine et Beni H\u2019midane, une (1) pour Ibn Ziad et une (1) pour Messaoud Boujeriou dans le but de faciliter le d\u00e9placement des \u00e9l\u00e8ves de ces collectivit\u00e9s locales vers les \u00e9tablissements scolaires, selon la m\u00eame source.<\/p>\n<p>Le vice-pr\u00e9sident de l\u2019Assembl\u00e9e populaire communale (APC) de Constantine, Nabil Bousba\u00e2, a pr\u00e9cis\u00e9 que le transport scolaire est \u00ab\u00a0disponible \u00e0 travers l\u2019ensemble des \u00e9coles de cette collectivit\u00e9 locale du fait de son implantation en milieu urbain, \u00e0 l\u2019exception de certaines zones nouvellement dot\u00e9es de lignes, \u00e0 l\u2019instar des zones d\u2019El Jedour, Benchergui, Tafrent et El Aifour\u00a0\u00bb. L\u2019ouverture de ces nouvelles lignes a n\u00e9cessit\u00e9 la mobilisation d\u2019une enveloppe financi\u00e8re de 7,25 millions DA, a fait savoir le m\u00eame responsable.<\/p>\n<p>De son c\u00f4t\u00e9, le pr\u00e9sident de l\u2019APC de Beni H\u2019midene, Abdelhak Cherouana, a d\u00e9clar\u00e9 qu\u2019un montant financier estim\u00e9 \u00e0 6 millions DA, puis\u00e9 du budget de la wilaya, a \u00e9t\u00e9 allou\u00e9 au titre de l\u2019ann\u00e9e en cours pour le transport scolaire, en plus de l\u2019ouverture de quatre (4) nouvelles lignes au profit des mechtas El Hamri, Ferifet, Sidi Idriss et Djenane El Baz. Le m\u00eame \u00e9lu a ajout\u00e9 que plus de 800 \u00e9l\u00e8ves b\u00e9n\u00e9ficient du transport scolaire durant l\u2019exercice actuel, \u00e9tant donn\u00e9, a-t-il dit, que cette localit\u00e9 est compos\u00e9e majoritairement de mechtas, n\u00e9cessitant 12 bus pour assurer le transport des scolaris\u00e9s.<br \/>\nSelon M. Cherouana, la couverture en mati\u00e8re de transport scolaire est jug\u00e9e \u00ab bonne \u00bb dans cette commune, en attendant l\u2019ouverture prochaine d\u2019une ligne suppl\u00e9mentaire pour la zone rurale de Fedj Ferhat.<\/p>\n<p>Pour sa part, Amel Lemnai, chef de da\u00efra d\u2019Ibn Ziad, rel\u00e8ve que \u00ab la plus grande aide accord\u00e9e par la wilaya et l\u2019APC est destin\u00e9e au secteur de l\u2019\u00e9ducation \u00bb\u2019, soulignant qu\u2019 \u00bbune enveloppe financi\u00e8re de 9,29 millions DA a \u00e9t\u00e9 consacr\u00e9e pour la couverture des charges du transport scolaire \u00bb.<span style=\"text-transform: initial;\">Elle a ajout\u00e9 que l\u2019ouverture de deux (2) lignes au profit des communes d\u2019Ibn Ziad et Messaoud Boudjeriou a profit\u00e9 aux mechtas Ain Terab et Oueldjet El Kadi.<\/span><\/p>\n<p>Le parc r\u00e9serv\u00e9 au transport scolaire dans la commune d\u2019Ibn Ziad qui a b\u00e9n\u00e9fici\u00e9, par ailleurs, de la r\u00e9alisation d\u2019une \u00e9cole primaire dans la mechta Oueldjet El Kadi, compte actuellement 18 bus destin\u00e9s \u00e0 couvrir 14 \u00e9coles primaires, 2 coll\u00e8ges d\u2019enseignement moyen (CEM) et un (1) lyc\u00e9e. La localit\u00e9 de Messaoud Boudjeriou compte 8 bus pour les scolaris\u00e9s de 7 \u00e9coles primaires, un (1) CEM et un (1) lyc\u00e9e, a-t-elle conclu.<\/p>\n<p>lecourrier-dalgerie.com 21 avril 2022<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le transport scolaire a \u00e9t\u00e9 renforc\u00e9 dans les communes de Beni H\u2019midane, Ibn Ziad, Messaoud Boujeriou et au chef-lieu de la wilaya&hellip;<\/p>\n","protected":false},"author":70,"featured_media":51351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[32,39,45,37,52],"tags":[],"class_list":["post-51350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-algerie","category-articles-en-vedette","category-derniers-articles","category-education-fr","category-sport-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zones d\u2019ombre \u00e0 Constantine : Ouverture de 10 nouvelles lignes de\u2008transport scolaire - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de\u2008transport-scolaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zones d\u2019ombre \u00e0 Constantine : Ouverture de 10 nouvelles lignes de\u2008transport scolaire - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Le transport scolaire a \u00e9t\u00e9 renforc\u00e9 dans les communes de Beni H\u2019midane, Ibn Ziad, Messaoud Boujeriou et au chef-lieu de la wilaya&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de\u2008transport-scolaire\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-26T10:00:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/04\/Transport-scolaire-580x330-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CHRYSALIDE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CHRYSALIDE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\\\/\"},\"author\":{\"name\":\"CHRYSALIDE\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\"},\"headline\":\"Zones d\u2019ombre \u00e0 Constantine : Ouverture de 10 nouvelles lignes de\u2008transport scolaire\",\"datePublished\":\"2022-04-26T10:00:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\\\/\"},\"wordCount\":585,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Transport-scolaire-580x330-1.jpg\",\"articleSection\":[\"Alg\u00e9rie Alg\u00e9rienne\",\"Articles en vedette\",\"Derniers articles\",\"\u00c9ducation\",\"Sport &amp; Soci\u00e9t\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\\\/\",\"name\":\"Zones d\u2019ombre \u00e0 Constantine : Ouverture de 10 nouvelles lignes de\u2008transport scolaire - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Transport-scolaire-580x330-1.jpg\",\"datePublished\":\"2022-04-26T10:00:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Transport-scolaire-580x330-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Transport-scolaire-580x330-1.jpg\",\"width\":580,\"height\":330},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zones d\u2019ombre \u00e0 Constantine : Ouverture de 10 nouvelles lignes de\u2008transport scolaire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\",\"name\":\"CHRYSALIDE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"caption\":\"CHRYSALIDE\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/chrysalide\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zones d\u2019ombre \u00e0 Constantine : Ouverture de 10 nouvelles lignes de\u2008transport scolaire - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de\u2008transport-scolaire\/","og_locale":"fr_FR","og_type":"article","og_title":"Zones d\u2019ombre \u00e0 Constantine : Ouverture de 10 nouvelles lignes de\u2008transport scolaire - AAH.JZR","og_description":"Le transport scolaire a \u00e9t\u00e9 renforc\u00e9 dans les communes de Beni H\u2019midane, Ibn Ziad, Messaoud Boujeriou et au chef-lieu de la wilaya&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de\u2008transport-scolaire\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2022-04-26T10:00:34+00:00","og_image":[{"width":580,"height":330,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/04\/Transport-scolaire-580x330-1.jpg","type":"image\/jpeg"}],"author":"CHRYSALIDE","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"CHRYSALIDE","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\/"},"author":{"name":"CHRYSALIDE","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be"},"headline":"Zones d\u2019ombre \u00e0 Constantine : Ouverture de 10 nouvelles lignes de\u2008transport scolaire","datePublished":"2022-04-26T10:00:34+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\/"},"wordCount":585,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/04\/Transport-scolaire-580x330-1.jpg","articleSection":["Alg\u00e9rie Alg\u00e9rienne","Articles en vedette","Derniers articles","\u00c9ducation","Sport &amp; Soci\u00e9t\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\/","url":"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\/","name":"Zones d\u2019ombre \u00e0 Constantine : Ouverture de 10 nouvelles lignes de\u2008transport scolaire - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/04\/Transport-scolaire-580x330-1.jpg","datePublished":"2022-04-26T10:00:34+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/04\/Transport-scolaire-580x330-1.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/04\/Transport-scolaire-580x330-1.jpg","width":580,"height":330},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/zones-dombre-a-constantine-ouverture-de-10-nouvelles-lignes-de%e2%80%88transport-scolaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Zones d\u2019ombre \u00e0 Constantine : Ouverture de 10 nouvelles lignes de\u2008transport scolaire"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be","name":"CHRYSALIDE","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","caption":"CHRYSALIDE"},"url":"https:\/\/jazairhope.org\/fr\/author\/chrysalide\/"}]}},"views":310,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/51350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=51350"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/51350\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/51351"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=51350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=51350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=51350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}