{"id":54147,"date":"2022-06-02T21:30:23","date_gmt":"2022-06-02T20:30:23","guid":{"rendered":"https:\/\/jazairhope.org\/?p=54147"},"modified":"2022-06-02T21:43:06","modified_gmt":"2022-06-02T20:43:06","slug":"le-spectacle-de-danse-sublimes-expressions-presente-a-alger","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/","title":{"rendered":"Le spectacle de danse &#8220;Sublimes Expressions&#8221; pr\u00e9sent\u00e9 \u00e0 Alger"},"content":{"rendered":"<div class=\"itemIntroText col-xs-hidden  selectionShareable\">\n<p><strong>ALGER &#8211; Un bel hommage \u00e0 l\u2019expression par la gr\u00e2ce du mouvement et la beaut\u00e9 du geste a \u00e9t\u00e9 rendu, lundi \u00e0 Alger, \u00e0 travers &#8220;Sublimes Expressions&#8221;, un spectacle de danse d\u00e9di\u00e9 \u00e0 la mise en valeur de la diversit\u00e9 de l&#8217;expression chor\u00e9graphique.<\/strong><\/p>\n<\/div>\n<div class=\"itemFullText selectionShareable\">\n<p>Con\u00e7ue par la chor\u00e9graphe et professeure de danse, Nouara Idami, la troisi\u00e8me \u00e9dition du spectacle &#8220;Sublimes Expressions&#8221;, pr\u00e9sent\u00e9e au th\u00e9\u00e2tre nationale Mahieddine-Bachtarzi, a \u00e9t\u00e9 organis\u00e9e par la Coop\u00e9rative culturelle et artistique &#8220;Nouara&#8221;, en collaboration avec le &#8220;Studio Sylphide&#8221; et le TNA.<\/p>\n<p>Durant pr\u00e8s de deux heures de temps, quelques 80 ballerines se sont succ\u00e9d\u00e9 sur la sc\u00e8ne de la salle Mustapha-Kateb au TNA, pour rendre, dans des atmosph\u00e8res de grands soirs, une prestation en deux parties, aux \u00e9poques diff\u00e9rentes, empreintes de richesse et de diversit\u00e9 dans leurs contenus.<\/p>\n<p>Enchainant une dizaine de tableaux, les ballerines ont d\u2019abord d\u00e9ploy\u00e9 leur talent dans une adaptation de &#8220;Chopiniana&#8221;, c\u00e9l\u00e8bre ballet de Michel Fokine (1880-1942), en &#8220;hommage au ballet romantique&#8221;, dira la ma\u00eetresse des lieux, Nouara Idami.<\/p>\n<p>Occupant la sc\u00e8ne dans une g\u00e9om\u00e9trie du mouvement bas\u00e9e sur la sym\u00e9trie, les ballerines, pimpantes et souriantes, se sont d\u00e9ploy\u00e9es sur des cadences simples \u00e0 quatre et \u00e0 trois temps, sous un \u00e9clairage judicieux, vif et aux couleurs vari\u00e9es.<\/p>\n<p>D\u2019autres registres chor\u00e9graphiques ont \u00e9t\u00e9 pr\u00e9sent\u00e9s, avec notamment le genre traditionnel et la danse du Na\u00efli, brillamment ex\u00e9cut\u00e9e par le duo Fatiha Bekhti et Mahfoud Lekhal, celui du &#8220;Modern Jazz&#8221; ou du &#8220;Contemporain&#8221;, rendu dans une courte prestation au titre de &#8220;L\u2019Artiste&#8221;, et \u00e9galement, la danse indienne \u00e0 l\u2019intitul\u00e9 \u00e9vocateur de &#8220;Bollywood&#8221;.<\/p>\n<p>Savourant tous les instants du spectacle dans la d\u00e9lectation, le nombreux public a longtemps applaudi la p\u00e9pini\u00e8re d\u2019artistes mise en avant, gr\u00e2ce au savoir faire et \u00e0 l\u2019exp\u00e9rience de la chor\u00e9graphe-professeure, Nouara Idami.<\/p>\n<p>Les solistes, Adel Nazih Aouchette, Lyna Hamadouche, Am\u00e9lia Benyoun\u00e8s, Dalia Khermane, Celia Cecilia, Djazia Almi, Yasmine Benkrily, Sara Mekkaoui et la douce Rania Senane, ont brill\u00e9 de ma\u00eetrise et de technique, offrant au public de belles figures esth\u00e9tiques.<\/p>\n<p>&#8220;Je suis tellement heureuse d\u2019avoir pris part \u00e0 cette belle aventure, o\u00f9 le corps exprime ses joies et ses peines par l\u2019\u00e9l\u00e9gance du geste et la gr\u00e2ce du mouvement&#8221;, a r\u00e9agi Rania Senane, jeune ballerine au &#8220;potentiel prometteur, augurant d\u2019un bel avenir artistique&#8221;, de l\u2019avis d\u2019un professeur de danse contemporaine, pr\u00e9sent au spectacle.<\/p>\n<p>A travers le geste pr\u00e9cis et le mouvement gracieux, le corps s\u2019est exprim\u00e9, racontant sa propre histoire qui rappelle \u00e0 tous, l\u2019importance de pr\u00e9server et de transmettre le patrimoine culturel de la danse, dans la &#8220;diversit\u00e9 de ses contenus et de ses formes&#8221;, explique la metteure en sc\u00e8ne.<\/p>\n<p>Les jeunes chanteurs, aux voix pr\u00e9sentes et \u00e9toff\u00e9es, &#8220;Noe\u00ef&#8221;, In\u00e8s Kada et Mustapha Fekiri, ainsi que le jeune groupe &#8220;El A\u00e2yla&#8221; (la famille), de musiciens virtuoses, ont livr\u00e9 un floril\u00e8ge de chansons du terroir, faisant montre de toute l\u2019\u00e9tendue de leurs talents respectifs.<\/p>\n<p>Grande passionn\u00e9e de danse depuis plusieurs d\u00e9cennies, Nouara Idami a con\u00e7u et mis en sc\u00e8ne plusieurs Ballets, et particip\u00e9 \u00e0 nombre de manifestations culturelles dans diff\u00e9rents registres de danse, en Alg\u00e9rie et \u00e0 l\u2019\u00e9tranger.<\/p>\n<p>Nouara Idami est dipl\u00f4m\u00e9e de l&#8217;Ecole national d&#8217;art dramatique et chor\u00e9graphique de Bordj El Kiffan (actuel ISMAS), de &#8220;The Bolshoi Ballet Academy&#8221; et du &#8220;GITIS Russian Academy of Theatre Arts&#8221;, entre autre.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ALGER &#8211; Un bel hommage \u00e0 l\u2019expression par la gr\u00e2ce du mouvement et la beaut\u00e9 du geste a \u00e9t\u00e9 rendu, lundi \u00e0&hellip;<\/p>\n","protected":false},"author":70,"featured_media":54148,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[34],"tags":[],"class_list":["post-54147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le spectacle de danse &quot;Sublimes Expressions&quot; pr\u00e9sent\u00e9 \u00e0 Alger - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le spectacle de danse &quot;Sublimes Expressions&quot; pr\u00e9sent\u00e9 \u00e0 Alger - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"ALGER &#8211; Un bel hommage \u00e0 l\u2019expression par la gr\u00e2ce du mouvement et la beaut\u00e9 du geste a \u00e9t\u00e9 rendu, lundi \u00e0&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-02T20:30:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-02T20:43:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/06\/upload-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CHRYSALIDE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CHRYSALIDE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\\\/\"},\"author\":{\"name\":\"CHRYSALIDE\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\"},\"headline\":\"Le spectacle de danse &#8220;Sublimes Expressions&#8221; pr\u00e9sent\u00e9 \u00e0 Alger\",\"datePublished\":\"2022-06-02T20:30:23+00:00\",\"dateModified\":\"2022-06-02T20:43:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\\\/\"},\"wordCount\":618,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/upload-4.jpg\",\"articleSection\":[\"Art &amp; Culture\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\\\/\",\"name\":\"Le spectacle de danse \\\"Sublimes Expressions\\\" pr\u00e9sent\u00e9 \u00e0 Alger - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/upload-4.jpg\",\"datePublished\":\"2022-06-02T20:30:23+00:00\",\"dateModified\":\"2022-06-02T20:43:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/upload-4.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/upload-4.jpg\",\"width\":580,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le spectacle de danse \u00ab\u00a0Sublimes Expressions\u00a0\u00bb pr\u00e9sent\u00e9 \u00e0 Alger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\",\"name\":\"CHRYSALIDE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"caption\":\"CHRYSALIDE\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/chrysalide\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le spectacle de danse \"Sublimes Expressions\" pr\u00e9sent\u00e9 \u00e0 Alger - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/","og_locale":"fr_FR","og_type":"article","og_title":"Le spectacle de danse \"Sublimes Expressions\" pr\u00e9sent\u00e9 \u00e0 Alger - AAH.JZR","og_description":"ALGER &#8211; Un bel hommage \u00e0 l\u2019expression par la gr\u00e2ce du mouvement et la beaut\u00e9 du geste a \u00e9t\u00e9 rendu, lundi \u00e0&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2022-06-02T20:30:23+00:00","article_modified_time":"2022-06-02T20:43:06+00:00","og_image":[{"width":580,"height":350,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/06\/upload-4.jpg","type":"image\/jpeg"}],"author":"CHRYSALIDE","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"CHRYSALIDE","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/"},"author":{"name":"CHRYSALIDE","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be"},"headline":"Le spectacle de danse &#8220;Sublimes Expressions&#8221; pr\u00e9sent\u00e9 \u00e0 Alger","datePublished":"2022-06-02T20:30:23+00:00","dateModified":"2022-06-02T20:43:06+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/"},"wordCount":618,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/06\/upload-4.jpg","articleSection":["Art &amp; Culture"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/","url":"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/","name":"Le spectacle de danse \"Sublimes Expressions\" pr\u00e9sent\u00e9 \u00e0 Alger - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/06\/upload-4.jpg","datePublished":"2022-06-02T20:30:23+00:00","dateModified":"2022-06-02T20:43:06+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/06\/upload-4.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/06\/upload-4.jpg","width":580,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/le-spectacle-de-danse-sublimes-expressions-presente-a-alger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Le spectacle de danse \u00ab\u00a0Sublimes Expressions\u00a0\u00bb pr\u00e9sent\u00e9 \u00e0 Alger"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be","name":"CHRYSALIDE","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","caption":"CHRYSALIDE"},"url":"https:\/\/jazairhope.org\/fr\/author\/chrysalide\/"}]}},"views":459,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/54147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=54147"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/54147\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/54148"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=54147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=54147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=54147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}