{"id":56099,"date":"2022-06-29T13:22:34","date_gmt":"2022-06-29T12:22:34","guid":{"rendered":"https:\/\/jazairhope.org\/?p=56099"},"modified":"2022-06-29T13:22:34","modified_gmt":"2022-06-29T12:22:34","slug":"pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/","title":{"rendered":"Pr Abdelouahab Mansour admis en tant que r\u00e9viseur dans la revue mondiale &#8220;Mathematical reviews&#8221;"},"content":{"rendered":"<p>Le choix de l\u2019enseignant de math\u00e9matiques Pr Abdelouahab Mansour pour faire partie de l&#8217;\u00e9quipe d&#8217;experts charg\u00e9e du traitement du contenu de Mathematical reviews permettra d\u2019 apporter une valeur ajout\u00e9e \u00e0 cette base de donn\u00e9es qui englobe des r\u00e9sum\u00e9s, des \u00e9valuations d&#8217;articles de math\u00e9matiques, des statistiques et de l&#8217;informatique th\u00e9orique. La premi\u00e8re \u00e9dition de cette revue sp\u00e9cialis\u00e9e \u00e0 1940, a-t-on pr\u00e9cis\u00e9.<\/p>\n<p>Le professeur Abdelouahab Mansour, qui a \u00e9t\u00e9 s\u00e9lectionn\u00e9 par l\u2019association professionnelle am\u00e9ricaine de math\u00e9maticiens professionnels &#8220;American Mathematical Association&#8221; pour faire partie de son staff scientifique, figure parmi les c\u00e9l\u00e8bres experts math\u00e9maticiens en Alg\u00e9rie et en Afrique du Nord.<\/p>\n<p>L\u2019enseignant qui a \u00e0 son actif de nombreuses publications scientifiques en math\u00e9matiques, a travaill\u00e9 dans plusieurs centres de recherche dans des pays europ\u00e9ens.<\/p>\n<p>Pr Mansour a, dans une d\u00e9claration \u00e0 l\u2019APS, consid\u00e9r\u00e9 son adoption par la plus grande base de donn\u00e9es de math\u00e9matiques au monde, fond\u00e9e en 1888, comme &#8220;un couronnement&#8221; de ses \u0153uvres au service des math\u00e9matiques dans son pays, l&#8217;Alg\u00e9rie, et le monde.<\/p>\n<p>Le scientifique a fait toutes ses \u00e9tudes en Alg\u00e9rie, jusqu&#8217;\u00e0 l&#8217;obtention de son doctorat en 2009. Il a particip\u00e9 dans diverses missions scientifiques dans des pays europ\u00e9ens, arabes et africains, et publi\u00e9 plusieurs articles scientifiques.<\/p>\n<p>Lundi, 27 Juin 2022 APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le choix de l\u2019enseignant de math\u00e9matiques Pr Abdelouahab Mansour pour faire partie de l&#8217;\u00e9quipe d&#8217;experts charg\u00e9e du traitement du contenu de Mathematical&hellip;<\/p>\n","protected":false},"author":70,"featured_media":56100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[32,39,45,50],"tags":[],"class_list":["post-56099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-algerie","category-articles-en-vedette","category-derniers-articles","category-science-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr Abdelouahab Mansour admis en tant que r\u00e9viseur dans la revue mondiale &quot;Mathematical reviews&quot; - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr Abdelouahab Mansour admis en tant que r\u00e9viseur dans la revue mondiale &quot;Mathematical reviews&quot; - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Le choix de l\u2019enseignant de math\u00e9matiques Pr Abdelouahab Mansour pour faire partie de l&#8217;\u00e9quipe d&#8217;experts charg\u00e9e du traitement du contenu de Mathematical&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-29T12:22:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/06\/7f3bbec131d0fdbae6a2ff9faf92e627_M.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"345\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CHRYSALIDE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CHRYSALIDE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\\\/\"},\"author\":{\"name\":\"CHRYSALIDE\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\"},\"headline\":\"Pr Abdelouahab Mansour admis en tant que r\u00e9viseur dans la revue mondiale &#8220;Mathematical reviews&#8221;\",\"datePublished\":\"2022-06-29T12:22:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\\\/\"},\"wordCount\":249,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/7f3bbec131d0fdbae6a2ff9faf92e627_M.jpg\",\"articleSection\":[\"Alg\u00e9rie Alg\u00e9rienne\",\"Articles en vedette\",\"Derniers articles\",\"Science &amp; Technologie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\\\/\",\"name\":\"Pr Abdelouahab Mansour admis en tant que r\u00e9viseur dans la revue mondiale \\\"Mathematical reviews\\\" - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/7f3bbec131d0fdbae6a2ff9faf92e627_M.jpg\",\"datePublished\":\"2022-06-29T12:22:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/7f3bbec131d0fdbae6a2ff9faf92e627_M.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/7f3bbec131d0fdbae6a2ff9faf92e627_M.jpg\",\"width\":580,\"height\":345},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr Abdelouahab Mansour admis en tant que r\u00e9viseur dans la revue mondiale \u00ab\u00a0Mathematical reviews\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\",\"name\":\"CHRYSALIDE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"caption\":\"CHRYSALIDE\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/chrysalide\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr Abdelouahab Mansour admis en tant que r\u00e9viseur dans la revue mondiale \"Mathematical reviews\" - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/","og_locale":"fr_FR","og_type":"article","og_title":"Pr Abdelouahab Mansour admis en tant que r\u00e9viseur dans la revue mondiale \"Mathematical reviews\" - AAH.JZR","og_description":"Le choix de l\u2019enseignant de math\u00e9matiques Pr Abdelouahab Mansour pour faire partie de l&#8217;\u00e9quipe d&#8217;experts charg\u00e9e du traitement du contenu de Mathematical&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2022-06-29T12:22:34+00:00","og_image":[{"width":580,"height":345,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/06\/7f3bbec131d0fdbae6a2ff9faf92e627_M.jpg","type":"image\/jpeg"}],"author":"CHRYSALIDE","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"CHRYSALIDE","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/"},"author":{"name":"CHRYSALIDE","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be"},"headline":"Pr Abdelouahab Mansour admis en tant que r\u00e9viseur dans la revue mondiale &#8220;Mathematical reviews&#8221;","datePublished":"2022-06-29T12:22:34+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/"},"wordCount":249,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/06\/7f3bbec131d0fdbae6a2ff9faf92e627_M.jpg","articleSection":["Alg\u00e9rie Alg\u00e9rienne","Articles en vedette","Derniers articles","Science &amp; Technologie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/","url":"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/","name":"Pr Abdelouahab Mansour admis en tant que r\u00e9viseur dans la revue mondiale \"Mathematical reviews\" - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/06\/7f3bbec131d0fdbae6a2ff9faf92e627_M.jpg","datePublished":"2022-06-29T12:22:34+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/06\/7f3bbec131d0fdbae6a2ff9faf92e627_M.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/06\/7f3bbec131d0fdbae6a2ff9faf92e627_M.jpg","width":580,"height":345},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/pr-abdelouahab-mansour-admis-en-tant-que-reviseur-dans-la-revue-mondiale-mathematical-reviews\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Pr Abdelouahab Mansour admis en tant que r\u00e9viseur dans la revue mondiale \u00ab\u00a0Mathematical reviews\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be","name":"CHRYSALIDE","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","caption":"CHRYSALIDE"},"url":"https:\/\/jazairhope.org\/fr\/author\/chrysalide\/"}]}},"views":327,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/56099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=56099"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/56099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/56100"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=56099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=56099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=56099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}