{"id":57793,"date":"2022-07-21T14:48:42","date_gmt":"2022-07-21T13:48:42","guid":{"rendered":"https:\/\/jazairhope.org\/?p=57793"},"modified":"2022-07-21T14:48:42","modified_gmt":"2022-07-21T13:48:42","slug":"championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/","title":{"rendered":"Championnat arabe de natation &#8220;Oran-2022&#8221; l\u2019Alg\u00e9rie d\u00e9croche trois m\u00e9dailles d\u2019or lors de la 1re journ\u00e9e"},"content":{"rendered":"<p>Les nageurs alg\u00e9riens ont d\u00e9croch\u00e9 trois m\u00e9dailles d\u2019or lors de la premi\u00e8re journ\u00e9e de la cinqui\u00e8me \u00e9dition du championnat arabe de natation ouverte mercredi \u00e0 Oran et qui a vu une l\u00e9g\u00e8re domination des sportifs de la s\u00e9lection \u00e9gyptienne.<br \/>\nLes trois m\u00e9dailles en vermeil remport\u00e9es par l\u2019Alg\u00e9rie \u00e0 l\u2019occasion de cette journ\u00e9e inaugurale de l\u2019\u00e9preuve arabe que le pays organise pour la premi\u00e8re fois sont l\u2019\u0153uvre de Rania Nefsi (200 m 4 nages) Jawad Syoud (200 m 4 nages), et l\u2019\u00e9quipe ayant particip\u00e9 \u00e0 la course des 4X100m nage libre.<\/p>\n<p>Outre ces trois m\u00e9dailles, les Verts ont d\u00e9croch\u00e9 au cours de cette premi\u00e8re journ\u00e9e trois autres m\u00e9dailles en argent ainsi que six en bronze, alors que les Egyptiens ont termin\u00e9 cette journ\u00e9e en t\u00eate du tableau des m\u00e9dailles avec quatre en or.<\/p>\n<p>La c\u00e9r\u00e9monie d\u2019ouverture de cette cinqui\u00e8me \u00e9dition du championnat arabe de natation, qu\u2019abrite le Centre nautique du nouveau complexe sportif Miloud-Hadefi, a \u00e9t\u00e9 pr\u00e9sid\u00e9e par le ministre de la Jeunesse et des Sports Abderrezak Sebgag qui a d\u00e9clar\u00e9 \u00e0 la presse que cette \u00e9preuve est une occasion pour les nageurs alg\u00e9riens et arabes de se frotter au niveau sup\u00e9rieur dans une ambiance conviviale.<\/p>\n<p>&#8220;J&#8217;esp\u00e8re que cette comp\u00e9tition sera une aubaine pour les sportifs alg\u00e9riens et nos h\u00f4tes des pays arabes pour gagner en exp\u00e9rience et poursuivre leur progression. Il s\u2019agit aussi pour Oran d\u2019une nouvelle \u00e9preuve internationale qui sera le pr\u00e9lude pour cette ville afin d\u2019accueillir d\u2019autres comp\u00e9titions de haut niveau \u00e0 l\u2019avenir&#8221;, a-t-il dit.<\/p>\n<p>Pour sa part, le pr\u00e9sident de la l\u2019Union arabe de natation, l&#8217;Omanais Taha El Kouchari a affich\u00e9 son admiration pour l\u2019ambiance r\u00e9gnant dans les tribunes du Centre nautique gr\u00e2ce \u00e0 la pr\u00e9sence des spectateurs en grand nombre, ajoutant que la forte participation des pays arabes donne un cachet sp\u00e9cial \u00e0 cette comp\u00e9tition.<\/p>\n<p>Outre l\u2019Alg\u00e9rie et l\u2019Egypte, la Tunisie a r\u00e9ussi \u00e9galement \u00e0 monter sur la plus haute marche du podium \u00e0 deux reprises, alors que le Kowe\u00eft et la Jordanie ont termin\u00e9 cette journ\u00e9e inaugurale avec une seule m\u00e9daille d\u2019or pour chacun des deux pays.<\/p>\n<p>Le nageur alg\u00e9rien, Jaouad Syoud, champion m\u00e9diterran\u00e9en, a \u00e9t\u00e9 encore au rendez-vous en remportant deux m\u00e9dailles d\u2019or (200 m 4 nages et 4X100 m libre mixtes). Il a d\u00e9clar\u00e9 \u00e0 l\u2019issue des courses que les prouesses qu\u2019il a r\u00e9alis\u00e9es \u00e0 l\u2019occasion de la premi\u00e8re journ\u00e9e sont &#8220;de bon augure&#8221; pour la suite, promettant d\u2019autres m\u00e9dailles lors des prochaines courses auxquelles il prendra part pendant ce championnat.<\/p>\n<p>Quant \u00e0 l\u2019Egyptien, Echamaa Yacine, deuxi\u00e8me aux 200 m 4 nages derri\u00e8re Syoud, il a mis en exergue la pr\u00e9sence massive des spectateurs, indiquant qu\u2019il n\u2019\u00e9tait pas habitu\u00e9 \u00e0 une telle ambiance dans les piscines arabes o\u00f9 la natation est un sport peu populaire.<\/p>\n<p>Il a, en outre, affich\u00e9 sa satisfaction pour avoir termin\u00e9 \u00e0 la deuxi\u00e8me place &#8220;derri\u00e8re un nageur de renom comme Syoud&#8221;, estimant que le niveau des premi\u00e8res courses &#8220;est tr\u00e8s honorable&#8221;.<\/p>\n<p>Plus de 200 nageurs et nageuses repr\u00e9sentant 11 pays prennent part \u00e0 cette cinqui\u00e8me \u00e9dition du championnat arabe qui se poursuivra jusqu\u2019au 24 de ce mois, date de la course en eau libre sur une distance de 5 km au niveau de la plage \u2018\u2019New Beach\u2019\u2019 \u00e0 A\u00efn El-Turck.<\/p>\n<p>Les podiums de la premi\u00e8re journ\u00e9e de la cinqui\u00e8me \u00e9dition du championnat arabe de natation qui se d\u00e9roule \u00e0 Oran du 20 au 24 juillet en cours.<\/p>\n<p>&#8211; 50m dos (dames) :<\/p>\n<p>1-Samiha Mohecen (Egypte)\u00a0\u00a0\u00a0 29.23 (record arabe)<\/p>\n<p>2-Sara Hemida (Egypte)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 29.95<\/p>\n<p>3-Meroua Merniz (Alg\u00e9rie)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 30.46<\/p>\n<p>&#8211; 50m dos (hommes)<\/p>\n<p>1-Ali Azamil (Kowe\u00eft)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 25.72<\/p>\n<p>2-Abdellah Ardjoune (Alg\u00e9rie) 25.99<\/p>\n<p>3-Mehdi Nazim Benbara (Alg\u00e9rie)\u00a0 26.65<\/p>\n<p>&#8211; 200m 4 nages (dames)<\/p>\n<p>1-Hamida Rania Nefsi (Alg\u00e9rie)\u00a0\u00a0\u00a0 2 :21.52<\/p>\n<p>2-Rawan Eldamaty (Egyote)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2 :23.18<\/p>\n<p>3-Jihane Benchadli (Alg\u00e9rie)\u00a0\u00a0\u00a0\u00a0\u00a0 2 :24.24<\/p>\n<p>&#8211; 200m 4nages (hommes)<\/p>\n<p>1-Jaouad Syoud (Alg\u00e9rie)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1 :58.93<\/p>\n<p>2-Yacine ElShamaa (Egypte)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2 :02.85<\/p>\n<p>3-Ramzi Chouchar (Alg\u00e9rie)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2 :05.41<\/p>\n<p>&#8211; 100m papillon (dames)<\/p>\n<p>1-Osmane Farida (Egypte)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1 :00.72<\/p>\n<p>2-Medjahed Nesrine (Alg\u00e9rie)\u00a0 1 :03.18<\/p>\n<p>3-Rawan Eldamati (Egypte)\u00a0\u00a0\u00a0\u00a0 1 :03.90<\/p>\n<p>&#8211; 100m papillon (hommes)<\/p>\n<p>1-Youcef Ramadane (Egypte)\u00a0\u00a0 52.15 (record arabe)<\/p>\n<p>2-Walaa Abdulrazak (Kowe\u00eft)\u00a0\u00a0\u00a0 54.29<\/p>\n<p>3-Abdellah Youcef (Egypte)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 55.02<\/p>\n<p>&#8211; 100m brasse dames<\/p>\n<p>1-Hamida Rania Nefsi (Alg\u00e9rie)\u00a0\u00a0 1 :<\/p>\n<p>12.47<\/p>\n<p>2-Hedi Hamouda (Egypte)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1 :13.10<\/p>\n<p>3-Julie Salah (Egypte)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1 :14.31<\/p>\n<p>&#8211; 800m libre (dames)<\/p>\n<p>1-Maram Souissi (Tunisie)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 9 :21.36<\/p>\n<p>2-Samara Abdellaoui (Alg\u00e9rie) 9 :21.43<\/p>\n<p>3-Rabie Leyla (Egypte)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 9 :41.23<\/p>\n<p>&#8211; 800m libre (hommes)<\/p>\n<p>1-Marwan El Kemash (Egypte)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 8 :11.00<\/p>\n<p>2-Mohamed Khalil Ben Ajmia (Tunisie)\u00a0\u00a0 8 :15.55<\/p>\n<p>3-Lounis Khendriche (Alg\u00e9rie)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 8 :20.60<\/p>\n<p>&#8211; 100m brasse (hommes)<\/p>\n<p>1-Amro Al-wir (Jordanie)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1 :02.64<\/p>\n<p>2-Adnane Bedji (Tunisie)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a01 :03.03<\/p>\n<p>3-A\u00efmen Moncef Balamane (Alg\u00e9rie)\u00a0\u00a0\u00a0 1 :03.24<\/p>\n<p>&#8211; 4x100m libre mixte<\/p>\n<p>1-Alg\u00e9rie\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3 :37.80<\/p>\n<p>2-Egypte\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3 :39.80<\/p>\n<p>3-Jordanie\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a03 :50.02.<\/p>\n<p>lesoirdalgerie.com 21\/07\/2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les nageurs alg\u00e9riens ont d\u00e9croch\u00e9 trois m\u00e9dailles d\u2019or lors de la premi\u00e8re journ\u00e9e de la cinqui\u00e8me \u00e9dition du championnat arabe de natation&hellip;<\/p>\n","protected":false},"author":70,"featured_media":57794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[32,39,45,52],"tags":[],"class_list":["post-57793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-algerie","category-articles-en-vedette","category-derniers-articles","category-sport-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Championnat arabe de natation &quot;Oran-2022&quot; l\u2019Alg\u00e9rie d\u00e9croche trois m\u00e9dailles d\u2019or lors de la 1re journ\u00e9e - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Championnat arabe de natation &quot;Oran-2022&quot; l\u2019Alg\u00e9rie d\u00e9croche trois m\u00e9dailles d\u2019or lors de la 1re journ\u00e9e - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Les nageurs alg\u00e9riens ont d\u00e9croch\u00e9 trois m\u00e9dailles d\u2019or lors de la premi\u00e8re journ\u00e9e de la cinqui\u00e8me \u00e9dition du championnat arabe de natation&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-21T13:48:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/07\/d_85d26d6671b925cb4cfe114e181cc740.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CHRYSALIDE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CHRYSALIDE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\\\/\"},\"author\":{\"name\":\"CHRYSALIDE\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\"},\"headline\":\"Championnat arabe de natation &#8220;Oran-2022&#8221; l\u2019Alg\u00e9rie d\u00e9croche trois m\u00e9dailles d\u2019or lors de la 1re journ\u00e9e\",\"datePublished\":\"2022-07-21T13:48:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\\\/\"},\"wordCount\":818,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/d_85d26d6671b925cb4cfe114e181cc740.jpg\",\"articleSection\":[\"Alg\u00e9rie Alg\u00e9rienne\",\"Articles en vedette\",\"Derniers articles\",\"Sport &amp; Soci\u00e9t\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\\\/\",\"name\":\"Championnat arabe de natation \\\"Oran-2022\\\" l\u2019Alg\u00e9rie d\u00e9croche trois m\u00e9dailles d\u2019or lors de la 1re journ\u00e9e - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/d_85d26d6671b925cb4cfe114e181cc740.jpg\",\"datePublished\":\"2022-07-21T13:48:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/d_85d26d6671b925cb4cfe114e181cc740.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/d_85d26d6671b925cb4cfe114e181cc740.jpg\",\"width\":850,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Championnat arabe de natation \u00ab\u00a0Oran-2022\u00a0\u00bb l\u2019Alg\u00e9rie d\u00e9croche trois m\u00e9dailles d\u2019or lors de la 1re journ\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\",\"name\":\"CHRYSALIDE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"caption\":\"CHRYSALIDE\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/chrysalide\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Championnat arabe de natation \"Oran-2022\" l\u2019Alg\u00e9rie d\u00e9croche trois m\u00e9dailles d\u2019or lors de la 1re journ\u00e9e - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/","og_locale":"fr_FR","og_type":"article","og_title":"Championnat arabe de natation \"Oran-2022\" l\u2019Alg\u00e9rie d\u00e9croche trois m\u00e9dailles d\u2019or lors de la 1re journ\u00e9e - AAH.JZR","og_description":"Les nageurs alg\u00e9riens ont d\u00e9croch\u00e9 trois m\u00e9dailles d\u2019or lors de la premi\u00e8re journ\u00e9e de la cinqui\u00e8me \u00e9dition du championnat arabe de natation&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2022-07-21T13:48:42+00:00","og_image":[{"width":850,"height":480,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/07\/d_85d26d6671b925cb4cfe114e181cc740.jpg","type":"image\/jpeg"}],"author":"CHRYSALIDE","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"CHRYSALIDE","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/"},"author":{"name":"CHRYSALIDE","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be"},"headline":"Championnat arabe de natation &#8220;Oran-2022&#8221; l\u2019Alg\u00e9rie d\u00e9croche trois m\u00e9dailles d\u2019or lors de la 1re journ\u00e9e","datePublished":"2022-07-21T13:48:42+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/"},"wordCount":818,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/07\/d_85d26d6671b925cb4cfe114e181cc740.jpg","articleSection":["Alg\u00e9rie Alg\u00e9rienne","Articles en vedette","Derniers articles","Sport &amp; Soci\u00e9t\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/","url":"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/","name":"Championnat arabe de natation \"Oran-2022\" l\u2019Alg\u00e9rie d\u00e9croche trois m\u00e9dailles d\u2019or lors de la 1re journ\u00e9e - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/07\/d_85d26d6671b925cb4cfe114e181cc740.jpg","datePublished":"2022-07-21T13:48:42+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/07\/d_85d26d6671b925cb4cfe114e181cc740.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/07\/d_85d26d6671b925cb4cfe114e181cc740.jpg","width":850,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/championnat-arabe-de-natation-oran-2022-lalgerie-decroche-trois-medailles-dor-lors-de-la-1re-journee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Championnat arabe de natation \u00ab\u00a0Oran-2022\u00a0\u00bb l\u2019Alg\u00e9rie d\u00e9croche trois m\u00e9dailles d\u2019or lors de la 1re journ\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be","name":"CHRYSALIDE","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","caption":"CHRYSALIDE"},"url":"https:\/\/jazairhope.org\/fr\/author\/chrysalide\/"}]}},"views":282,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/57793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=57793"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/57793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/57794"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=57793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=57793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=57793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}