{"id":57902,"date":"2022-07-23T16:41:29","date_gmt":"2022-07-23T15:41:29","guid":{"rendered":"https:\/\/jazairhope.org\/?p=57902"},"modified":"2022-07-23T16:41:29","modified_gmt":"2022-07-23T15:41:29","slug":"presence-remarquable-de-la-culture-algerienne-a-travers-le-monde","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/","title":{"rendered":"Pr\u00e9sence remarquable de la culture alg\u00e9rienne \u00e0 travers le monde"},"content":{"rendered":"<div class=\"itemIntroText col-xs-hidden  selectionShareable\">\n<p><strong>ALGER- La culture alg\u00e9rienne a connu, en 60 ans d&#8217;ind\u00e9pendance, un rayonnement remarquable \u00e0 travers le monde en se distinguant dans les rencontres et forums\u00a0 internationaux dans divers domaines dont le cin\u00e9ma, la musique, la litt\u00e9rature, les arts plastiques, le th\u00e9\u00e2tre et le patrimoine.<\/strong><\/p>\n<\/div>\n<div class=\"itemFullText selectionShareable\">\n<p>&nbsp;<\/p>\n<p>Dans le domaine cin\u00e9matographique, l&#8217;Alg\u00e9rie s&#8217;est mondialement illustr\u00e9e par une gamme de films sociaux, des films de guerre et des com\u00e9dies, sign\u00e9s par des metteurs en sc\u00e8ne de grand talent de la trempe d&#8217;Ahmed Rachedi, Mohamed Zinet, Merzak Allouache et de jeunes cin\u00e9astes talentueux.<\/p>\n<p>Certains films ont \u00e9t\u00e9 prim\u00e9s dans de nombreux festivals internationaux, dont &#8220;Chronique des ann\u00e9es de braise&#8221; de Mohamed Lakhdar-Hamina qui a d\u00e9croch\u00e9 la Palme d&#8217;or au Festival de Cannes en 1975, &#8220;Z&#8221; de Costa-Gavras qui a remport\u00e9 l&#8217;Oscar du meilleur film \u00e9tranger en 1969 et &#8220;La bataille d&#8217;Alger&#8221; de Gillo Pontecorvo a remport\u00e9 le Lion d&#8217;or \u00e0 la Mostra de Venise en 1966.<\/p>\n<p>Dans le domaine de la litt\u00e9rature et de la pens\u00e9e intellectuelle, de nombreux auteurs et penseurs de prestige se sont illustr\u00e9s, \u00e0 l&#8217;instar de Mohamed Dib, Kateb Yacine, Ahlam Mosteghanemi, Tahar Ouettar, Malek Bennabi et Assia Djebar.<\/p>\n<p>De nombreux salons du livre ont \u00e9t\u00e9 organis\u00e9s, dont le Salon international du livre d&#8217;Alger (SILA) qui reste l&#8217;\u00e9v\u00e9nement culturel le plus important en Alg\u00e9rie et l&#8217;un des plus grands salons au monde.<\/p>\n<p>Dans le domaine de la musique, plusieurs genres sont apparus. Le Rai, en t\u00eate, s&#8217;est modernis\u00e9 puis internationalis\u00e9 dans les ann\u00e9es 1990.<\/p>\n<p>D&#8217;autres genres musicaux se sont distingu\u00e9s marquant la diversit\u00e9 et la grande richesse de la culture alg\u00e9rienne, comme le cha\u00e2bi, le Diwan, l&#8217;andalou, les chansons chaouie, Kabyle, b\u00e9douine et targuie qui connait actuellement un franc succ\u00e8s international.<\/p>\n<p>Dans les Arts plastiques, l&#8217;Alg\u00e9rie a enfant\u00e9 des artistes prestigieux de la trempe de Mohamed Racim, l&#8217;un des pionniers de l&#8217;art de la miniature, et Baya Mehieddine, pionni\u00e8re de l&#8217;art na\u00eff, Bachir Yeles, Mohamed Khedda, Choukri Mesli, M&#8217;hamed Issiakhem, Abdelkader Guermaz et Rachid Koraichi.<\/p>\n<p>Dans le 4e art, le Th\u00e9\u00e2tre national alg\u00e9rien (TNA) verra le jour en 1963 et sera baptis\u00e9 du nom de Mahieddine Bachtarzi, un des pionniers de l&#8217;art et de la culture en Alg\u00e9rie. Des hommes de th\u00e9\u00e2tre d&#8217;exception notamment Ould Abderrahmane Kaki connu pour son \u0153uvre &#8220;El Guerrab oua Salihine&#8221; et Abdelkader Alloula auteur de la c\u00e9l\u00e8bre trilogie &#8220;Lgoual&#8221;, &#8220;Lejouad&#8221; et &#8220;Lithem&#8221; et bien d&#8217;autres grands noms.<\/p>\n<p>Plusieurs festivals ont \u00e9t\u00e9 institu\u00e9s, dont le festival national du th\u00e9\u00e2tre amateur (FNTA) de Mostaganem (1967), l&#8217;un des plus anciens festivals du th\u00e9\u00e2tre amateur dans le monde.<\/p>\n<p>Dans la bande dessin\u00e9e (BD), plusieurs noms de cr\u00e9ateurs ont \u00e9merg\u00e9 d\u00e8s les premi\u00e8res ann\u00e9es de l&#8217;ind\u00e9pendance, \u00e0 l&#8217;instar de Mohamed Mazari (Maz) et Menouar Merabtine (Slim). Le Festival international de la bande dessin\u00e9e d&#8217;Alger (FIBDA) est l&#8217;une des plus importantes manifestations d\u00e9di\u00e9es \u00e0 la bande dessin\u00e9e en Afrique et dans le monde arabe.<\/p>\n<p>L&#8217;Alg\u00e9rie a organis\u00e9 de grandes manifestations marquant son appartenance civilisationnelle et sa position de leader, la plus importante \u00e9tant le Festival culturel africain qui s&#8217;est tenu uniquement en Alg\u00e9rie \u00e0 deux reprises, en 1969 et en 2009, en pr\u00e9sence d&#8217;artistes et d&#8217;intellectuels de diff\u00e9rents pays africains et des communaut\u00e9s africaines \u00e0 travers le monde.<\/p>\n<p>Figurent \u00e9galement parmi ces manifestations &#8220;Alg\u00e9rie, Capitale de la Culture Arabe&#8221; en 2007, &#8220;Constantine, Capitale de la Culture Arabe&#8221; en 2015, ainsi que &#8220;Tlemcen, Capitale de la Culture Islamique&#8221; en 2011, \u00e0 laquelle ont particip\u00e9 plusieurs pays membres de l&#8217;Organisation islamique\u00a0 pour l&#8217;\u00e9ducation, les sciences et la culture (ISESCO) et hors ISESCO.<\/p>\n<p>De nombreux autres festivals ont \u00e9t\u00e9 organis\u00e9s pour la promotion de la dimension amazighe de la culture alg\u00e9rienne, comme le Festival du th\u00e9\u00e2tre amazigh \u00e0 Batna, le Festival de la chanson amazighe \u00e0 Tamanrasset. Tamazight a \u00e9t\u00e9 constitutionnalis\u00e9e en tant que langue officielle en 2016, parall\u00e8lement \u00e0 la constitutionnalisation du droit \u00e0 la culture.<\/p>\n<p><strong>Patrimoine mondial de l&#8217;humanit\u00e9<\/strong><\/p>\n<p>L&#8217;Alg\u00e9rie compte huit (8) \u00e9l\u00e9ments du patrimoine immat\u00e9riel inscrits au patrimoine mondial de l&#8217;humanit\u00e9 par l&#8217;Unesco, qui sont L&#8217;Ahellil de Gourara (2008), le costume nuptial de Tlemcen (Chedda de Tlemcen\/2012), S&#8217;boue du Mawlid Ennabawi \u00e0 Timimoun\u00a0 et l&#8217;Imzad (inscrit patrimoine commun \u00e0 l&#8217;Alg\u00e9rie, Mali et Niger en 2013).<\/p>\n<p>La liste comprend \u00e9galement Rakb Ouled Sidi Cheikh (le p\u00e8lerinage annuel au mausol\u00e9e de Sidi Cheikh) \u00e0 El-Bayadh, et la c\u00e9r\u00e9monie de la Sebe\u00efba \u00e0 Djanet (2014), ainsi que les rites et traditions li\u00e9es \u00e0 la production et \u00e0 la consommation du couscous class\u00e9 patrimoine commun aux peuples du Maghreb (2020), et la calligraphie arabe class\u00e9e patrimoine commun au monde arabo-musulman (2021).,<\/p>\n<p>Concernant le patrimoine mat\u00e9riel, l&#8217;Alg\u00e9rie a introduit sept (7) \u00e9l\u00e9ments dans la liste du Patrimoine mondial de l&#8217;humanit\u00e9 de l&#8217;Unesco \u00e0 savoir &#8220;Kal\u00e2a des B\u00e9ni Hammad&#8221; \u00e0 M&#8217;sila en 1980, les sites arch\u00e9ologiques antiques de &#8220;Djemila&#8221; \u00e0 S\u00e9tif, &#8220;Timgad&#8221; \u00e0 Batna et &#8220;Tipasa&#8221;, en 1982.<\/p>\n<p>Ont \u00e9galement \u00e9t\u00e9 class\u00e9s patrimoine mondial, \u00e0 la m\u00eame ann\u00e9e, le mus\u00e9e \u00e0 ciel ouvert &#8220;Tassili N&#8217;Ajjer&#8221; et la &#8220;Vall\u00e9e du M&#8217;Zab&#8221; \u00e0 Gharda\u00efa, suivis de la &#8220;Casbah d&#8217;Alger&#8221; en 1992.<\/p>\n<p>L&#8217;Alg\u00e9rie dispose aussi de cinq parcs culturels nationaux \u00e0 savoir &#8220;Tassili N&#8217;Ajjer&#8221;, &#8220;L&#8217;Ahaggar&#8221;, &#8220;Touat-Gourara-Tidikelt&#8221;, &#8220;l&#8217;Atlas saharien&#8221; et &#8220;le Parc culturel de Tindouf&#8221;, ainsi qu&#8217;une vingtaine de secteurs prot\u00e9g\u00e9s d&#8217;une grande valeur patrimoniale.<\/p>\n<p>Elle s&#8217;emploie, actuellement, en coordination avec l&#8217;Union africaine (UA) \u00e0 la r\u00e9alisation du projet du Grand Mus\u00e9e de l&#8217;Afrique.<\/p>\n<p>Cr\u00e9\u00e9 et plac\u00e9 sous l&#8217;\u00e9gide de l&#8217;Unesco, le Centre r\u00e9gional pour la sauvegarde du patrimoine culturel immat\u00e9riel en Afrique (Crespiaf) se veut un espace de rencontre des anthropologues africains sp\u00e9cialistes du patrimoine immat\u00e9riel de l&#8217;Afrique.<\/p>\n<p><strong>L&#8217;Alg\u00e9rie, un des berceaux de l&#8217;humanit\u00e9<\/strong><\/p>\n<p>En novembre 2018, des arch\u00e9ologues alg\u00e9riens et \u00e9trangers ont d\u00e9couvert des traces de pr\u00e9sence humaine datant d&#8217;environ 2,4 millions d&#8217;ann\u00e9es sur le site de &#8220;Ain Boucherit&#8221; dans la r\u00e9gion d&#8217;Ain Lahnech \u00e0 S\u00e9tif (Nord-Est du pays).<\/p>\n<p>Une \u00e9quipe de chercheurs alg\u00e9riens, espagnols, australiens et fran\u00e7ais a annonc\u00e9 la d\u00e9couverte d&#8217;outils lithiques en pierre taill\u00e9e et d&#8217;ossements fossiles d&#8217;animaux prouvant que ce site est le deuxi\u00e8me plus ancien au monde apr\u00e8s celui de Kouna en Ethiopie qui remonte \u00e0 2,6 millions d&#8217;ann\u00e9es et consid\u00e9r\u00e9 comme le berceau de l&#8217;humanit\u00e9.<\/p>\n<p>Cette importante d\u00e9couverte arch\u00e9ologique dont les fouilles ont \u00e9t\u00e9 lanc\u00e9es dans les ann\u00e9es 90 et qui a \u00e9t\u00e9 publi\u00e9e dans la prestigieuse revue scientifique am\u00e9ricaine &#8220;Science&#8221;, vient confirmer l&#8217;hypoth\u00e8se de l&#8217;existence d&#8217;origines multiples du d\u00e9part de la civilisation humaine \u00e0 la fois en Afrique de l&#8217;Est et du Nord.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ALGER- La culture alg\u00e9rienne a connu, en 60 ans d&#8217;ind\u00e9pendance, un rayonnement remarquable \u00e0 travers le monde en se distinguant dans les&hellip;<\/p>\n","protected":false},"author":70,"featured_media":57903,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[32,34,42],"tags":[],"class_list":["post-57902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-algerie","category-art-fr","category-histoire-et-patrimoine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr\u00e9sence remarquable de la culture alg\u00e9rienne \u00e0 travers le monde - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00e9sence remarquable de la culture alg\u00e9rienne \u00e0 travers le monde - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"ALGER- La culture alg\u00e9rienne a connu, en 60 ans d&#8217;ind\u00e9pendance, un rayonnement remarquable \u00e0 travers le monde en se distinguant dans les&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-23T15:41:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/07\/up-42.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"387\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CHRYSALIDE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CHRYSALIDE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\\\/\"},\"author\":{\"name\":\"CHRYSALIDE\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\"},\"headline\":\"Pr\u00e9sence remarquable de la culture alg\u00e9rienne \u00e0 travers le monde\",\"datePublished\":\"2022-07-23T15:41:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\\\/\"},\"wordCount\":1199,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/up-42.jpg\",\"articleSection\":[\"Alg\u00e9rie Alg\u00e9rienne\",\"Art &amp; Culture\",\"Histoire et Patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\\\/\",\"name\":\"Pr\u00e9sence remarquable de la culture alg\u00e9rienne \u00e0 travers le monde - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/up-42.jpg\",\"datePublished\":\"2022-07-23T15:41:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/up-42.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/up-42.jpg\",\"width\":580,\"height\":387},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr\u00e9sence remarquable de la culture alg\u00e9rienne \u00e0 travers le monde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\",\"name\":\"CHRYSALIDE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"caption\":\"CHRYSALIDE\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/chrysalide\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00e9sence remarquable de la culture alg\u00e9rienne \u00e0 travers le monde - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/","og_locale":"fr_FR","og_type":"article","og_title":"Pr\u00e9sence remarquable de la culture alg\u00e9rienne \u00e0 travers le monde - AAH.JZR","og_description":"ALGER- La culture alg\u00e9rienne a connu, en 60 ans d&#8217;ind\u00e9pendance, un rayonnement remarquable \u00e0 travers le monde en se distinguant dans les&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2022-07-23T15:41:29+00:00","og_image":[{"width":580,"height":387,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/07\/up-42.jpg","type":"image\/jpeg"}],"author":"CHRYSALIDE","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"CHRYSALIDE","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/"},"author":{"name":"CHRYSALIDE","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be"},"headline":"Pr\u00e9sence remarquable de la culture alg\u00e9rienne \u00e0 travers le monde","datePublished":"2022-07-23T15:41:29+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/"},"wordCount":1199,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/07\/up-42.jpg","articleSection":["Alg\u00e9rie Alg\u00e9rienne","Art &amp; Culture","Histoire et Patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/","url":"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/","name":"Pr\u00e9sence remarquable de la culture alg\u00e9rienne \u00e0 travers le monde - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/07\/up-42.jpg","datePublished":"2022-07-23T15:41:29+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/07\/up-42.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/07\/up-42.jpg","width":580,"height":387},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/presence-remarquable-de-la-culture-algerienne-a-travers-le-monde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Pr\u00e9sence remarquable de la culture alg\u00e9rienne \u00e0 travers le monde"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be","name":"CHRYSALIDE","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","caption":"CHRYSALIDE"},"url":"https:\/\/jazairhope.org\/fr\/author\/chrysalide\/"}]}},"views":393,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/57902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=57902"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/57902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/57903"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=57902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=57902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=57902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}