{"id":59845,"date":"2022-08-16T01:30:21","date_gmt":"2022-08-16T00:30:21","guid":{"rendered":"https:\/\/jazairhope.org\/?p=59845"},"modified":"2022-08-15T20:20:56","modified_gmt":"2022-08-15T19:20:56","slug":"festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/","title":{"rendered":"Festival de musique et chant Chaouis de Khenchela: la 10\u00e8 \u00e9dition en ao\u00fbt"},"content":{"rendered":"<p><strong>KHENCHELA &#8211; La 10\u00e8me \u00e9dition du festival local culturel de musique et chanson Chaouis est pr\u00e9vue dans la p\u00e9riode du 20 au 23 ao\u00fbt prochain, a-t-on appris dimanche du commissariat de cette manifestation artistique.<\/strong><!--more--><\/p>\n<p>Apr\u00e8s 4 ans d\u2019interruption, les pr\u00e9paratifs de la c\u00e9r\u00e9monie d\u2019ouverture de ce festival pr\u00e9vue \u00e0 la maison de la culture Ali Soua\u00ef du chef-lieu de wilaya sont en cours pour assurer la r\u00e9ussite \u00e0 cette \u00e9dition, a indiqu\u00e9 \u00e0 l\u2019APS le commissaire du festival, Abdelouahab Zaim.<\/p>\n<p>La 10\u00e8me \u00e9dition de ce festival sera marqu\u00e9e par la participation de 30 artistes, dont la majorit\u00e9 des jeunes repr\u00e9sentant les wilayas de Khenchela, T\u00e9bessa, Batna, Oum El Bouaghi et de Biskra qui animeront les soir\u00e9es de cet \u00e9v\u00e9nement culturel \u00e0 la place Chahid Abbas Laghrour en plein centre ville du chef-lieu de wilaya, a pr\u00e9cis\u00e9, M Zaim.<\/p>\n<p>En marge de cette \u00e9dition, des ateliers de formation ont \u00e9t\u00e9 programm\u00e9s au profit des jeunes chanteurs qui seront encadr\u00e9s par des sp\u00e9cialistes de la chanson et musique Chaouis en sus de la tenue d\u2019une conf\u00e9rence intitul\u00e9e &#8220;le r\u00f4le de la chanson r\u00e9volutionnaire dans l\u2019enrichissement du chant chaoui&#8221; et ce dans le cadre de la comm\u00e9moration de la journ\u00e9e nationale du moudjahid (20 aout de chaque ann\u00e9e), a ajout\u00e9 le commissaire du festival.<\/p>\n<p>Un jur\u00e9 compos\u00e9 de quatre (4) membres suivra de pr\u00e8s les soir\u00e9es de cette \u00e9dition, au cours de laquelle des symboles de la chanson chaoui seront honor\u00e9s, a indiqu\u00e9 le commissaire du festival sans citer des noms.<\/p>\n<p>Le chanteur vainqueur de la premi\u00e8re place de la 10\u00e8me \u00e9dition du festival local culturel de musique et chanson chaouis sera qualifi\u00e9 \u00e0 participer au festival culturel national de chant et musique amazighs pr\u00e9vus en novembre prochain \u00e0 Tamanrasset, a-t-on appris de m\u00eame source.<br \/>\nAPS -Dimanche 14 ao\u00fbt 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p>KHENCHELA &#8211; La 10\u00e8me \u00e9dition du festival local culturel de musique et chanson Chaouis est pr\u00e9vue dans la p\u00e9riode du 20 au&hellip;<\/p>\n","protected":false},"author":1,"featured_media":59847,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[32,34],"tags":[],"class_list":["post-59845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-algerie","category-art-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festival de musique et chant Chaouis de Khenchela: la 10\u00e8 \u00e9dition en ao\u00fbt - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festival de musique et chant Chaouis de Khenchela: la 10\u00e8 \u00e9dition en ao\u00fbt - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"KHENCHELA &#8211; La 10\u00e8me \u00e9dition du festival local culturel de musique et chanson Chaouis est pr\u00e9vue dans la p\u00e9riode du 20 au&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-16T00:30:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/08\/Musique-CHAOUIE-VkrEXqYz2S98.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ssuperadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ssuperadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\\\/\"},\"author\":{\"name\":\"Ssuperadmin\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/43650ebd889d8960700b5456ed9264c4\"},\"headline\":\"Festival de musique et chant Chaouis de Khenchela: la 10\u00e8 \u00e9dition en ao\u00fbt\",\"datePublished\":\"2022-08-16T00:30:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\\\/\"},\"wordCount\":333,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Musique-CHAOUIE-VkrEXqYz2S98.jpg\",\"articleSection\":[\"Alg\u00e9rie Alg\u00e9rienne\",\"Art &amp; Culture\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\\\/\",\"name\":\"Festival de musique et chant Chaouis de Khenchela: la 10\u00e8 \u00e9dition en ao\u00fbt - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Musique-CHAOUIE-VkrEXqYz2S98.jpg\",\"datePublished\":\"2022-08-16T00:30:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/43650ebd889d8960700b5456ed9264c4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Musique-CHAOUIE-VkrEXqYz2S98.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Musique-CHAOUIE-VkrEXqYz2S98.jpg\",\"width\":580,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festival de musique et chant Chaouis de Khenchela: la 10\u00e8 \u00e9dition en ao\u00fbt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/43650ebd889d8960700b5456ed9264c4\",\"name\":\"Ssuperadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g\",\"caption\":\"Ssuperadmin\"},\"sameAs\":[\"https:\\\/\\\/jazairhope.org\"],\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/superadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festival de musique et chant Chaouis de Khenchela: la 10\u00e8 \u00e9dition en ao\u00fbt - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/","og_locale":"fr_FR","og_type":"article","og_title":"Festival de musique et chant Chaouis de Khenchela: la 10\u00e8 \u00e9dition en ao\u00fbt - AAH.JZR","og_description":"KHENCHELA &#8211; La 10\u00e8me \u00e9dition du festival local culturel de musique et chanson Chaouis est pr\u00e9vue dans la p\u00e9riode du 20 au&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2022-08-16T00:30:21+00:00","og_image":[{"width":580,"height":350,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/08\/Musique-CHAOUIE-VkrEXqYz2S98.jpg","type":"image\/jpeg"}],"author":"Ssuperadmin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ssuperadmin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/"},"author":{"name":"Ssuperadmin","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/43650ebd889d8960700b5456ed9264c4"},"headline":"Festival de musique et chant Chaouis de Khenchela: la 10\u00e8 \u00e9dition en ao\u00fbt","datePublished":"2022-08-16T00:30:21+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/"},"wordCount":333,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/08\/Musique-CHAOUIE-VkrEXqYz2S98.jpg","articleSection":["Alg\u00e9rie Alg\u00e9rienne","Art &amp; Culture"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/","url":"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/","name":"Festival de musique et chant Chaouis de Khenchela: la 10\u00e8 \u00e9dition en ao\u00fbt - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/08\/Musique-CHAOUIE-VkrEXqYz2S98.jpg","datePublished":"2022-08-16T00:30:21+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/43650ebd889d8960700b5456ed9264c4"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/08\/Musique-CHAOUIE-VkrEXqYz2S98.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/08\/Musique-CHAOUIE-VkrEXqYz2S98.jpg","width":580,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/festival-de-musique-et-chant-chaouis-de-khenchela-la-10e-edition-en-aout\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Festival de musique et chant Chaouis de Khenchela: la 10\u00e8 \u00e9dition en ao\u00fbt"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/43650ebd889d8960700b5456ed9264c4","name":"Ssuperadmin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g","caption":"Ssuperadmin"},"sameAs":["https:\/\/jazairhope.org"],"url":"https:\/\/jazairhope.org\/fr\/author\/superadmin\/"}]}},"views":332,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/59845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=59845"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/59845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/59847"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=59845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=59845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=59845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}