{"id":60285,"date":"2022-08-18T13:15:51","date_gmt":"2022-08-18T12:15:51","guid":{"rendered":"https:\/\/jazairhope.org\/?p=60285"},"modified":"2022-08-18T13:15:51","modified_gmt":"2022-08-18T12:15:51","slug":"lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/","title":{"rendered":"L\u2019Alg\u00e9rie entame avec \u00ab succ\u00e8s \u00bb l\u2019exploitation de Gara Djebilet"},"content":{"rendered":"<p>L&#8217;Alg\u00e9rie a entam\u00e9 avec \u00ab\u00a0succ\u00e8s\u00a0\u00bb l\u2019extraction du minerai de fer du gisement g\u00e9ant de Gara Djebilet \u00e0 Tindouf dont la production pourrait atteindre les 50 millions de tonnes \u00e0 partir de 2026.<\/p>\n<div class=\"teads-adCall\"><\/div>\n<p><span data-originalfontsize=\"12pt\" data-originalcomputedfontsize=\"16\">L\u2019inauguration officielle du projet d\u2019exploitation de cette mine a \u00e9t\u00e9 faite officiellement le 30 juillet dernier par le ministre de l\u2019Energie et des mines Mohamed Arkab. Aussit\u00f4t,\u00a0le chantier a \u00e9t\u00e9 install\u00e9 et les travaux d\u2019extraction ont \u00e9t\u00e9 lanc\u00e9s avec \u00ab\u00a0succ\u00e8s\u00a0\u00bb.<\/span><\/p>\n<div class=\"article__article-ads\">\n<div id=\"div-gpt-ad-1575149819433-0\" data-google-query-id=\"CPq26ZGu0PkCFVHYswodxDoKXQ\">\n<div id=\"google_ads_iframe_\/60169273\/TSA_fr_728x90_Milieu_Article_Desktop_0__container__\"><\/div>\n<\/div>\n<\/div>\n<p><span data-originalfontsize=\"12pt\" data-originalcomputedfontsize=\"16\">Les services de la wilaya de Tindouf ont annonc\u00e9 dans un communiqu\u00e9 publi\u00e9 le mardi 16 ao\u00fbt le d\u00e9but des op\u00e9rations d\u2019extraction du fer au niveau de la mine de Gara Djebilet.<iframe src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fwilaya37tindouf%2Fposts%2Fpfbid0z3JSYaRTPPVuouirH6RvPAVJqqS7jrJfocgyvxNxKMN8mgpPjwfpGkpJrReo1rjDl&amp;show_text=true&amp;width=500\" width=\"500\" height=\"616\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/span><\/p>\n<p><span data-originalfontsize=\"12pt\" data-originalcomputedfontsize=\"16\">Selon la m\u00eame source, cette op\u00e9ration a \u00e9t\u00e9 r\u00e9alis\u00e9e \u00ab avec succ\u00e8s \u00bb et a permis l\u2019extraction de quantit\u00e9s importantes de fer.<\/span><\/p>\n<p><span data-originalfontsize=\"12pt\" data-originalcomputedfontsize=\"16\">\u00ab Ce matin, \u00e0 l\u2019aide d\u2019explosifs, il a \u00e9t\u00e9 proc\u00e9d\u00e9 avec succ\u00e8s au d\u00e9but de l\u2019op\u00e9ration d\u2019extraction de quantit\u00e9 importante de minerai de fer \u00bb, peut-on lire sur le communiqu\u00e9.<\/span><\/p>\n<p><span data-originalfontsize=\"12pt\" data-originalcomputedfontsize=\"16\">Les services de la wilaya de Tindouf ont soulign\u00e9 que la quantit\u00e9 extraite sera\u00a0 achemin\u00e9e, par voie terrestre, vers le nord du pays et qu\u2019une partie sera transf\u00e9r\u00e9e \u00e0 l\u2019\u00e9tranger pour \u00eatre \u00bb transform\u00e9e par de nos partenaires \u00e9conomiques en Chine et en Russie \u00bb, tandis qu\u2019une autre partie sera transform\u00e9e par les soci\u00e9t\u00e9s de raffinage en Alg\u00e9rie.<\/span><\/p>\n<p><span data-originalfontsize=\"12pt\" data-originalcomputedfontsize=\"16\">D\u2019apr\u00e8s la cha\u00eene publique AL24 News, 1000 tonnes de minerai de fer ont \u00e9t\u00e9 extraites du gisement de Gara Djebilet lors de cette premi\u00e8re op\u00e9ration. Selon le ministre de l\u2019Energie, entre deux \u00e0 trois millions de tonnes de minerai de fer peuvent \u00eatre extraites de cette mise durant la p\u00e9riode 2022-2025, avant que cette quantit\u00e9 augmente \u00e0 40-50 millions \u00e0 partir de 2026.\u00a0<\/span><\/p>\n<p>tsa-algerie.com 17\/08\/2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Alg\u00e9rie a entam\u00e9 avec \u00ab\u00a0succ\u00e8s\u00a0\u00bb l\u2019extraction du minerai de fer du gisement g\u00e9ant de Gara Djebilet \u00e0 Tindouf dont la production pourrait&hellip;<\/p>\n","protected":false},"author":70,"featured_media":60286,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[32,39,45,35],"tags":[],"class_list":["post-60285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-algerie","category-articles-en-vedette","category-derniers-articles","category-economie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019Alg\u00e9rie entame avec \u00ab succ\u00e8s \u00bb l\u2019exploitation de Gara Djebilet - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Alg\u00e9rie entame avec \u00ab succ\u00e8s \u00bb l\u2019exploitation de Gara Djebilet - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"L&#8217;Alg\u00e9rie a entam\u00e9 avec \u00ab\u00a0succ\u00e8s\u00a0\u00bb l\u2019extraction du minerai de fer du gisement g\u00e9ant de Gara Djebilet \u00e0 Tindouf dont la production pourrait&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-18T12:15:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/08\/telechargement-2022-08-18T081318.567.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"574\" \/>\n\t<meta property=\"og:image:height\" content=\"352\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CHRYSALIDE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CHRYSALIDE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\\\/\"},\"author\":{\"name\":\"CHRYSALIDE\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\"},\"headline\":\"L\u2019Alg\u00e9rie entame avec \u00ab succ\u00e8s \u00bb l\u2019exploitation de Gara Djebilet\",\"datePublished\":\"2022-08-18T12:15:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\\\/\"},\"wordCount\":322,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/telechargement-2022-08-18T081318.567.jpg\",\"articleSection\":[\"Alg\u00e9rie Alg\u00e9rienne\",\"Articles en vedette\",\"Derniers articles\",\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\\\/\",\"name\":\"L\u2019Alg\u00e9rie entame avec \u00ab succ\u00e8s \u00bb l\u2019exploitation de Gara Djebilet - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/telechargement-2022-08-18T081318.567.jpg\",\"datePublished\":\"2022-08-18T12:15:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/telechargement-2022-08-18T081318.567.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/telechargement-2022-08-18T081318.567.jpg\",\"width\":574,\"height\":352},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019Alg\u00e9rie entame avec \u00ab succ\u00e8s \u00bb l\u2019exploitation de Gara Djebilet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/f1c3341bc57ca2fc53f3a9ab568335be\",\"name\":\"CHRYSALIDE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g\",\"caption\":\"CHRYSALIDE\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/chrysalide\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019Alg\u00e9rie entame avec \u00ab succ\u00e8s \u00bb l\u2019exploitation de Gara Djebilet - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019Alg\u00e9rie entame avec \u00ab succ\u00e8s \u00bb l\u2019exploitation de Gara Djebilet - AAH.JZR","og_description":"L&#8217;Alg\u00e9rie a entam\u00e9 avec \u00ab\u00a0succ\u00e8s\u00a0\u00bb l\u2019extraction du minerai de fer du gisement g\u00e9ant de Gara Djebilet \u00e0 Tindouf dont la production pourrait&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2022-08-18T12:15:51+00:00","og_image":[{"width":574,"height":352,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/08\/telechargement-2022-08-18T081318.567.jpg","type":"image\/jpeg"}],"author":"CHRYSALIDE","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"CHRYSALIDE","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/"},"author":{"name":"CHRYSALIDE","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be"},"headline":"L\u2019Alg\u00e9rie entame avec \u00ab succ\u00e8s \u00bb l\u2019exploitation de Gara Djebilet","datePublished":"2022-08-18T12:15:51+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/"},"wordCount":322,"commentCount":1,"image":{"@id":"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/08\/telechargement-2022-08-18T081318.567.jpg","articleSection":["Alg\u00e9rie Alg\u00e9rienne","Articles en vedette","Derniers articles","\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/","url":"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/","name":"L\u2019Alg\u00e9rie entame avec \u00ab succ\u00e8s \u00bb l\u2019exploitation de Gara Djebilet - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/08\/telechargement-2022-08-18T081318.567.jpg","datePublished":"2022-08-18T12:15:51+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/08\/telechargement-2022-08-18T081318.567.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/08\/telechargement-2022-08-18T081318.567.jpg","width":574,"height":352},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/lalgerie-entame-avec-succes-lexploitation-de-gara-djebilet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019Alg\u00e9rie entame avec \u00ab succ\u00e8s \u00bb l\u2019exploitation de Gara Djebilet"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/f1c3341bc57ca2fc53f3a9ab568335be","name":"CHRYSALIDE","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8689a2780b185ffd50584cebbeb934253e26ca1844d28eea3f737bc38cba889f?s=96&d=mm&r=g","caption":"CHRYSALIDE"},"url":"https:\/\/jazairhope.org\/fr\/author\/chrysalide\/"}]}},"views":598,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/60285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=60285"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/60285\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/60286"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=60285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=60285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=60285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}