{"id":64540,"date":"2022-12-05T14:21:56","date_gmt":"2022-12-05T13:21:56","guid":{"rendered":"https:\/\/jazairhope.org\/?p=64540"},"modified":"2022-12-05T11:38:19","modified_gmt":"2022-12-05T10:38:19","slug":"3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/","title":{"rendered":"3e Conf\u00e9rence des ministres arabes de l&#8217;enseignement technique et professionnel du 24 au 26 d\u00e9cembre \u00e0 Alger"},"content":{"rendered":"<p>L&#8217;Alg\u00e9rie abritera du 24 au 26 d\u00e9cembre les travaux de la 3e Conf\u00e9rence des ministres et responsables de l&#8217;enseignement et de la formation techniques et professionnels dans le monde arabe consacr\u00e9e \u00e0 des th\u00e8mes comme l&#8217;adaptation de l&#8217;enseignement et de la formation techniques et professionnels au march\u00e9 du travail, l&#8217;avenir de l&#8217;\u00e9conomie verte et le num\u00e9rique.<\/p>\n<p>L&#8217;\u00e9v\u00e9nement pr\u00e9vu au Centre international de conf\u00e9rences (CIC), en pr\u00e9sence de plus de 120 participants de divers pays et instances internationales et arabes, vise &#8220;l&#8217;adoption du plan de d\u00e9veloppement global du secteur de l&#8217;enseignement et de la formation techniques et professionnels dans le monde arabe et l&#8217;enrichissement des exp\u00e9riences nationales dans ce domaine&#8221;, a-t-on appris aupr\u00e8s du minist\u00e8re de la Formation et de l&#8217;Enseignement professionnels.<\/p>\n<p>Les r\u00e9sultats de la 2e Conf\u00e9rence des ministres et responsables de l&#8217;enseignement et de la formation techniques et professionnels dans le monde arabe, tenue \u00e0 Tunis en 2021, seront pass\u00e9s en revue lors des travaux d&#8217;Alger, selon la m\u00eame source.<\/p>\n<p>Il s&#8217;agira \u00e9galement de &#8220;renforcer le syst\u00e8me juridique, p\u00e9dagogique et structurel du secteur dans le monde arabe&#8221; et de &#8220;d\u00e9velopper un cadre de r\u00e9f\u00e9rence arabe unifi\u00e9 des qualifications afin de garantir la qualit\u00e9 de la formation conform\u00e9ment aux normes et exigences du march\u00e9 du travail aux niveaux arabe et international&#8221;.<\/p>\n<p>La Conf\u00e9rence vise aussi \u00e0 &#8220;mettre au point des m\u00e9canismes \u00e0 m\u00eame de renforcer l&#8217;apport du secteur au march\u00e9 du travail et au d\u00e9veloppement des \u00e9conomies nationales&#8221; et \u00e0 &#8220;am\u00e9liorer l&#8217;attractivit\u00e9 du secteur&#8221;.<\/p>\n<p>Des cadres de l&#8217;Organisation arabe pour l&#8217;\u00e9ducation, la culture et les sciences (ALECSO), des experts du secteur de l&#8217;enseignement et de la formation techniques et professionnels dans les pays arabes et des repr\u00e9sentants d&#8217;organisations arabes et internationales et d&#8217;institutions partenaires du secteur de la Formation et de l&#8217;Enseignement professionnels en Alg\u00e9rie participeront \u00e0 cette conf\u00e9rence, qui se veut un &#8220;espace participatif de partage de visions pour op\u00e9rer un saut qualitatif dans les \u00e9conomies nationales \u00e0 travers le secteur de la formation et de l&#8217;enseignement techniques et professionnels&#8221;.<\/p>\n<p>APS-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Alg\u00e9rie abritera du 24 au 26 d\u00e9cembre les travaux de la 3e Conf\u00e9rence des ministres et responsables de l&#8217;enseignement et de la&hellip;<\/p>\n","protected":false},"author":55,"featured_media":64547,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[32,37],"tags":[],"class_list":["post-64540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-algerie","category-education-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3e Conf\u00e9rence des ministres arabes de l&#039;enseignement technique et professionnel du 24 au 26 d\u00e9cembre \u00e0 Alger - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3e Conf\u00e9rence des ministres arabes de l&#039;enseignement technique et professionnel du 24 au 26 d\u00e9cembre \u00e0 Alger - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"L&#8217;Alg\u00e9rie abritera du 24 au 26 d\u00e9cembre les travaux de la 3e Conf\u00e9rence des ministres et responsables de l&#8217;enseignement et de la&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-05T13:21:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/12\/MFP-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"321\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7272df8f2babf1943bbce2f7d382a636\"},\"headline\":\"3e Conf\u00e9rence des ministres arabes de l&#8217;enseignement technique et professionnel du 24 au 26 d\u00e9cembre \u00e0 Alger\",\"datePublished\":\"2022-12-05T13:21:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\\\/\"},\"wordCount\":394,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/MFP-1.png\",\"articleSection\":[\"Alg\u00e9rie Alg\u00e9rienne\",\"\u00c9ducation\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\\\/\",\"name\":\"3e Conf\u00e9rence des ministres arabes de l'enseignement technique et professionnel du 24 au 26 d\u00e9cembre \u00e0 Alger - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/MFP-1.png\",\"datePublished\":\"2022-12-05T13:21:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7272df8f2babf1943bbce2f7d382a636\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/MFP-1.png\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/MFP-1.png\",\"width\":660,\"height\":321},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3e Conf\u00e9rence des ministres arabes de l&rsquo;enseignement technique et professionnel du 24 au 26 d\u00e9cembre \u00e0 Alger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7272df8f2babf1943bbce2f7d382a636\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3e Conf\u00e9rence des ministres arabes de l'enseignement technique et professionnel du 24 au 26 d\u00e9cembre \u00e0 Alger - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/","og_locale":"fr_FR","og_type":"article","og_title":"3e Conf\u00e9rence des ministres arabes de l'enseignement technique et professionnel du 24 au 26 d\u00e9cembre \u00e0 Alger - AAH.JZR","og_description":"L&#8217;Alg\u00e9rie abritera du 24 au 26 d\u00e9cembre les travaux de la 3e Conf\u00e9rence des ministres et responsables de l&#8217;enseignement et de la&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2022-12-05T13:21:56+00:00","og_image":[{"width":660,"height":321,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/12\/MFP-1.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/"},"author":{"name":"admin","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7272df8f2babf1943bbce2f7d382a636"},"headline":"3e Conf\u00e9rence des ministres arabes de l&#8217;enseignement technique et professionnel du 24 au 26 d\u00e9cembre \u00e0 Alger","datePublished":"2022-12-05T13:21:56+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/"},"wordCount":394,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/12\/MFP-1.png","articleSection":["Alg\u00e9rie Alg\u00e9rienne","\u00c9ducation"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/","url":"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/","name":"3e Conf\u00e9rence des ministres arabes de l'enseignement technique et professionnel du 24 au 26 d\u00e9cembre \u00e0 Alger - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/12\/MFP-1.png","datePublished":"2022-12-05T13:21:56+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7272df8f2babf1943bbce2f7d382a636"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/12\/MFP-1.png","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/12\/MFP-1.png","width":660,"height":321},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/3e-conference-des-ministres-arabes-de-lenseignement-technique-et-professionnel-du-24-au-26-decembre-a-alger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"3e Conf\u00e9rence des ministres arabes de l&rsquo;enseignement technique et professionnel du 24 au 26 d\u00e9cembre \u00e0 Alger"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7272df8f2babf1943bbce2f7d382a636","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/jazairhope.org\/fr\/author\/admin\/"}]}},"views":273,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/64540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=64540"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/64540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/64547"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=64540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=64540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=64540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}