{"id":65009,"date":"2022-12-11T12:15:39","date_gmt":"2022-12-11T11:15:39","guid":{"rendered":"https:\/\/jazairhope.org\/?p=65009"},"modified":"2022-12-11T09:59:58","modified_gmt":"2022-12-11T08:59:58","slug":"fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/","title":{"rendered":"FICA : \u00c0 J\u00c9RUSALEM, LES PALESTINIENS S\u2019ATTACHENT AU HOUMOUS, UN SYMBOLE IDENTITAIRE"},"content":{"rendered":"<p>Dans le documentaire \u00ab\u00a0Hummus, a story of appropriation\u00a0\u00bb, en comp\u00e9tition au 11\u00e8me Festival international du cin\u00e9ma d\u2019Alger (FICA) jusqu\u2019au 10 d\u00e9cembre 2022, le cin\u00e9aste Abood Lafi a choisi un angle original pour montrer les souffrances \u00a0des Palestiniens \u00e0 J\u00e9rusalem, El Qods.<\/p>\n<p>Il s\u2019est int\u00e9ress\u00e9 au houmous, plat traditionnel moyen-oriental, compos\u00e9 d\u2019une pur\u00e9e de pois-chiche et de s\u00e9same m\u00e9lang\u00e9e \u00e0 de l\u2019huile d\u2019olive. Le houmous, quotidiennement pr\u00e9sent dans les tables en Syrie, au Liban, en Palestine et en Irak, est aujourd\u2019hui revendiqu\u00e9 publiquement par Isra\u00ebl comme \u00ab un plat national \u00bb.<\/p>\n<p>Abood Lafi montre dans son documentaire des extraits de d\u00e9clarations faites par des Isra\u00e9liens qui pr\u00e9tendent que le houmous serait \u00ab\u00a0une pr\u00e9paration culinaire juive\u00a0\u00bb. Ce n\u2019est l\u00e0 qu\u2019un pr\u00e9texte pour le cin\u00e9aste pour aborder la th\u00e9matique de l\u2019identit\u00e9 palestinienne menac\u00e9e de toutes parts et expliquer comment les habitants d\u2019El Qods tentent de r\u00e9sister. \u00ab\u00a0L\u2019identit\u00e9 des Palestiniens est vol\u00e9e chaque jour\u00a0\u00bb, a soutenu le r\u00e9alisateur lors d\u2019un d\u00e9bat \u00e0 la salle Ibn Zeydoun, \u00e0 l\u2019Office Riad El Feth. Le\u00a0humous n\u2019est donc qu\u2019une m\u00e9taphore.<\/p>\n<p>\u00ab Ils ont tout pris, pris nos terres, nos dignit\u00e9s, tout. L\u2019occupation vole tout, ma vie et m\u00eame mon humous. Elle veut prendre le houmous pour dire qu\u2019elle est sur ses terres \u00bb, d\u00e9clare un homme dont le propos est amer. \u00ab C\u00e9der sur le humous, c\u2019est comme c\u00e9der sur notre patrimoine et notre terre \u00bb, ajoute Sameer, un militant palestinien, plusieurs fois d\u00e9tenu, ami de la journaliste Shireen Abu Akleh, tu\u00e9e par un soldat isra\u00e9lien le 11 mai 2022.<\/p>\n<p><strong>\u00a0<\/strong><strong>\u00ab\u00a0On se sent en prison\u2026.\u00a0\u00bb<\/strong><\/p>\n<p><strong>\u00a0<\/strong>La cam\u00e9ra d\u2019Abood Lafi voyage presque avec un regard nostalgique \u00e0 l\u2019int\u00e9rieur du centre historique de J\u00e9rusalem-Est avec ses arcades, ses ruelles \u00e9troites, ses \u00e9choppes, ses parfums et ses souvenirs. \u00ab\u00a0Et si les murs de J\u00e9rusalem disaient la douleur des Palestiniens ?\u00a0\u00bb, s\u2019interroge Abood Lafi \u00a0 dans son commentaire.<\/p>\n<p>\u00ab Nous attendons la mort \u00e0 tout moment. On se sent en prison \u00bb, confie un habitant de l\u2019une des plus anciennes villes sur Terre.\u00a0 Le documentaire montre l\u2019intervention muscl\u00e9e des soldats isra\u00e9liens contre les manifestants.<\/p>\n<p>Abood Lafi a indiqu\u00e9 que les militaires isra\u00e9liens ne l\u2019ont pas emp\u00each\u00e9 de filmer leurs interventions. \u00ab En r\u00e9alit\u00e9, ils font ce qu\u2019ils veulent que vous filmiez ou non. En plus, \u00e0 El Qds, il y des centaines de journalistes qui filment chaque jour \u00bb, a-t-il not\u00e9.<\/p>\n<p>\u00ab Les Palestiniens n\u2019ont aucun droit. Il s\u2019agit d\u2019une v\u00e9ritable colonisation et d\u2019une discrimination raciste. Durant les derni\u00e8res 72 heures, dix enfants sont morts en Palestine. La r\u00e9pression touche les personnes de tous les \u00e2ges. Ils peuvent toujours le cacher, mais ils n\u2019y parviendront pas. La version isra\u00e9lienne ne fonctionne plus \u00bb, a d\u00e9clar\u00e9 Abood Lafi.<\/p>\n<p><strong>\u00ab\u00a0On sait qu\u2019il existe des relations entre Isra\u00ebl et les pays arabes depuis longtemps\u00a0\u00bb<\/strong><\/p>\n<p>Il a critiqu\u00e9 les positions arabes et occidentales par rapport \u00e0 la cause palestinienne. \u00ab\u00a0En tant que palestiniens, ne nous croyons plus \u00e0 cette pi\u00e8ce th\u00e9\u00e2tre relative \u00ab\u00a0\u00e0 un soutien\u00a0\u00bb ext\u00e9rieur au peuple palestinien. Nous savons parfaitement que les Alg\u00e9riens ont une grande admiration pour nous. Cet appui est important\u00a0\u00bb, a-t-il dit.<\/p>\n<p>Interrog\u00e9 sur le processus de normalisation de certains pays arabes avec Isra\u00ebl, Abood Lafi, qui est install\u00e9 aux \u00c9mirats arabes unis, a r\u00e9pondu en soulignant la d\u00e9ception des Palestiniens. \u00ab Mais, ce n\u2019est pas nouveau. On sait qu\u2019il existe des relations entre Isra\u00ebl et les pays arabes depuis longtemps, depuis le processus d\u2019Oslo (\u00e0 partir de 1991). Certains normalisent pour des raisons \u00e9conomiques, d\u2019autres pour des raisons curieuses comme le Soudan. Que les Palestiniens comprennent qu\u2019ils ne doivent compter que sur eux-m\u00eames \u00bb, a-t-il soutenu.<\/p>\n<p>Selon lui, la d\u00e9cision de Washington de transf\u00e9rer son ambassade de Tel-Aviv \u00e0 J\u00e9rusalem ne vient rien changer \u00e0 la donne.<\/p>\n<p>Il a accus\u00e9 \u00ab le lobby isra\u00e9lien \u00bb d\u2019avoir emp\u00each\u00e9 la diffusion mondiale de \u00ab Hummus, a story of appropriation \u00bb. \u00ab Cela importe peu pour moi. Si une seule personne arrive \u00e0 voir ce documentaire, j\u2019aurai r\u00e9ussi \u00e0 faire mon travail \u00bb, a-t-il conclu.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=-e3C-Pp10Hs&amp;t=2s\">(1034) Hummus A Story of Appropriation &#8211; YouTube<\/a><\/p>\n<p><strong><em>FC-DZ<\/em><\/strong><\/p>\n<p><strong><em>Source\u00a0: 24H Alg\u00e9rie \u2013 Fay\u00e7al M\u00e9taoui<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le documentaire \u00ab\u00a0Hummus, a story of appropriation\u00a0\u00bb, en comp\u00e9tition au 11\u00e8me Festival international du cin\u00e9ma d\u2019Alger (FICA) jusqu\u2019au 10 d\u00e9cembre 2022,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":65045,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[34,49],"tags":[],"class_list":["post-65009","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-art-fr","category-politique","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FICA : \u00c0 J\u00c9RUSALEM, LES PALESTINIENS S\u2019ATTACHENT AU HOUMOUS, UN SYMBOLE IDENTITAIRE - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FICA : \u00c0 J\u00c9RUSALEM, LES PALESTINIENS S\u2019ATTACHENT AU HOUMOUS, UN SYMBOLE IDENTITAIRE - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Dans le documentaire \u00ab\u00a0Hummus, a story of appropriation\u00a0\u00bb, en comp\u00e9tition au 11\u00e8me Festival international du cin\u00e9ma d\u2019Alger (FICA) jusqu\u2019au 10 d\u00e9cembre 2022,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-11T11:15:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/12\/maxresdefault-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ssuperadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ssuperadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\\\/\"},\"author\":{\"name\":\"Ssuperadmin\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/43650ebd889d8960700b5456ed9264c4\"},\"headline\":\"FICA : \u00c0 J\u00c9RUSALEM, LES PALESTINIENS S\u2019ATTACHENT AU HOUMOUS, UN SYMBOLE IDENTITAIRE\",\"datePublished\":\"2022-12-11T11:15:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\\\/\"},\"wordCount\":750,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/maxresdefault-3.jpg\",\"articleSection\":[\"Art &amp; Culture\",\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\\\/\",\"name\":\"FICA : \u00c0 J\u00c9RUSALEM, LES PALESTINIENS S\u2019ATTACHENT AU HOUMOUS, UN SYMBOLE IDENTITAIRE - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/maxresdefault-3.jpg\",\"datePublished\":\"2022-12-11T11:15:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/43650ebd889d8960700b5456ed9264c4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/maxresdefault-3.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/maxresdefault-3.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FICA : \u00c0 J\u00c9RUSALEM, LES PALESTINIENS S\u2019ATTACHENT AU HOUMOUS, UN SYMBOLE IDENTITAIRE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/43650ebd889d8960700b5456ed9264c4\",\"name\":\"Ssuperadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g\",\"caption\":\"Ssuperadmin\"},\"sameAs\":[\"https:\\\/\\\/jazairhope.org\"],\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/superadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FICA : \u00c0 J\u00c9RUSALEM, LES PALESTINIENS S\u2019ATTACHENT AU HOUMOUS, UN SYMBOLE IDENTITAIRE - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/","og_locale":"fr_FR","og_type":"article","og_title":"FICA : \u00c0 J\u00c9RUSALEM, LES PALESTINIENS S\u2019ATTACHENT AU HOUMOUS, UN SYMBOLE IDENTITAIRE - AAH.JZR","og_description":"Dans le documentaire \u00ab\u00a0Hummus, a story of appropriation\u00a0\u00bb, en comp\u00e9tition au 11\u00e8me Festival international du cin\u00e9ma d\u2019Alger (FICA) jusqu\u2019au 10 d\u00e9cembre 2022,&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2022-12-11T11:15:39+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/12\/maxresdefault-3.jpg","type":"image\/jpeg"}],"author":"Ssuperadmin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ssuperadmin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/"},"author":{"name":"Ssuperadmin","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/43650ebd889d8960700b5456ed9264c4"},"headline":"FICA : \u00c0 J\u00c9RUSALEM, LES PALESTINIENS S\u2019ATTACHENT AU HOUMOUS, UN SYMBOLE IDENTITAIRE","datePublished":"2022-12-11T11:15:39+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/"},"wordCount":750,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/12\/maxresdefault-3.jpg","articleSection":["Art &amp; Culture","Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/","url":"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/","name":"FICA : \u00c0 J\u00c9RUSALEM, LES PALESTINIENS S\u2019ATTACHENT AU HOUMOUS, UN SYMBOLE IDENTITAIRE - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/12\/maxresdefault-3.jpg","datePublished":"2022-12-11T11:15:39+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/43650ebd889d8960700b5456ed9264c4"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/12\/maxresdefault-3.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2022\/12\/maxresdefault-3.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/fica-a-jerusalem-les-palestiniens-sattachent-au-houmous-un-symbole-identitaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"FICA : \u00c0 J\u00c9RUSALEM, LES PALESTINIENS S\u2019ATTACHENT AU HOUMOUS, UN SYMBOLE IDENTITAIRE"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/43650ebd889d8960700b5456ed9264c4","name":"Ssuperadmin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4068e88b9c557952c81ca0efc4e11e19a2ed480173b8cef95a240894b16bf22?s=96&d=mm&r=g","caption":"Ssuperadmin"},"sameAs":["https:\/\/jazairhope.org"],"url":"https:\/\/jazairhope.org\/fr\/author\/superadmin\/"}]}},"views":211,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/65009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=65009"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/65009\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/65045"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=65009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=65009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=65009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}