{"id":66890,"date":"2023-01-02T17:29:43","date_gmt":"2023-01-02T16:29:43","guid":{"rendered":"https:\/\/jazairhope.org\/?p=66890"},"modified":"2023-01-02T10:34:21","modified_gmt":"2023-01-02T09:34:21","slug":"tizi-ouzou-2emes-journees-de-la-marionnette","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/","title":{"rendered":"Tizi Ouzou: 2\u00e8mes Journ\u00e9es de la marionnette"},"content":{"rendered":"<p>La deuxi\u00e8me \u00e9dition des Journ\u00e9es de la marionnette, organis\u00e9e dans la wilaya de Tizi Ouzou, se tiendra du 4 au 7 janvier prochain, ont fait savoir les organisateurs. Initi\u00e9e par l&#8217;association culturelle Irathen et la direction locale de la culture et des arts, cette manifestation, qui co\u00efncidera avec la c\u00e9l\u00e9bration du Nouvel An amazigh (12 janvier), vise \u00e0 promouvoir ce genre th\u00e9\u00e2tral. La nouvelle \u00e9dition sera d\u00e9di\u00e9e cette ann\u00e9e \u00e0 l&#8217;artiste humoriste Krikeche, de son vrai nom Ahmed Kadri, a indiqu\u00e9 \u00e0 l&#8217;APS la premi\u00e8re responsable du secteur de la culture au niveau local, Nabila Goumeziane. \u00abPlusieurs animations artistiques et culturelles seront au programme de ces journ\u00e9es auxquelles six troupes de diff\u00e9rentes wilayas seront en comp\u00e9tition pour le prix Irathen d&#8217;or\u00bb, a-t-elle fait savoir.<br \/>\nLa c\u00e9r\u00e9monie d&#8217;ouverture de ces 2\u00e8mes Journ\u00e9es sera marqu\u00e9e par l&#8217;organisation, dans la matin\u00e9e, au chef-lieu de wilaya, d&#8217;un carnaval sur la marionnette qui s&#8217;\u00e9branlera de la Maison de la culture Mouloud Mammeri pour rejoindre le th\u00e9\u00e2tre r\u00e9gional Kateb Yacine, en passant par le centre-ville, selon le programme communiqu\u00e9 \u00e0 l&#8217;APS. Organis\u00e9 avec le soutien du minist\u00e8re de la Culture et des Arts, en collaboration avec le th\u00e9\u00e2tre r\u00e9gional Kateb Yacine, la direction locale de la jeunesse et des sports, l&#8217;Assembl\u00e9e populaire de wilaya (APW), la commune d&#8217;Irjen, ainsi que la da\u00efra et la commune de Larba\u00e2 Nath Irathen, l&#8217;\u00e9v\u00e8nement sera cl\u00f4tur\u00e9 par un spectacle et une c\u00e9r\u00e9monie de remise de prix aux meilleures troupes de marionnettes, selon la m\u00eame source. Pour rappel, la premi\u00e8re \u00e9dition des Journ\u00e9es de la marionnette a eu lieu du 23 au 26 septembre 2019 et a vu la participation de sept7 wilayas, dont Tizi-Ouzou.<\/p>\n<p>L&#8217;organisation de la 2e \u00e9dition a \u00e9t\u00e9 diff\u00e9r\u00e9e en raison de la crise sanitaire li\u00e9e \u00e0 la pand\u00e9mie de la Covid-19, a relev\u00e9 la directrice la culture.<\/p>\n<p><div class=\"ose-wrapper ose-uid-667b671e11afc2d2c312a57b381b6c19 ose-embedpress-responsive\" style=\"width:600px; height:550px; max-height:550px; max-width:100%; display:inline-block;\" data-embed-type=\"SelfHosted\"><iframe allowFullScreen=\"true\" width=\"600\" height=\"550\" src=\"https:\/\/www.lexpressiondz.com\/culture\/2emes-journees-de-la-marionnette-364536\" > <\/iframe><\/div><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La deuxi\u00e8me \u00e9dition des Journ\u00e9es de la marionnette, organis\u00e9e dans la wilaya de Tizi Ouzou, se tiendra du 4 au 7 janvier&hellip;<\/p>\n","protected":false},"author":55,"featured_media":66891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[32,34],"tags":[],"class_list":["post-66890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-algerie","category-art-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tizi Ouzou: 2\u00e8mes Journ\u00e9es de la marionnette - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tizi Ouzou: 2\u00e8mes Journ\u00e9es de la marionnette - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"La deuxi\u00e8me \u00e9dition des Journ\u00e9es de la marionnette, organis\u00e9e dans la wilaya de Tizi Ouzou, se tiendra du 4 au 7 janvier&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-02T16:29:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/Festival_Marionnettes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tizi-ouzou-2emes-journees-de-la-marionnette\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tizi-ouzou-2emes-journees-de-la-marionnette\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7272df8f2babf1943bbce2f7d382a636\"},\"headline\":\"Tizi Ouzou: 2\u00e8mes Journ\u00e9es de la marionnette\",\"datePublished\":\"2023-01-02T16:29:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tizi-ouzou-2emes-journees-de-la-marionnette\\\/\"},\"wordCount\":356,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tizi-ouzou-2emes-journees-de-la-marionnette\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Festival_Marionnettes.jpg\",\"articleSection\":[\"Alg\u00e9rie Alg\u00e9rienne\",\"Art &amp; Culture\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tizi-ouzou-2emes-journees-de-la-marionnette\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tizi-ouzou-2emes-journees-de-la-marionnette\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tizi-ouzou-2emes-journees-de-la-marionnette\\\/\",\"name\":\"Tizi Ouzou: 2\u00e8mes Journ\u00e9es de la marionnette - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tizi-ouzou-2emes-journees-de-la-marionnette\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tizi-ouzou-2emes-journees-de-la-marionnette\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Festival_Marionnettes.jpg\",\"datePublished\":\"2023-01-02T16:29:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7272df8f2babf1943bbce2f7d382a636\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tizi-ouzou-2emes-journees-de-la-marionnette\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tizi-ouzou-2emes-journees-de-la-marionnette\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tizi-ouzou-2emes-journees-de-la-marionnette\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Festival_Marionnettes.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Festival_Marionnettes.jpg\",\"width\":850,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/tizi-ouzou-2emes-journees-de-la-marionnette\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tizi Ouzou: 2\u00e8mes Journ\u00e9es de la marionnette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7272df8f2babf1943bbce2f7d382a636\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tizi Ouzou: 2\u00e8mes Journ\u00e9es de la marionnette - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/","og_locale":"fr_FR","og_type":"article","og_title":"Tizi Ouzou: 2\u00e8mes Journ\u00e9es de la marionnette - AAH.JZR","og_description":"La deuxi\u00e8me \u00e9dition des Journ\u00e9es de la marionnette, organis\u00e9e dans la wilaya de Tizi Ouzou, se tiendra du 4 au 7 janvier&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2023-01-02T16:29:43+00:00","og_image":[{"width":850,"height":480,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/Festival_Marionnettes.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/"},"author":{"name":"admin","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7272df8f2babf1943bbce2f7d382a636"},"headline":"Tizi Ouzou: 2\u00e8mes Journ\u00e9es de la marionnette","datePublished":"2023-01-02T16:29:43+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/"},"wordCount":356,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/Festival_Marionnettes.jpg","articleSection":["Alg\u00e9rie Alg\u00e9rienne","Art &amp; Culture"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/","url":"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/","name":"Tizi Ouzou: 2\u00e8mes Journ\u00e9es de la marionnette - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/Festival_Marionnettes.jpg","datePublished":"2023-01-02T16:29:43+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7272df8f2babf1943bbce2f7d382a636"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/Festival_Marionnettes.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/Festival_Marionnettes.jpg","width":850,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/tizi-ouzou-2emes-journees-de-la-marionnette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Tizi Ouzou: 2\u00e8mes Journ\u00e9es de la marionnette"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7272df8f2babf1943bbce2f7d382a636","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/jazairhope.org\/fr\/author\/admin\/"}]}},"views":257,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/66890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=66890"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/66890\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/66891"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=66890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=66890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=66890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}