{"id":67073,"date":"2023-01-05T14:28:34","date_gmt":"2023-01-05T13:28:34","guid":{"rendered":"https:\/\/jazairhope.org\/?p=67073"},"modified":"2023-01-04T21:32:07","modified_gmt":"2023-01-04T20:32:07","slug":"hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/","title":{"rendered":"Hidaoui: miser sur les jeunes pour construire une &#8220;vision unifi\u00e9e&#8221;"},"content":{"rendered":"<p><strong>Le pr\u00e9sident du Conseil sup\u00e9rieur de la jeunesse (CSJ), Mustapha Hidaoui a affirm\u00e9, mercredi \u00e0 Alger, que le Conseil misait sur les jeunes qu&#8217;il compte associer \u00e0 la construction d&#8217;une &#8220;vision unifi\u00e9e&#8221; afin de contribuer au d\u00e9veloppement national.<\/strong><\/p>\n<p>Dans son allocution \u00e0 l&#8217;occasion du lancement des rencontres de la jeunesse de proximit\u00e9 sous le slogan &#8220;D\u00e9fis et aspirations&#8221;, M. Hidaoui a indiqu\u00e9 que l&#8217;int\u00e9r\u00eat accord\u00e9 par le CSJ &#8220;est ax\u00e9 sur les sorties sur terrain pour aller d\u00e9couvrir les points de force des jeunes&#8221;, notamment ceux qui ne sont pas structur\u00e9s en organisations et associations, tout en \u0153uvrant \u00e0 r\u00e9tablir leur confiance.<\/p>\n<p>Cette d\u00e9marche devrait &#8220;construire une vision unifi\u00e9e qui cr\u00e9e une orientation nationale&#8221; pour contribuer au d\u00e9veloppement national, a-t-il dit.<\/p>\n<p>Dans ce cadre, il a \u00e9voqu\u00e9 le r\u00f4le de cette cat\u00e9gorie dans la r\u00e9alisation du d\u00e9veloppement durable, soulignant que cela &#8220;n\u00e9cessite une coordination entre le Conseil et les centres de d\u00e9cision, \u00e0 partir des collectivit\u00e9s locales, loin des formalit\u00e9s et des rencontres saisonni\u00e8res&#8221;.<\/p>\n<p>A cette occasion, M. Hidaoui a exhort\u00e9 les jeunes \u00e0 travailler \u00e0 partir du niveau local (quartiers et communes), rappelant le changement op\u00e9r\u00e9 par les jeunes de la R\u00e9volution, apr\u00e8s avoir jou\u00e9 un r\u00f4le pionnier qui a abouti \u00e0 l&#8217;ind\u00e9pendance et au recouvrement de la souverainet\u00e9 nationale.<\/p>\n<p>Pour sa part, le wali d\u00e9l\u00e9gu\u00e9 de la circonscription administrative de Draria, Abdelwahab Bertima a fait part de la disponibilit\u00e9 de ses services \u00e0 accompagner le Conseil et \u00e0 \u00e9couter les pr\u00e9occupations des jeunes \u00e0 travers la tenue de s\u00e9ances conjointes visant \u00e0 \u00e9tablir des &#8220;plans d&#8217;action pour examiner les m\u00e9canismes de mise en \u0153uvre des diff\u00e9rents projets&#8221;.<\/p>\n<p>Dans le m\u00eame contexte, il a \u00e9voqu\u00e9 les axes sur lesquels repose le Plan national de la jeunesse 2020-2024, qui comportent les domaines de l&#8217;entrepreneuriat, du logement, de la sant\u00e9, de la num\u00e9risation, des sports et des loisirs, ainsi que de la vie associative, soulignant la n\u00e9cessit\u00e9 de la coordination et de la coop\u00e9ration pour trouver des m\u00e9canismes pour les concr\u00e9tiser.<\/p>\n<p>APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sident du Conseil sup\u00e9rieur de la jeunesse (CSJ), Mustapha Hidaoui a affirm\u00e9, mercredi \u00e0 Alger, que le Conseil misait sur les&hellip;<\/p>\n","protected":false},"author":55,"featured_media":67075,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[32,52],"tags":[],"class_list":["post-67073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-algerie","category-sport-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hidaoui: miser sur les jeunes pour construire une &quot;vision unifi\u00e9e&quot; - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hidaoui: miser sur les jeunes pour construire une &quot;vision unifi\u00e9e&quot; - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Le pr\u00e9sident du Conseil sup\u00e9rieur de la jeunesse (CSJ), Mustapha Hidaoui a affirm\u00e9, mercredi \u00e0 Alger, que le Conseil misait sur les&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-05T13:28:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/jeunesse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7272df8f2babf1943bbce2f7d382a636\"},\"headline\":\"Hidaoui: miser sur les jeunes pour construire une &#8220;vision unifi\u00e9e&#8221;\",\"datePublished\":\"2023-01-05T13:28:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\\\/\"},\"wordCount\":377,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/jeunesse.jpg\",\"articleSection\":[\"Alg\u00e9rie Alg\u00e9rienne\",\"Sport &amp; Soci\u00e9t\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\\\/\",\"name\":\"Hidaoui: miser sur les jeunes pour construire une \\\"vision unifi\u00e9e\\\" - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/jeunesse.jpg\",\"datePublished\":\"2023-01-05T13:28:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7272df8f2babf1943bbce2f7d382a636\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/jeunesse.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/jeunesse.jpg\",\"width\":580,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hidaoui: miser sur les jeunes pour construire une \u00ab\u00a0vision unifi\u00e9e\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7272df8f2babf1943bbce2f7d382a636\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hidaoui: miser sur les jeunes pour construire une \"vision unifi\u00e9e\" - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/","og_locale":"fr_FR","og_type":"article","og_title":"Hidaoui: miser sur les jeunes pour construire une \"vision unifi\u00e9e\" - AAH.JZR","og_description":"Le pr\u00e9sident du Conseil sup\u00e9rieur de la jeunesse (CSJ), Mustapha Hidaoui a affirm\u00e9, mercredi \u00e0 Alger, que le Conseil misait sur les&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2023-01-05T13:28:34+00:00","og_image":[{"width":580,"height":350,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/jeunesse.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/"},"author":{"name":"admin","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7272df8f2babf1943bbce2f7d382a636"},"headline":"Hidaoui: miser sur les jeunes pour construire une &#8220;vision unifi\u00e9e&#8221;","datePublished":"2023-01-05T13:28:34+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/"},"wordCount":377,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/jeunesse.jpg","articleSection":["Alg\u00e9rie Alg\u00e9rienne","Sport &amp; Soci\u00e9t\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/","url":"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/","name":"Hidaoui: miser sur les jeunes pour construire une \"vision unifi\u00e9e\" - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/jeunesse.jpg","datePublished":"2023-01-05T13:28:34+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7272df8f2babf1943bbce2f7d382a636"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/jeunesse.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/jeunesse.jpg","width":580,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/hidaoui-miser-sur-les-jeunes-pour-construire-une-vision-unifiee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Hidaoui: miser sur les jeunes pour construire une \u00ab\u00a0vision unifi\u00e9e\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7272df8f2babf1943bbce2f7d382a636","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/jazairhope.org\/fr\/author\/admin\/"}]}},"views":257,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/67073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=67073"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/67073\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/67075"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=67073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=67073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=67073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}