{"id":68117,"date":"2023-01-17T10:25:32","date_gmt":"2023-01-17T09:25:32","guid":{"rendered":"https:\/\/jazairhope.org\/?p=68117"},"modified":"2023-01-16T21:35:46","modified_gmt":"2023-01-16T20:35:46","slug":"un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/","title":{"rendered":"Un soutien affich\u00e9 \u00e0 l\u2019adh\u00e9sion de l\u2019Alg\u00e9rie aux BRICS"},"content":{"rendered":"<div id=\"content\" class=\"clearfix\">\n<article id=\"post-34176\" class=\"post-34176 post type-post status-publish format-standard has-post-thumbnail hentry category-a-la-une category-actualite grow-content-body\">\n<div class=\"article-content clearfix\">\n<div class=\"entry-content clearfix\">\n<p>En plus de la Chine et de la Russie, l\u2019Alg\u00e9rie peut d\u2019ores et d\u00e9j\u00e0 compter sur le soutien du Congr\u00e8s national africain (ANC), parti au pouvoir en Afrique du Sud pour soutenir sa demande d\u2019adh\u00e9sion aux BRICS.<\/p>\n<p>L\u2019Alg\u00e9rie devrait conna\u00eetre la suite r\u00e9serv\u00e9e \u00e0 sa demande d\u2019adh\u00e9sion au groupe des Brics qui comprend le Br\u00e9sil, la Russie, l\u2019Inde, la Chine et l\u2019Afrique du Sud avant la fin de l\u2019ann\u00e9e. L\u2019annonce a \u00e9t\u00e9 faite durant le week-end par la ministre sud-africaine des Affaires \u00e9trang\u00e8res, Naledi Pandor. \u00abUn certain nombre de pays ont demand\u00e9 de rejoindre le bloc des BRICS sous la pr\u00e9sidence de la Chine. Nous devons maintenant nous pencher sur ces demandes et cet int\u00e9r\u00eat tr\u00e8s important pour l\u2019\u00e9largissement du groupe \u00bb, a-t-elle d\u00e9clar\u00e9 lors d\u2019une conf\u00e9rence de presse \u00e0 Johannesburg. \u00abVers la fin de la pr\u00e9sidence de l\u2019Afrique du Sud, nous serons en mesure d\u2019indiquer si nous nous \u00e9largissons et qui fera partie d\u2019un BRICS Plus ou de tout autre format \u00bb, a ajout\u00e9 la ministre, dont le pays a pris la pr\u00e9sidence tournante du groupe depuis le 1er janvier 2023.<\/p>\n<p>Naledi Pandor a indiqu\u00e9 \u00e0 l\u2019occasion que de nombreux pays s\u2019int\u00e9ressent au groupe des BRICS et \u00e0 l\u2019approche que ses membres d\u00e9fendent. Les BRICS sont per\u00e7us comme une alternative au monde unipolaire domin\u00e9 par les Etats-Unis. Plus de membres augmenterait par ailleurs le r\u00f4le du groupe en tant que contrepoids \u00e0 l\u2019Occident. \u00abLe monde \u00e9volue de mani\u00e8re tr\u00e8s inqui\u00e9tante. Les pays sont \u00e0 la recherche de partenaires partageant les m\u00eames id\u00e9es dans le monde entier. De nombreux pays constatent que l\u2019approche des BRICS est celle \u00e0 laquelle ils aimeraient adh\u00e9rer \u00bb, a fait remarquer la responsable sud-africaine.<\/p>\n<p>Pour le moment, il est difficile de savoir si la demande de l\u2019Alg\u00e9rie sera accept\u00e9e ou non. Une chose para\u00eet certaine, les Alg\u00e9riens peuvent d\u2019ores et d\u00e9j\u00e0 compter sur le soutien du Congr\u00e8s national africain (ANC). Le parti au pouvoir en Afrique du Sud a d\u00e9j\u00e0 commenc\u00e9 \u00e0 mettre la pression sur le pr\u00e9sident Cyril Ramaphosa pour qu\u2019il \u00e9largisse les BRICS \u00e0 de nouveaux membres et qu\u2019il fasse en sorte que les relations entre les pays BRICS et les \u00c9tats membres de la Zone de libre-\u00e9change continentale africaine soient renforc\u00e9es. Le pr\u00e9sident sud-africain compte visiblement aller dans ce sens puisqu\u2019il a d\u00e9clar\u00e9 la semaine derni\u00e8re que d\u2019autres nations africaines seront invit\u00e9es au sommet qu\u2019il accueillera cette ann\u00e9e.<\/p>\n<p><strong>Le soutien de l\u2019ANC<\/strong><\/p>\n<p>L\u2019Alg\u00e9rie n\u2019est pas le seul pays \u00e0 vouloir les BRICS. L\u2019Argentine et l\u2019Iran ont \u00e9galement officiellement d\u00e9pos\u00e9 des demandes d\u2019adh\u00e9sion. L\u2019Arabie Saoudite, l\u2019Egypte et la Turquie ont \u00e9galement exprim\u00e9 leur int\u00e9r\u00eat pour une adh\u00e9sion \u00e0 la coalition. Mais jusqu\u2019ici et contrairement \u00e0 l\u2019Alg\u00e9rie ils n\u2019ont pas d\u00e9pos\u00e9 de demandes officielles. L\u2019id\u00e9e de l\u2019\u00e9largissement du bloc des BRICS est venue de la Chine. Le minist\u00e8re chinois des Affaires \u00e9trang\u00e8res avait d\u2019ailleurs annonc\u00e9, d\u00e9but mai dernier, le d\u00e9but d\u2019un processus d\u2019\u00e9largissement du groupe des BRICS.La Chine est \u00e9galement le premier pays \u00e0 avoir soutenu la demande d\u2019adh\u00e9sion de l\u2019Alg\u00e9rie. \u00ab La Chine soutient l\u2019Alg\u00e9rie qui assure actuellement la pr\u00e9sidence tournante de la Ligue arabe et accueille favorablement sa volont\u00e9 d\u2019adh\u00e9sion \u00e0 la famille des BRICS \u00bb, a d\u00e9clar\u00e9 Wang Yi \u00e0 Xinhua, \u00e0 l\u2019issue de sa rencontre avec le ministre des Affaires \u00e9trang\u00e8res, Ramtane Lamamra, en marge de la 77e session de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale de l\u2019ONU. Le chef de la diplomatie chinoise a \u00e9galement indiqu\u00e9 que P\u00e9kin appr\u00e9ciait le soutien apport\u00e9 par Alger \u00e0 l\u2019Initiative pour le d\u00e9veloppement mondial (IDM), propos\u00e9e par le pr\u00e9sident chinois Xi Jinping en septembre 2021, tout en notant que l\u2019Alg\u00e9rie est \u00ab un grand pays en d\u00e9veloppement et un repr\u00e9sentant des \u00e9conomies \u00e9mergentes \u00bb.<\/p>\n<p>L\u2019Alg\u00e9rie a annonc\u00e9 le 7 novembre dernier avoir officiellement d\u00e9pos\u00e9 une demande d\u2019adh\u00e9sion au groupe des BRICS. \u00abNous avons d\u00e9pos\u00e9 notre demande qui est appuy\u00e9e par la Chine et la Russie\u00bb, avait d\u00e9clar\u00e9 Leila Zerrouki, envoy\u00e9e sp\u00e9ciale charg\u00e9e des grands partenariats internationaux au minist\u00e8re alg\u00e9rien des Affaires \u00e9trang\u00e8res et de la communaut\u00e9 nationale \u00e0 l\u2019\u00e9tranger sur les ondes de la Radio alg\u00e9rienne. \u00abLors de la derni\u00e8re r\u00e9union des BRICS \u00e0 laquelle le pr\u00e9sident de la R\u00e9publique Abdelmadjid Tebboune a \u00e9t\u00e9 convi\u00e9 avec d\u2019autres chefs d\u2019\u00c9tats, une d\u00e9cision a \u00e9t\u00e9 prise pour ouvrir les portes de l\u2019adh\u00e9sion \u00e0 de nouveaux pays\u00bb, a-t-elle ajout\u00e9.<\/p>\n<p>C\u2019est en juillet dernier que le pr\u00e9sident Abdelmadjid Tebboune avait exprim\u00e9 l\u2019int\u00e9r\u00eat de l\u2019Alg\u00e9rie pour les BRICS. \u00ab Cela est envisageable, mais n\u2019anticipons pas. Ce qui est s\u00fbr, c\u2019est qu\u2019il y aura de bonnes nouvelles. [\u2026] l\u2019Alg\u00e9rie s\u2019int\u00e9resse aux BRICS, en ce qu\u2019ils constituent une puissance \u00e9conomique et politique \u00bb, avait-il fait savoir. Il a \u00e9galement pr\u00e9cis\u00e9 que cela \u00ab mettrait l\u2019Alg\u00e9rie, pays pionnier du non-alignement, \u00e0 l\u2019abri des tiraillements entre deux p\u00f4les \u00bb. Le groupe des BRICS, rappelle-t-on, repr\u00e9sente 42 % de la population de la plan\u00e8te (3,2 milliards de personnes) et environ 25 % du produit int\u00e9rieur brut (PIB) mondial. Le groupe, qui a cr\u00e9\u00e9 en 2014 sa propre banque de d\u00e9veloppement pour tenter de bousculer l\u2019architecture financi\u00e8re mondiale dessin\u00e9e par les accords de Bretton Woods, s\u2019efforce d\u00e9sormais de jouer un r\u00f4le pr\u00e9pond\u00e9rant dans la gouvernance mondiale.<\/p>\n<p><strong>Khider Larbi, In La Sentinelle.<\/strong><\/p>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En plus de la Chine et de la Russie, l\u2019Alg\u00e9rie peut d\u2019ores et d\u00e9j\u00e0 compter sur le soutien du Congr\u00e8s national africain&hellip;<\/p>\n","protected":false},"author":55,"featured_media":68118,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[32,35,49],"tags":[],"class_list":["post-68117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-algerie","category-economie","category-politique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un soutien affich\u00e9 \u00e0 l\u2019adh\u00e9sion de l\u2019Alg\u00e9rie aux BRICS - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un soutien affich\u00e9 \u00e0 l\u2019adh\u00e9sion de l\u2019Alg\u00e9rie aux BRICS - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"En plus de la Chine et de la Russie, l\u2019Alg\u00e9rie peut d\u2019ores et d\u00e9j\u00e0 compter sur le soutien du Congr\u00e8s national africain&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-17T09:25:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/BRICS-800x445-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7272df8f2babf1943bbce2f7d382a636\"},\"headline\":\"Un soutien affich\u00e9 \u00e0 l\u2019adh\u00e9sion de l\u2019Alg\u00e9rie aux BRICS\",\"datePublished\":\"2023-01-17T09:25:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\\\/\"},\"wordCount\":1009,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/BRICS-800x445-1.png\",\"articleSection\":[\"Alg\u00e9rie Alg\u00e9rienne\",\"\u00c9conomie\",\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\\\/\",\"name\":\"Un soutien affich\u00e9 \u00e0 l\u2019adh\u00e9sion de l\u2019Alg\u00e9rie aux BRICS - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/BRICS-800x445-1.png\",\"datePublished\":\"2023-01-17T09:25:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7272df8f2babf1943bbce2f7d382a636\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/BRICS-800x445-1.png\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/BRICS-800x445-1.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un soutien affich\u00e9 \u00e0 l\u2019adh\u00e9sion de l\u2019Alg\u00e9rie aux BRICS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/7272df8f2babf1943bbce2f7d382a636\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un soutien affich\u00e9 \u00e0 l\u2019adh\u00e9sion de l\u2019Alg\u00e9rie aux BRICS - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/","og_locale":"fr_FR","og_type":"article","og_title":"Un soutien affich\u00e9 \u00e0 l\u2019adh\u00e9sion de l\u2019Alg\u00e9rie aux BRICS - AAH.JZR","og_description":"En plus de la Chine et de la Russie, l\u2019Alg\u00e9rie peut d\u2019ores et d\u00e9j\u00e0 compter sur le soutien du Congr\u00e8s national africain&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2023-01-17T09:25:32+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/BRICS-800x445-1.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/"},"author":{"name":"admin","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7272df8f2babf1943bbce2f7d382a636"},"headline":"Un soutien affich\u00e9 \u00e0 l\u2019adh\u00e9sion de l\u2019Alg\u00e9rie aux BRICS","datePublished":"2023-01-17T09:25:32+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/"},"wordCount":1009,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/BRICS-800x445-1.png","articleSection":["Alg\u00e9rie Alg\u00e9rienne","\u00c9conomie","Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/","url":"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/","name":"Un soutien affich\u00e9 \u00e0 l\u2019adh\u00e9sion de l\u2019Alg\u00e9rie aux BRICS - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/BRICS-800x445-1.png","datePublished":"2023-01-17T09:25:32+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7272df8f2babf1943bbce2f7d382a636"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/BRICS-800x445-1.png","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/01\/BRICS-800x445-1.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/un-soutien-affiche-a-ladhesion-de-lalgerie-aux-brics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Un soutien affich\u00e9 \u00e0 l\u2019adh\u00e9sion de l\u2019Alg\u00e9rie aux BRICS"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/7272df8f2babf1943bbce2f7d382a636","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d312d5d4b6df9e432b841b4a558b052e8176d56ad9ab20f7f6c823117e9450d?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/jazairhope.org\/fr\/author\/admin\/"}]}},"views":311,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/68117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=68117"}],"version-history":[{"count":0,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/68117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/68118"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=68117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=68117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=68117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}