{"id":70560,"date":"2023-02-17T19:44:55","date_gmt":"2023-02-17T18:44:55","guid":{"rendered":"https:\/\/jazairhope.org\/?p=70560"},"modified":"2023-02-17T19:45:42","modified_gmt":"2023-02-17T18:45:42","slug":"entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/","title":{"rendered":"Entretien \u2013 Pr. Yazid Ben Hounet : \u00ab La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale \u00bb"},"content":{"rendered":"<p><strong><span style=\"color: #003366\">lapatrienews.dz<\/span><\/strong><\/p>\n<p><span style=\"color: #003366\"><strong>Entretien<\/strong><\/span><\/p>\n<blockquote><p><span style=\"color: #003366\"><strong>Pr. Yazid Ben Hounet\u00a0: \u00ab\u00a0La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale\u00a0\u00bb<\/strong><\/span><\/p>\n<p><span style=\"color: #003366\"><b>\u00a0<\/b><\/span><\/p><\/blockquote>\n<p><span style=\"color: #003366\"><b>Le professeur Yazid Ben Hounet, chercheur au CNRS, ne m\u00e2che gu\u00e8re ses mots quand il s\u2019agit de monter au front pour d\u00e9fendre les causes nobles et justes que sont celles du Sahara Occidental et de la Palestine. Moins de 24 heures apr\u00e8s notre sollicitation, il a r\u00e9pondu pr\u00e9sent \u00e0 notre demande d\u2019entretien pour r\u00e9pondre du tac-au-tac \u00e0 la tribune parue sur le monde, et concoct\u00e9e sur fond d\u2019intrigues innommables par une personne qui ne fait pas secret de sa haine pour l\u2019Alg\u00e9rie, et de son inf\u00e9odation aux gens du Makhzen. Pr Yazid Ben Hounet rappelle fort \u00e0 propos que la promptitude du Monde \u00e0 publier cette tribune n\u00e9ocoloniale le dispute au refus syst\u00e9matique de ce m\u00eame journal \u00e0 publier les contributions d\u2019\u00e9minents chercheurs favorables au Sahara Occidental et \u00e0 la Palestine. Pour notre interlocuteur, il y a un lien \u00e9vident entre cette tribune, qui tombe comme un cheveu dans la soupe et les nombreux scandales qui \u00e9claboussent pr\u00e9sentement le Maroc. On laisse nos lecteurs d\u00e9couvrir le pourquoi et le comment de ces sordides intrigues\u2026<\/b><\/span><\/p>\n<p><span style=\"color: #003366\"><b>Propos recueillis par Mohamed Abdoun<\/b><\/span><\/p>\n<p><span style=\"color: #003366\"><b>La Patrie News\u00a0: Une tribune vient de paraitre sur le journal Le Monde qui, en r\u00e9sum\u00e9, ignore l\u2019existence du peuple sahraoui ainsi que l\u2019option r\u00e9f\u00e9rendaire en tentant de place face \u00e0 face Alger et Rabat. Quels commentaires \u00e0 chauds en tirez-vous, vous qui \u00eates \u00e0 cheval concernant la d\u00e9fense du peuple sahraoui ?<\/b><\/span><\/p>\n<p><span style=\"color: #003366\">Je suis \u00e0 cheval concernant la d\u00e9fense du peuple sahraoui (comme du peuple palestinien) puisque la raison humaniste et le droit international sont de leur cot\u00e9. Tout simplement. Seuls les ignorants et ceux qui consid\u00e8rent \u00ab la raison du plus fort comme la meilleure \u00bb sont de l\u2019autre c\u00f4t\u00e9.<\/span><\/p>\n<p><span style=\"color: #003366\">La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale. Hypocrite car le quotidien Le Monde a \u00e9cart\u00e9, censur\u00e9, d\u2019autres contributions autrement plus s\u00e9rieuses sur le sujet du Sahara Occidental, en ligne avec le droit international. Ce quotidien refuse en effet les tribunes qui s\u2019\u00e9cartent de sa ligne \u00e9ditoriale qui consiste \u00e0 pr\u00e9senter la question du Sahara Occidental comme \u00ab un conflit opposant le Marocau Polisario, un groupe ind\u00e9pendantiste soutenu par l\u2019Alg\u00e9rie \u00bb. C\u2019est syst\u00e9matiquement de cette mani\u00e8re que Le Monde \u2013 et notamment son responsable de la rubrique Afrique du Nord, Fr\u00e9d\u00e9ricBobin \u2013 pr\u00e9sente le sujet. Ce quotidien induit volontairement en erreur le lectorat en omettant m\u00e9thodiquement de pr\u00e9ciser d\u2019une part le fait que la R\u00e9publique Arabe Sahraouie et D\u00e9mocratique (RASD) est membre de l\u2019Union Africaine depuis 1982 \u2013 elle est donc logiquement soutenue par la majorit\u00e9 des pays africains. D\u2019autre part, ce quotidien ne dit pas le droit international. Il s\u2019agit de fait d\u2019une d\u00e9colonisation entrav\u00e9e par le Maroc, qui occupe ill\u00e9galement pr\u00e9s de 70% du territoire du Sahara Occidental, avec l\u2019appui en coulisse de la France :\u00a0<a style=\"color: #003366\" href=\"http:\/\/ouiso.recherche.parisdescartes.fr\/fr\/2022\/11\/28\/sahara-occidental-esprit-de-censure\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/ouiso.recherche.parisdescartes.fr\/fr\/2022\/11\/28\/sahara-occidental-esprit-de-censure\/&amp;source=gmail&amp;ust=1676715303295000&amp;usg=AOvVaw0Q6lgyJczveAp7XINze8N1\">http:\/\/ouiso.recherche.parisdescartes.fr\/fr\/2022\/11\/28\/sahara-occidental-esprit-de-censure\/<\/a>.<\/span><\/p>\n<p><span style=\"color: #003366\">En avril 2018,il y a d\u00e9j\u00e0 pr\u00e8s de 5 ans de cela, une centaine de chercheurs internationaux avaient adress\u00e9 \u00e0 Emmanuel Macron une lettre ouverte pointant du doigt la lourde responsabilit\u00e9 de la France dans la non d\u00e9colonisation de la derni\u00e8re colonie d\u2019Afrique. \u00c0 ma connaissance Le Monde \u00e9tait \u00e9galement destinataire de cette lettre ouverte. Seule L\u2019Humanit\u00e9 a daign\u00e9 la publier en France :\u00a0<a style=\"color: #003366\" href=\"https:\/\/www.humanite.fr\/monde\/sahara-occidental\/la-france-une-lourde-responsabilite-dans-la-non-decolonisation-du-sahara\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.humanite.fr\/monde\/sahara-occidental\/la-france-une-lourde-responsabilite-dans-la-non-decolonisation-du-sahara&amp;source=gmail&amp;ust=1676715303295000&amp;usg=AOvVaw3tgIOqy5gZiA5Een4UFg6k\">https:\/\/www.humanite.fr\/monde\/sahara-occidental\/la-france-une-lourde-responsabilite-dans-la-non-decolonisation-du-sahara<\/a><\/span><\/p>\n<p><span style=\"color: #003366\">Je sugg\u00e8re aussi au lectorat de lire la d\u00e9claration de l\u2019association espagnole des professeurs de droit international et des relations internationales, suite \u00e0 l\u2019alignement de Pedro Sanchez sur le plan d\u2019autonomie marocain. Elle est sign\u00e9e par des centaines de professeurs. Elle est disponible ici :\u00a0<a style=\"color: #003366\" href=\"https:\/\/www.aepdiri.org\/index.php\/actividades-aepdiri\/declaracion-sahara\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.aepdiri.org\/index.php\/actividades-aepdiri\/declaracion-sahara&amp;source=gmail&amp;ust=1676715303295000&amp;usg=AOvVaw05j1r2036G-SZ0R-wZxx7Z\">https:\/\/www.aepdiri.org\/index.php\/actividades-aepdiri\/declaracion-sahara<\/a><\/span><\/p>\n<p><span style=\"color: #003366\">La tribune en France et la d\u00e9claration en Espagne sont sign\u00e9es par beaucoup plus de chercheurs et de professeurs, et en particulier par des sp\u00e9cialistes du sujet. Ce qui est nullement le cas de la tribune parue dans Le Monde, sign\u00e9e par des journalistes, des \u00ab experts \u00bb thinkthank, une poign\u00e9e d\u2019universitaires copains du Monde (ou les copains des copains).<\/span><\/p>\n<p><span style=\"color: #003366\">Ce qu\u2019il y a d\u2019int\u00e9ressant dans la tribune en France, publi\u00e9e en 2018 par l\u2019Humanit\u00e9, et la d\u00e9claration en Espagne, c\u2019est que les deux convergent. On y voit d\u2019ailleurs que, dans les deux cas,\u00a0 l\u2019Alg\u00e9rie n\u2019est nullement mentionn\u00e9e. Outre le Polisario (RASD) et le Maroc, deux autres pays apparaissent : l\u2019Espagne, ancienne puissance coloniale et toujours reconnue l\u00e9galement comme puissance administrante ; ainsi que la France. \u00c0 la fin de l\u2019article 3 de la d\u00e9claration tr\u00e8s solennelle et fond\u00e9e en droit de l\u2019association espagnole des professeurs de droit international et des relations internationales, on lit ceci : \u201cOnlyFrance\u2019s veto in the Security Council prevented the MINURSO fromcompletingitswork in organizing the referendum\u201d. En fran\u00e7ais : \u00ab Seul le veto de la France au Conseil de s\u00e9curit\u00e9 a emp\u00each\u00e9 la MINURSO de terminer son travail d\u2019organisation du r\u00e9f\u00e9rendum \u00bb.<\/span><\/p>\n<p><span style=\"color: #003366\">La tribune est in fine n\u00e9ocoloniale car elle en appelle \u00e0 l\u2019arbitrage de la France, alors que la question de la derni\u00e8re colonie d\u2019Afrique rel\u00e8ve des instances de l\u2019UA et de l\u2019ONU. Elle entend par la m\u00eame livrer le sort des Sahraouis \u2013 grands absents de la tribune \u2013 au pays protecteur du Maroc : la France.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\"><b>A votre avis, quels objectifs vise cette tribune ? S\u2019agit-il de faire sortir de l\u2019ONU la question sahraouie ?<\/b><\/span><\/p>\n<p><span style=\"color: #003366\">Elle vise, \u00e0 mon avis, tout simplement \u00e0 donner du cr\u00e9dit au narratif du Monde (\u00ab un conflit opposant le Maroc \u00e0 l\u2019Alg\u00e9rie \u00bb), et plus largement \u00e0 celui des autorit\u00e9s fran\u00e7aises, s\u2019agissant de la derni\u00e8re colonie d\u2019Afrique, tout en essayant de donner le beau r\u00f4le \u00e0 la France. Elle n\u2019engage que leurs auteurs mais si Le Monde la publie c\u2019est parce qu\u2019il conforte son narratif sournois.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\"><b>Parlons des signataires maintenant si vous le permettez. Najem Sidi, seul sahraoui \u00ab signataire \u00bb de cette tribune a \u00e9t\u00e9 victime d\u2019une gravissime manipulation. Il me l\u2019a personnellement d\u00e9clar\u00e9 lors d\u2019un entretien t\u00e9l\u00e9phonique. Il a contact\u00e9 Le Monde pour un d\u00e9menti. A votre avis, quels sont les desseins poursuivis par les autres signataires, chacun selon son parcours et\/ou nationalit\u00e9 ?<\/b><\/span><\/p>\n<p><span style=\"color: #003366\">Difficile \u00e0 dire. Il y a d\u00e9j\u00e0 les deux personnes \u00e0 l\u2019initiative \u2013 Khadija Mohsen-Finan et Jean-Pierre Sereni. La premi\u00e8re est politologue travaillant pour des think thanks (dont la Hicham Alaoui Foundation), le second est journaliste. Ils donnent des gages \u00e0 leurs financeurs. Ils jouent l\u00e0 le jeu des intellectuels organiques de la diplomatie fran\u00e7aise et de certains int\u00e9r\u00eats fran\u00e7ais et peut \u00eatre marocains, en essayant de tronquer le d\u00e9bat et de nier sournoisement le r\u00f4le d\u00e9terminant de la France dans la non d\u00e9colonisation du Sahara Occidental. Ce doit \u00eatre le cas d\u2019autres signataires. Puis il y a ceux qui sont de bonne foi, qui pensent bien faire, qui ne connaissent rien au sujet, ne lisent que Le Monde et font confiance aux copains. Enfin, il y a les Marocains qui sont dans leur logique.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\"><b>Peut-on lier cette tribune aux nombreux scandales qui \u00e9claboussent pr\u00e9sentement le Maroc ?<\/b><\/span><\/p>\n<p><span style=\"color: #003366\">Oui. On peut. Les nombreux scandales qui \u00e9claboussent le Maroc fragilisent la France qui est\u00a0 tr\u00e8s li\u00e9e \u00e9conomiquement et politiquement au Maroc. Ce genre de tribune vise \u00e0 poser la France en tant qu\u2019arbitre dans un moment o\u00f9 la politique maghr\u00e9bine de la France est de plus en plus d\u00e9cri\u00e9e, \u00e9galement en Europe.<\/span><\/p>\n<p><span style=\"color: #003366\">Le Monde a une attitude tr\u00e8s conciliante, amicale voire paternaliste \u00e0 l\u2019\u00e9gard du Maroc. Je vous laisse lire les prises de position de ce quotidien s\u2019agissant la \u201ccrise des migrants \u00e0 Ceuta\u201d (21 mai 2021), et le \u201cdrame\u201d de Mellila(8 et 23 juillet 2022), pour reprendre les euph\u00e9mismes utilis\u00e9s par \u00ab le journal de r\u00e9f\u00e9rence \u00bb fran\u00e7ais. Sur ce dernier \u00e9v\u00e9nement, qu\u2019il convient de qualifier de massacre, vous pouvez comparer leur point de vue, plus qu\u2019indigne, avec un article autrement plus document\u00e9, celui du m\u00e9dia lundi matin du 21 novembre 2022 \u2013\u00a0<a style=\"color: #003366\" href=\"https:\/\/lundi.am\/On-a-dit-que-c-etait-une-bataille-mais-c-etait-un-massacre-contre-l-humanite\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/lundi.am\/On-a-dit-que-c-etait-une-bataille-mais-c-etait-un-massacre-contre-l-humanite&amp;source=gmail&amp;ust=1676715303295000&amp;usg=AOvVaw0v_85bbBT1QyYSPSXbsm5N\">https:\/\/lundi.am\/On-a-dit-que-c-etait-une-bataille-mais-c-etait-un-massacre-contre-l-humanite<\/a>\u00a0\u2013 ainsi que le reportage de la BBC :\u00a0<a style=\"color: #003366\" href=\"https:\/\/www.youtube.com\/watch?v=MJoL7E4uvuU&amp;t=632s\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.youtube.com\/watch?v%3DMJoL7E4uvuU%26t%3D632s&amp;source=gmail&amp;ust=1676715303295000&amp;usg=AOvVaw3R2hHbyOz-AgteNyrRylRp\">https:\/\/www.youtube.com\/watch?v=MJoL7E4uvuU&amp;t=632s<\/a><\/span><\/p>\n<p><span style=\"color: #003366\">Une hypoth\u00e8se est que les actionnaires du Monde ont des int\u00e9r\u00eats \u00e0 sauvegarder au Maroc. Une deuxi\u00e8me hypoth\u00e8se et que le marocgate ne se limite nullement au parlement europ\u00e9en. \u00c0 l\u2019inverse, Le Monde a une obsession pour l\u2019Alg\u00e9rie et publie des textes tr\u00e8s \u00e0 charge et tronqu\u00e9s s\u2019agissant de ce pays.\u00a0 132 ans de colonisation, 193 ans de m\u00e9pris\u2026 Les journalistes du Monde doivent apprendre \u00e0 d\u00e9coloniser leurs regards sur l\u2019Afrique du Nord et plus largement l\u2019Afrique.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366\"><b>Si le pr\u00e9sident Macron se r\u00e9sout \u00e0 se rendre au Maroc, quels avantages politique pourrait en retirer Rabat, comme par exemple un soutien fran\u00e7ais franc au plan d\u2019autonomie marocain ?<\/b><\/span><\/p>\n<p><span style=\"color: #003366\">C\u2019est ce que le Maroc va tenter de faire. Reste \u00e0 savoir si Macron et son entourage iront dans ce sens. Mais apr\u00e8s le scandale Pegasus, le chantage migratoire de Ceuta (17 mai 2021), le massacre de Mellila (24 juin 2022), le Marocgate, l\u2019enqu\u00eate Story Killers et l\u2019affaire du journaliste marocain Rachid M\u2019barki, les condamnations du Maroc s\u2019agissant d\u2019Omar Radi, de Naama Asfari, etc., etc. il serait d\u2019une part risqu\u00e9 pour Macron de se rendre \u00e0 Rabat. D\u2019autre part, s\u2019il s\u2019aligne sur les demandes du Maroc, il discr\u00e9ditera totalement la diplomatie fran\u00e7aise dans l\u2019ar\u00e8ne africaine et au regard des sp\u00e9cialistes du droit international.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>lapatrienews.dz Entretien Pr. Yazid Ben Hounet\u00a0: \u00ab\u00a0La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale\u00a0\u00bb \u00a0 Le&hellip;<\/p>\n","protected":false},"author":58,"featured_media":70561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[49],"tags":[],"class_list":["post-70560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entretien \u2013 Pr. Yazid Ben Hounet : \u00ab La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale \u00bb - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entretien \u2013 Pr. Yazid Ben Hounet : \u00ab La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale \u00bb - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"lapatrienews.dz Entretien Pr. Yazid Ben Hounet\u00a0: \u00ab\u00a0La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale\u00a0\u00bb \u00a0 Le&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-17T18:44:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-17T18:45:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/02\/Capture-57.png\" \/>\n\t<meta property=\"og:image:width\" content=\"799\" \/>\n\t<meta property=\"og:image:height\" content=\"462\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mohamed Redha Chettibi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mohamed Redha Chettibi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\\\/\"},\"author\":{\"name\":\"Mohamed Redha Chettibi\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\"},\"headline\":\"Entretien \u2013 Pr. Yazid Ben Hounet : \u00ab La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale \u00bb\",\"datePublished\":\"2023-02-17T18:44:55+00:00\",\"dateModified\":\"2023-02-17T18:45:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\\\/\"},\"wordCount\":1685,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Capture-57.png\",\"articleSection\":[\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\\\/\",\"name\":\"Entretien \u2013 Pr. Yazid Ben Hounet : \u00ab La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale \u00bb - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Capture-57.png\",\"datePublished\":\"2023-02-17T18:44:55+00:00\",\"dateModified\":\"2023-02-17T18:45:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Capture-57.png\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Capture-57.png\",\"width\":799,\"height\":462},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entretien \u2013 Pr. Yazid Ben Hounet : \u00ab La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\",\"name\":\"Mohamed Redha Chettibi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"caption\":\"Mohamed Redha Chettibi\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/mrc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entretien \u2013 Pr. Yazid Ben Hounet : \u00ab La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale \u00bb - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/","og_locale":"fr_FR","og_type":"article","og_title":"Entretien \u2013 Pr. Yazid Ben Hounet : \u00ab La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale \u00bb - AAH.JZR","og_description":"lapatrienews.dz Entretien Pr. Yazid Ben Hounet\u00a0: \u00ab\u00a0La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale\u00a0\u00bb \u00a0 Le&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2023-02-17T18:44:55+00:00","article_modified_time":"2023-02-17T18:45:42+00:00","og_image":[{"width":799,"height":462,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/02\/Capture-57.png","type":"image\/png"}],"author":"Mohamed Redha Chettibi","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mohamed Redha Chettibi","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/"},"author":{"name":"Mohamed Redha Chettibi","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77"},"headline":"Entretien \u2013 Pr. Yazid Ben Hounet : \u00ab La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale \u00bb","datePublished":"2023-02-17T18:44:55+00:00","dateModified":"2023-02-17T18:45:42+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/"},"wordCount":1685,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/02\/Capture-57.png","articleSection":["Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/","url":"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/","name":"Entretien \u2013 Pr. Yazid Ben Hounet : \u00ab La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale \u00bb - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/02\/Capture-57.png","datePublished":"2023-02-17T18:44:55+00:00","dateModified":"2023-02-17T18:45:42+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/02\/Capture-57.png","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/02\/Capture-57.png","width":799,"height":462},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/entretien-pr-yazid-ben-hounet-la-tribune-qui-vient-de-paraitre-dans-le-monde-est-hypocrite-sournoise-et-neocoloniale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Entretien \u2013 Pr. Yazid Ben Hounet : \u00ab La tribune qui vient de para\u00eetre dans Le Monde est hypocrite, sournoise et n\u00e9ocoloniale \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77","name":"Mohamed Redha Chettibi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","caption":"Mohamed Redha Chettibi"},"url":"https:\/\/jazairhope.org\/fr\/author\/mrc\/"}]}},"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/70560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=70560"}],"version-history":[{"count":2,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/70560\/revisions"}],"predecessor-version":[{"id":70567,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/70560\/revisions\/70567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/70561"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=70560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=70560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=70560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}