{"id":70612,"date":"2023-02-18T19:22:08","date_gmt":"2023-02-18T18:22:08","guid":{"rendered":"https:\/\/jazairhope.org\/?p=70612"},"modified":"2023-02-18T19:22:08","modified_gmt":"2023-02-18T18:22:08","slug":"maroc-et-algerie-ni-paix-ni-guerre","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/","title":{"rendered":"Maroc et Alg\u00e9rie : ni paix, ni guerre"},"content":{"rendered":"<p><span style=\"color: #003366\">Source:<strong> nvo.ng.ru<\/strong><\/span><\/p>\n<p><span style=\"color: #003366\">Par <strong>Alexander Anatolyevich Khramchikhin<\/strong>, expert militaire ind\u00e9pendant.<\/span><\/p>\n<p><span style=\"color: #003366\">Traduit du Russe<\/span><\/p>\n<article class=\"typical\"><span style=\"color: #003366\">L&#8217;affrontement entre l&#8217;Alg\u00e9rie et le Maroc, anciennement partie de l&#8217;empire colonial fran\u00e7ais, s&#8217;\u00e9ternise depuis plus d&#8217;un demi-si\u00e8cle.\u00a0Cela ne s&#8217;est jamais transform\u00e9 en une guerre directe, mais il n&#8217;y a pas de fin en vue \u00e0 la confrontation.\u00a0Les voisins de l&#8217;ouest du Maghreb continuent d&#8217;\u00e9changer des d\u00e9clarations extr\u00eamement dures, continuant \u00e0 renforcer leur puissance militaire.<\/span><\/p>\n<p><span style=\"color: #003366\">L&#8217;Alg\u00e9rie a acc\u00e9d\u00e9 \u00e0 l&#8217;ind\u00e9pendance par la plus difficile des guerres anti-coloniales (&#8220;Op\u00e9rations de combat de la France apr\u00e8s la Seconde Guerre mondiale&#8221;, &#8220;NVO&#8221;, 15\/11\/19) contre un million de contingents fran\u00e7ais.\u00a0C&#8217;est gr\u00e2ce \u00e0 cette guerre que le Maroc a acc\u00e9d\u00e9 pacifiquement \u00e0 son ind\u00e9pendance.\u00a0&#8220;En signe de gratitude&#8221;, le Maroc pr\u00e9sente des revendications territoriales \u00e0 son voisin et, en octobre 1963, proc\u00e8de \u00e0 une invasion militaire directe de l&#8217;Alg\u00e9rie.<\/span><\/p>\n<p><span style=\"color: #003366\">Cuba est venu en aide \u00e0 l&#8217;Alg\u00e9rie.\u00a0L&#8217;invasion s&#8217;est arr\u00eat\u00e9e l\u00e0, mais la &#8220;pr\u00e9cipitation&#8221; est rest\u00e9e, et tr\u00e8s forte.\u00a0Par cons\u00e9quent, lorsque le Maroc a commenc\u00e9 la guerre pour le Sahara occidental, l&#8217;Alg\u00e9rie a fourni une assistance globale au Front Polisario.\u00a0Il a fourni aux Sahraouis les armes sovi\u00e9tiques les plus modernes et a parfois combattu directement contre le Maroc (par exemple, les syst\u00e8mes de d\u00e9fense a\u00e9rienne alg\u00e9riens ont abattu des avions marocains au-dessus du Sahara occidental depuis leur territoire).\u00a0En 1987, les parties ont m\u00eame \u00e9chang\u00e9 des prisonniers.<\/span><\/p>\n<p><span style=\"color: #003366\">Plusieurs fois, les pays ont sembl\u00e9 se r\u00e9concilier en signant des accords politiques et \u00e9conomiques, mais la paix n&#8217;a pas fonctionn\u00e9.\u00a0Depuis 1994, la fronti\u00e8re entre les deux pays est officiellement ferm\u00e9e, bien que la contrebande (dont la drogue) et les migrants ill\u00e9gaux la traversent dans les deux sens.<\/span><\/p>\n<p><span style=\"color: #003366\">Rabat a r\u00e9cemment quelque peu g\u00e2ch\u00e9 ses relations avec Paris, mais entretient des liens \u00e9troits avec les \u00c9tats-Unis et avec les monarchies arabes.\u00a0L&#8217;Alg\u00e9rie continue d&#8217;\u00eatre amie avec la Russie (notamment sur la base de la coop\u00e9ration militaro-technique) et entretient des relations favorables avec la plupart des pays europ\u00e9ens.\u00a0La Chine est pragmatiquement amicale avec les deux parties, tout en reconnaissant pleinement le droit du Maroc au Sahara Occidental.<\/span><\/p>\n<p><span style=\"color: #003366\">Les deux pays marchent constamment au bord de la guerre, mais ne la traversent jamais.\u00a0Une telle marche peut-elle \u00eatre interminable ou un jour les pays se briseront encore (probablement \u00e0 cause du m\u00eame Sahara Occidental) ?<\/span><\/p>\n<p><span style=\"color: #003366\">Si une panne survient, alors sans aide ext\u00e9rieure, le sort du Maroc ne semble pas rose.\u00a0L&#8217;Alg\u00e9rie, d&#8217;une part, est beaucoup plus vaste, son territoire a une profondeur op\u00e9rationnelle importante.\u00a0Le Maroc, en revanche, est de petite superficie et \u00e9tir\u00e9 le long de la mer, sa largeur est insignifiante, surtout dans la partie sud.<\/span><\/p>\n<p><span style=\"color: #003366\">Mais l&#8217;essentiel, bien s\u00fbr, n&#8217;est pas cela, mais la sup\u00e9riorit\u00e9 tr\u00e8s significative de l&#8217;Alg\u00e9rie sur le Maroc dans toutes les classes d&#8217;\u00e9quipements militaires.<\/span><\/p>\n<p><span style=\"color: #003366\"><b>POSSIBILIT\u00c9 \u00c9VIDENTE<\/b><\/span><\/p>\n<p><span style=\"color: #003366\">La flotte de chars marocaine est une combinaison unique d&#8217;Abrams am\u00e9ricains, de T-72 sovi\u00e9tiques et de Tour 96 chinois (dans la version d&#8217;exportation du VT-4).\u00a0Leur nombre total n&#8217;est pas beaucoup plus que celui de l&#8217;Alg\u00e9rie &#8211; seulement des T-72.\u00a0\u00c0 peu pr\u00e8s \u00e9galement sur les c\u00f4t\u00e9s des chars plus anciens (M60 au Maroc, T-54\/55\/62 en Alg\u00e9rie).\u00a0Mais dans le m\u00eame temps, l&#8217;Alg\u00e9rie poss\u00e8de toujours 508 des derniers T-90, que le Maroc n&#8217;est en aucun cas en mesure de compenser.\u00a0Par ailleurs, l&#8217;Alg\u00e9rie est \u00e9galement en avance en mati\u00e8re de syst\u00e8mes antichars, tant sur le plan quantitatif que qualitatif.<\/span><\/p>\n<p><span style=\"color: #003366\">Le nombre d&#8217;h\u00e9licopt\u00e8res d&#8217;attaque SA342 au Maroc et Mi-24 en Alg\u00e9rie est \u00e0 peu pr\u00e8s le m\u00eame, mais les machines sovi\u00e9tiques sont beaucoup plus puissantes.\u00a0Ils sont compl\u00e9t\u00e9s par trois douzaines des derniers Mi-28N russes, contre lesquels le Maroc n&#8217;a rien.\u00a0&#8220;En m\u00eame temps&#8221;, l&#8217;arm\u00e9e alg\u00e9rienne dispose du MLRS &#8220;Smerch&#8221; et du TOS-1A russes, ainsi que du SR-5 chinois, qui sont tr\u00e8s bien adapt\u00e9s pour percer n&#8217;importe quelle d\u00e9fense.<\/span><\/p>\n<p><span style=\"color: #003366\">Les Marocains n&#8217;ont pas d&#8217;analogues aux bombardiers de premi\u00e8re ligne Su-24, et plus encore aux chasseurs-bombardiers Su-30MKA, dont le nombre total dans l&#8217;arm\u00e9e de l&#8217;air alg\u00e9rienne est proche d&#8217;une centaine.\u00a023 nouveaux F-16 marocains sont enti\u00e8rement compens\u00e9s par trois douzaines de MiG-29 alg\u00e9riens.\u00a0Il est peu probable que les F-5 et Mirage-F1 marocains obsol\u00e8tes aident contre les v\u00e9hicules alg\u00e9riens modernes.<\/span><\/p>\n<p><span style=\"color: #003366\">De plus, le Maroc est tr\u00e8s mauvais en d\u00e9fense a\u00e9rienne au sol.\u00a0Il ne dispose que d&#8217;un nombre limit\u00e9 d&#8217;installations \u00e0 basse altitude, dont les meilleures sont 12 syst\u00e8mes de d\u00e9fense a\u00e9rienne de Tunguska.\u00a0L&#8217;Alg\u00e9rie a des moyens beaucoup plus similaires et ils sont g\u00e9n\u00e9ralement de meilleure qualit\u00e9 (notamment 38 syst\u00e8mes de d\u00e9fense a\u00e9rienne Pantsir-S1).\u00a0Mais en plus de cela, il y a huit autres divisions du syst\u00e8me de d\u00e9fense a\u00e9rienne S-300P, au moins une division du syst\u00e8me de d\u00e9fense a\u00e9rienne Buk-M2 et plus de 20 divisions de syst\u00e8mes de d\u00e9fense a\u00e9rienne plus anciens (S-75, S-125, Kvadrat).\u00a0Dans le m\u00eame temps, les capacit\u00e9s de l&#8217;aviation alg\u00e9rienne sont \u00e9galement compl\u00e9t\u00e9es par le syst\u00e8me de missile op\u00e9rationnel-tactique Iskander, auquel le Maroc ne peut rien opposer du tout.<\/span><\/p>\n<p><span style=\"color: #003366\">La sup\u00e9riorit\u00e9 de l&#8217;Alg\u00e9rie dans les airs aggrave encore la situation sur terre pour le Maroc.\u00a0En fait, tout le territoire marocain est \u00e0 la port\u00e9e des avions et des missiles alg\u00e9riens.\u00a0Alors que l&#8217;aviation marocaine a peu de chances de pouvoir influencer au moins les r\u00e9gions les plus occidentales de l&#8217;Alg\u00e9rie, sans parler du reste de son vaste territoire.\u00a0Autrement dit, l&#8217;arri\u00e8re de l&#8217;Alg\u00e9rie pourra travailler presque sans entrave, tandis que le Maroc n&#8217;aura pas d&#8217;arri\u00e8re du tout &#8211; l&#8217;ennemi l&#8217;aura partout.<\/span><\/p>\n<p><span style=\"color: #003366\">La situation est similaire en mer.\u00a0La marine marocaine dispose de trois fr\u00e9gates modernes de construction fran\u00e7aise, mais elles ne disposent pas de sous-marins, de corvettes et de bateaux lance-missiles, ni de grands navires de d\u00e9barquement.\u00a0L&#8217;Alg\u00e9rie a tout, et tr\u00e8s moderne.\u00a0Certes, en pr\u00e9sence d&#8217;une longue fronti\u00e8re terrestre, la guerre sur mer ne deviendra pas la principale, mais l&#8217;Alg\u00e9rie pourrait bien organiser un d\u00e9barquement sur la c\u00f4te m\u00e9diterran\u00e9enne du Maroc, sur le flanc droit de son groupe avan\u00e7ant sur Rabat.<\/span><\/p>\n<p><span style=\"color: #003366\">Attendre l&#8217;aide des monarchies arabes du Maroc est inutile pour des raisons au moins d&#8217;ordre g\u00e9ographique.\u00a0Madrid et Paris ont une relation ambigu\u00eb avec Rabat, de plus, l&#8217;Espagne et la France ne sont tout simplement pas pr\u00eates pour la guerre contre un adversaire comme l&#8217;Alg\u00e9rie.\u00a0Le seul espoir du Maroc est aux \u00c9tats-Unis, mais il n&#8217;est pas du tout \u00e9vident que Washington doive participer \u00e0 une telle guerre.<\/span><\/p>\n<p><span style=\"color: #003366\">Une autre chose est que l&#8217;Alg\u00e9rie n&#8217;en a pas non plus besoin maintenant.\u00a0Concr\u00e8tement, une victoire sur le Maroc ne lui apportera rien, et d&#8217;ailleurs, il n&#8217;y a pas de raison directe de guerre.\u00a0Et le Maroc essaiera de ne pas donner une telle raison, bien qu&#8217;il ne soit cat\u00e9goriquement pas pr\u00eat \u00e0 abandonner le Sahara Occidental.<\/span><\/p>\n<p><span style=\"color: #003366\">Tr\u00e8s probablement, la guerre alg\u00e9ro-marocaine restera une possibilit\u00e9 latente : elle peut commencer \u00e0 tout moment, mais ce moment ne vient jamais.\u00a0<\/span><\/p>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Source: nvo.ng.ru Par Alexander Anatolyevich Khramchikhin, expert militaire ind\u00e9pendant. Traduit du Russe L&#8217;affrontement entre l&#8217;Alg\u00e9rie et le Maroc, anciennement partie de l&#8217;empire&hellip;<\/p>\n","protected":false},"author":58,"featured_media":70613,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[49],"tags":[],"class_list":["post-70612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maroc et Alg\u00e9rie : ni paix, ni guerre - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maroc et Alg\u00e9rie : ni paix, ni guerre - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"Source: nvo.ng.ru Par Alexander Anatolyevich Khramchikhin, expert militaire ind\u00e9pendant. Traduit du Russe L&#8217;affrontement entre l&#8217;Alg\u00e9rie et le Maroc, anciennement partie de l&#8217;empire&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-18T18:22:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/02\/Capture-61.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mohamed Redha Chettibi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mohamed Redha Chettibi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/maroc-et-algerie-ni-paix-ni-guerre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/maroc-et-algerie-ni-paix-ni-guerre\\\/\"},\"author\":{\"name\":\"Mohamed Redha Chettibi\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\"},\"headline\":\"Maroc et Alg\u00e9rie : ni paix, ni guerre\",\"datePublished\":\"2023-02-18T18:22:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/maroc-et-algerie-ni-paix-ni-guerre\\\/\"},\"wordCount\":1324,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/maroc-et-algerie-ni-paix-ni-guerre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Capture-61.png\",\"articleSection\":[\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/maroc-et-algerie-ni-paix-ni-guerre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/maroc-et-algerie-ni-paix-ni-guerre\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/maroc-et-algerie-ni-paix-ni-guerre\\\/\",\"name\":\"Maroc et Alg\u00e9rie : ni paix, ni guerre - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/maroc-et-algerie-ni-paix-ni-guerre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/maroc-et-algerie-ni-paix-ni-guerre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Capture-61.png\",\"datePublished\":\"2023-02-18T18:22:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/maroc-et-algerie-ni-paix-ni-guerre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/maroc-et-algerie-ni-paix-ni-guerre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/maroc-et-algerie-ni-paix-ni-guerre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Capture-61.png\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Capture-61.png\",\"width\":600,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/maroc-et-algerie-ni-paix-ni-guerre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maroc et Alg\u00e9rie : ni paix, ni guerre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\",\"name\":\"Mohamed Redha Chettibi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"caption\":\"Mohamed Redha Chettibi\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/mrc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maroc et Alg\u00e9rie : ni paix, ni guerre - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/","og_locale":"fr_FR","og_type":"article","og_title":"Maroc et Alg\u00e9rie : ni paix, ni guerre - AAH.JZR","og_description":"Source: nvo.ng.ru Par Alexander Anatolyevich Khramchikhin, expert militaire ind\u00e9pendant. Traduit du Russe L&#8217;affrontement entre l&#8217;Alg\u00e9rie et le Maroc, anciennement partie de l&#8217;empire&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2023-02-18T18:22:08+00:00","og_image":[{"width":600,"height":360,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/02\/Capture-61.png","type":"image\/png"}],"author":"Mohamed Redha Chettibi","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mohamed Redha Chettibi","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/"},"author":{"name":"Mohamed Redha Chettibi","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77"},"headline":"Maroc et Alg\u00e9rie : ni paix, ni guerre","datePublished":"2023-02-18T18:22:08+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/"},"wordCount":1324,"commentCount":0,"image":{"@id":"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/02\/Capture-61.png","articleSection":["Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/","url":"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/","name":"Maroc et Alg\u00e9rie : ni paix, ni guerre - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/02\/Capture-61.png","datePublished":"2023-02-18T18:22:08+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/02\/Capture-61.png","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/02\/Capture-61.png","width":600,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/maroc-et-algerie-ni-paix-ni-guerre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Maroc et Alg\u00e9rie : ni paix, ni guerre"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77","name":"Mohamed Redha Chettibi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","caption":"Mohamed Redha Chettibi"},"url":"https:\/\/jazairhope.org\/fr\/author\/mrc\/"}]}},"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/70612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=70612"}],"version-history":[{"count":1,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/70612\/revisions"}],"predecessor-version":[{"id":70616,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/70612\/revisions\/70616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/70613"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=70612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=70612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=70612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}