{"id":95153,"date":"2023-12-23T16:41:00","date_gmt":"2023-12-23T15:41:00","guid":{"rendered":"https:\/\/jazairhope.org\/?p=95153"},"modified":"2023-12-23T16:41:00","modified_gmt":"2023-12-23T15:41:00","slug":"un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024","status":"publish","type":"post","link":"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/","title":{"rendered":"Un long m\u00e9trage sur Frantz Fanon programm\u00e9 \u00e0 la Berlinale 2024"},"content":{"rendered":"<p>lesoirdalgerie.com<\/p>\n<blockquote><p><strong>Le long m\u00e9trage de fiction, &#8220;Chroniques fid\u00e8les survenues au si\u00e8cle dernier \u00e0 l\u2019h\u00f4pital psychiatrique Blida-Joinville, au temps o\u00f9 le docteur Frantz Fanon \u00e9tait chef de la cinqui\u00e8me division entre 1953 et 1956&#8221; du r\u00e9alisateur alg\u00e9rien Abdenour Zahzah sera projet\u00e9 au 74e Festival international du film de Berlin (Allemagne), pr\u00e9vu du 15 au 25 f\u00e9vrier 2024, ont indiqu\u00e9 les organisateurs sur le Site officiel de la Berlinale.<\/strong><\/p><\/blockquote>\n<p>Le film alg\u00e9ro-fran\u00e7ais d\u2019Abdenour Zahzah, programm\u00e9 \u00e0 la section &#8220;Forum&#8221; de la &#8220;Berlinale 2024&#8221;, est &#8220;coproduit par le Centre alg\u00e9rien du d\u00e9veloppement du cin\u00e9ma (CADC) et deux autres soci\u00e9t\u00e9s priv\u00e9es de production&#8221;, explique le r\u00e9alisateur.<\/p>\n<p>Dans ce long m\u00e9trage, le r\u00e9alisateur revient sur les in\u00e9galit\u00e9s et les injustices, ouvertement commises et pratiqu\u00e9es, entre 1953 et 1956 durant la colonisation fran\u00e7aise, par le personnel soignant de l\u2019h\u00f4pital psychiatrique &#8220;Blida-Joinville&#8221; (rebaptis\u00e9 apr\u00e8s l&#8217;Ind\u00e9pendance H\u00f4pital Frantz Fanon) \u00e0 l\u2019encontre des malades intern\u00e9s alg\u00e9riens (musulmans).<br \/>\nCe traitement discriminatoire et inhumain, va conduire Frantz Fanon \u00e0 embrasser la cause nationale, rejoignant alors, le combat pour l\u2019ind\u00e9pendance de l\u2019Alg\u00e9rie.<\/p>\n<p>D\u2019une dur\u00e9e de 90mn, ce film de fiction est servi par une pl\u00e9iade de com\u00e9diens alg\u00e9riens et \u00e9trangers dont, l&#8217;acteur fran\u00e7ais d&#8217;origine ha\u00eftienne Alexandre Desane (dans le r\u00f4le de Frantz Fanon).<\/p>\n<p>N\u00e9 en 1973 \u00e0 Blida, Abdenour Zahzah a suivi des \u00e9tudes sup\u00e9rieures dans le domaine audiovisuel, abouties \u00e0 l\u2019universit\u00e9 d\u2019Alger en 1997, pour se voir, ensuite, nomm\u00e9 en 1998 \u00e0 la t\u00eate de la cin\u00e9math\u00e8que de Blida qu\u2019il dirigera jusqu\u2019en 2003.<\/p>\n<p>Revenu en Alg\u00e9rie en 2006, il r\u00e9alise, trois ann\u00e9es plus tard pour le compte du 2e Festival Panafricain d\u2019Alger, &#8220;La Longue Marche vers le Nepad&#8221; un film autour du d\u00e9veloppement de l\u2019Afrique, tourn\u00e9 dans quatre pays: Alg\u00e9rie, Afrique du Sud, Burkina Faso et S\u00e9n\u00e9gal, pour signer, ensuite en 2010, &#8220;Garagouz&#8221; sa premi\u00e8re fiction.<\/p>\n<p>D\u2019autres films sont \u00e9galement \u00e0 l\u2019actif du cin\u00e9aste, &#8220;M\u00e9moire d\u2019asile&#8221; (2002), &#8220;Sous le soleil, le plomb&#8221; (2005), &#8220;Le Non-Faire&#8221; et &#8220;Maurice Pons, \u00e9crivain de l\u2019\u00e9trange&#8221; (2007) et &#8220;El Oued, El Oued&#8221; (2013).<\/p>\n<p>Cr\u00e9\u00e9 en 1951, le Festival international du film de Berlin est l\u2019&#8221;un des plus anciens et plus importants festivals comp\u00e9titifs au monde&#8221; qui se tient le mois de f\u00e9vrier de chaque ann\u00e9e, repr\u00e9sentant un &#8220;carrefour consid\u00e9rable pour le march\u00e9 mondial du film&#8221;, peut-on lire sur le Site officiel de pr\u00e9sentation de la &#8220;Berlinale&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>lesoirdalgerie.com Le long m\u00e9trage de fiction, &#8220;Chroniques fid\u00e8les survenues au si\u00e8cle dernier \u00e0 l\u2019h\u00f4pital psychiatrique Blida-Joinville, au temps o\u00f9 le docteur Frantz&hellip;<\/p>\n","protected":false},"author":58,"featured_media":95154,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[34,39,42],"tags":[],"class_list":["post-95153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art-fr","category-articles-en-vedette","category-histoire-et-patrimoine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un long m\u00e9trage sur Frantz Fanon programm\u00e9 \u00e0 la Berlinale 2024 - AAH.JZR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un long m\u00e9trage sur Frantz Fanon programm\u00e9 \u00e0 la Berlinale 2024 - AAH.JZR\" \/>\n<meta property=\"og:description\" content=\"lesoirdalgerie.com Le long m\u00e9trage de fiction, &#8220;Chroniques fid\u00e8les survenues au si\u00e8cle dernier \u00e0 l\u2019h\u00f4pital psychiatrique Blida-Joinville, au temps o\u00f9 le docteur Frantz&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"AAH.JZR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jazairhope\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-23T15:41:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/12\/Capture-2-20.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"848\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mohamed Redha Chettibi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mohamed Redha Chettibi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\\\/\"},\"author\":{\"name\":\"Mohamed Redha Chettibi\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\"},\"headline\":\"Un long m\u00e9trage sur Frantz Fanon programm\u00e9 \u00e0 la Berlinale 2024\",\"datePublished\":\"2023-12-23T15:41:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\\\/\"},\"wordCount\":444,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Capture-2-20.jpg\",\"articleSection\":[\"Art &amp; Culture\",\"Articles en vedette\",\"Histoire et Patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\\\/\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\\\/\",\"name\":\"Un long m\u00e9trage sur Frantz Fanon programm\u00e9 \u00e0 la Berlinale 2024 - AAH.JZR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Capture-2-20.jpg\",\"datePublished\":\"2023-12-23T15:41:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Capture-2-20.jpg\",\"contentUrl\":\"https:\\\/\\\/jazairhope.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Capture-2-20.jpg\",\"width\":848,\"height\":423},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un long m\u00e9trage sur Frantz Fanon programm\u00e9 \u00e0 la Berlinale 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/\",\"name\":\"AAH.JZR\",\"description\":\"Environment, Health, Science, Art, Economics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/#\\\/schema\\\/person\\\/25f89793241399d8600e452019d99b77\",\"name\":\"Mohamed Redha Chettibi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g\",\"caption\":\"Mohamed Redha Chettibi\"},\"url\":\"https:\\\/\\\/jazairhope.org\\\/fr\\\/author\\\/mrc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un long m\u00e9trage sur Frantz Fanon programm\u00e9 \u00e0 la Berlinale 2024 - AAH.JZR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/","og_locale":"fr_FR","og_type":"article","og_title":"Un long m\u00e9trage sur Frantz Fanon programm\u00e9 \u00e0 la Berlinale 2024 - AAH.JZR","og_description":"lesoirdalgerie.com Le long m\u00e9trage de fiction, &#8220;Chroniques fid\u00e8les survenues au si\u00e8cle dernier \u00e0 l\u2019h\u00f4pital psychiatrique Blida-Joinville, au temps o\u00f9 le docteur Frantz&hellip;","og_url":"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/","og_site_name":"AAH.JZR","article_publisher":"https:\/\/www.facebook.com\/jazairhope","article_published_time":"2023-12-23T15:41:00+00:00","og_image":[{"width":848,"height":423,"url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/12\/Capture-2-20.jpg","type":"image\/jpeg"}],"author":"Mohamed Redha Chettibi","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mohamed Redha Chettibi","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/#article","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/"},"author":{"name":"Mohamed Redha Chettibi","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77"},"headline":"Un long m\u00e9trage sur Frantz Fanon programm\u00e9 \u00e0 la Berlinale 2024","datePublished":"2023-12-23T15:41:00+00:00","mainEntityOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/"},"wordCount":444,"commentCount":1,"image":{"@id":"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/12\/Capture-2-20.jpg","articleSection":["Art &amp; Culture","Articles en vedette","Histoire et Patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/","url":"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/","name":"Un long m\u00e9trage sur Frantz Fanon programm\u00e9 \u00e0 la Berlinale 2024 - AAH.JZR","isPartOf":{"@id":"https:\/\/jazairhope.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/#primaryimage"},"image":{"@id":"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/12\/Capture-2-20.jpg","datePublished":"2023-12-23T15:41:00+00:00","author":{"@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77"},"breadcrumb":{"@id":"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/#primaryimage","url":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/12\/Capture-2-20.jpg","contentUrl":"https:\/\/jazairhope.org\/wp-content\/uploads\/2023\/12\/Capture-2-20.jpg","width":848,"height":423},{"@type":"BreadcrumbList","@id":"https:\/\/jazairhope.org\/fr\/un-long-metrage-sur-frantz-fanon-programme-a-la-berlinale-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jazairhope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Un long m\u00e9trage sur Frantz Fanon programm\u00e9 \u00e0 la Berlinale 2024"}]},{"@type":"WebSite","@id":"https:\/\/jazairhope.org\/fr\/#website","url":"https:\/\/jazairhope.org\/fr\/","name":"AAH.JZR","description":"Environment, Health, Science, Art, Economics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jazairhope.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/jazairhope.org\/fr\/#\/schema\/person\/25f89793241399d8600e452019d99b77","name":"Mohamed Redha Chettibi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbd403d607af3d36f26025d8726b5d4b27c7ea4fe21ef10d17299a6c717ed442?s=96&d=mm&r=g","caption":"Mohamed Redha Chettibi"},"url":"https:\/\/jazairhope.org\/fr\/author\/mrc\/"}]}},"views":369,"_links":{"self":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/95153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/comments?post=95153"}],"version-history":[{"count":1,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/95153\/revisions"}],"predecessor-version":[{"id":95157,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/posts\/95153\/revisions\/95157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media\/95154"}],"wp:attachment":[{"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/media?parent=95153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/categories?post=95153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jazairhope.org\/fr\/wp-json\/wp\/v2\/tags?post=95153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}